{"id":97,"name":"Eduardo Domingo de Miguel","url":"","description":"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School.\r\nDirector de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad.\r\nFundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).","link":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/","slug":"eduardo-domingo-de-miguel","avatar_urls":{"24":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-24x24.jpeg","48":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-48x48.jpeg","96":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-96x96.jpeg"},"meta":[],"simple_local_avatar":{"media_id":104039,"full":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo.jpeg","blog_id":1,"192":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-192x192.jpeg","96":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-96x96.jpeg","300":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo.jpeg","150":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-150x150.jpeg","500":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo.jpeg","234":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-234x234.jpeg","117":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-117x117.jpeg","24":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-24x24.jpeg","48":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-48x48.jpeg","25":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-25x25.jpeg"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eduardo Domingo de Miguel<\/title>\n<meta name=\"description\" content=\"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Eduardo Domingo de Miguel\" \/>\n<meta property=\"og:description\" content=\"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"262\" \/>\n\t<meta property=\"og:image:height\" content=\"262\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/\",\"name\":\"Eduardo Domingo de Miguel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"description\":\"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archivos por Eduardo Domingo de Miguel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/045d09656201ee1c6cb9886c2364ab16\",\"name\":\"Eduardo Domingo de Miguel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-domingo-eduardo-96x96.jpeg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-domingo-eduardo-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cropped-domingo-eduardo-96x96.jpeg\",\"caption\":\"Eduardo Domingo de Miguel\"},\"description\":\"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).\",\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/eduardo.domingo.demiguel\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/eduardo-domingo-de-miguel\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eduardo Domingo de Miguel","description":"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/","og_locale":"es_ES","og_type":"profile","og_title":"Eduardo Domingo de Miguel","og_description":"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).","og_url":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","og_image":[{"width":262,"height":262,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@veredes","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/","url":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/","name":"Eduardo Domingo de Miguel","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"description":"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Archivos por Eduardo Domingo de Miguel"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/045d09656201ee1c6cb9886c2364ab16","name":"Eduardo Domingo de Miguel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-96x96.jpeg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-96x96.jpeg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/cropped-domingo-eduardo-96x96.jpeg","caption":"Eduardo Domingo de Miguel"},"description":"Licenciado en Biolog\u00eda y en Bioqu\u00edmica, Doctor en Biolog\u00eda y PDG por el IESE Business School. Director de Desarrollo de la Escuela T\u00e9cnica Superior de Arquitectura de la Universidad de Navarra, puesto que ocupa desde 2011.Con anterioridad, desempe\u00f1\u00f3 diversos cargos de responsabilidad en la gesti\u00f3n de otras \u00e1reas de la Universidad. Fundador del \u201cForo Am\u00e9rica\u201d, convenio marco de colaboraci\u00f3n entre la Universidad de Navarra y la Federaci\u00f3n Panamericana de Asociaciones de Arquitectos (FPAA).","sameAs":["https:\/\/www.instagram.com\/eduardo.domingo.demiguel"],"mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/author\/eduardo-domingo-de-miguel\/"}}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/97","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users"}]}}