{"id":98425,"date":"2024-05-15T00:01:44","date_gmt":"2024-05-14T22:01:44","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=98425"},"modified":"2024-04-19T19:34:31","modified_gmt":"2024-04-19T17:34:31","slug":"casa-cedofeita-paulo-moreira-architectures","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/","title":{"rendered":"Casa Cedofeita | Paulo Moreira Architectures"},"content":{"rendered":"<figure id=\"attachment_98428\" aria-describedby=\"caption-attachment-98428\" style=\"width: 1708px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-98428 size-full\" title=\"Casa Cedofeita Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-scaled.jpg\" alt=\"Casa Cedofeita Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\" width=\"1708\" height=\"2560\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-scaled.jpg 1708w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-200x300.jpg 200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-683x1024.jpg 683w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-1025x1536.jpg 1025w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-1366x2048.jpg 1366w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-280x420.jpg 280w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-696x1043.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-1-1068x1601.jpg 1068w\" sizes=\"auto, (max-width: 1708px) 100vw, 1708px\" \/><figcaption id=\"caption-attachment-98428\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Casa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Un antiguo edificio burgu\u00e9s en el centro de la ciudad de Oporto ha sido convertido en una casa de cinco habitaciones. El proyecto tiene dos dimensiones clave: una cuidadosa <a href=\"https:\/\/veredes.es\/blog\/tag\/rehabilitacion\/\" target=\"_blank\" rel=\"noopener\">restauraci\u00f3n<\/a> de la estructura existente utilizando materiales y t\u00e9cnicas de construcci\u00f3n tradicionales, y la inserci\u00f3n de nuevos vol\u00famenes de madera para albergar la infraestructura y \u00e1reas de servicio.<\/p>\n<figure id=\"attachment_98429\" aria-describedby=\"caption-attachment-98429\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-98429 size-full\" title=\"Casa Cedofeita | Paulo Moreira Architectures | Axonometria\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria.jpg\" alt=\"Casa Cedofeita Paulo Moreira Architectures 5 Axonometria\" width=\"1400\" height=\"724\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria-300x155.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria-1024x530.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria-812x420.jpg 812w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria-696x360.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-5-Axonometria-1068x552.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-98429\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Casa Cedofeita | Paulo Moreira Architectures | Axonometria<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Los nuevos vol\u00famenes de forma triangular se adaptan a las caracter\u00edsticas de cada habitaci\u00f3n, creando variaciones dentro de una sola familia de elementos. Acomodan el ba\u00f1o, el armario, \u00e1reas de almacenamiento y una peque\u00f1a cocina, permitiendo el uso independiente de cada unidad cuando sea necesario.<\/p>\n<div id='gallery-1' class='gallery galleryid-98425 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-2-1-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-2-1-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita no Porto do Atelier de Arquitectura Paulo Moreira\" aria-describedby=\"gallery-1-98438\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98438'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-3-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-3-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita no Porto do Atelier de Arquitectura Paulo Moreira\" aria-describedby=\"gallery-1-98431\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98431'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-4-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-4-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98432\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98432'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-5-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-5-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98433\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98433'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-8-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-8-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98436\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98436'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-7-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-7-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98435\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98435'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-6-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-6-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98434\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98434'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-9-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-9-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita com Arquitectura Paulo Moreira Architectures\" aria-describedby=\"gallery-1-98437\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-1-98437'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">Las caracter\u00edsticas originales: paredes de piedra de granito, techos de estuco, vigas de madera, contraventanas, puertas, escaleras y tragaluces, se restauran de manera respetuosa y \u00absilenciosa\u00bb. Diferentes caracter\u00edsticas se destacan en cada habitaci\u00f3n para crear una serie de espacios \u00fanicos.<\/p>\n<div id='gallery-2' class='gallery galleryid-98425 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-1-Situacion.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-1-Situacion-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita Paulo Moreira Architectures 1 Situaci\u00f3n\" aria-describedby=\"gallery-2-98439\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-98439'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures | Situaci\u00f3n\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-2-Plantas.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-2-Plantas-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita Paulo Moreira Architectures 2 Plantas\" aria-describedby=\"gallery-2-98440\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-98440'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures | Plantas\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-3-Modelos.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-3-Modelos-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita Paulo Moreira Architectures 3 Modelos\" aria-describedby=\"gallery-2-98441\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-98441'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures | Modelos\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-4-Conceptual-Plan.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-4-Conceptual-Plan-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita Paulo Moreira Architectures 4 Conceptual Plan\" aria-describedby=\"gallery-2-98442\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-2-98442'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures | Concepto\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">Los materiales utilizados van desde madera hasta m\u00e1rmol, arcilla, azulejos y granito. A pesar de la variedad de materiales, la combinaci\u00f3n de tonos y texturas refuerza el di\u00e1logo entre lo antiguo y lo nuevo.<\/p>\n<div id='gallery-3' class='gallery galleryid-98425 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-11-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-11-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98444\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98444'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-12-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-12-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98445\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98445'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-13-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-13-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98446\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98446'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-14-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-14-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98447\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98447'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-15-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-15-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98448\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98448'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-16-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-16-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98449\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98449'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-17-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-17-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-3-98450\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98450'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-18-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-18-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"Casa Cedofeita Paulo Moreira Architectures \u00a9 Ivo Tavares Studio 18\" aria-describedby=\"gallery-3-98451\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-3-98451'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">Las dos dimensiones principales del proyecto: restauraci\u00f3n tradicional y adiciones contempor\u00e1neas, se extienden al aire libre, donde se requiri\u00f3 una peque\u00f1a sala t\u00e9cnica. La soluci\u00f3n de forma triangular aporta un sentido de coherencia al proyecto en su conjunto.<\/p>\n<div id='gallery-4' class='gallery galleryid-98425 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-19-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-19-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98452\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98452'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-21-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-21-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98453\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98453'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-22-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-22-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98454\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98454'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98455\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98455'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-24-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-24-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98456\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98456'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-25-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-25-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98457\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98457'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-26-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-26-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98458\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98458'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-27-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-27-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" aria-describedby=\"gallery-4-98459\" \/><\/a>\n\t\t\t<\/div>\n\t\t\t\t<figcaption class='wp-caption-text gallery-caption' id='gallery-4-98459'>\n\t\t\t\tCasa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\n\t\t\t\t<\/figcaption><\/figure>\n\t\t<\/div>\n\n<p style=\"text-align: justify;\">Obra: Casa Cedofeita<br \/>\nAutor: Paulo Moreira Architectures (Paulo Moreira)<br \/>\nColaboraci\u00f3n: Herm\u00ednio Santos, Elena Borghese, Flavia Micelli, Lauranne Coornaert, Carlos Gomes, Mario Mart\u00ednez<br \/>\nLocalizaci\u00f3n: Porto, Portugal<br \/>\nA\u00f1o: 2017<br \/>\n\u00c1rea: 220m2<br \/>\nConstructora: Jos\u00e9 Silva<br \/>\nFot\u00f3grafo: <a href=\"https:\/\/www.ivotavares.net\/\" target=\"_blank\" rel=\"noopener\">Ivo Tavares Studio\u00a0<\/a><br \/>\n<span style=\"color: #999999;\"><a style=\"color: #999999;\" href=\"https:\/\/paulomoreira.net\/\" target=\"_blank\" rel=\"noopener\">+ paulomoreira.net<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un antiguo edificio burgu\u00e9s en el centro de la ciudad de Oporto ha sido convertido en una casa de cinco habitaciones. El proyecto tiene dos dimensiones clave: una cuidadosa restauraci\u00f3n de la estructura existente utilizando materiales y t\u00e9cnicas de construcci\u00f3n tradicionales, y la inserci\u00f3n de nuevos vol\u00famenes de madera para albergar la infraestructura y \u00e1reas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":98455,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,23,1159,5951,59],"tags":[5819,17424,17423,12464,12455],"class_list":["post-98425","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arquitectura","category-obras","category-rehabilitacion","category-slider-principal","category-vivienda-unifamiliar","tag-arquitectura-portuguesa","tag-paulo-moreira","tag-paulo-moreira-architectures","tag-rehabilitacion","tag-vivienda-unifamiliar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa Cedofeita | Paulo Moreira Architectures - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa Cedofeita | Paulo Moreira Architectures - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-14T22:01:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Casa Cedofeita | Paulo Moreira Architectures\",\"datePublished\":\"2024-05-14T22:01:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/\"},\"wordCount\":332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg\",\"keywords\":[\"arquitectura portuguesa\",\"Paulo Moreira\",\"Paulo Moreira Architectures\",\"rehabilitaci\u00f3n\",\"vivienda unifamiliar\"],\"articleSection\":[\"arquitectura\",\"obras\",\"rehabilitaci\u00f3n\",\"slider principal\",\"vivienda unifamiliar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/\",\"name\":\"Casa Cedofeita | Paulo Moreira Architectures - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg\",\"datePublished\":\"2024-05-14T22:01:44+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Casa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-cedofeita-paulo-moreira-architectures\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa Cedofeita | Paulo Moreira Architectures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa Cedofeita | Paulo Moreira Architectures - veredes","description":"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/","og_locale":"es_ES","og_type":"article","og_title":"Casa Cedofeita | Paulo Moreira Architectures - veredes","og_description":"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures","og_url":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2024-05-14T22:01:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Casa Cedofeita | Paulo Moreira Architectures","datePublished":"2024-05-14T22:01:44+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/"},"wordCount":332,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg","keywords":["arquitectura portuguesa","Paulo Moreira","Paulo Moreira Architectures","rehabilitaci\u00f3n","vivienda unifamiliar"],"articleSection":["arquitectura","obras","rehabilitaci\u00f3n","slider principal","vivienda unifamiliar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/","url":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/","name":"Casa Cedofeita | Paulo Moreira Architectures - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg","datePublished":"2024-05-14T22:01:44+00:00","description":"Toda la informaci\u00f3n sobre: Casa Cedofeita | Paulo Moreira Architectures","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/05\/Casa-Cedofeita-Paulo-Moreira-Architectures-\u00a9-Ivo-Tavares-Studio-23-scaled.jpg","width":2560,"height":1707,"caption":"Casa Cedofeita | Paulo Moreira Architectures \u00a9 Ivo Tavares Studio"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/casa-cedofeita-paulo-moreira-architectures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Casa Cedofeita | Paulo Moreira Architectures"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/98425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=98425"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/98425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/98455"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=98425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=98425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=98425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}