{"id":96747,"date":"2024-01-29T00:01:32","date_gmt":"2024-01-28T23:01:32","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=96747"},"modified":"2024-01-23T19:50:06","modified_gmt":"2024-01-23T18:50:06","slug":"una-charla-en-weimar-oscar-tenreiro-degwitz","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/","title":{"rendered":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz"},"content":{"rendered":"<figure id=\"attachment_96748\" aria-describedby=\"caption-attachment-96748\" style=\"width: 1279px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96748 size-full\" title=\"Una charla en WeimaEscuela de Arquitectura de la Bauhaus Universit\u00e4t en Weimar, Alemania. Funciona en el edificio originalmente ocupado por la Bauhaus\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\" alt=\"Una charla en WeimaEscuela de Arquitectura de la Bauhaus Universit\u00e4t en Weimar, Alemania. Funciona en el edificio originalmente ocupado por la Bauhaus\" width=\"1279\" height=\"851\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg 1279w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus-300x200.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus-1024x681.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus-696x463.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus-1068x711.jpg 1068w\" sizes=\"auto, (max-width: 1279px) 100vw, 1279px\" \/><figcaption id=\"caption-attachment-96748\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Escuela de Arquitectura de la Bauhaus Universit\u00e4t en Weimar, Alemania. Funciona en el edificio originalmente ocupado por la Bauhaus, proyectado por Henry Van de Velde (1863-1957) y construido en 1911 \u00a9 \u00d3scar Tenreiro Degwitz<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La primera vez que estuve en Weimar, en la Escuela de Arquitectura que funciona en el edificio de <strong><a href=\"https:\/\/veredes.es\/blog\/tag\/henry-van-de-velde\/\" target=\"_blank\" rel=\"noopener\">Henry van de Velde<\/a><\/strong> (1863-1957) construido como sede de una Escuela de Arte que se transform\u00f3 despu\u00e9s en la Bauhaus, me sent\u00ed intimidado.<\/p>\n<p style=\"text-align: justify;\">Desde que entr\u00e9 en nuestra Facultad de Arquitectura en 1955, el nombre Bauhaus era muy sonoro y se\u00f1alaba una experiencia que los estudiantes de entonces est\u00e1bamos obligados a conocer. Y en los a\u00f1os posteriores inevitablemente ca\u00edan en manos de uno textos, comentarios o libros que trataban sobre lo que ella hab\u00eda significado para el desarrollo del dise\u00f1o y el modo como influ\u00eda en los m\u00e9todos docentes utilizados en la mayor parte de las Escuelas de Arquitectura de esos tiempos. Estar en la que hab\u00eda sido su sede inicial ten\u00eda para m\u00ed, pues, como lo tendr\u00eda para cualquier compa\u00f1ero de generaci\u00f3n, una especial repercusi\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Sent\u00eda algo parecido a lo que se siente en muchos lugares de Alemania: que all\u00ed han pasado cosas que marcaron muy fuertemente al mundo, para bien o para mal, y que uno, a\u00fan desde muy lejos, en cierto modo fue testigo de sus consecuencias o tuvo noticia viva de ellas. Testigo lejano pero testigo al fin. Es el privilegio o, visto de otra forma, el peso que tiene en ese pa\u00eds y su cultura, el haber protagonizado episodios decisivos muy frescos a\u00fan en la memoria colectiva universal.<\/p>\n<p style=\"text-align: justify;\">Me asaltaba una actitud reverencial el caminar por el edificio. En los descansos de las escaleras secundarias pod\u00eda ver los murales de algunos de los maestros tantas veces nombrados, pintados simplemente (y por eso constantemente restaurados), porque se trataba de gestos espont\u00e1neos que no aspiraban a la permanencia. A ambos lados de la escalera principal sendos bustos de Van de Velde y <a href=\"https:\/\/veredes.es\/blog\/?s=Walter+Gropius\" target=\"_blank\" rel=\"noopener\">Walter Gropius<\/a> a\u00f1ad\u00edan un toque de solemnidad.<\/p>\n<figure id=\"attachment_96749\" aria-describedby=\"caption-attachment-96749\" style=\"width: 1068px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96749 size-full\" title=\"Una charla en Weimar \u00d3scar Tenreiro Degwitz Escalera Principal de Bauhaus Universit\u00e4t en Weimar, Alemania\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Escalera-Principal-de-Bauhaus-Universitat-en-Weimar-Alemania.jpg\" alt=\"Una charla en Weimar \u00d3scar Tenreiro Degwitz Escalera Principal de Bauhaus Universit\u00e4t en Weimar, Alemania\" width=\"1068\" height=\"710\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Escalera-Principal-de-Bauhaus-Universitat-en-Weimar-Alemania.jpg 1068w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Escalera-Principal-de-Bauhaus-Universitat-en-Weimar-Alemania-300x199.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Escalera-Principal-de-Bauhaus-Universitat-en-Weimar-Alemania-1024x681.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Escalera-Principal-de-Bauhaus-Universitat-en-Weimar-Alemania-696x463.jpg 696w\" sizes=\"auto, (max-width: 1068px) 100vw, 1068px\" \/><figcaption id=\"caption-attachment-96749\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Escalera Principal de Bauhaus Universit\u00e4t en Weimar, Alemania \u00a9 \u00d3scar Tenreiro Degwitz<\/span><\/figcaption><\/figure>\n<h5><strong>Mi tercera visita <\/strong><\/h5>\n<p style=\"text-align: justify;\">Pero esta era mi tercera visita y en fin de cuentas estaba en una Escuela de Arquitectura, una m\u00e1s, eso era todo. Las resonancias personales<sup>1<\/sup>\u00a0cedieron espacio a la realidad de estos centros de ense\u00f1anza, bastante parecidos en lo esencial a la Escuela en la que me form\u00e9, la de aqu\u00ed, hoy transformada por los a\u00f1os pero no tan distinta de la que conoc\u00ed como estudiante, siempre referencia cada vez que visito otra, por m\u00e1s distinta que parezca.<\/p>\n<p style=\"text-align: justify;\">Y es que la ense\u00f1anza de la arquitectura difiere muy poco hoy, pese a todas las invasiones tecnol\u00f3gicas, de lo que ha sido desde los tiempos\u00a0Beaux Arts, hace m\u00e1s de tres siglos: una experiencia de Taller dirigida por un profesor y sus ayudantes, en la que el estudiante\u00a0aprende\u00a0a partir de la prueba y el error; y sus aproximaciones a la arquitectura se van enriqueciendo con los conocimientos t\u00e9cnicos y el desarrollo de destrezas. Y cuando uno discute los trabajos con los alumnos, lo cual ya hab\u00eda hecho en anteriores visitas, al ver sus inseguridades, o\u00edr de sus expectativas, resulta evidente que entre la gente m\u00e1s joven de aqu\u00ed y de all\u00e1 hay m\u00e1s similitudes que diferencias.<\/p>\n<p style=\"text-align: justify;\">Las verdaderas diferencias, las que conformar\u00e1n la arquitectura que algunos de ellos producir\u00e1n, son las diferencias culturales de la sociedad en la que viven. Son ellas las que los trascender\u00e1n, las que modelar\u00e1n su proceder por encima de sus particularidades personales, dictar\u00e1n sus conductas.<\/p>\n<p style=\"text-align: justify;\">Esas diferencias se expresan fundamentalmente en la ciudad. Es la ciudad la que\u00a0muestra\u00a0el desarrollo cultural, es su portadora podr\u00eda decirse. Y cuando uno se da cuenta que nuestra dirigencia olvida que en la forma de la ciudad,<sup>2<\/sup>\u00a0en su din\u00e1mica vital, en su capacidad de ser lugar democr\u00e1tico de tolerancia y convivencia, es donde se concreta y se expresa una acci\u00f3n pol\u00edtica, hay mucho espacio para nuestro desaliento.<\/p>\n<figure id=\"attachment_96750\" aria-describedby=\"caption-attachment-96750\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96750\" title=\"Una charla en Weimar \u00d3scar Tenreiro Escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg\" alt=\"Una charla en Weimar \u00d3scar Tenreiro Escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania\" width=\"750\" height=\"1128\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg 472w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania-199x300.jpg 199w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-96750\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania \u00a9 \u00d3scar Tenreiro Degwitz<\/span><\/figcaption><\/figure>\n<h5 style=\"text-align: justify;\"><strong>Una referencia al contexto<\/strong><\/h5>\n<p style=\"text-align: justify;\">La ciudad venezolana es la muestra de que nuestras condiciones de trabajo y el medio que condiciona nuestra arquitectura est\u00e1n a una enorme distancia de las de un pa\u00eds como Alemania. Y por ello hablar del trabajo personal sin ensayar una referencia al contexto, me parece una omisi\u00f3n imperdonable. Como eso no siempre es posible, lo que est\u00e1 m\u00e1s a la mano es intentar trasmitir lo que uno es. Hablo de las ra\u00edces culturales que le han dado forma a mis preferencias, de los obst\u00e1culos de actuar en un medio marcado por el atraso, donde la arquitectura est\u00e1 muy lejos de ser parte de la escena cultural.<\/p>\n<p style=\"text-align: justify;\">Y por all\u00ed va mi discurso, intentando situar las preocupaciones, las b\u00fasquedas, lo que considero aciertos. Me doy cuenta al hacerlo de las discontinuidades, de los caminos cerrados, de las dificultades a veces insuperables. Me muestro, podr\u00eda decir, como parte de un medio lleno de peque\u00f1as y grandes incoherencias, que tambi\u00e9n de alg\u00fan modo me han marcado.<\/p>\n<figure id=\"attachment_96751\" aria-describedby=\"caption-attachment-96751\" style=\"width: 1067px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96751 size-full\" title=\"Una charla en Weimar \u00d3scar Tenreiro Degwitz Composi\u00f3n en rellano de escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Composion-en-rellano-de-escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg\" alt=\"Una charla en Weimar \u00d3scar Tenreiro Degwitz Composi\u00f3n en rellano de escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania\" width=\"1067\" height=\"710\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Composion-en-rellano-de-escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg 1067w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Composion-en-rellano-de-escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania-300x200.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Composion-en-rellano-de-escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania-1024x681.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Composion-en-rellano-de-escalera-secundaria-en-Bauhaus-Universitat-en-Weimar-Alemania-696x463.jpg 696w\" sizes=\"auto, (max-width: 1067px) 100vw, 1067px\" \/><figcaption id=\"caption-attachment-96751\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Composi\u00f3n en rellano de escalera secundaria en Bauhaus Universit\u00e4t en Weimar, Alemania \u00a9 \u00d3scar Tenreiro Degwitz<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Aceptemos que hay historias personales diversas y que algunos por razones de temperamento o porque han vivido condiciones m\u00e1s o menos excepcionales (origen, medio, capacidad de adaptaci\u00f3n) tienen una trayectoria m\u00e1s lineal, m\u00e1s predecible. Pero a\u00fan esas excepciones no hacen sino confirmar una regla problem\u00e1tica: un arquitecto en la Venezuela de hoy est\u00e1 y ha estado sometido a tensiones y exigencias radicalmente contradictorias que marcan lo que hace o espera hacer. Somos hijos de un medio en el que lo normal es la anormalidad \u00bfpodemos ocultarlo? \u00bfes posible aparentar que no nos afecta?<sup>3\u00a0<\/sup><\/p>\n<p style=\"text-align: justify;\">Y se me hacen evidentes otro tipo de diferencias, que podr\u00eda llamar generacionales y que afectan claramente a los pa\u00edses latinoamericanos emergentes: los m\u00e1s j\u00f3venes se esfuerzan en aparentar extrema coherencia.<sup>4<\/sup>\u00a0Pareciera que s\u00f3lo as\u00ed pueden situarse en la escena internacional para merecer alguna atenci\u00f3n, como lo atestiguan algunos nombres generalmente sure\u00f1os que comienzan a circular en el mundo de la notoriedad.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00bfCu\u00e1nto hay de sostenible, para usar ese t\u00e9rmino tan a la moda, en esa pretensi\u00f3n de ser m\u00e1s que el medio en el que se vive?<\/strong><strong><sup>5<\/sup><\/strong><\/p>\n<figure id=\"attachment_96752\" aria-describedby=\"caption-attachment-96752\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96752\" title=\"Busto de Walter Gropius en Bauhaus Universit\u00e4t en Weimar, Alemania \u00a9 \u00d3scar Tenreiro Degwitz\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Busto-de-Walter-Gropius-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg\" alt=\"Una charla en Weimar \u00d3scar Tenreiro Degwitz Busto de Walter Gropius en Bauhaus Universit\u00e4t en Weimar, Alemania\" width=\"750\" height=\"1128\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Busto-de-Walter-Gropius-en-Bauhaus-Universitat-en-Weimar-Alemania.jpg 472w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-Weimar-Oscar-Tenreiro-Degwitz-Busto-de-Walter-Gropius-en-Bauhaus-Universitat-en-Weimar-Alemania-199x300.jpg 199w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-96752\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Busto de Walter Gropius en Bauhaus Universit\u00e4t en Weimar, Alemania \u00a9 \u00d3scar Tenreiro Degwitz<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\u00d3scar Tenreiro Degwitz, arquitecto.<br \/>\nVenezuela, Diciembre 2012<\/p>\n<h6><strong>Notas:<\/strong><\/h6>\n<p style=\"text-align: justify;\"><sup>1 <\/sup>Cada vez que recibo una invitaci\u00f3n para hablar de mi trabajo, no lo tengo simple. Durante una muy larga etapa de mi vida no me ocup\u00e9 de organizar lo que hac\u00eda, de documentarlo, de tenerlo ordenado y a la vista, con lo cual no hac\u00eda sino reproducir lo que era una constante en mi generaci\u00f3n: hac\u00edamos lo que nos era dado hacer\u2026y a otra cosa. Para completar el panorama, cuando ten\u00eda un encargo nunca dispon\u00eda ni de fondos adicionales ni de tiempo disponible para hacer planos de presentaci\u00f3n publicables, o de reunir ordenadamente la documentaci\u00f3n producida. Y las pocas cosas que fui logrando construir no las consideraba merecedoras de un registro fotogr\u00e1fico adecuado y de calidad.<\/p>\n<p style=\"text-align: justify;\">De ese modo, de casi todo lo que hice durante dos d\u00e9cadas, desde 1962, dos a\u00f1os despu\u00e9s de terminar mis estudios, tengo poca documentaci\u00f3n, mientras que lo producido posteriormente, si bien est\u00e1 mejor documentado es complicado presentarlo de una manera ordenada. No creo ser un caso especial entre la gente de mi edad. Es s\u00f3lo muy recientemente cuando los arquitectos aqu\u00ed en Venezuela documentan lo que hacen y lo preparan para publicarlo, siendo adem\u00e1s parte del panorama el hecho de que no hay publicaciones de arquitectura locales que puedan competir en calidad a nivel internacional. Y las que hay funcionan con est\u00e1ndares gr\u00e1ficos muy poco exigentes.<\/p>\n<p style=\"text-align: justify;\">Todo esto marca una distancia muy grande con cualquier arquitecto europeo, que ya desde los primeros esquemas se prepara para publicar, aparte de que no concibe hacer un trabajo que no est\u00e9 correctamente documentado.<\/p>\n<p style=\"text-align: justify;\"><sup>2 <\/sup>\u00bfC\u00f3mo ha influido en nuestro desarrollo personal el medio en el que hemos vivido? Trato de responder esa pregunta pero resulta arduo, si no imposible, ser preciso. Lo que s\u00e9 es que nuestras condiciones de trabajo son muy particulares. Por dif\u00edciles, siempre ajenas a una m\u00ednima estabilidad, amenazadas por la discontinuidad. Pero deteng\u00e1monos en la que menciono en la nota de hoy: la ciudad.<\/p>\n<p style=\"text-align: justify;\">\u00bfC\u00f3mo conciliar por ejemplo la b\u00fasqueda de armon\u00eda, de coherencia, que es el objetivo m\u00ednimo de nuestro trabajo de arquitectos, con el desprecio permanente a esos valores que se expresa en nuestras ciudades? \u00bfDe qu\u00e9 modo nuestro trabajo se inserta en esa realidad?<\/p>\n<p style=\"text-align: justify;\">Todas nuestras ciudades son muestras agresivas de una escasez de intenciones civilizadoras en t\u00e9rminos de forma urbana, de continuidad, de coherencia. Han crecido a partir de la inversi\u00f3n privada que se suma sin otra ley que el aprovechamiento de lo disponible luchando por adaptarse, viol\u00e1ndola cuando se puede, a una normativa legal \u00abmoderna\u00bb (\u00bf?) ajena a la forma de la ciudad. Crecimiento que va con las preferencias de una clase media que lucha por escapar de la ciudad tradicional. Ciudad tradicional que se ha desmembrado, agredido, despreciado, mientras se crean enclaves relativamente amables donde puede aspirarse a una vida que en general transcurre ajena a la convivencia ciudadana: vida de autom\u00f3vil que permite el traslado entre el hogar y el trabajo en ambiente protegido ajeno a cualquier conexi\u00f3n real con el espacio p\u00fablico, que, precisamente por ello, por carecer de presencia para los sectores m\u00e1s acomodados, se le presta apenas atenci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Y lo m\u00e1s notorio en ese panorama es que mientras en Venezuela esa situaci\u00f3n de derrota se ha hecho com\u00fan, en casi todas las dem\u00e1s ciudades latinoamericanas se vienen desarrollando planes que buscan revertir esa tendencia.<\/p>\n<p style=\"text-align: justify;\">En el pa\u00eds donde m\u00e1s dinero en divisas extranjeras ha llegado a manos del Estado es donde menos se ha hecho. En una sociedad dominada y controlada por un fen\u00f3meno pol\u00edtico que presume de ser revolucionario, la revoluci\u00f3n no ha hecho de la ganancia de espacio p\u00fablico y la acci\u00f3n sobre la ciudad algo merecedor de inter\u00e9s.<\/p>\n<p style=\"text-align: justify;\"><sup>3 <\/sup>Pensaba estas cosas hace poco en mi reciente visita a Maracaibo, la segunda ciudad de Venezuela, atendiendo a una invitaci\u00f3n de Distop\u00eda Lab, un grupo de arquitectos locales. Una ciudad que se percibe desde el autom\u00f3vil, pasando r\u00e1pidamente seg\u00fan lo permita la amenaza de los atascos, de zonas formales a informales, de sectores acomodados a desprovistos, de abandono a cierta civilidad, todo como una constante lucha de opuestos. Una ciudad que extiende su tejido de modo aparentemente indiferente a cualquier plan, que convive con un fen\u00f3meno natural \u00fanico, el Lago de Maracaibo, sin apenas percibirlo, m\u00e1s bien ignor\u00e1ndolo. Ciudad que sabemos que tiene virtudes, como las tienen otras ciudades nuestras, pero que se ocultan tras la din\u00e1mica del traslado de un lugar a otro, la rutina fundamental de sus habitantes.<\/p>\n<p style=\"text-align: justify;\"><sup>4 <\/sup>Estas incoherencias y desigualdades se repiten en cada ciudad venezolana. \u00bfSer\u00e1 ese radical divorcio entre nuestras aspiraciones como arquitectos y lo que acontece en la ciudad lo que nos define? \u00bfLo que influye en nuestro modo de pensar el edificio? Sea cual sea la respuesta me parece esencial que se piense en la conexi\u00f3n, que se trate de identificar. Cada vez que tengo que exponer lo que he hecho, se me hace necesario ir a esta relaci\u00f3n entre contexto y producci\u00f3n. Trato de encontrar las claves que han influido en nuestro desarrollo personal, m\u00e1s all\u00e1 de limitaciones o talentos.<\/p>\n<p style=\"text-align: justify;\"><sup>5 <\/sup>Y por eso me interno en una b\u00fasqueda no siempre exitosa para identificar mejor los l\u00edmites y est\u00edmulos, dejando un poco aparte el esfuerzo de presentarme solamente como arquitecto que opera en una escena parecida a la de cualquier otra parte del mundo. No, somos de un lugar distinto, espec\u00edfico, que ha pesado sobre nosotros.<\/p>\n<p style=\"text-align: justify;\">Y no lo hago para que me sirva de excusa por los errores u omisiones, sino para insistir en que la arquitectura est\u00e1 estrechamente vinculada a la vida y de ninguna manera puede ser juzgada fuera de la conexi\u00f3n con el espacio cultural donde se construye. En eso soy, definitivamente, hijo de un modo de ver la arquitectura esencialmente moderno.<\/p>\n<p style=\"text-align: justify;\">Y aclaro, es moderno, no \u00abmodernista\u00bb como gustan decir los periodistas norteamericanos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La primera vez que estuve en Weimar, en la Escuela de Arquitectura que funciona en el edificio de Henry van de Velde (1863-1957) construido como sede de una Escuela de Arte que se transform\u00f3 despu\u00e9s en la Bauhaus, me sent\u00ed intimidado. Desde que entr\u00e9 en nuestra Facultad de Arquitectura en 1955, el nombre Bauhaus era [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":96748,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[199,5989,10064,668,11762,1865,1278,3615],"class_list":["post-96747","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulos","category-slider-principal","tag-bauhaus","tag-ecole-de-beaux-arts","tag-henry-van-de-velde","tag-historia","tag-oscar-tenreiro-degwitz","tag-reflexion","tag-teoria","tag-walter-gropius"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-28T23:01:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1279\" \/>\n\t<meta property=\"og:image:height\" content=\"851\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/\"},\"author\":{\"name\":\"\u00d3scar Tenreiro Degwitz\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\"},\"headline\":\"Una charla en Weimar | \u00d3scar Tenreiro Degwitz\",\"datePublished\":\"2024-01-28T23:01:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/\"},\"wordCount\":2198,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\",\"keywords\":[\"Bauhaus\",\"ecole de beaux arts\",\"Henry van de Velde\",\"historia\",\"\u00d3scar Tenreiro Degwitz\",\"reflexi\u00f3n\",\"teor\u00eda\",\"Walter Gropius\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/\",\"name\":\"Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\",\"datePublished\":\"2024-01-28T23:01:32+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg\",\"width\":1279,\"height\":851,\"caption\":\"Escuela de Arquitectura de la Bauhaus Universit\u00e4t en Weimar, Alemania. Funciona en el edificio originalmente ocupado por la Bauhaus, proyectado por Henry Van de Velde (1863-1957) y construido en 1911\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/una-charla-en-weimar-oscar-tenreiro-degwitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una charla en Weimar | \u00d3scar Tenreiro Degwitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\",\"name\":\"\u00d3scar Tenreiro Degwitz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"caption\":\"\u00d3scar Tenreiro Degwitz\"},\"description\":\"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.\",\"sameAs\":[\"https:\\\/\\\/oscartenreiro.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/oscar-tenreiro-degwitz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes","description":"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/","og_locale":"es_ES","og_type":"article","og_title":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes","og_description":"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz","og_url":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2024-01-28T23:01:32+00:00","og_image":[{"width":1279,"height":851,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg","type":"image\/jpeg"}],"author":"\u00d3scar Tenreiro Degwitz","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"\u00d3scar Tenreiro Degwitz","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/"},"author":{"name":"\u00d3scar Tenreiro Degwitz","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19"},"headline":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz","datePublished":"2024-01-28T23:01:32+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/"},"wordCount":2198,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg","keywords":["Bauhaus","ecole de beaux arts","Henry van de Velde","historia","\u00d3scar Tenreiro Degwitz","reflexi\u00f3n","teor\u00eda","Walter Gropius"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/","url":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/","name":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg","datePublished":"2024-01-28T23:01:32+00:00","description":"Toda la informaci\u00f3n sobre: Una charla en Weimar | \u00d3scar Tenreiro Degwitz","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Una-charla-en-WeimaEscuela-de-Arquitectura-de-la-Bauhaus-Universitat-en-Weimar-Alemania.-Funciona-en-el-edificio-originalmente-ocupado-por-la-Bauhaus.jpg","width":1279,"height":851,"caption":"Escuela de Arquitectura de la Bauhaus Universit\u00e4t en Weimar, Alemania. Funciona en el edificio originalmente ocupado por la Bauhaus, proyectado por Henry Van de Velde (1863-1957) y construido en 1911"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/una-charla-en-weimar-oscar-tenreiro-degwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Una charla en Weimar | \u00d3scar Tenreiro Degwitz"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19","name":"\u00d3scar Tenreiro Degwitz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","caption":"\u00d3scar Tenreiro Degwitz"},"description":"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.","sameAs":["https:\/\/oscartenreiro.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/oscar-tenreiro-degwitz\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/96747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=96747"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/96747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/96748"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=96747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=96747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=96747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}