{"id":96613,"date":"2024-05-06T00:01:03","date_gmt":"2024-05-05T22:01:03","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=96613"},"modified":"2024-02-23T16:40:57","modified_gmt":"2024-02-23T15:40:57","slug":"cinco-miquel-lacasta","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/","title":{"rendered":"Cinco | Miquel Lacasta"},"content":{"rendered":"<figure id=\"attachment_96615\" aria-describedby=\"caption-attachment-96615\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-96615\" title=\"Cinco Miquel Lacasta un fragmento del frontispicio del libro\u00a0Arithmologia\u00a0de Athanasius Kircher\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\" alt=\"Cinco Miquel Lacasta un fragmento del frontispicio del libro\u00a0Arithmologia\u00a0de Athanasius Kircher\" width=\"750\" height=\"459\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg 640w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher-300x184.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-96615\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Un fragmento del frontispicio del libro <a href=\"http:\/\/diglib.hab.de\/drucke\/1-1arithm\/start.htm?image=00237\" target=\"_blank\" rel=\"noopener\">Arithmologia<\/a> de Athanasius Kircher.<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El n\u00famero m\u00e1s importante, la personalidad m\u00e1s influyente entre los arquetipos num\u00e9ricos fue para los pitag\u00f3ricos el cinco o la p\u00e9ntada y el diez o la d\u00e9cada.<\/p>\n<p style=\"text-align: justify;\">Cinco era el n\u00famero del amor si sum\u00e1bamos dos, el primer n\u00famero femenino y tres el primer n\u00famero impar masculino. Es interesante remarcar que los estudiantes chinos del\u00a0<em>Pa-Ka\u00a0<\/em>o los Ocho Trigramas M\u00e1gicos, reconocer\u00edan esta concepci\u00f3n de id\u00e9ntica manera, y curiosamente queda tambi\u00e9n justificada esta idea por la moderna teor\u00eda de los cromosomas y los genes. Cinco tambi\u00e9n es el n\u00famero de la higiene y la armon\u00eda. Con la p\u00e9ntada o el cinco iba asociada su s\u00edmbolo geom\u00e9trico, el pentagrama o pentalfa, cinco as entrelazadas, y se sabe que el pentagrama era el signo secreto de hermanamiento entre los pitag\u00f3ricos. La importancia de este s\u00edmbolo y de las construcciones relacionadas con \u00e9l, todas basadas en la secci\u00f3n \u00e1urea, eran celosamente guardadas como uno de los secretos m\u00e1s importantes de la Fraternidad.<\/p>\n<p style=\"text-align: justify;\">Hip\u00f3crates de Chios fue expulsado de la Fraternidad seg\u00fan consta, por haber explicado y divulgado la construcci\u00f3n de un pent\u00e1gono. La importancia asociada al pent\u00e1gono queda relatada por Athanasius Kircher en el cap\u00edtulo\u00a0<em>De Magicis Amuletis<\/em>\u00a0de su obra\u00a0<em><a href=\"http:\/\/diglib.hab.de\/drucke\/1-1arithm\/start.htm?image=00237\" target=\"_blank\" rel=\"noopener\">Arithmologia<\/a>,<\/em><sup>1<\/sup>donde cuenta c\u00f3mo los galates, el enemigo, fueron derrotados despu\u00e9s que Antiochus llevara consigo a la batalla un\u00a0<em>vexillum<\/em>, bandera empleada durante la antig\u00fcedad cl\u00e1sica, con el pentagrama, al ser advertido por sus augures tras interpretar uno de sus sue\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s de ver el destacado papel de la simetr\u00eda pentagonal y de la secci\u00f3n \u00e1urea asociada al pent\u00e1gono en la morfolog\u00eda de la vida y del crecimiento de lo vivo, la elecci\u00f3n de este s\u00edmbolo parece haber sido guiada por una extraordinaria intuici\u00f3n. En el\u00a0<em>Timeo<\/em>, Plat\u00f3n escoge el dodecaedro, que es la proyecci\u00f3n en tres dimensiones de un pent\u00e1gono, como gui\u00f3n esquem\u00e1tico de la armon\u00eda del cosmos. Realmente parece que Plat\u00f3n haya seguido la inspiraci\u00f3n pitag\u00f3rica.<\/p>\n<p style=\"text-align: justify;\">El pentagrama se convertir\u00e1 m\u00e1s tarde, especialmente en la sabidur\u00eda m\u00e1gica medieval, en el s\u00edmbolo especial del hombre, del microcosmos, en correspondencia por analog\u00eda con el universo o macrocosmos. El principio de analog\u00eda, formulado por el arquitecto alem\u00e1n August Thiersch y que durante el siglo XIX se convirti\u00f3 en el principio que lider\u00f3 el arte de occidente, ya se pod\u00eda encontrar en los pitag\u00f3ricos como una ley general:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>T\u00fa sabr\u00e1s, tan lejos como es posible en un mortal, que la Naturaleza es desde todos los puntos de vista, similar a s\u00ed misma<\/em>.<sup>2<\/sup><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">El s\u00edmbolo num\u00e9rico del macrocosmos o el universo era la d\u00e9cada o diez; La forma geom\u00e9trica correspondiente era el dec\u00e1gono. Sabemos que el dec\u00e1gono y el pent\u00e1gono tienen la misma l\u00f3gica en lo referente a la simetr\u00eda, regulada como no puede ser de otra manera, por la secci\u00f3n \u00e1urea. El concepto esot\u00e9rico de correspondencia o analog\u00eda entre el macrocosmos, simbolizado por el n\u00famero diez, y el microcosmos, simbolizado por el n\u00famero cinco, fue condensado por los herm\u00e9ticos, los cabalistas, los magos, los componentes de la Rosacruz, etc., y por la sentencia\u00a0<em>ID QUOD INFERIUS SICUT QUOD SUPERIUS\u00a0<\/em>tomada de la\u00a0<em>Tabla Esmeralda.<\/em><sup>3<\/sup><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/veredes.es\/blog\/tag\/vitruvio\/\" target=\"_blank\" rel=\"noopener\">Vitruvio<\/a> subraya las virtudes del n\u00famero diez, pero tambi\u00e9n la perfecci\u00f3n del n\u00famero seis; El n\u00famero seis, simbolizado geom\u00e9tricamente por un pseudo-hexagrama o por la estrella de David, est\u00e1 asociado como ya sabemos con la dura perfecci\u00f3n sim\u00e9trica de los cristales y la cristalograf\u00eda. La asociaci\u00f3n entre el diez y el seis como n\u00famero armonizadores importantes, ya fueron usados por los antiguos egipcios, especialmente por el cociente 10\/6=5\/3 que es la aproximaci\u00f3n de Fibonacci al n\u00famero \u03a6, para rect\u00e1ngulos y vol\u00famenes. Posteriormente esta relaci\u00f3n fue tomada por los arquitectos del renacimiento.<\/p>\n<h6 style=\"text-align: justify;\"><strong>El secreto del s\u00edmbolo<\/strong><\/h6>\n<p style=\"text-align: justify;\">Ahondando en lo esot\u00e9rico, quiz\u00e1s la aportaci\u00f3n m\u00e1s sugerente del libro\u00a0<em><a href=\"https:\/\/amzn.to\/47CNvQH\" target=\"_blank\" rel=\"noopener\">The geometry of art and life<\/a>,<\/em><sup>4 <\/sup>Matila Ghyka desenreda toda la simbolog\u00eda que acompa\u00f1a a la geometr\u00eda y los n\u00fameros. El pentagrama fue transmitido a lo largo de la historia de tres secretas y escondidas maneras posibles: como marco de los diagramas de planificaci\u00f3n secreta de arquitectos y maestros de masones, transmitidos de padres a hijos, como uno de los esot\u00e9ricos signos o s\u00edmbolos de reconocimiento de ciertas sociedades secretas y finalmente como un elemento que forma parte de rituales m\u00e1gicos.<\/p>\n<p style=\"text-align: justify;\">Los secretos pr\u00e1cticos del labrado de la piedra para la construcci\u00f3n de edificios fueron transmitidos por los gremios masones de la piedra, desde la antigua\u00a0<em>Collegia Opificum<\/em>\u00a0que ya exist\u00eda en los tiempos de la Rep\u00fablica Romana, a trav\u00e9s de sus sucesores por todo el imperio romano, m\u00e1s tarde mediante los talleres de arquitectura en los monasterios carolingios mayormente de la orden de los benedictinos, y finalmente entre los gremios de constructores y los masones federados durante el per\u00edodo g\u00f3tico en la\u00a0<em>Bauh\u00fctte,\u00a0<\/em>con la suprema sede central en la logia adosada a la catedral de Estrasburgo.<sup>5<\/sup><\/p>\n<p style=\"text-align: justify;\">En Inglaterra, los documentos masones m\u00e1s antiguos,\u00a0<em>Ordinationes of York<\/em>, de 1352 y 1409, mencionan al rey de Athelstan, 925 a 940, como aquel que estableci\u00f3 la primera sociedad mas\u00f3nica en las Islas Brit\u00e1nicas. Es interesante anotar aqu\u00ed que el\u00a0<a href=\"https:\/\/es.wikipedia.org\/wiki\/Manuscrito_Cooke\" target=\"_blank\" rel=\"noopener\"><em>Cooke Manuscript<\/em><\/a>, actualmente expuesto en el\u00a0<em>British Museum,\u00a0<\/em>copia de un texto del siglo XIV datado en 1430, menciona a Pit\u00e1goras y a Hermes como aquellos que revelaron los secretos de la geometr\u00eda a la raza humana. El mismo manuscrito en su parte estatutaria insiste en la obligaci\u00f3n de los Masones de no traicionar los secretos de su destreza.<\/p>\n<p style=\"text-align: justify;\">Mientras el Pentagrama viajaba como s\u00edmbolo m\u00e1gico y como herramienta a trav\u00e9s de c\u00edrculos ocultistas y de la Rosacruz,<sup>6 <\/sup>viajaba tambi\u00e9n en otra trayectoria, m\u00e1s pol\u00edtico-esot\u00e9rica, desde la Sociedad Pitag\u00f3rica hasta la moderna masoner\u00eda, donde la <em>Estrella Llameante\u00a0<\/em>no es m\u00e1s que el pentagrama, con una letra G en el medio, inscripci\u00f3n latina del hebreo\u00a0<em>Yold,\u00a0<\/em>es decir el n\u00famero diez o d\u00e9cada.<\/p>\n<p style=\"text-align: justify;\">Miquel Lacasta Codorniu. Doctor arquitecto<br \/>\nBarcelona, Abril 2015<\/p>\n<p style=\"text-align: justify;\"><sup>1<\/sup> Kircher, Athanasius, <em><a href=\"http:\/\/diglib.hab.de\/drucke\/1-1arithm\/start.htm?image=00237\" target=\"_blank\" rel=\"noopener\">Arithmologia<\/a>,\u00a0<\/em>Roma, 1665, p. 217.<\/p>\n<p style=\"text-align: justify;\"><sup>2<\/sup>\u00a0Esta cita se puede encontrar en la obra <em><a href=\"https:\/\/amzn.to\/4b1yACs\" target=\"_blank\" rel=\"noopener\">Hieros Logos<\/a>\u00a0<\/em>o\u00a0<em>Conversaciones Sagradas,\u00a0<\/em>dentro de la colecci\u00f3n\u00a0<em>Maestros de Samos<\/em>, ver\u00a0<em>Op. Cit.,<\/em>\u00a0GHYKA, 1977 (1946), p. 115.<\/p>\n<p style=\"text-align: justify;\"><sup>3<\/sup>\u00a0La Tabla Esmeralda de Hermes es la fuente original de la filosof\u00eda y la alquimia herm\u00e9tica. Seg\u00fan la leyenda, el texto fue originalmente tallado por Hermes en unas tablas esmeraldas y guardado en la C\u00e1mara Real de la gran pir\u00e1mide de Keops. La traducci\u00f3n de esta sentencia podr\u00eda ser:<em> \u201cLo que est\u00e1 abajo, se corresponde con lo que est\u00e1 arriba\u201d<\/em>.<\/p>\n<p style=\"text-align: justify;\"><sup>4<\/sup> Ghyka, Matila, <a href=\"https:\/\/amzn.to\/47CNvQH\" target=\"_blank\" rel=\"noopener\"><em>The Geometry of Art and Life<\/em><\/a>, Dover Publications Inc, Nueva York, 1977 (1946).<\/p>\n<p style=\"text-align: justify;\"><sup>5<\/sup>\u00a0La <em>Bauh\u00fctte<\/em>\u00a0se cre\u00f3 como federaci\u00f3n de las logias de los talladores de piedra, asociadas a las cuatro grandes logias de Estrasburgo, Colonia, Viena y Berna.\u00a0La de Estrasburgo fue reconocida como la Gran Logia Suprema y el Maestro de Obras de su catedral ejerc\u00eda la autoridad sobre todas las asociaciones locales dependientes de las otras logias mencionadas.<\/p>\n<p style=\"text-align: justify;\"><sup>6<\/sup>\u00a0Estos c\u00edrculos se encuentran en la obra de Agrippa de Nettesheim, <em>De Occulta Philosophia,\u00a0<\/em>de 1530, en\u00a0<em>Amphitheatre de l\u2019Eternelle Sapience\u00a0<\/em>de Henry Kunrath, 1609 y finalmente como pent\u00e1culo defensivo usado por Fausto contra Mephistopheles en el drama de Goethe, ver\u00a0<em>Op.\u00a0<\/em><em>Cit.,<\/em>\u00a0GHYKA, 1977 (1946), p. 118<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El n\u00famero m\u00e1s importante, la personalidad m\u00e1s influyente entre los arquetipos num\u00e9ricos fue para los pitag\u00f3ricos el cinco o la p\u00e9ntada y el diez o la d\u00e9cada. Cinco era el n\u00famero del amor si sum\u00e1bamos dos, el primer n\u00famero femenino y tres el primer n\u00famero impar masculino. Es interesante remarcar que los estudiantes chinos del\u00a0Pa-Ka\u00a0o [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":96615,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[17285,668,17286,4522,1021,1865,1278,2048,5771],"class_list":{"0":"post-96613","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articulos","8":"category-slider-principal","9":"tag-athanasius-kircher","10":"tag-historia","11":"tag-matila-ghyka","12":"tag-miquel-lacasta","13":"tag-pensamiento","14":"tag-reflexion","15":"tag-teoria","16":"tag-teoria-e-historia","17":"tag-vitruvio"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cinco | Miquel Lacasta - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinco | Miquel Lacasta - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/MikelLacastaCodorniu\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T22:01:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Miquel Lacasta Codorniu\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/miquelacasta\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Miquel Lacasta Codorniu\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/\"},\"author\":{\"name\":\"Miquel Lacasta Codorniu\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/11c5393188d51787b8b13761dea40343\"},\"headline\":\"Cinco | Miquel Lacasta\",\"datePublished\":\"2024-05-05T22:01:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/\"},\"wordCount\":1332,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\",\"keywords\":[\"Athanasius Kircher\",\"historia\",\"Matila Ghyka\",\"Miquel Lacasta\",\"pensamiento\",\"reflexi\u00f3n\",\"teor\u00eda\",\"teor\u00eda e historia\",\"Vitruvio\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/\",\"name\":\"Cinco | Miquel Lacasta - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\",\"datePublished\":\"2024-05-05T22:01:03+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg\",\"width\":640,\"height\":392,\"caption\":\"un fragmento del frontispicio del libro Arithmologia de Athanasius Kircher.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cinco-miquel-lacasta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cinco | Miquel Lacasta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/11c5393188d51787b8b13761dea40343\",\"name\":\"Miquel Lacasta Codorniu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g\",\"caption\":\"Miquel Lacasta Codorniu\"},\"description\":\"Es cofundador en ARCHIKUBIK y tambi\u00e9n en @kubik - espacio multidisciplinario. Obtuvo un Ph.D. con honores (cum laude) en ESARQ Universitat Internacional de Catalunya UIC y tambi\u00e9n fue galardonado con el premio especial Ph.D (UIC 2012), M.arch en ESARQ Universitat Internacional de Catalunya, y se gradu\u00f3 como arquitecto en ETSAB Universitat Polit\u00e8cnica de Catalunya . Miquel es profesor asociado en ESARQ desde 1996. Anteriormente, fue profesor en Elisava y Escola LAI, y tambi\u00e9n en programas de postgrado en ETSAB y La Salle. Fue arquitecto en la oficina de Manuel Brullet desde 1989 desde 1995. Ha sido galardonado en \\\"Taller Barcelona'96. El TGV, una oportunidad por estructurar la periferia \\\". Fue codirector del taller \\\"Territorio Virtual, L\u00edmite Urbano\\\" en ITSEM Guadalajara, M\u00e9xico en 2000 y tambi\u00e9n codirector del taller \\\"Ravalizar Barcelona\\\" en ITSEM Guadalajara, M\u00e9xico, y CCNY, Nueva York, EE. UU. En 2002, 2003 y 2004. Gan\u00f3 el premio A + en 2010 por Sunion School en el Best Educational Building, The International Architecture Award 2008 en The Chicago Athenaeum por Colin's House y el primer premio en Corian Prize en 2006. Su obra ha sido expuesta en Barcelona , Madrid, Florencia, Cannes y en Le Pavillon de l'Arsenal en Par\u00eds. Varias publicaciones han sido reconocidas por su trabajo como Quaderns, ON, Arquitectura Plus, Piso, Arquitectura y Dise\u00f1o, El Pa\u00eds, ABC, La Vanguardia, Clar\u00edn, Sole 24 Ore, y otros. Recientemente realiz\u00f3 conferencias en ITSEM Guadalajara, M\u00e9xico, Facolta di Architettura di l'Alghero, Italia, msa M\u00fcnster School of Architecture, M\u00fcnster Alemania, IBM Think Tank en Par\u00eds, Francia, y varias universidades y organizaciones en Espa\u00f1a. Recientemente fue galardonado con el ZAC RN5 en el concurso Vitry-sur-Seine, un Eco-distrito de 255 residencias sociales y privadas y una residencia de estudiantes en Ivry, y 32 apartamentos asistidos para personas mayores en Olesa de Montserrat.\",\"sameAs\":[\"https:\\\/\\\/axonometrica.wordpress.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/MikelLacastaCodorniu\",\"https:\\\/\\\/www.instagram.com\\\/mikel3\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/miquel-lacasta-profile\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/miquelacasta\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/miquel-lacasta-codorniu\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinco | Miquel Lacasta - veredes","description":"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/","og_locale":"es_ES","og_type":"article","og_title":"Cinco | Miquel Lacasta - veredes","og_description":"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta","og_url":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/MikelLacastaCodorniu","article_published_time":"2024-05-05T22:01:03+00:00","og_image":[{"width":640,"height":392,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg","type":"image\/jpeg"}],"author":"Miquel Lacasta Codorniu","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/miquelacasta","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Miquel Lacasta Codorniu","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/"},"author":{"name":"Miquel Lacasta Codorniu","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/11c5393188d51787b8b13761dea40343"},"headline":"Cinco | Miquel Lacasta","datePublished":"2024-05-05T22:01:03+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/"},"wordCount":1332,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg","keywords":["Athanasius Kircher","historia","Matila Ghyka","Miquel Lacasta","pensamiento","reflexi\u00f3n","teor\u00eda","teor\u00eda e historia","Vitruvio"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/","url":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/","name":"Cinco | Miquel Lacasta - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg","datePublished":"2024-05-05T22:01:03+00:00","description":"Toda la informaci\u00f3n sobre: Cinco | Miquel Lacasta","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2024\/01\/Cinco-Miquel-Lacasta-un-fragmento-del-frontispicio-del-libro-Arithmologia-de-Athanasius-Kircher.jpg","width":640,"height":392,"caption":"un fragmento del frontispicio del libro Arithmologia de Athanasius Kircher."},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/cinco-miquel-lacasta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Cinco | Miquel Lacasta"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/11c5393188d51787b8b13761dea40343","name":"Miquel Lacasta Codorniu","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/08c0363dcfecc8314962e22fc525294dd6549dd4a7630af6a4f7053ff640935d?s=96&r=g","caption":"Miquel Lacasta Codorniu"},"description":"Es cofundador en ARCHIKUBIK y tambi\u00e9n en @kubik - espacio multidisciplinario. Obtuvo un Ph.D. con honores (cum laude) en ESARQ Universitat Internacional de Catalunya UIC y tambi\u00e9n fue galardonado con el premio especial Ph.D (UIC 2012), M.arch en ESARQ Universitat Internacional de Catalunya, y se gradu\u00f3 como arquitecto en ETSAB Universitat Polit\u00e8cnica de Catalunya . Miquel es profesor asociado en ESARQ desde 1996. Anteriormente, fue profesor en Elisava y Escola LAI, y tambi\u00e9n en programas de postgrado en ETSAB y La Salle. Fue arquitecto en la oficina de Manuel Brullet desde 1989 desde 1995. Ha sido galardonado en \"Taller Barcelona'96. El TGV, una oportunidad por estructurar la periferia \". Fue codirector del taller \"Territorio Virtual, L\u00edmite Urbano\" en ITSEM Guadalajara, M\u00e9xico en 2000 y tambi\u00e9n codirector del taller \"Ravalizar Barcelona\" en ITSEM Guadalajara, M\u00e9xico, y CCNY, Nueva York, EE. UU. En 2002, 2003 y 2004. Gan\u00f3 el premio A + en 2010 por Sunion School en el Best Educational Building, The International Architecture Award 2008 en The Chicago Athenaeum por Colin's House y el primer premio en Corian Prize en 2006. Su obra ha sido expuesta en Barcelona , Madrid, Florencia, Cannes y en Le Pavillon de l'Arsenal en Par\u00eds. Varias publicaciones han sido reconocidas por su trabajo como Quaderns, ON, Arquitectura Plus, Piso, Arquitectura y Dise\u00f1o, El Pa\u00eds, ABC, La Vanguardia, Clar\u00edn, Sole 24 Ore, y otros. Recientemente realiz\u00f3 conferencias en ITSEM Guadalajara, M\u00e9xico, Facolta di Architettura di l'Alghero, Italia, msa M\u00fcnster School of Architecture, M\u00fcnster Alemania, IBM Think Tank en Par\u00eds, Francia, y varias universidades y organizaciones en Espa\u00f1a. Recientemente fue galardonado con el ZAC RN5 en el concurso Vitry-sur-Seine, un Eco-distrito de 255 residencias sociales y privadas y una residencia de estudiantes en Ivry, y 32 apartamentos asistidos para personas mayores en Olesa de Montserrat.","sameAs":["https:\/\/axonometrica.wordpress.com\/","https:\/\/www.facebook.com\/MikelLacastaCodorniu","https:\/\/www.instagram.com\/mikel3\/","https:\/\/www.linkedin.com\/in\/miquel-lacasta-profile\/","https:\/\/x.com\/https:\/\/twitter.com\/miquelacasta"],"url":"https:\/\/veredes.es\/blog\/author\/miquel-lacasta-codorniu\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/96613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=96613"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/96613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/96615"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=96613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=96613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=96613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}