{"id":95681,"date":"2023-10-31T00:01:02","date_gmt":"2023-10-30T23:01:02","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=95681"},"modified":"2023-10-24T19:01:31","modified_gmt":"2023-10-24T17:01:31","slug":"asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/","title":{"rendered":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/veredes.es\/blog\/tag\/asemas\/\" target=\"_blank\" rel=\"noopener\">ASEMAS<\/a>, <\/strong>Mutua de Seguros y Reaseguros a Prima Fija, ha anunciado los ganadores de la V edici\u00f3n del <a href=\"https:\/\/veredes.es\/blog\/arranca-5o-concurso-asemas-pfc-dirigido-a-jovenes-arquitectos-espanoles\/\" target=\"_blank\" rel=\"noopener\">Concurso ASEMAS PFC Arquitectura 2023<\/a>. Conscientes de que la incorporaci\u00f3n al mundo laboral es uno de los desaf\u00edos principales para los j\u00f3venes titulados de las Escuelas de Arquitectura en Espa\u00f1a, ASEMAS, la Mutua de los Arquitectos con la intenci\u00f3n de poner en valor sus Proyectos Fin de Carrera, reconociendo su calidad y competencia profesional, ha fallado esta quinta edici\u00f3n de sus premios PFC premiando los mejores trabajos fin de carrera presentados.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00abReconocimiento a la calidad, al talento y a la competencia profesional, mediante la puesta en valor de los proyectos preprofesionales como ayuda a la incorporaci\u00f3n al mundo laboral\u00bb.<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_95682\" aria-describedby=\"caption-attachment-95682\" style=\"width: 1302px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-95682 size-full\" title=\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\" alt=\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura\" width=\"1302\" height=\"696\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png 1302w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura-300x160.png 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura-1024x547.png 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura-696x372.png 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura-1068x571.png 1068w\" sizes=\"auto, (max-width: 1302px) 100vw, 1302px\" \/><figcaption id=\"caption-attachment-95682\" class=\"wp-caption-text\"><span style=\"color: #999999;\">ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El jurado ha otorgado el primer premio a Luis M\u00ednguez Gonz\u00e1lez, de la Escuela T\u00e9cnica Superior de Arquitectura de Madrid, por su propuesta titulada \u201cBasamento\u201d. El segundo premio ha reca\u00eddo en Candela Picado de Blas, Escuela de Arquitectura CEU San Pablo de Madrid, por su proyecto \u201cReescribiendo el l\u00edmite\u201d y, en tercer lugar, el premio ha sido para Manuel P\u00e9rez Bernat, alumno de la Escuela T\u00e9cnica Superior de Arquitectura de Valencia por \u201cJubilada\u201d.<\/p>\n<p style=\"text-align: justify;\">Los premios, valorados en 10.000 euros, est\u00e1n repartidos en un primer premio de 6.000 euros y otros dos de 2.000 euros cada uno, acompa\u00f1ados de un trofeo y diploma conmemorativo.<\/p>\n<p style=\"text-align: justify;\">Junto a las tres obras premiadas, se ha otorgado una menci\u00f3n extraordinaria a Marta Morato Costa de la Escuela T\u00e9cnica Superior de Arquitectura de Madrid, con el lema \u00abGaro\u00e9\u00bb. Adem\u00e1s, se concedieron cuatro menciones especiales, y otras 22 propuestas resultaron finalistas.<\/p>\n<p style=\"text-align: justify;\">Tanto las tres obras premiadas como los 27 finalistas est\u00e1n disponibles en la <a href=\"https:\/\/bit.ly\/45Kv3Ve\" target=\"_blank\" rel=\"noopener\">p\u00e1gina web.<\/a><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00ab10.000 euros repartidos en tres premios\u00bb.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">El jurado, formado por cinco arquitectos, con una extensa experiencia tanto en estudios de arquitectura como en la docencia, ha valorado en su veredicto, la calidad y concreci\u00f3n de las ideas, su originalidad e innovaci\u00f3n, as\u00ed como la materialidad, cumplimiento de normativas y correcci\u00f3n de la propuesta constructiva de los proyectos presentados. Del mismo modo, ha querido destacar calidad de la formaci\u00f3n que reciben las escuelas de arquitectura en Espa\u00f1a, as\u00ed como el alto nivel de competencia de nuestros j\u00f3venes arquitectos, patente entre los m\u00e1s de 190 proyectos presentados al <strong>V Concurso ASEMAS PFC Arquitectura<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ASEMAS, Mutua de Seguros y Reaseguros a Prima Fija, ha anunciado los ganadores de la V edici\u00f3n del Concurso ASEMAS PFC Arquitectura 2023. Conscientes de que la incorporaci\u00f3n al mundo laboral es uno de los desaf\u00edos principales para los j\u00f3venes titulados de las Escuelas de Arquitectura en Espa\u00f1a, ASEMAS, la Mutua de los Arquitectos con [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":95682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,5951],"tags":[2631,9080,355,535,10109,758,759,2310,1038,1093],"class_list":["post-95681","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos","tag-arquitectura-espanola","tag-asemas","tag-concurso","tag-estudiante","tag-herramienta","tag-joven-arquitecto","tag-joven-valor","tag-jurado","tag-pfc","tag-premio-eventos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T23:01:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1302\" \/>\n\t<meta property=\"og:image:height\" content=\"696\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023\",\"datePublished\":\"2023-10-30T23:01:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/\"},\"wordCount\":425,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\",\"keywords\":[\"arquitectura espa\u00f1ola\",\"asemas\",\"concurso\",\"estudiante\",\"herramienta\",\"joven arquitecto\",\"joven valor\",\"jurado\",\"pfc\",\"premio\"],\"articleSection\":[\"eventos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/\",\"name\":\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\",\"datePublished\":\"2023-10-30T23:01:02+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png\",\"width\":1302,\"height\":696,\"caption\":\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes","description":"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/","og_locale":"es_ES","og_type":"article","og_title":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes","og_description":"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023","og_url":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2023-10-30T23:01:02+00:00","og_image":[{"width":1302,"height":696,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png","type":"image\/png"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023","datePublished":"2023-10-30T23:01:02+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/"},"wordCount":425,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png","keywords":["arquitectura espa\u00f1ola","asemas","concurso","estudiante","herramienta","joven arquitecto","joven valor","jurado","pfc","premio"],"articleSection":["eventos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/","url":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/","name":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023 - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png","datePublished":"2023-10-30T23:01:02+00:00","description":"Toda la informaci\u00f3n sobre: ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/10\/ASEMAS-anuncia-los-ganadores-del-Concurso-PFC-de-Arquitectura.png","width":1302,"height":696,"caption":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/asemas-anuncia-los-ganadores-del-concurso-pfc-de-arquitectura-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"ASEMAS anuncia los ganadores del Concurso PFC de Arquitectura 2023"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/95681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=95681"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/95681\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/95682"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=95681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=95681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=95681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}