{"id":94540,"date":"2023-07-03T00:01:29","date_gmt":"2023-07-02T22:01:29","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=94540"},"modified":"2023-06-16T19:06:17","modified_gmt":"2023-06-16T17:06:17","slug":"hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/","title":{"rendered":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo"},"content":{"rendered":"<figure id=\"attachment_94543\" aria-describedby=\"caption-attachment-94543\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94543 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Maqueta del Hospital M\u00e9xico (1961) dise\u00f1o de los arquitectos Alberto Linner, Carlos B. Zetina y Alejandro Prieto\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Maqueta del Hospital M\u00e9xico (1961) dise\u00f1o de los arquitectos Alberto Linner, Carlos B. Zetina y Alejandro Prieto\" width=\"1400\" height=\"926\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto-300x198.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto-1024x677.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto-696x460.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Maqueta-del-Hospital-Mexico-1961-diseno-de-los-arquitectos-Alberto-Linner-Carlos-B.-Zetina-y-Alejandro-Prieto-1068x706.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94543\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Maqueta del Hospital M\u00e9xico (1961) dise\u00f1o de los arquitectos Alberto Linner, Carlos B. Zetina y Alejandro Prieto, con la asesor\u00eda del Doctor Manuel Barqu\u00edn.<\/span><\/figcaption><\/figure>\n<h5 style=\"text-align: justify;\"><strong>La Historia del Hospital M\u00e9xico de Costa Rica<\/strong><\/h5>\n<p style=\"text-align: justify;\">La Caja Costarricense del Seguro Social (CCSS) nace en la administraci\u00f3n del presidente Rafael \u00c1ngel Calder\u00f3n Guardia (1940-1944) como un ente semiaut\u00f3nomo mediante la Ley N.\u00ba 17 del 1 de noviembre de 1941, pero el 22 de octubre de 1943 se reforma esa Ley para que sea reconocida como una instituci\u00f3n aut\u00f3noma. Cabe destacar que en Costa Rica en esa \u00e9poca los hospitales eran administrados por Juntas de salud, los servicios m\u00e9dicos en esos nosocomios los brindaban en algunos casos m\u00e9dicos privados y las farmacias privadas entregaban los medicamentos, porque estos costos eran muy elevados para una administraci\u00f3n de recursos limitados. Lo anterior potenciado por la crisis mundial producto de la Segunda Guerra Mundial, y la imposibilidad de exportar caf\u00e9<sup>1<\/sup> a los mercados europeos.<\/p>\n<p style=\"text-align: justify;\">En esa \u00e9poca y a pesar de la necesidad evidente de infraestructura, la falta de recursos hac\u00eda impensable la construcci\u00f3n de un nuevo hospital, sin embargo la instituci\u00f3n siempre busc\u00f3 una manera para desarrollar esa iniciativa, tal como lo inform\u00f3 el domingo 10 de agosto de 1952 el peri\u00f3dico La Rep\u00fablica, \u201cModerno Hospital de 500 camas piensa construir el seguro Social\u201d, haciendo referencia a que la Junta Directiva de la Instituci\u00f3n defini\u00f3 que el actual Hospital Central<sup>2<\/sup><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cNo ofrece ninguna perspectiva para proceder al mejoramiento y ampliaci\u00f3n de sus servicios [\u2026] En vista de tal situaci\u00f3n se decidi\u00f3 iniciar inmediatamente las gestiones [\u2026] para formular los planes y estudios necesarios con el fin de realizar la construcci\u00f3n de un moderno hospital, dotado de 500 camas y de todos los servicios m\u00e9dicos necesarios.\u201d<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_94544\" aria-describedby=\"caption-attachment-94544\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-94544\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Publicaci\u00f3n del peri\u00f3dico La Rep\u00fablica del 10 de agosto de 1952\" width=\"1400\" height=\"792\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952-300x170.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952-1024x579.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952-696x394.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Publicacion-del-periodico-La-Republica-del-10-de-agosto-de-1952-1068x604.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94544\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Publicaci\u00f3n del peri\u00f3dico La Rep\u00fablica del 10 de agosto de 1952<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Sin embargo, el mandato constitucional de cobertura total de la poblaci\u00f3n que hizo la reforma aprobada en 1961 por la Ley 2783, oblig\u00f3 a acelerar la hoja de ruta a seguir por el Seguro Social en Costa Rica. El proceso se inicia con la priorizaci\u00f3n de la construcci\u00f3n de las Cl\u00ednicas Perif\u00e9ricas Metropolitanas, el edificio para las Oficinas Centrales en la Avenida Segunda (Laureano Echandi), los Almacenes Generales y se crea adem\u00e1s una Comisi\u00f3n T\u00e9cnica para iniciar el estudio para un nuevo hospital central.<\/p>\n<p style=\"text-align: justify;\">Ante la falta de experiencia nacional para un proyecto de esta envergadura, la Comisi\u00f3n T\u00e9cnica abri\u00f3 una licitaci\u00f3n internacional para consultoras hospitalarias y fue seleccionada una empresa peruana, que dirig\u00eda el Arq. Ricardo Malachowski Benavides,<sup>3<\/sup> quien desarroll\u00f3 para el Seguro Social del Per\u00fa los hospitales en Chiclayo, Tarma, Arequipa entre otros y el Hospital de la Fuerza A\u00e9rea del Per\u00fa, pero, poco tiempo despu\u00e9s fue el propio arquitecto quien solicit\u00f3 a la Junta Directiva de la CCSS disolver el contrato por las dificultades que creaba la comunicaci\u00f3n a distancia.<\/p>\n<p style=\"text-align: justify;\">Quiso el destino que posteriormente a este fallido intento el Dr. Fernando Escalante Pradilla, Gerente de la Caja del Seguro, visitara ciudad de M\u00e9xico para asistir a la reuni\u00f3n anual de la Asociaci\u00f3n Interamericana de Seguridad Social, entidad patrocinada por el Gobierno mexicano. Durante el evento el Dr. Escalante se quej\u00f3 de la poca capacidad que ten\u00edan los Seguros Sociales peque\u00f1os como el de Costa Rica para desarrollar grandes infraestructuras y relat\u00f3 lo ocurrido con el planeamiento de su nuevo hospital y la imposibilidad hasta ahora para llevarlo a cabo.<\/p>\n<figure id=\"attachment_94546\" aria-describedby=\"caption-attachment-94546\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94546 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Diferentes fotograf\u00edas de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesentab\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Diferentes fotograf\u00edas de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesentab\" width=\"1400\" height=\"965\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab-300x207.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab-1024x706.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab-218x150.jpg 218w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab-696x480.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesentab-1068x736.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94546\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotograf\u00eda de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesenta<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">All\u00ed mismo el Lic. Benito Coquet Lagunes director del Instituto Mexicano del Seguro Social le ofreci\u00f3 sin costo toda la colaboraci\u00f3n t\u00e9cnica. Adem\u00e1s, se encarg\u00f3 al Dr. Ignacio Morones, director Servicios M\u00e9dicos a coordinar la capacitaci\u00f3n del futuro personal, al Dr. Manuel Barqu\u00edn como colaborador del proyecto y al departamento de Inmuebles y Construcciones, bajo la direcci\u00f3n del Arq. Carlos B. Zetina, a desarrollar el proyecto de un hospital de 600 camas para Costa Rica.<\/p>\n<figure id=\"attachment_94545\" aria-describedby=\"caption-attachment-94545\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94545 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Diferentes fotograf\u00edas de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesenta\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Diferentes fotograf\u00edas de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesenta\" width=\"1400\" height=\"951\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta-300x204.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta-1024x696.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta-696x473.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/06\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Diferentes-fotografias-de-archivo-de-la-obra-en-construccion-a-principios-de-los-anos-sesenta-1068x725.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94545\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotograf\u00eda de archivo de la obra en construcci\u00f3n a principios de los a\u00f1os sesenta<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Se comision\u00f3 para desarrollarlo al arquitecto de origen nicarag\u00fcense Alberto Linner D\u00edaz (1933), graduado del Instituto Tecnol\u00f3gico de Monterrey, quien fue seleccionado gracias a la experiencia obtenida en desarrollar el hospital de Celaya y su tesis sobre el hospital de Morelos, adem\u00e1s se asign\u00f3 como supervisor al reconocido arquitecto mexicano Alejandro Prieto Posada (1924-1997) director de arquitectura y autor en M\u00e9xico de obras como: el Teatro de los Insurgentes (1952), Laboratorios CIBA (1954), Teatro Hidalgo (1962), y los hospitales de Quer\u00e9taro, de Jalapa y de Taxco.<\/p>\n<p style=\"text-align: justify;\">Con relaci\u00f3n a esto, ya para el 5 de enero de 1958 en el peri\u00f3dico La Naci\u00f3n sale publicada la siguiente noticia:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cUn monobloque de ocho pisos ser\u00e1 el edificio central del nuevo Hospital de la CCSS. Cubrir\u00e1 un \u00e1rea de 20 manzanas, estar\u00e1 en la Uruca, en las vecindades de la supercarretera que llevar\u00e1 al aeropuerto El Coco,<sup>4 <\/sup>un poco retirado de la capital\u201d.<\/em><\/p>\n<\/blockquote>\n<h5 style=\"text-align: justify;\"><strong>La Construcci\u00f3n <\/strong><strong>del Hospital M\u00e9xico de Costa Rica<\/strong><\/h5>\n<p style=\"text-align: justify;\">Para octubre de 1961 los funcionarios mexicanos del Seguro Social presentaron ante las autoridades de la Caja los planos y la maqueta del futuro del Hospital M\u00e9xico de Costa Rica (Imagen 1) y los planos de la CCSS se firmaron en diciembre de 1962. Se inicia la construcci\u00f3n el 2 de abril de 1963, el acto de la primera piedra se realiz\u00f3 el d\u00eda 7 de abril 1963. Para el d\u00eda 26 de mayo 1963 se inicia la construcci\u00f3n de las calles adyacentes y del estacionamiento. El 7 de noviembre de 1964 se termina la lavander\u00eda y la casa de m\u00e1quinas, para el 23 de diciembre se finaliza la instalaci\u00f3n el\u00e9ctrica y el 2 de julio de 1965 se concluyen los acabados. El 19 de enero de 1965 el Se\u00f1or presidente de M\u00e9xico Lic. Gustavo D\u00edaz Ordaz visita las instalaciones del nuevo hospital. El atraso en culminar las obras experimentado se debi\u00f3 principalmente a la necesidad de recalcular la estructura en el edificio principal, debido a que hubo variaciones entre el acero usado en la construcci\u00f3n y el propuesto en el dise\u00f1o.<\/p>\n<figure id=\"attachment_94548\" aria-describedby=\"caption-attachment-94548\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94548 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda tomada durante la inauguraci\u00f3n del 19 de marzo de 1969\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda tomada durante la inauguraci\u00f3n del 19 de marzo de 1969\" width=\"1400\" height=\"1010\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969-300x216.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969-1024x739.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969-696x502.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-tomada-durante-la-inauguracion-del-19-de-marzo-de-1969-1068x770.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94548\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotograf\u00eda tomada durante la inauguraci\u00f3n del 19 de marzo de 1969<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Finalmente, el 31 de enero de 1968 se hace entrega formal del edificio se finaliza la construcci\u00f3n el 5 de julio de 1968 y el 15 de julio del mismo a\u00f1o se da por terminada toda la instalaci\u00f3n mec\u00e1nica del Hospital. En la sesi\u00f3n N. 3907 de enero 1969, la Junta Directiva fija el 19 de marzo para la inauguraci\u00f3n del Hospital, y al ser las 4 de la tarde de ese d\u00eda es inaugurado el del Hospital M\u00e9xico de Costa Rica.<sup>5<\/sup> Aunque presta servicios integralmente hasta el 1 de setiembre de 1969, siendo la Sra. Jacinta Jim\u00e9nez Cascante la primera paciente oficial del nuevo hospital. Para setiembre de 1969, se inaugura el Hospital M\u00e9xico ya como centro en plena operaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Mientras tanto, la instituci\u00f3n recibi\u00f3 toda la asesor\u00eda necesaria para la organizaci\u00f3n funcional del nuevo Hospital de parte del gobierno azteca, incluido el entrenamiento del personal m\u00e9dico en universidades mexicanas. Fue debido a la gran colaboraci\u00f3n del gobierno mexicano y del Seguro Social de ese pa\u00eds que el Doctor Guido Miranda Guti\u00e9rrez sugiri\u00f3 el nombre de del Hospital M\u00e9xico de Costa Rica como muestra de agradecimiento.<sup>6<\/sup><\/p>\n<p style=\"text-align: justify;\">Oficialmente en la Sesi\u00f3n 2949 de la Junta Directiva de la CCSS se le da de nombre del Hospital M\u00e9xico de Costa Rica, en reconocimiento a la labor del IMSS quienes donaron los planos,<sup>7<\/sup>\u00a0y gestionaron la capacitaci\u00f3n del personal. De hecho, cabe destacar que, para esa \u00e9poca de 973 m\u00e9dicos incorporados al Colegio de M\u00e9dicos, 426 fueron graduados en M\u00e9xico. As\u00ed a grandes rasgos fue como se construy\u00f3 financiado con recursos propios el primer Hospital del Seguro Social con un \u00e1rea de 90.120 m<sup>2<\/sup>, el centro de m\u00e1s alta calidad t\u00e9cnica y asistencial de Costa Rica, gracias al inmenso apoyo del Gobierno mexicano.<\/p>\n<figure id=\"attachment_94549\" aria-describedby=\"caption-attachment-94549\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94549 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda del Hospital M\u00e9xico presumiblemente de principios de los a\u00f1os setenta\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda del Hospital M\u00e9xico presumiblemente de principios de los a\u00f1os setenta\" width=\"1400\" height=\"1001\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta-300x215.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta-1024x732.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta-696x498.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta-1068x764.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94549\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotograf\u00eda del Hospital M\u00e9xico presumiblemente de principios de los a\u00f1os setenta<\/span><\/figcaption><\/figure>\n<h5 style=\"text-align: justify;\"><strong>El edificio,<\/strong><strong>\u00a0Hospital M\u00e9xico de Costa Rica<\/strong><\/h5>\n<p style=\"text-align: justify;\">Para mayo de 1962, el arquitecto Linner viaja a Costa Rica y se integra de inmediato a la Comisi\u00f3n T\u00e9cnica que contar\u00eda adem\u00e1s con las visitas peri\u00f3dicas del especialista en administraci\u00f3n de hospitales Dr. Manuel Barqu\u00edn, recordado director del Hospital de la Raza en M\u00e9xico. Durante ese tiempo al arquitecto Linner se le ofrece que asuma el dise\u00f1o y la supervisi\u00f3n de otras obras institucionales en el pa\u00eds como la cl\u00ednica Clorito Picado (1965), o la cl\u00ednica Carlos Dur\u00e1n (1967), as\u00ed como algunas obras privadas entre ellas la Iglesia de N.S. de F\u00e1tima (1969), lo que gener\u00f3 la oportunidad para que el arquitecto decidiera radicar definitivamente en el pa\u00eds con toda su familia.<\/p>\n<p style=\"text-align: justify;\">El Hospital M\u00e9xico fue desde sus inicios el m\u00e1s grande y moderno centro m\u00e9dico del pa\u00eds, se dice que para la \u00e9poca incluso era el m\u00e1s moderno de la regi\u00f3n centroamericana. Arquitect\u00f3nicamente consta de un edificio central rectangular de \u201ctorre\u201d vertical angosta para hospitalizaci\u00f3n lo que le aporta facilidad de movimiento al personal, y la posibilidad de contar con ventilaci\u00f3n cruzada en las salas de encamados. La torre se asienta sobre una \u201cplaca\u201d, pues es un edificio fiel al Estilo Internacional de Placa y Torre. Esta \u201cplaca\u201d incluye las jefaturas, la consulta externa, el auditorio y la biblioteca entre otros elementos de un nivel.<\/p>\n<figure id=\"attachment_94551\" aria-describedby=\"caption-attachment-94551\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94551 size-full\" title=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda de los a\u00f1os noventa en que se muestra la modificaci\u00f3n de la fachada producto del reforzamiento estructural\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda de los a\u00f1os noventa en que se muestra la modificaci\u00f3n de la fachada producto del reforzamiento estructural\" width=\"1400\" height=\"913\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural-300x196.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural-1024x668.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural-696x454.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-de-los-anos-noventa-en-que-se-muestra-la-modificacion-de-la-fachada-producto-del-reforzamiento-estructural-1068x696.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94551\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotograf\u00eda de los a\u00f1os noventa en que se muestra la modificaci\u00f3n de la fachada producto del reforzamiento estructural<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con el tiempo y debido los trabajos del reforzamiento antis\u00edsmico del hospital M\u00e9xico a principios de los a\u00f1os noventa se modificaron las fachadas del edificio principal pasando de un prisma puro a una exoestructura de concreto. Estos trabajos tuvieron una duraci\u00f3n de 3 a\u00f1os y medio y fueron la \u00faltima intervenci\u00f3n que el arquitecto Linner realiz\u00f3 al hospital, pues, a partir de 1994 se retir\u00f3 como funcionario de la Instituci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">La consulta externa es un gran edificio distribuido en un solo nivel de altura, con tipolog\u00eda de pabellones y jardines, al menos hasta que empezaron las ampliaciones sin planificaci\u00f3n que han cercenado los jardines, rompiendo la din\u00e1mica de iluminaci\u00f3n natural y ventilaci\u00f3n cruzada con que se idearon. En ese terreno hab\u00eda otros edificios de Linner ya demolidos, el \u00fanico que se mantiene es el del CENDEISSS, el centro de capacitaci\u00f3n de personal m\u00e9dico de la CCSS.<\/p>\n<figure id=\"attachment_94552\" aria-describedby=\"caption-attachment-94552\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94552 size-full\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Monumento a Calder\u00f3n Guardia, ya demolido\" width=\"1400\" height=\"897\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido-300x192.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido-1024x656.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido-696x446.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolido-1068x684.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94552\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Monumento a Calder\u00f3n Guardia, ya demolido<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Originalmente la torre estaba precedida por una imponente plaza moderna al noreste frente a la autopista, que otrora resaltaba la majestuosidad y la escala del edificio. Esta plaza estuvo adornada con un monumento a Rafael \u00c1ngel Calder\u00f3n Guardia presidente que fund\u00f3 la CCSS, ese monumento fue realizado por el arquitecto Hern\u00e1n Jim\u00e9nez Fonseca (1942) y el escultor Francisco Z\u00fa\u00f1iga Chavarr\u00eda (1912-1998), pero fue demolida. Hoy en d\u00eda en lugar de esa plaza y de ese monumento hay dos edificios de cuestionable valor arquitect\u00f3nico, el m\u00e1s reciente con ning\u00fan respeto hacia el edificio original.<\/p>\n<figure id=\"attachment_94553\" aria-describedby=\"caption-attachment-94553\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94553 size-full\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Monumento a Calder\u00f3n Guardia, ya demolido\" width=\"1400\" height=\"941\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob-300x202.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob-1024x688.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob-696x468.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Monumento-a-Calderon-Guardia-ya-demolidob-1068x718.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94553\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Monumento a Calder\u00f3n Guardia, ya demolido<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Resta recordarles a los encargados de estas intervenciones las sabias palabras del arquitecto Alberto Linner:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cla forma y la funci\u00f3n, o la funci\u00f3n y la forma no se anteponen ni se posponen una a la otra, son amigas que se unen para dar resultados arquitect\u00f3nicos positivos, en el equilibrio est\u00e1 la majestad de la arquitectura. No hay vuelta de hoja, la arquitectura est\u00e1 al servicio del hombre y \u00e9l que logra servirle en la creaci\u00f3n de espacios funcionales y bellos o m\u00e1s funcionalmente bellos est\u00e1 haciendo arquitectura. Est\u00e1 mal hacer un hospital feo porque funciona, pero es peor hacer un hospital feo y que adem\u00e1s no funcione. En cambio, para todos los hospitales y las cl\u00ednicas que trabajen trate de equilibrar ambos conceptos\u00bb.<sup>8<\/sup><\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_94554\" aria-describedby=\"caption-attachment-94554\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-94554 size-full\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto.jpg\" alt=\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo mural del hospital M\u00e9xico y uno de los jardines originales del proyecto\" width=\"1400\" height=\"1050\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto-300x225.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto-1024x768.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto-696x522.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-mural-del-hospital-Mexico-y-uno-de-los-jardines-originales-del-proyecto-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-94554\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Mural del hospital M\u00e9xico y uno de los jardines originales del proyecto \u00a9 Luis Alberto Monge, 2008<\/span><\/figcaption><\/figure>\n<h6><strong><span style=\"color: #333333;\">Notas:<\/span><\/strong><\/h6>\n<p style=\"text-align: justify;\"><sup>1<\/sup>\u00a0El caf\u00e9 fue el principal producto exportado desde de Costa Rica a partir de finales de 1800.<br \/>\n<sup>2<\/sup>\u00a0El actual Hospital Calder\u00f3n Guardia, que a pesar de esa instrucci\u00f3n de 1952 en los \u00faltimos a\u00f1os ha recibido muchas ampliaciones y edificaciones nuevas que buscan acondicionarlo.<br \/>\n<sup>3<\/sup> <a href=\"https:\/\/veredes.es\/blog\/tag\/ricardo-malachowski\/\" target=\"_blank\" rel=\"noopener\">Ricardo Malachowski<\/a> ilustr\u00f3 el libro <em>Historia de la arquitectura<\/em> de<a href=\"https:\/\/veredes.es\/blog\/tag\/hector-velarde\/\" target=\"_blank\" rel=\"noopener\"> H\u00e9ctor Velarde<\/a> (1949), y es hijo del renombrado arquitecto de origen polaco: Ryszard (Ricardo) de Jaxa Malachowski Kulisicz (1887 &#8211; 1972), que estudi\u00f3 ingenier\u00eda en L&#8217;\u00c9cole Speciale Centrale des <em>Arts et Manufactures<\/em>, pero continu\u00f3 sus estudios como arquitecto en <em>L&#8217;\u00c9cole Speciale D&#8217;Architecture<\/em>. Para 1908 ingresa a la Escuela de Bellas Artes de Par\u00eds en el primer puesto entre 180 postulantes extranjeros. Entre sus obras en Lima est\u00e1n el Palacio de Gobierno, el Palacio Legislativo, el Edificio R\u00edmac, la fachada del Palacio Arzobispal, el Club Nacional y la plaza Dos de Mayo.<br \/>\n<sup>4<\/sup> Hoy en d\u00eda ser\u00eda el Aeropuerto Juan Santamar\u00eda, y la supercarretera es la actual autopista General Ca\u00f1as, parte de la Ruta 1 inaugurada en 1965.<br \/>\n<sup>5<\/sup> Hospital M\u00e9xico. <em>Bolet\u00edn Edici\u00f3n Especial Hospital M\u00e9xico<\/em>. 32 aniversario (San Jos\u00e9 Costa Rica, 2001).<br \/>\n<sup>6<\/sup> G. Miranda,\u00a0<em>Desarrollo hist\u00f3rico de la Caja Costarricense de Seguro Social<\/em> (Gaceta M\u00e9dica de Costa Rica, 2006); 181.<br \/>\n<sup>7<\/sup>\u00a0Se estima que el costo de los planos eran de dos millones de pesos mexicanos de esa \u00e9poca.<br \/>\n<sup>8<\/sup> V\u00e9ase: <a href=\"https:\/\/veredes.es\/blog\/author\/luis-alberto-monge-calvo\/\" target=\"_blank\" rel=\"noopener\">Luis Alberto Monge<\/a>, <em>Di\u00e1logos con el arquitecto Alberto Linner<\/em>\u00a0(2011).<\/p>\n<h6 style=\"text-align: justify;\"><strong>Bibliograf\u00eda<\/strong><\/h6>\n<p style=\"text-align: justify;\">Jaramillo, J. \u00abLa salud y la medicina\u00bb. En E. Rodr\u00edguez, &amp; E. R. Vega (Ed.), <em>Costa Rica del siglo XX. <\/em>Vol. 2 (San Jos\u00e9: Editorial UNED, 2004); 195- 238.<\/p>\n<p style=\"text-align: justify;\">G. Miranda, \u00ab<a href=\"https:\/\/amzn.to\/3Nab5Mt\" target=\"_blank\" rel=\"noopener\">Alberto Linner<\/a> y la Seguridad Social\u00bb. En L. MONGE, G. P\u00c9REZ &amp; A. y. CASTRO, <em>Monograf\u00eda del Arq. Alberto Linner D\u00edaz<\/em>\u00a0(San Jos\u00e9, Costa Rica: Colegio de Arquitectos de Costa Rica, 2016); 27.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Historia del Hospital M\u00e9xico de Costa Rica La Caja Costarricense del Seguro Social (CCSS) nace en la administraci\u00f3n del presidente Rafael \u00c1ngel Calder\u00f3n Guardia (1940-1944) como un ente semiaut\u00f3nomo mediante la Ley N.\u00ba 17 del 1 de noviembre de 1941, pero el 22 de octubre de 1943 se reforma esa Ley para que sea [&hellip;]<\/p>\n","protected":false},"author":63,"featured_media":94549,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[16051,5554,16052,16573,16574,5556,16575,14574,7982,16572],"class_list":{"0":"post-94540","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articulos","8":"category-slider-principal","9":"tag-alberto-linner-diaz","10":"tag-alfredo-baertl-montori","11":"tag-arquitectura-costarricense","12":"tag-carlos-b-zetina","13":"tag-francisco-zuniga-chavarria","14":"tag-hector-velarde","15":"tag-hernan-jimenez-fonseca","16":"tag-luis-alberto-monge-calvo","17":"tag-ricardo-malachowski","18":"tag-ricardo-malachowski-benavides"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/luismongecalvo\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-02T22:01:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1001\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luis Alberto Monge Calvo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/monarquicr\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luis Alberto Monge Calvo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/\"},\"author\":{\"name\":\"Luis Alberto Monge Calvo\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/1e2b8306c83c643165e9f94b92e4570f\"},\"headline\":\"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo\",\"datePublished\":\"2023-07-02T22:01:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/\"},\"wordCount\":2468,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\",\"keywords\":[\"Alberto Linner D\u00edaz\",\"Alfredo Baertl Montori\",\"arquitectura costarricense\",\"Carlos B. Zetina\",\"Francisco Z\u00fa\u00f1iga Chavarr\u00eda\",\"H\u00e9ctor Velarde\",\"Hern\u00e1n Jim\u00e9nez Fonseca\",\"Luis Alberto Monge Calvo\",\"Ricardo Malachowski\",\"Ricardo Malachowski Benavides\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/\",\"name\":\"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\",\"datePublished\":\"2023-07-02T22:01:29+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg\",\"width\":1400,\"height\":1001,\"caption\":\"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda del Hospital M\u00e9xico presumiblemente de principios de los a\u00f1os setenta\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/1e2b8306c83c643165e9f94b92e4570f\",\"name\":\"Luis Alberto Monge Calvo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Luis-Alberto-Monge-Calvo-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Luis-Alberto-Monge-Calvo-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Luis-Alberto-Monge-Calvo-96x96.jpg\",\"caption\":\"Luis Alberto Monge Calvo\"},\"description\":\"Arquitecto por la Universidad Aut\u00f3noma de Centro Am\u00e9rica, Mag\u00edster en Arquitectura de la Universidad Cat\u00f3lica de Chile. Posee estudios de posgrado en Urbanismo de la Universidade Federal do Rio de Janeiro y en la Maestr\u00eda de Proyecto Arquitect\u00f3nico de la Universidad de Buenos Aires. Tiene doble Certificaci\u00f3n de actualizaci\u00f3n Profesional, y es miembro de la Asociaci\u00f3n Costarricense de Profesionales en Arquitectura. Trabaja en la Direcci\u00f3n de Arquitectura e Ingenier\u00eda de la Caja Costarricense del Seguro Social Tambi\u00e9n es profesor universitario e investigador en Arquitectura para la Universidad Internacional de las Am\u00e9ricas, es representante nacional en Smart Urbanization del H2020 de la Comisi\u00f3n Europea. Actualmente es colaborador del blog Veredes: arquitectura y divulgaci\u00f3n de Espa\u00f1a y para la revista Mondo Nostrum. Ha escrito cuatro libros, ha sido editor de cuatro m\u00e1s y ha publicado decenas de art\u00edculos de investigaci\u00f3n y profesionales en revistas de Latinoam\u00e9rica y Europa. Ha sido Becario de la Red de entrenamiento universitario para el desarrollo urbano sostenible de la Uni\u00f3n Europea, e Investigador asociado en el Concurso Nacional de Proyectos FONDECYT Chile, profesor invitado Instituto Tecnol\u00f3gico de Monterrey, M\u00e9xico. \u00c1rbitro evaluador externo de la Universidad de los Andes; Colombia. Es miembro y fundador del Comisi\u00f3n Editorial Ganador de Menci\u00f3n al Premio en la categor\u00eda de difusi\u00f3n de la arquitectura y urbanismo 2020 de la Federaci\u00f3n Panamericana de Asociaciones de arquitectos y es Coordinador de la Comisi\u00f3n de Investigaci\u00f3n del CACR.\",\"sameAs\":[\"http:\\\/\\\/monarqui.blogspot.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/luismongecalvo\",\"https:\\\/\\\/www.instagram.com\\\/monarqui\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/luis-alberto-monge-calvo-68498956\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/monarquicr\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/luis-alberto-monge-calvo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes","description":"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/","og_locale":"es_ES","og_type":"article","og_title":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes","og_description":"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo","og_url":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/luismongecalvo","article_published_time":"2023-07-02T22:01:29+00:00","og_image":[{"width":1400,"height":1001,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg","type":"image\/jpeg"}],"author":"Luis Alberto Monge Calvo","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/monarquicr","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Luis Alberto Monge Calvo","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/"},"author":{"name":"Luis Alberto Monge Calvo","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/1e2b8306c83c643165e9f94b92e4570f"},"headline":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo","datePublished":"2023-07-02T22:01:29+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/"},"wordCount":2468,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg","keywords":["Alberto Linner D\u00edaz","Alfredo Baertl Montori","arquitectura costarricense","Carlos B. Zetina","Francisco Z\u00fa\u00f1iga Chavarr\u00eda","H\u00e9ctor Velarde","Hern\u00e1n Jim\u00e9nez Fonseca","Luis Alberto Monge Calvo","Ricardo Malachowski","Ricardo Malachowski Benavides"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/","url":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/","name":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg","datePublished":"2023-07-02T22:01:29+00:00","description":"Toda la informaci\u00f3n sobre: Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/07\/Hospital-Mexico-de-Costa-Rica-Luis-Alberto-Monge-Calvo-Fotografia-del-Hospital-Mexico-presumiblemente-de-principios-de-los-anos-setenta.jpg","width":1400,"height":1001,"caption":"Hospital M\u00e9xico de Costa Rica Luis Alberto Monge Calvo Fotograf\u00eda del Hospital M\u00e9xico presumiblemente de principios de los a\u00f1os setenta"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/hospital-mexico-de-costa-rica-resena-historica-y-arquitectonica-del-principal-centro-de-salud-costarricense-del-siglo-xx-luis-alberto-monge-calvo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Hospital M\u00e9xico de Costa Rica. Rese\u00f1a hist\u00f3rica y arquitect\u00f3nica del principal centro de salud costarricense del Siglo XX | Luis Alberto Monge Calvo"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/1e2b8306c83c643165e9f94b92e4570f","name":"Luis Alberto Monge Calvo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/03\/Luis-Alberto-Monge-Calvo-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/03\/Luis-Alberto-Monge-Calvo-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/03\/Luis-Alberto-Monge-Calvo-96x96.jpg","caption":"Luis Alberto Monge Calvo"},"description":"Arquitecto por la Universidad Aut\u00f3noma de Centro Am\u00e9rica, Mag\u00edster en Arquitectura de la Universidad Cat\u00f3lica de Chile. Posee estudios de posgrado en Urbanismo de la Universidade Federal do Rio de Janeiro y en la Maestr\u00eda de Proyecto Arquitect\u00f3nico de la Universidad de Buenos Aires. Tiene doble Certificaci\u00f3n de actualizaci\u00f3n Profesional, y es miembro de la Asociaci\u00f3n Costarricense de Profesionales en Arquitectura. Trabaja en la Direcci\u00f3n de Arquitectura e Ingenier\u00eda de la Caja Costarricense del Seguro Social Tambi\u00e9n es profesor universitario e investigador en Arquitectura para la Universidad Internacional de las Am\u00e9ricas, es representante nacional en Smart Urbanization del H2020 de la Comisi\u00f3n Europea. Actualmente es colaborador del blog Veredes: arquitectura y divulgaci\u00f3n de Espa\u00f1a y para la revista Mondo Nostrum. Ha escrito cuatro libros, ha sido editor de cuatro m\u00e1s y ha publicado decenas de art\u00edculos de investigaci\u00f3n y profesionales en revistas de Latinoam\u00e9rica y Europa. Ha sido Becario de la Red de entrenamiento universitario para el desarrollo urbano sostenible de la Uni\u00f3n Europea, e Investigador asociado en el Concurso Nacional de Proyectos FONDECYT Chile, profesor invitado Instituto Tecnol\u00f3gico de Monterrey, M\u00e9xico. \u00c1rbitro evaluador externo de la Universidad de los Andes; Colombia. Es miembro y fundador del Comisi\u00f3n Editorial Ganador de Menci\u00f3n al Premio en la categor\u00eda de difusi\u00f3n de la arquitectura y urbanismo 2020 de la Federaci\u00f3n Panamericana de Asociaciones de arquitectos y es Coordinador de la Comisi\u00f3n de Investigaci\u00f3n del CACR.","sameAs":["http:\/\/monarqui.blogspot.com\/","https:\/\/www.facebook.com\/luismongecalvo","https:\/\/www.instagram.com\/monarqui\/","https:\/\/www.linkedin.com\/in\/luis-alberto-monge-calvo-68498956\/","https:\/\/x.com\/https:\/\/twitter.com\/monarquicr"],"url":"https:\/\/veredes.es\/blog\/author\/luis-alberto-monge-calvo\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/94540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=94540"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/94540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/94549"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=94540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=94540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=94540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}