{"id":9363,"date":"2011-01-19T08:20:39","date_gmt":"2011-01-19T08:20:39","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=9363"},"modified":"2020-11-25T14:26:51","modified_gmt":"2020-11-25T13:26:51","slug":"ha-llegado-el-momento-de-actuar-sindicatoarquitectos","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/","title":{"rendered":"Ha llegado el momento de ACTUAR | sindicatoarquitectos"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-9364\" title=\"cab_presentacion\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg\" alt=\"\" width=\"620\" height=\"155\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg 500w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion-300x75.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Estimado\/a amigo\/a:<br \/>\nQueremos agradecerte en primer lugar que formes parte del grupo de amigos del Sindicato de Arquitectos de Espa\u00f1a en Facebook.\u00a0 Como puedes ver, es un grupo din\u00e1mico, con m\u00e1s de 3000 amigos, en el que muchos arquitectos y profesionales de la arquitectura hemos entrado en contacto.\u00a0Gracias a todos vosotros, nuestro recorrido en Facebook ha sido espectacular, nuestra repercusi\u00f3n en medios de \u00e1mbito nacional y auton\u00f3mico tambi\u00e9n. Mediante la primera encuesta hecha a arquitectos colegiados y no colegiados hemos detectado y hecho visibles los problemas de nuestra profesi\u00f3n, pero\u2026 ha llegado el momento de actuar. La intenci\u00f3n, cuando creamos el grupo de Facebook, era la de explicar las razones de la existencia del sindicato y difundir mensajes \u00fatiles para arquitectos y profesionales de la arquitectura de la manera m\u00e1s r\u00e1pida y sencilla posible. Tambi\u00e9n la de conseguir el mayor n\u00famero de afiliados posible, algo fundamental para poder conseguir nuestros objetivos. El sindicato es una asociaci\u00f3n democr\u00e1tica de trabajadores que defienden sus intereses. Los intereses los definen sus afiliados democr\u00e1ticamente. Los objetivos b\u00e1sicos del sindicato son, actualmente:<\/p>\n<p style=\"text-align: justify;\">1. Promover el cumplimiento de la legislaci\u00f3n laboral en empresas de Arquitectura en todo el Estado Espa\u00f1ol. Esto significa luchar porque los arquitectos tengamos acceso a los derechos de todos los trabajadores, entre otros: paro, baja remunerada, jubilaci\u00f3n acorde a categor\u00eda profesional. Las inspecciones de trabajo de oficio han empezado ya en las comunidades aut\u00f3nomas con afiliaci\u00f3n activa.<br \/>\n2. Conseguir un Convenio Colectivo para Arquitectos de \u00e1mbito estatal (o la extensi\u00f3n de uno existente de otros profesionales), que determine, entre otras cosas un Salario m\u00ednimo digno para arquitectos empleados*\u00b9.<br \/>\n3. Facilitar el acceso al trabajo de los arquitectos j\u00f3venes y mejorar las condiciones de trabajo de todo tipo de arquitectos y profesionales del \u00e1mbito de la arquitectura. Somos un cauce para ejecutar las propuestas de los afiliados. Esperamos tus propuestas.<\/p>\n<p style=\"text-align: justify;\">Estos son objetivos que podr\u00eda hacer suyos toda la profesi\u00f3n. La degradaci\u00f3n del oficio del arquitecto, comenz\u00f3 hace tiempo con la degradaci\u00f3n de los empleados arquitectos. No valorar el trabajo del arquitecto o del profesional de la arquitectura empleado, perjudica a todos los arquitectos, tanto al profesional empleado directamente, como al arquitecto aut\u00f3nomo o al empresario por la competencia desleal o dumping (bajada de honorarios) de empresas que se aprovechan de trabajadores sin derechos y en precario. Si est\u00e1s de acuerdo con estos objetivos, por favor, af\u00edliate. Te explicamos por qu\u00e9 es necesario:<\/p>\n<p style=\"text-align: justify;\">Es imposible cumplir estos objetivos si no tenemos un m\u00ednimo de afiliaci\u00f3n. Ese m\u00ednimo lo estimamos en 1500 afiliados, cantidad de la que estamos todav\u00eda muy lejos. El m\u00ednimo de afiliados necesario cumplir nuestros fines, lo define la ley.*\u00b2<\/p>\n<p style=\"text-align: justify;\">Este n\u00famero de afiliados, adem\u00e1s de darnos opciones en la consecuci\u00f3n de nuestros fines, garantizar\u00eda la supervivencia y renovaci\u00f3n peri\u00f3dica de los cargos electos del sindicato en todo el territorio Espa\u00f1ol. Tambi\u00e9n garantizar\u00e1 la capacidad de actuaci\u00f3n y autonom\u00eda de los afiliados del sindicato en las distintas autonom\u00edas. Promovemos que los arquitectos asuman en cada Comunidad Aut\u00f3noma la responsabilidad en la defensa de sus intereses.<\/p>\n<p style=\"text-align: justify;\">El sindicato es una organizaci\u00f3n sin \u00e1nimo de lucro, y los cargos electos no reciben ning\u00fan tipo de compensaci\u00f3n econ\u00f3mica. Hasta ahora todo el trabajo ha sido gracias al esfuerzo voluntario y no remunerado de algunos afiliados. Tambi\u00e9n al pr\u00e9stamo desinteresado de locales de reuni\u00f3n en viviendas y estudios de arquitectura. Si el n\u00famero de afiliados lo permite, podremos contratar servicios \u00fatiles que hasta ahora hemos realizado nosotros mismos, pero que a largo plazo ser\u00e1 imposible realizar mediante voluntariado. (p\u00e1gina web, gestiones judiciales, encuesta, difusi\u00f3n prensa, etc).<\/p>\n<p style=\"text-align: justify;\">La cuota de afiliaci\u00f3n, 20 Euros anuales es la quinta o sexta parte de la de muchos otros sindicatos. Se pact\u00f3 deliberadamente baja, casi simb\u00f3lica, para favorecer la afiliaci\u00f3n en masa. Ser muchos en poco tiempo es pr\u00e1cticamente nuestra \u00fanica opci\u00f3n de supervivencia en un entorno extra\u00f1o a los sindicatos como el de la arquitectura, con una inercia en la ilegalidad y precariedad laboral dif\u00edcil de romper.\u00a0 Puedes tomarte la afiliaci\u00f3n como una firma para conseguir unos objetivos. Si est\u00e1s de acuerdo con ellos, por favor, ap\u00f3yanos.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 te ofrecemos?<br \/>\nLa capacidad de defender nuestros derechos e intereses colectivamente, y las ventajas que ello conlleva. (objetivos 1, 2 y 3)<br \/>\nServicio de asesor\u00eda jur\u00eddica gratuita especializada en relaciones laborales.<br \/>\nUna red fuerte de informaci\u00f3n, contactos y apoyo en momentos duros como \u00e9ste, con capacidad de transformar la profesi\u00f3n poco a poco, pero tambi\u00e9n de ayudarte a buscar trabajo o de fomentar el autoempleo. Frente al profesional d\u00f3cil y desinformado, trabajamos por un profesional informado y exigente en la valoraci\u00f3n de su trabajo.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 te pedimos como afiliado?<br \/>\nTu \u00fanica obligaci\u00f3n es rellenar el formulario de afiliaci\u00f3n y estar al corriente de pago de la cuota de afiliaci\u00f3n, decida democr\u00e1ticamente: 20 Euros anuales.<br \/>\nTus datos estar\u00e1n en una base de datos protegida, y si te quieres dar de baja los destruiremos.<\/p>\n<p style=\"text-align: justify;\">\u00bfAlgo m\u00e1s?<br \/>\nSi quieres, puedes participar y elegir o ser elegido en los procesos democr\u00e1ticos del sindicato. Existen distintas \u00e1reas de actuaci\u00f3n (aut\u00f3nomos, trabajadores por cuenta ajena, becarios, estudiantes)<br \/>\nSi quieres, puedes tambi\u00e9n participar en nuestros grupos de trabajo, o ejercitar tus derechos como representante de los trabajadores de tu empresa.<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 requisitos tengo que cumplir?<br \/>\nCualquiera de los siguientes requisitos:<br \/>\nSer arquitecto o estudiante de arquitectura, en cualquiera de sus especialidades.<br \/>\nSer arquitecto t\u00e9cnico (aparejador) o arquitecto de interiores.<br \/>\nTrabajar, cualquiera que sea tu oficio en empresas o estudios de arquitectura, dise\u00f1o, urbanismo, paisajismo, ingenier\u00eda, promoci\u00f3n inmobiliaria, construcci\u00f3n, tasaci\u00f3n o asimilables.<br \/>\nTrabajar en centros de ense\u00f1anza e investigaci\u00f3n de todo tipo (universidades, academias, centros de investigaci\u00f3n) de las especialidades descritas en el anterior p\u00e1rrafo que voluntariamente soliciten su afiliaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Gracias otra vez por seguir a nuestro lado!<br \/>\nCONTAMOS CONTIGO<\/p>\n<p style=\"text-align: justify;\">*\u00b9 El sindicato persigue la extensi\u00f3n del convenio de empresas de ingenier\u00eda y oficinas de estudios t\u00e9cnicos al \u00e1mbito de la arquitectura, como camino m\u00e1s r\u00e1pido para proteger a los arquitectos. Este convenio marca un m\u00ednimo salarial de 22800 Euros brutos anuales.<\/p>\n<p style=\"text-align: justify;\">*\u00b2 La ley vigente en Espa\u00f1a exige a un sindicato que tenga un 10 % de la representaci\u00f3n en los \u00f3rganos de representaci\u00f3n de los trabajadores en los estudios de toda Espa\u00f1a para poder firmar un convenio colectivo de \u00e1mbito nacional. En las empresas de Arquitectura apenas hay \u00f3rganos de representaci\u00f3n nombrados (delegados de personal), por lo que esa fracci\u00f3n no ser\u00eda dif\u00edcil de conseguir si tuvi\u00e9ramos un n\u00famero suficiente de delegados de personal afiliados.\u00a0 No obstante, el n\u00famero de afiliados total es muy importante de cara a la representatividad simb\u00f3lica y al peso del sindicato en los medios y frente a la administraci\u00f3n o patronal. , por ejemplo , y en caso de no llegar a la representatividad en delegados de personal. Intentaremos defender nuestra representatividad como una fracci\u00f3n del total de los arquitectos que trabajan por cuenta ajena.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.sindicatoarquitectos.es\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #888888;\">+\u00a0 sindicatoarquitectos.es<\/span><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Estimado\/a amigo\/a: Queremos agradecerte en primer lugar que formes parte del grupo de amigos del Sindicato de Arquitectos de Espa\u00f1a en Facebook.\u00a0 Como puedes ver, es un grupo din\u00e1mico, con m\u00e1s de 3000 amigos, en el que muchos arquitectos y profesionales de la arquitectura hemos entrado en contacto.\u00a0Gracias a todos vosotros, nuestro recorrido en Facebook [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9364,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[43,16],"tags":[2937,521,758,4798,1103,8338],"class_list":{"0":"post-9363","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-cursos-talleres","8":"category-eventos","10":"tag-espana","11":"tag-joven-arquitecto","12":"tag-modelo-profesional","13":"tag-profesion","14":"tag-sindicato-de-arquitectos"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ha llegado el momento de ACTUAR | sindicatoarquitectos - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-19T08:20:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T13:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Ha llegado el momento de ACTUAR | sindicatoarquitectos\",\"datePublished\":\"2011-01-19T08:20:39+00:00\",\"dateModified\":\"2020-11-25T13:26:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/\"},\"wordCount\":3672,\"commentCount\":35,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/cab_presentacion.jpg\",\"keywords\":[\"colegio de arquitectos\",\"Espa\u00f1a\",\"joven arquitecto\",\"modelo profesional\",\"profesi\u00f3n\",\"sindicato de arquitectos\"],\"articleSection\":[\"cursos-talleres\",\"eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/\",\"name\":\"[:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/cab_presentacion.jpg\",\"datePublished\":\"2011-01-19T08:20:39+00:00\",\"dateModified\":\"2020-11-25T13:26:51+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/cab_presentacion.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/01\\\/cab_presentacion.jpg\",\"width\":\"500\",\"height\":\"125\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ha llegado el momento de ACTUAR | sindicatoarquitectos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]","og_url":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2011-01-19T08:20:39+00:00","article_modified_time":"2020-11-25T13:26:51+00:00","og_image":[{"width":500,"height":125,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Ha llegado el momento de ACTUAR | sindicatoarquitectos","datePublished":"2011-01-19T08:20:39+00:00","dateModified":"2020-11-25T13:26:51+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/"},"wordCount":3672,"commentCount":35,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg","keywords":["colegio de arquitectos","Espa\u00f1a","joven arquitecto","modelo profesional","profesi\u00f3n","sindicato de arquitectos"],"articleSection":["cursos-talleres","eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/","url":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/","name":"[:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg","datePublished":"2011-01-19T08:20:39+00:00","dateModified":"2020-11-25T13:26:51+00:00","description":"Toda la informaci\u00f3n sobre: [:es]Ha llegado el momento de ACTUAR | sindicatoarquitectos[:gl]Chegou o momento de ACTUAR | sindicatoarquitectos[:en]It has arrived the moment to ACT | sindicatoarquitectos[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/01\/cab_presentacion.jpg","width":"500","height":"125"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/ha-llegado-el-momento-de-actuar-sindicatoarquitectos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Ha llegado el momento de ACTUAR | sindicatoarquitectos"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/9363","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=9363"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/9363\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/9364"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=9363"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=9363"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=9363"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}