{"id":92318,"date":"2023-02-14T00:01:32","date_gmt":"2023-02-13T23:01:32","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=92318"},"modified":"2024-02-15T16:23:12","modified_gmt":"2024-02-15T15:23:12","slug":"las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/","title":{"rendered":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible"},"content":{"rendered":"<h4 style=\"text-align: justify;\"><strong>Menores costes, m\u00e1s ligereza, agilidad y versatilidad en la obra y \u00f3ptimos resultados para el aislamiento t\u00e9rmico<\/strong><\/h4>\n<p style=\"text-align: justify;\">El <a href=\"https:\/\/www.hispalyt.es\/es\" target=\"_blank\" rel=\"noopener\">Gremi de Rajolers de la Comunitat Valenciana<\/a> e <a href=\"https:\/\/www.hispalyt.es\/es\" target=\"_blank\" rel=\"noopener\">Hispalyt <\/a>recuerdan la idoneidad de las soluciones constructivas con ladrillo y bloque cer\u00e1mico por su capacidad para mejorar la eficiencia energ\u00e9tica y mitigar la embestida de los costes energ\u00e9ticos.<\/p>\n<figure id=\"attachment_92321\" aria-describedby=\"caption-attachment-92321\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-92321 size-full\" title=\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible Casa en Pedrezuela Slow Studio\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\" alt=\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible Casa en Pedrezuela Slow Studio\" width=\"1400\" height=\"1867\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio-225x300.jpg 225w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio-768x1024.jpg 768w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio-1152x1536.jpg 1152w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio-696x928.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio-1068x1424.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-92321\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Casa en Pedrezuela, 2021, Slow Studio \u00a9 Salva L\u00f3pez<\/span><\/figcaption><\/figure>\n<h5 style=\"text-align: justify;\"><strong>El aumento del precio de los combustibles y la urgencia clim\u00e1tica exigen soluciones constructivas sostenibles<\/strong><\/h5>\n<p style=\"text-align: justify;\">Aunque m\u00e1s tarde de lo que corresponde al calendario, las bajas temperaturas ya han llegado.<\/p>\n<p style=\"text-align: justify;\">La prolongada crisis geopol\u00edtica en Ucrania y las tensiones inflacionistas derivadas de la carest\u00eda de los combustibles han puesto el foco en dos de las principales preocupaciones de una Europa que trabaja intensamente en su resiliencia y sostenibilidad: el ahorro energ\u00e9tico y la reducci\u00f3n de los gases de efecto invernadero.<\/p>\n<p style=\"text-align: justify;\">En materia de edificaci\u00f3n, la v\u00eda legislativa ya ha dado pasos de gigante para corregir estos sobrecostes econ\u00f3micos y sociales con exigencias para nuevas construcciones y rehabilitaciones que inciden en el uso de materiales y certificaciones que garanticen la eficiencia energ\u00e9tica. Tambi\u00e9n trata de evitar las desigualdades y proteger el estado del bienestar en estos momentos de p\u00e9rdida de poder adquisitivo en los que la eficiencia es tambi\u00e9n una cuesti\u00f3n de primer orden para el bolsillo de los ciudadanos.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan un estudio reciente de <a href=\"https:\/\/www.camecon.com\/what\/our-work\/new-findings-on-fossil-fuels-and-recent-inflation-in-spain\/\" target=\"_blank\" rel=\"noopener\">Cambridge Econometrics<\/a>, el precio final de la luz y el gas &#8211; el que abonan los consumidores dom\u00e9sticos-, casi se ha duplicado en los \u00faltimos dos a\u00f1os en Espa\u00f1a.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cEl ahorro energ\u00e9tico no es solo una cuesti\u00f3n de Estado por motivos de sostenibilidad o dependencia, se ha convertido en una de las principales preocupaciones y gasto de los ciudadanos, con precios hist\u00f3ricos que obligan a destinar buena parte de los ingresos de las familias a algo tan b\u00e1sico como el confort en el hogar\u201d, <\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">explica el presidente del Gremi de Rajolers de la Comunitat Valenciana, Ismael Alonso.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cLa resistencia t\u00e9rmica de los materiales constructivos es fundamental para corregir este desequilibrio y reducir la dependencia energ\u00e9tica\u201d.<\/em><\/p>\n<\/blockquote>\n<h5 style=\"text-align: justify;\"><strong>El precio final de la luz y el gas para los hogares espa\u00f1oles se ha multiplicado por dos en dos a\u00f1os<\/strong><\/h5>\n<p style=\"text-align: justify;\">La Asociaci\u00f3n valenciana de fabricantes de <a href=\"https:\/\/veredes.es\/blog\/?s=cer%C3%A1mica\" target=\"_blank\" rel=\"noopener\">ladrillos y tejas<\/a> contin\u00faa desarrollando su campa\u00f1a de promoci\u00f3n junto con <a href=\"https:\/\/www.hispalyt.es\/es\" target=\"_blank\" rel=\"noopener\">Hispalyt<\/a>, en la que, bajo la denominaci\u00f3n \u201c<a href=\"https:\/\/paredesdeladrillo.com\/wp-content\/uploads\/documentos\/manual_hispalyt_ladrillo_ceramico_web.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Paredes de Ladrillo, soluciones que cumplen<\/strong><\/a>\u201d, reivindica la capacidad de las soluciones de fachadas y paredes separadoras de ladrillo y bloque cer\u00e1mico para reducir el consumo energ\u00e9tico e incrementar el confort y la seguridad en cualquier proyecto constructivo.<\/p>\n<p style=\"text-align: justify;\">Sus promotores destacan que sus materiales aportan soluciones con una elevada inercia t\u00e9rmica que cumplen requisitos t\u00e9cnicos establecidos para las certificaciones ambientales m\u00e1s exigentes, permitiendo un gran ahorro energ\u00e9tico. Adem\u00e1s,<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201clos ladrillos y bloques cer\u00e1micos tienen un coste de instalaci\u00f3n m\u00e1s bajo que el de otras alternativas que podemos encontrar en el mercado: requieren menos mortero, son materiales m\u00e1s ligeros que permiten el uso de piezas de mayor formato y agilizan el montaje\u201d, <\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">explica Alonso.<\/p>\n<p style=\"text-align: justify;\">La <a href=\"https:\/\/paredesdeladrillo.com\/wp-content\/uploads\/documentos\/folleto_ladrillo_y_bloque_ceramico_hispalyt_sep_2022.pdf\" target=\"_blank\" rel=\"noopener\">resistencia t\u00e9rmica<\/a> de las f\u00e1bricas de ladrillos y bloques cer\u00e1micos es mayor que la de otros materiales, lo que unido a un buen dise\u00f1o permite optimizar el aislamiento. Incluso en las condiciones clim\u00e1ticas m\u00e1s duras, estas soluciones constructivas contribuyen a reducir las necesidades de calefacci\u00f3n en el interior de los edificios.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, gracias a su hermeticidad y transpirabilidad, contribuyen a conseguir una buena estanqueidad, manteniendo unas \u00f3ptimas condiciones en el ambiente interior del inmueble y reduciendo la aparici\u00f3n de patolog\u00edas que pudiesen comprometer su durabilidad y la salud de sus usuarios.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #999999;\"><em>El <a href=\"https:\/\/www.hispalyt.es\/es\" target=\"_blank\" rel=\"noopener\">Gremi de Rajolers de la Comunitat Valenciana<\/a> desarrolla, junto a Hispalyt, la campa\u00f1a \u201c<a style=\"color: #999999;\" href=\"https:\/\/bit.ly\/3f5zyVN\" target=\"_blank\" rel=\"noopener\">Paredes de ladrillo, soluciones que cumplen<\/a>\u201d, cuyo objetivo es mostrar las prestaciones y ventajas de las soluciones para fachadas y tabiquer\u00eda interior para el cumplimiento integral del C\u00f3digo T\u00e9cnico de la Edificaci\u00f3n.<\/em><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Menores costes, m\u00e1s ligereza, agilidad y versatilidad en la obra y \u00f3ptimos resultados para el aislamiento t\u00e9rmico El Gremi de Rajolers de la Comunitat Valenciana e Hispalyt recuerdan la idoneidad de las soluciones constructivas con ladrillo y bloque cer\u00e1mico por su capacidad para mejorar la eficiencia energ\u00e9tica y mitigar la embestida de los costes energ\u00e9ticos. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":92321,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10089,5951],"tags":[12448,13218,296,365,10108,13216,841],"class_list":{"0":"post-92318","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-aparejo","8":"category-slider-principal","9":"tag-arquitectura","10":"tag-arquitectura-de-ladrillo","11":"tag-ceramica","12":"tag-construccion","13":"tag-cte","14":"tag-hispalyt","15":"tag-material"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T23:01:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-15T15:23:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"1867\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible\",\"datePublished\":\"2023-02-13T23:01:32+00:00\",\"dateModified\":\"2024-02-15T15:23:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/\"},\"wordCount\":729,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\",\"keywords\":[\"arquitectura\",\"arquitectura de ladrillo\",\"cer\u00e1mica\",\"construcci\u00f3n\",\"CTE\",\"Hispalyt\",\"material\"],\"articleSection\":[\"aparejo\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/\",\"name\":\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\",\"datePublished\":\"2023-02-13T23:01:32+00:00\",\"dateModified\":\"2024-02-15T15:23:12+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg\",\"width\":1400,\"height\":1867,\"caption\":\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible Casa en Pedrezuela Slow Studio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes","description":"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/","og_locale":"es_ES","og_type":"article","og_title":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes","og_description":"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible","og_url":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2023-02-13T23:01:32+00:00","article_modified_time":"2024-02-15T15:23:12+00:00","og_image":[{"width":1400,"height":1867,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible","datePublished":"2023-02-13T23:01:32+00:00","dateModified":"2024-02-15T15:23:12+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/"},"wordCount":729,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg","keywords":["arquitectura","arquitectura de ladrillo","cer\u00e1mica","construcci\u00f3n","CTE","Hispalyt","material"],"articleSection":["aparejo","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/","url":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/","name":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg","datePublished":"2023-02-13T23:01:32+00:00","dateModified":"2024-02-15T15:23:12+00:00","description":"Toda la informaci\u00f3n sobre: Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible cer\u00e1mica ahorro eficiencia para la edificaci\u00f3n sostenible","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2023\/02\/Las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible-Casa-en-Pedrezuela-Slow-Studio.jpg","width":1400,"height":1867,"caption":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible Casa en Pedrezuela Slow Studio"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/las-fachadas-y-tabiques-ceramicos-un-metodo-de-ahorro-y-una-garantia-de-eficiencia-para-la-edificacion-sostenible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Las fachadas y tabiques cer\u00e1micos, un m\u00e9todo de ahorro y una garant\u00eda de eficiencia para la edificaci\u00f3n sostenible"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/92318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=92318"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/92318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/92321"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=92318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=92318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=92318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}