{"id":91397,"date":"2022-11-24T00:01:36","date_gmt":"2022-11-23T23:01:36","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=91397"},"modified":"2024-02-16T10:24:21","modified_gmt":"2024-02-16T09:24:21","slug":"rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/","title":{"rendered":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural"},"content":{"rendered":"<p style=\"text-align: justify;\">La intervenci\u00f3n consistente en la rehabilitaci\u00f3n integral del antiguo matadero de Benlloch, que data de 1926, para su transformaci\u00f3n en nuevo espacio de uso cultural; el Centro de la Memoria de Benlloch. El proyecto de rehabilitaci\u00f3n corri\u00f3 a cargo del arquitecto <a href=\"https:\/\/www.danielmas.com\/\" target=\"_blank\" rel=\"noopener\">Daniel J. Mas Mateu<\/a> y el arquitecto t\u00e9cnico Enrique Climent Radiu en la direcci\u00f3n facultativa.<\/p>\n<figure id=\"attachment_91398\" aria-describedby=\"caption-attachment-91398\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91398 size-full\" title=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final.jpg\" alt=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" width=\"1400\" height=\"1050\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final-300x225.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final-1024x768.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final-696x522.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-final-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91398\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El objetivo del proyecto era construir una edificaci\u00f3n de dos plantas a partir del antiguo edificio, de una sola planta, situado entre medianeras. Para ello, se ha reutilizado parte de la estructura del antiguo edificio y algunos elementos de su antiguo uso como matadero. El antiguo edificio ten\u00eda dos vol\u00famenes claramente diferenciados; un primer espacio semiabierto destinado a la matanza, y otro volumen de mayor altura destinado a las labores de preparaci\u00f3n de la carne. En el proyecto se ha intentado mantener esta diferenciaci\u00f3n, incluso las caracter\u00edsticas de cada uno de los dos vol\u00famenes.<\/p>\n<figure id=\"attachment_91399\" aria-describedby=\"caption-attachment-91399\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91399 size-full\" title=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA.jpg\" alt=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" width=\"1400\" height=\"1050\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA-300x225.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA-1024x768.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA-696x522.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ESPACIO-DOBL-ALTURA-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91399\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu | Doble altura<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En cuanto al exterior, la fachada norte mantiene el hermetismo original, y solo se abre en la parte ampliada diferenciando con este gesto lo nuevo de las preexistencias. En la zona sur se ha realizado una fachada muy di\u00e1fana y se ha mantenido la idea de patio abierto con la entrada de mucha luz, intentando armonizar con los antiguos lavaderos que lindan por la parte izquierda y reproduciendo la imagen de antigua \u201clogia\u201d de los mencionados lavaderos.<\/p>\n<figure id=\"attachment_91400\" aria-describedby=\"caption-attachment-91400\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91400 size-full\" title=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura.jpg\" alt=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" width=\"1400\" height=\"933\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura-300x200.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura-1024x682.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura-696x464.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-doble-altura-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91400\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu | Doble Altura<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Para la rehabilitaci\u00f3n de la cubierta, que ha afectado a una superficie total de 220 metros cuadrados, se ha optado por el <a href=\"https:\/\/es.onduline.com\/es\/profesional\/sistemas-cubierta-y-tejado\/sistema-integral-tejado-y-cubierta\/sistema-integral-tejado\" target=\"_blank\" rel=\"noopener\"><strong>Sistema Integral de cubierta Onduline<\/strong><\/a>.<\/p>\n<p style=\"text-align: justify;\">El espacio a doble altura del volumen principal est\u00e1 cubierto con una cubierta ligera realizada con estructura met\u00e1lica formada por un entramado de IPE. Sobre esta estructura ligera se instala el primer elemento del Sistema Integral de cubierta Onduline, el panel s\u00e1ndwich de madera Ondutherm. El tipo de panel s\u00e1ndwich instalado ha sido la referencia: H16+A80+FAN13, un panel s\u00e1ndwich con un tablero superior aglomerado hidr\u00f3fugo de 16mm, un aislamiento XPS de 80 mm y un tablero interior de friso de abeto natural de 13 mm.<\/p>\n<figure id=\"attachment_91401\" aria-describedby=\"caption-attachment-91401\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91401 size-full\" title=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA.jpg\" alt=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu\" width=\"1400\" height=\"1867\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA-225x300.jpg 225w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA-768x1024.jpg 768w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA-1152x1536.jpg 1152w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA-696x928.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-ENCUENTRO-LATERAL-CUBIERTA-1068x1424.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91401\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu | Encuentro lateral de cubierta<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El panel s\u00e1ndwich se fija mec\u00e1nicamente a las vigas IPE con torniller\u00eda autorroscante, sin necesidad de taladro previo, atornillando desde el tablero superior aglomerado hidrofugo hasta los perfiles met\u00e1licos. Los paneles se unen entre si gracias al encaje machihembrado del aislamiento, generando la rotura de puente t\u00e9rmico que garantiza un buen aislamiento. Una vez fijados los paneles s\u00e1ndwich a la estructura, se procede al sellado de juntas y a la impermeabilizaci\u00f3n de la cubierta inclinada con el segundo elemento del Sistema Integral de cubierta Onduline.<\/p>\n<figure id=\"attachment_91402\" aria-describedby=\"caption-attachment-91402\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91402 size-full\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\" alt=\"Rehabilitaci\u00f3n-antiguo-matadero-de-Benlloch-para-su-transformaci\u00f3n-en-un-espacio-cultural,-del-arquitecto-Daniel-J.-Mas-Mateu-interior\" width=\"1400\" height=\"933\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior-300x200.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior-1024x682.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior-696x464.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior-1068x712.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91402\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu | Interior<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La placa asf\u00e1ltica Onduline Bajo Teja DRS es el elemento de impermeabilizaci\u00f3n bajo teja que protege a los paneles s\u00e1ndwich evitando cualquier filtraci\u00f3n a trav\u00e9s de las tejas. Adem\u00e1s, gracias a su formato ondulado se genera un doble tiro de ventilaci\u00f3n que elimina las condensaciones y alarga la vida \u00fatil de los paneles s\u00e1ndwich y de la cubierta en general.<\/p>\n<figure id=\"attachment_91403\" aria-describedby=\"caption-attachment-91403\" style=\"width: 1400px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91403 size-full\" title=\"Rehabilitaci\u00f3n-antiguo-matadero-de-Benlloch-para-su-transformaci\u00f3n-en-un-espacio-cultural,-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO.jpg\" alt=\"Rehabilitaci\u00f3n-antiguo-matadero-de-Benlloch-para-su-transformaci\u00f3n-en-un-espacio-cultural,-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO\" width=\"1400\" height=\"1050\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO.jpg 1400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO-300x225.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO-1024x768.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO-696x522.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-FINAL-RIO-1068x801.jpg 1068w\" sizes=\"auto, (max-width: 1400px) 100vw, 1400px\" \/><figcaption id=\"caption-attachment-91403\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural, del arquitecto Daniel J. Mas Mateu | Alzado al R\u00edo<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La fijaci\u00f3n de las placas <a href=\"https:\/\/veredes.es\/blog\/tag\/onduline\/\" target=\"_blank\" rel=\"noopener\">Onduline<\/a> Bajo Teja DRS tambi\u00e9n es mec\u00e1nica, directamente sobre los paneles s\u00e1ndwich de madera Ondutherm con torniller\u00eda para madera. El modelo de placa O utilizado ha sido el BT-150 PLUS, v\u00e1lido tanto para tejas curvas como mixtas, planas o de hormig\u00f3n, porque se ha optado por colocar la teja cer\u00e1mica curva recuperada de la antigua cubierta. Se han utilizado tejas cer\u00e1micas nuevas como canales y tejas recuperadas como cobija. Su instalaci\u00f3n es muy r\u00e1pida y sencilla, gracias a la plantilla que forman las propias placas bajo teja. En este caso, se ha optado por su instalaci\u00f3n de forma tradicional con mortero de cal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La intervenci\u00f3n consistente en la rehabilitaci\u00f3n integral del antiguo matadero de Benlloch, que data de 1926, para su transformaci\u00f3n en nuevo espacio de uso cultural; el Centro de la Memoria de Benlloch. El proyecto de rehabilitaci\u00f3n corri\u00f3 a cargo del arquitecto Daniel J. Mas Mateu y el arquitecto t\u00e9cnico Enrique Climent Radiu en la direcci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":91402,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10089,5951],"tags":[12478,12448,13218,2631,2556,5243,296,312,6917,1997,365,397,16239,2397,15853,1862,473,530,3291,708,841,2081,15852,2787,12464,1168,1233,12469,3311],"class_list":["post-91397","post","type-post","status-publish","format-standard","has-post-thumbnail","category-aparejo","category-slider-principal","tag-aparejo","tag-arquitectura","tag-arquitectura-espanola","tag-arquitectura-sostenible","tag-cambio-climatico","tag-ceramica","tag-ciclo","tag-ciudad-sostenible","tag-clima","tag-construccion","tag-cubierta","tag-daniel-j-mas-mateu","tag-diseno-sostenible","tag-eduardo-dorado","tag-eficiencia","tag-energia","tag-estrategias","tag-etica-de-la-sostenibilidad","tag-industrializacion","tag-material","tag-monumento","tag-onduline","tag-patrimonio-cultural","tag-rehabilitacion","tag-restauracion","tag-sistema","tag-sostenibilidad","tag-tecnica-tradicional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-23T23:01:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-16T09:24:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural\",\"datePublished\":\"2022-11-23T23:01:36+00:00\",\"dateModified\":\"2024-02-16T09:24:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\",\"keywords\":[\"aparejo\",\"arquitectura\",\"arquitectura de ladrillo\",\"arquitectura espa\u00f1ola\",\"arquitectura sostenible\",\"cambio clim\u00e1tico\",\"cer\u00e1mica\",\"ciclo\",\"ciudad sostenible\",\"clima\",\"construcci\u00f3n\",\"cubierta\",\"Daniel J. Mas Mateu\",\"dise\u00f1o sostenible\",\"Eduardo Dorado\",\"eficiencia\",\"energ\u00eda\",\"estrategias\",\"\u00e9tica de la sostenibilidad\",\"industrializaci\u00f3n\",\"material\",\"monumento\",\"onduline\",\"patrimonio cultural\",\"rehabilitaci\u00f3n\",\"restauraci\u00f3n\",\"sistema\",\"sostenibilidad\",\"t\u00e9cnica tradicional\"],\"articleSection\":[\"aparejo\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/\",\"name\":\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\",\"datePublished\":\"2022-11-23T23:01:36+00:00\",\"dateModified\":\"2024-02-16T09:24:21+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg\",\"width\":1400,\"height\":933,\"caption\":\"Rehabilitaci\u00f3n-antiguo-matadero-de-Benlloch-para-su-transformaci\u00f3n-en-un-espacio-cultural,-del-arquitecto-Daniel-J.-Mas-Mateu-interior\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes","description":"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/","og_locale":"es_ES","og_type":"article","og_title":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes","og_description":"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural","og_url":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2022-11-23T23:01:36+00:00","article_modified_time":"2024-02-16T09:24:21+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural","datePublished":"2022-11-23T23:01:36+00:00","dateModified":"2024-02-16T09:24:21+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg","keywords":["aparejo","arquitectura","arquitectura de ladrillo","arquitectura espa\u00f1ola","arquitectura sostenible","cambio clim\u00e1tico","cer\u00e1mica","ciclo","ciudad sostenible","clima","construcci\u00f3n","cubierta","Daniel J. Mas Mateu","dise\u00f1o sostenible","Eduardo Dorado","eficiencia","energ\u00eda","estrategias","\u00e9tica de la sostenibilidad","industrializaci\u00f3n","material","monumento","onduline","patrimonio cultural","rehabilitaci\u00f3n","restauraci\u00f3n","sistema","sostenibilidad","t\u00e9cnica tradicional"],"articleSection":["aparejo","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/","url":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/","name":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg","datePublished":"2022-11-23T23:01:36+00:00","dateModified":"2024-02-16T09:24:21+00:00","description":"Toda la informaci\u00f3n sobre: Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Rehabilitacion-antiguo-matadero-de-Benlloch-para-su-transformacion-en-un-espacio-cultural-del-arquitecto-Daniel-J.-Mas-Mateu-interior.jpg","width":1400,"height":933,"caption":"Rehabilitaci\u00f3n-antiguo-matadero-de-Benlloch-para-su-transformaci\u00f3n-en-un-espacio-cultural,-del-arquitecto-Daniel-J.-Mas-Mateu-interior"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/rehabilitacion-antiguo-matadero-de-benlloch-para-su-transformacion-en-un-espacio-cultural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Rehabilitaci\u00f3n antiguo matadero de Benlloch para su transformaci\u00f3n en un espacio cultural"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/91397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=91397"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/91397\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/91402"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=91397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=91397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=91397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}