{"id":91247,"date":"2022-11-21T00:01:31","date_gmt":"2022-11-20T23:01:31","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=91247"},"modified":"2022-11-21T09:41:05","modified_gmt":"2022-11-21T08:41:05","slug":"ladrillo-textil-inigo-garcia-odiaga","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/","title":{"rendered":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga"},"content":{"rendered":"<figure id=\"attachment_91251\" aria-describedby=\"caption-attachment-91251\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91251\" title=\"Ladrillo textil \u00cd\u00f1igo Garc\u00eda Odiaga semper-der-stil-arquitectura-\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-semper-der-stil-arquitectura-.jpg\" alt=\"Ladrillo textil \u00cd\u00f1igo Garc\u00eda Odiaga semper-der-stil-arquitectura-\" width=\"750\" height=\"420\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-semper-der-stil-arquitectura-.jpg 528w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-semper-der-stil-arquitectura--300x168.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-91251\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Representaci\u00f3n de la caba\u00f1a caribe\u00f1a, en Der Stil; Gottfried Semper<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En 1860, <a href=\"https:\/\/veredes.es\/blog\/tag\/gottfried-semper\/\" target=\"_blank\" rel=\"noopener\">Gottfried Semper<\/a> public\u00f3 su obra cumbre Der Stil, <a href=\"https:\/\/veredes.es\/blog\/semper-el-estilo\/\" target=\"_blank\" rel=\"noopener\">El Estilo<\/a>, un texto en el que ligaba el origen primigenio de la arquitectura al origen de las t\u00e9cnicas textiles. Aquel hombre primitivo capaz de entrelazar tallos o fibras naturales, y alternarlos produciendo patrones en funci\u00f3n de su textura o color, pas\u00f3 f\u00e1cilmente a trenzar ramas o ca\u00f1as para construir cercados o peque\u00f1as empalizadas. Seg\u00fan la teor\u00eda de <a href=\"https:\/\/veredes.es\/blog\/vida-de-semper-y-origen-de-el-estilo-3\/\" target=\"_blank\" rel=\"noopener\">Semper<\/a>, bajo una tesis evolutiva similar a la elaborada por Charles Darwin, esos cerramientos textiles ir\u00edan incorporando materiales m\u00e1s evolucionados como la madera, la piedra o la cer\u00e1mica, pero manteniendo los patrones decorativos heredados de su origen textil. En cierto modo, Semper establece la l\u00f3gica de un proceso seg\u00fan el cual se pasa de cubrir el cuerpo, a a\u00f1adir otra capa que construye una c\u00e1scara en la que el cuerpo se mueve libremente, para posteriormente ir complejizando esa envolvente hasta formalizar una arquitectura, que siempre estar\u00e1 contaminada por su origen epid\u00e9rmico y textil. En ese sentido la arquitectura siempre estar\u00eda supeditada al poder simb\u00f3lico del revestimiento.<\/p>\n<figure id=\"attachment_91252\" aria-describedby=\"caption-attachment-91252\" style=\"width: 768px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-91252 size-full\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\" alt=\"Ladrillo textil \u00cd\u00f1igo Garc\u00eda Odiaga monadnock-landmark-nieuw-bergen-01\" width=\"768\" height=\"1074\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg 768w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01-215x300.jpg 215w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01-732x1024.jpg 732w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01-696x973.jpg 696w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption id=\"caption-attachment-91252\" class=\"wp-caption-text\"><a href=\"https:\/\/www.archdaily.cl\/cl\/781328\/hito-nieuw-bergen-monadnock\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #999999;\">Edificio Landmark en Nieuw-Bergen del estudio Monadnock |\u00a0Stijn Bollaert<\/span><\/a><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El <a href=\"https:\/\/tectonica.archi\/projects\/landmark-nieuw-bergen\/\" target=\"_blank\" rel=\"noopener\">estudio Monadnock<\/a> recibi\u00f3 el encargo para construir en la plaza del mercado de Nieuw-Bergen un peque\u00f1o bar o cafeter\u00eda. Las fachadas han sido realizadas con un ladrillo que presenta dos tonos, uno terroso de color verde y otro rojizo que contrasta con el anterior. Adem\u00e1s se han aplicado gran cantidad de aparejos diferentes para construir todo un repertorio de elementos extruidos, arcos y perforaciones, el resultado es una fachada que presenta diversos patrones y dibujos geom\u00e9tricos similares al punto, a la <a href=\"https:\/\/veredes.es\/blog\/tag\/arquitectura-textil\/\" target=\"_blank\" rel=\"noopener\">estructura textil<\/a> de telas y tejidos.<\/p>\n<p style=\"text-align: justify;\">Gracias a ese despliegue expresivo la fachada se muestra en cierto sentido atemporal, rememora motivos y patrones antiguos pero desde una composici\u00f3n contempor\u00e1nea. Es un objeto peque\u00f1o, abstracto y geom\u00e9trico, observado desde la distancia, pero \u00edntimo y lleno de matices bajo una inspecci\u00f3n m\u00e1s cercana.<\/p>\n<p style=\"text-align: justify;\">Estos juegos de patrones geom\u00e9tricos, le restan masividad a la f\u00e1brica de ladrillo, reduciendo as\u00ed su impacto urbano y al mismo tiempo transformando la imagen del edificio en un elemento arcaico, antiguo en el sentido de primigenio, equiparando su fachada cosida para la ocasi\u00f3n con las vestimentas de aquel hombre primitivo capaz de<a href=\"https:\/\/veredes.es\/blog\/es\/un-orden-hecho-de-tejidos-mario-desaulo-perez\/\" target=\"_blank\" rel=\"noopener\"> tejer<\/a>.<\/p>\n<p style=\"text-align: justify;\">\u00cd\u00f1igo Garc\u00eda Odiaga. Arquitecto<br \/>\nSan Sebasti\u00e1n. Abril 2017<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1860, Gottfried Semper public\u00f3 su obra cumbre Der Stil, El Estilo, un texto en el que ligaba el origen primigenio de la arquitectura al origen de las t\u00e9cnicas textiles. Aquel hombre primitivo capaz de entrelazar tallos o fibras naturales, y alternarlos produciendo patrones en funci\u00f3n de su textura o color, pas\u00f3 f\u00e1cilmente a trenzar [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":91252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[13218,12449,16228,2604,2375,536,6577,6578,4285,737,6576,16229],"class_list":["post-91247","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulos","category-slider-principal","tag-arquitectura-de-ladrillo","tag-arte","tag-charles-darwin","tag-docencia","tag-estetica","tag-estudio","tag-gottfried-semper","tag-harry-francis-mallgrave","tag-inigo-garcia-odiaga","tag-investigacion","tag-juan-ignacio-azpiazu","tag-monadnock"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/inigo.garciaodiaga\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-20T23:01:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T08:41:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"1074\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00cd\u00f1igo Garc\u00eda Odiaga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/IOdiaga\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00cd\u00f1igo Garc\u00eda Odiaga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/\"},\"author\":{\"name\":\"\u00cd\u00f1igo Garc\u00eda Odiaga\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/7edb23bf36ddbe2d9c8f4cf5fae64668\"},\"headline\":\"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga\",\"datePublished\":\"2022-11-20T23:01:31+00:00\",\"dateModified\":\"2022-11-21T08:41:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\",\"keywords\":[\"arquitectura de ladrillo\",\"arte\",\"Charles Darwin\",\"docencia\",\"est\u00e9tica\",\"estudio\",\"Gottfried Semper\",\"harry francis mallgrave\",\"\u00cd\u00f1igo Garc\u00eda Odiaga\",\"investigaci\u00f3n\",\"juan ignacio azpiazu\",\"Monadnock\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/\",\"name\":\"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\",\"datePublished\":\"2022-11-20T23:01:31+00:00\",\"dateModified\":\"2022-11-21T08:41:05+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg\",\"width\":768,\"height\":1074,\"caption\":\"Ladrillo textil \u00cd\u00f1igo Garc\u00eda Odiaga monadnock-landmark-nieuw-bergen-01\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/ladrillo-textil-inigo-garcia-odiaga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/7edb23bf36ddbe2d9c8f4cf5fae64668\",\"name\":\"\u00cd\u00f1igo Garc\u00eda Odiaga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg\",\"caption\":\"\u00cd\u00f1igo Garc\u00eda Odiaga\"},\"description\":\"Doctor Arquitecto y profesor asociado de Proyectos Arquitect\u00f3nicos, ETSASS. Editor de NOMU. 1\\\/5 del estudio de arquitectura VAUMM. Vivo en Donosti.\",\"sameAs\":[\"http:\\\/\\\/vaumm.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/inigo.garciaodiaga\",\"https:\\\/\\\/www.instagram.com\\\/okamika\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/IOdiaga\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/inigog\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes","description":"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/","og_locale":"es_ES","og_type":"article","og_title":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes","og_description":"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga","og_url":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/inigo.garciaodiaga","article_published_time":"2022-11-20T23:01:31+00:00","article_modified_time":"2022-11-21T08:41:05+00:00","og_image":[{"width":768,"height":1074,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg","type":"image\/jpeg"}],"author":"\u00cd\u00f1igo Garc\u00eda Odiaga","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/IOdiaga","twitter_site":"@veredes","twitter_misc":{"Escrito por":"\u00cd\u00f1igo Garc\u00eda Odiaga","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/"},"author":{"name":"\u00cd\u00f1igo Garc\u00eda Odiaga","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/7edb23bf36ddbe2d9c8f4cf5fae64668"},"headline":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga","datePublished":"2022-11-20T23:01:31+00:00","dateModified":"2022-11-21T08:41:05+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg","keywords":["arquitectura de ladrillo","arte","Charles Darwin","docencia","est\u00e9tica","estudio","Gottfried Semper","harry francis mallgrave","\u00cd\u00f1igo Garc\u00eda Odiaga","investigaci\u00f3n","juan ignacio azpiazu","Monadnock"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/","url":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/","name":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg","datePublished":"2022-11-20T23:01:31+00:00","dateModified":"2022-11-21T08:41:05+00:00","description":"Toda la informaci\u00f3n sobre: Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/11\/Ladrillo-textil-Inigo-Garcia-Odiaga-monadnock-landmark-nieuw-bergen-01.jpg","width":768,"height":1074,"caption":"Ladrillo textil \u00cd\u00f1igo Garc\u00eda Odiaga monadnock-landmark-nieuw-bergen-01"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/ladrillo-textil-inigo-garcia-odiaga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Ladrillo textil | \u00cd\u00f1igo Garc\u00eda Odiaga"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/7edb23bf36ddbe2d9c8f4cf5fae64668","name":"\u00cd\u00f1igo Garc\u00eda Odiaga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00cd\u00f1igo-Garc\u00eda-Odiaga-96x96.jpg","caption":"\u00cd\u00f1igo Garc\u00eda Odiaga"},"description":"Doctor Arquitecto y profesor asociado de Proyectos Arquitect\u00f3nicos, ETSASS. Editor de NOMU. 1\/5 del estudio de arquitectura VAUMM. Vivo en Donosti.","sameAs":["http:\/\/vaumm.com\/","https:\/\/www.facebook.com\/inigo.garciaodiaga","https:\/\/www.instagram.com\/okamika\/","https:\/\/x.com\/https:\/\/twitter.com\/IOdiaga"],"url":"https:\/\/veredes.es\/blog\/author\/inigog\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/91247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=91247"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/91247\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/91252"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=91247"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=91247"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=91247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}