{"id":88876,"date":"2022-06-17T00:01:48","date_gmt":"2022-06-16T22:01:48","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=88876"},"modified":"2022-04-18T19:26:47","modified_gmt":"2022-04-18T17:26:47","slug":"populismo-y-legado-oscar-tenreiro-degwitz","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/","title":{"rendered":"Populismo y legado | \u00d3scar Tenreiro Degwitz"},"content":{"rendered":"<figure id=\"attachment_88879\" aria-describedby=\"caption-attachment-88879\" style=\"width: 927px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-88879 size-full\" title=\"Populismo y legado  \u00d3scar Tenreiro Degwitz Esquema de circulaci\u00f3n en Planta Baja del Centro La Floresta, en Caracas, de Jes\u00fas Tenreiro (serigraf\u00eda, 1985; 64x48cm.)\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\" alt=\"Populismo y legado  \u00d3scar Tenreiro Degwitz Esquema de circulaci\u00f3n en Planta Baja del Centro La Floresta, en Caracas, de Jes\u00fas Tenreiro (serigraf\u00eda, 1985; 64x48cm.)\" width=\"927\" height=\"1280\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg 927w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm.-217x300.jpg 217w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm.-742x1024.jpg 742w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm.-696x961.jpg 696w\" sizes=\"auto, (max-width: 927px) 100vw, 927px\" \/><figcaption id=\"caption-attachment-88879\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Esquema de circulaci\u00f3n en Planta Baja del Centro La Floresta, en Caracas, de Jes\u00fas Tenreiro (serigraf\u00eda, 1985; 64x48cm.)<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La \u00abdesprofesionalizaci\u00f3n\u00bb de la acci\u00f3n p\u00fablica es consecuencia del populismo. La b\u00fasqueda de aceptaci\u00f3n privilegia la rapidez sobre la reflexi\u00f3n, haciendo del conocimiento profesional un obst\u00e1culo que debe dejarse de lado. La \u00abdesprofesionalizaci\u00f3n\u00bb ha caracterizado nuestro actual r\u00e9gimen pol\u00edtico de modo especialmente agudo, un rasgo sobre el cual insisti\u00f3 el colega Rafael Iribarren en el Colegio de Arquitectos en su d\u00eda.<\/p>\n<p style=\"text-align: justify;\">Es la explicaci\u00f3n de los disparates con que nos regalan a diario los m\u00e1s altos funcionarios, afortunadamente no siempre seguidos por los pocos que, detr\u00e1s de la fachada m\u00e1s aparente,\u00a0 buscan actuar de forma meditada y reflexiva, a salvo del mandato general de improvisaci\u00f3n y ausencia de rigor. Gracias a ellos no todo est\u00e1 perdido.<\/p>\n<p style=\"text-align: justify;\">Y es bueno hacer notar que desde que la visi\u00f3n populista se impuso hace m\u00e1s de medio siglo, el arquitecto y la arquitectura fueron las primeras bajas. La arquitectura es una dimensi\u00f3n superior del simple fen\u00f3meno de construir, algo que sociedades culturalmente maduras reconocen de modo natural, pero que resulta un \u00abextra\u00bb innecesario, en este contexto local marcado por el peso del <a href=\"https:\/\/veredes.es\/blog\/?s=Populismo\" target=\"_blank\" rel=\"noopener\">modo populista<\/a>.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, dejando atr\u00e1s una primera etapa en la cual profesionales de muy buen nivel tuvieron responsabilidades relevantes, se hizo fuerte aqu\u00ed una visi\u00f3n que devaluaba cualquier esfuerzo por reconocer los contenidos culturales de la arquitectura de las instituciones.. Una actitud que era como un reflejo por oposici\u00f3n de las tesis del sector marxista, que reviv\u00edan debates superados de la primera modernidad como el de considerar requisito excluyente de una arquitectura v\u00e1lida el uso de sistemas constructivos generalizables.<\/p>\n<p style=\"text-align: justify;\"><strong>El mito de los sistemas<\/strong><\/p>\n<p style=\"text-align: justify;\">El valor de la arquitectura, se dec\u00eda en cualquier debate, era \u00aba\u00f1adidura\u00bb de la eficiencia del sistema. Pero esa Ingenuidad interesada se olvid\u00f3 r\u00e1pidamente. Por eso a los j\u00f3venes de hoy les puede parecer incomprensible el prestigio que tuvieron en los sesenta las propuestas de Christopher Alexander (Viena 1936) que reduc\u00edan el ejercicio de la arquitectura a una rama del an\u00e1lisis de sistemas. Porque la visi\u00f3n del arquitecto dispensador de espect\u00e1culos, ant\u00edtesis de la visi\u00f3n \u00abcient\u00edfica\u00bb de Alexander, termin\u00f3 llenado el espacio del debate hasta ocultar totalmente la d\u00e9cada cuestionadora. Pasado que la crisis financiera podr\u00eda hacernos escudri\u00f1ar para entre otras cosas preguntarnos si ese paso hacia t\u00e9rminos radicalmente opuestos no ha sido, precisamente. simplificaci\u00f3n forzada, en suma una trampa populista.<\/p>\n<p style=\"text-align: justify;\">Porque hay muchas formas de populismo, no s\u00f3lo el que anida en la pol\u00edtica sino el que persigue la aceptaci\u00f3n del p\u00fablico como valor supremo.<\/p>\n<p style=\"text-align: justify;\">En la entrevista que hace poco me hizo Antonio Ochoa contest\u00e9 una de sus preguntas dici\u00e9ndole que llevar el \u00abderecho de\u00a0 existir\u00bb de Lady Gaga\u00a0 y Arvo P\u00e4rt,\u00a0 derecho leg\u00edtimo en una sociedad democr\u00e1tica, hasta el punto de equipararlos y aceptarlos en plano de igualdad como parte inevitable de una realidad cultural m\u00faltiple, era puro populismo. Que se impon\u00eda tomar partido y ejercer el derecho del rechazo activo. Llevo eso al terreno del relativismo imperante y hago la misma consideraci\u00f3n. El relativismo es una apolog\u00eda de la pasividad.\u00a0 Y el relativismo con todas sus consecuencias, asociado a una noci\u00f3n de la tolerancia que lleva al \u00abtodo vale\u00bb posmoderno, es la cuna donde ha nacido una forma de ver la arquitectura que ha terminado convirti\u00e9ndola, la de \u00e9xito, en icono de un sistema de prioridades econ\u00f3micas y de \u00abmarketing\u00bb que se ha derrumbado estruendosamente sobre sus propias incoherencias.<\/p>\n<p style=\"text-align: justify;\"><strong>Un legado<\/strong><\/p>\n<p style=\"text-align: justify;\">O sea que por un lado nos asedia el populismo de signo menos (para definir el nuestro) y por el otro el de signo m\u00e1s, el de los pa\u00edses \u00abpremium\u00bb que ignoran el resto del mundo. Y pregunt\u00e1ndose uno qu\u00e9 hacer ante esos dos falsos caminos le vienen en auxilio los valores esenciales, los m\u00e1s simples, los que est\u00e1n en el origen de las cosas.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Tenreiro, el hermano mayor de nosotros cinco, nacido en 1936 y fallecido hace poco, fue un arquitecto de singular valor. En lo que a m\u00ed concierne, el aspecto m\u00e1s importante de su legado es el intelectual, o, para ser menos solemne, el espiritual. Que se expresaba de modo tajante hacia nuestra disciplina a partir de ciertas convicciones. He mencionado muchas veces su idea, inspirada por la erosi\u00f3n del populismo, de que \u00abVenezuela es un pa\u00eds pre-arquitect\u00f3nico\u00bb, apreciaci\u00f3n certera y problem\u00e1tica. Pero hay otras dos que apuntan hacia lo esencial de nuestra disciplina: una, considerar siempre la \u00abampliaci\u00f3n del marco de lo posible\u00bb como requisito de la tarea de proponer una arquitectura. La segunda, el que la soluci\u00f3n de problemas es parte inseparable de la tarea del arquitecto. Ambos atributos son de \u00edndole moral y han sido sometidos a una devaluaci\u00f3n sistem\u00e1tica en clave de revisi\u00f3n de los postulados modernos. Sin embargo les da fuerza y los hace vigentes en la realidad actual, el que nos se\u00f1alen la importancia del cultivo del esp\u00edritu cr\u00edtico. El primero impuls\u00e1ndonos a abrir brechas, el segundo alej\u00e1ndonos de la irresponsabilidad. Ambos nos distancian\u00a0 de la neutralidad.<\/p>\n<p style=\"text-align: justify;\">Tienen adem\u00e1s particular importancia en una sociedad como la nuestra que lucha por encontrar un camino. Que no ser\u00e1 un residuo de la discusi\u00f3n europea, de las preocupaciones de los pa\u00edses centrales, obsesionados ante la perspectiva de perder privilegios, de reducir niveles, de renunciar a la estabilidad. Atrapados por el refinamiento. Tendr\u00e1 que ser resultado de un examen que profundice en nuestras expectativas, en lo que somos, para, precisamente, ampliar nuestras posibilidades. Y lo que aqu\u00ed logremos \u00bfpor qu\u00e9 no? podr\u00eda tener repercusi\u00f3n all\u00e1 en el centro, porque sus males son an\u00e1logos a los nuestros.<\/p>\n<p>\u00d3scar Tenreiro Degwitz, arquitecto.<br \/>\nVenezuela, Agosto 2011<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La \u00abdesprofesionalizaci\u00f3n\u00bb de la acci\u00f3n p\u00fablica es consecuencia del populismo. La b\u00fasqueda de aceptaci\u00f3n privilegia la rapidez sobre la reflexi\u00f3n, haciendo del conocimiento profesional un obst\u00e1culo que debe dejarse de lado. La \u00abdesprofesionalizaci\u00f3n\u00bb ha caracterizado nuestro actual r\u00e9gimen pol\u00edtico de modo especialmente agudo, un rasgo sobre el cual insisti\u00f3 el colega Rafael Iribarren en el [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":88879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,5951],"tags":[7137,13212,318,319,6942,3344,12778,668,11762,977,9160,15887,1278,2048],"class_list":{"0":"post-88876","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-faro","8":"category-slider-principal","9":"tag-arquitectura-popular","10":"tag-arquitectura-socialista","11":"tag-ciudad","12":"tag-ciudad-contemporanea","13":"tag-ciudad-historica","14":"tag-ciudad-ideal","15":"tag-ciudad-socialista","16":"tag-historia","17":"tag-oscar-tenreiro-degwitz","18":"tag-paisaje","19":"tag-paisaje-cultural","20":"tag-rafael-iribarren","21":"tag-teoria","22":"tag-teoria-e-historia"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-16T22:01:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"927\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/\"},\"author\":{\"name\":\"\u00d3scar Tenreiro Degwitz\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\"},\"headline\":\"Populismo y legado | \u00d3scar Tenreiro Degwitz\",\"datePublished\":\"2022-06-16T22:01:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/\"},\"wordCount\":1031,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\",\"keywords\":[\"arquitectura popular\",\"arquitectura socialista\",\"ciudad\",\"ciudad contempor\u00e1nea\",\"ciudad hist\u00f3rica\",\"ciudad ideal\",\"ciudad socialista\",\"historia\",\"\u00d3scar Tenreiro Degwitz\",\"paisaje\",\"paisaje cultural\",\"Rafael Iribarren\",\"teor\u00eda\",\"teor\u00eda e historia\"],\"articleSection\":[\"faro\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/\",\"name\":\"Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\",\"datePublished\":\"2022-06-16T22:01:48+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg\",\"width\":927,\"height\":1280,\"caption\":\"Esquema de circulaci\u00f3n en Planta Baja del Centro La Floresta, en Caracas, de Jes\u00fas Tenreiro (serigraf\u00eda, 1985; 64x48cm.)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/populismo-y-legado-oscar-tenreiro-degwitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Populismo y legado | \u00d3scar Tenreiro Degwitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\",\"name\":\"\u00d3scar Tenreiro Degwitz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"caption\":\"\u00d3scar Tenreiro Degwitz\"},\"description\":\"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.\",\"sameAs\":[\"https:\\\/\\\/oscartenreiro.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/oscar-tenreiro-degwitz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes","description":"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/","og_locale":"es_ES","og_type":"article","og_title":"Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes","og_description":"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz","og_url":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2022-06-16T22:01:48+00:00","og_image":[{"width":927,"height":1280,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg","type":"image\/jpeg"}],"author":"\u00d3scar Tenreiro Degwitz","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"\u00d3scar Tenreiro Degwitz","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/"},"author":{"name":"\u00d3scar Tenreiro Degwitz","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19"},"headline":"Populismo y legado | \u00d3scar Tenreiro Degwitz","datePublished":"2022-06-16T22:01:48+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/"},"wordCount":1031,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg","keywords":["arquitectura popular","arquitectura socialista","ciudad","ciudad contempor\u00e1nea","ciudad hist\u00f3rica","ciudad ideal","ciudad socialista","historia","\u00d3scar Tenreiro Degwitz","paisaje","paisaje cultural","Rafael Iribarren","teor\u00eda","teor\u00eda e historia"],"articleSection":["faro","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/","url":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/","name":"Populismo y legado | \u00d3scar Tenreiro Degwitz - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg","datePublished":"2022-06-16T22:01:48+00:00","description":"Toda la informaci\u00f3n sobre: Populismo y legado | \u00d3scar Tenreiro Degwitz","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2022\/04\/Populismo-y-legado-Oscar-Tenreiro-Degwitz-Esquema-de-circulacion-en-Planta-Baja-del-Centro-La-Floresta-en-Caracas-de-Jesus-Tenreiro-serigrafia-1985-64x48cm..jpg","width":927,"height":1280,"caption":"Esquema de circulaci\u00f3n en Planta Baja del Centro La Floresta, en Caracas, de Jes\u00fas Tenreiro (serigraf\u00eda, 1985; 64x48cm.)"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/populismo-y-legado-oscar-tenreiro-degwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Populismo y legado | \u00d3scar Tenreiro Degwitz"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19","name":"\u00d3scar Tenreiro Degwitz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","caption":"\u00d3scar Tenreiro Degwitz"},"description":"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.","sameAs":["https:\/\/oscartenreiro.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/oscar-tenreiro-degwitz\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/88876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=88876"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/88876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/88879"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=88876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=88876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=88876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}