{"id":86262,"date":"2021-12-02T00:01:56","date_gmt":"2021-12-01T23:01:56","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=86262"},"modified":"2021-11-10T10:08:18","modified_gmt":"2021-11-10T09:08:18","slug":"atlas-of-interior-design","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/","title":{"rendered":"Atlas of Interior Design"},"content":{"rendered":"<p style=\"text-align: justify;\">Phaidon publica el estudio global m\u00e1s exhaustivo sobre dise\u00f1o de interiores que se haya publicado nunca, incluyendo m\u00e1s de 400 residencias de m\u00e1s de 50 pa\u00edses y 9 regiones continentales, de las \u00faltimas 80 d\u00e9cadas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86264\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg\" alt=\"\" width=\"1800\" height=\"2074\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg 1800w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon-260x300.jpg 260w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon-889x1024.jpg 889w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon-1333x1536.jpg 1333w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon-1777x2048.jpg 1777w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/p>\n<p style=\"text-align: justify;\">Descubre los espacios residenciales m\u00e1s espectaculares e importantes del mundo con Atlas of Interior Design. Organizado geogr\u00e1ficamente, presenta m\u00e1s de 400 espacios que abarcan 9 regiones continentales y m\u00e1s de 50 pa\u00edses desde la d\u00e9cada de 1940 hasta la actualidad. En el libro se incluye a los grandes del interiorismo de ayer y de hoy: Kelly Behun, St\u00e9phane Boudin, Jacques Grange, Peter Marino, Brigette Romanek, Studio KO, Faye Toogood, Axel Vervoordt y Kelly Wearstler, as\u00ed como nuevos descubrimientos en Australia, \u00c1frica o Asia, como Tamsin Johnson, Katie Lockhart y Andr\u00e9 Fu.<\/p>\n<p style=\"text-align: justify;\">Este atlas contempor\u00e1neo presenta obras maestras del interiorismo de un modo totalmente original a trav\u00e9s de mapas estatales y regionales. El novedoso formato permite a los lectores, tanto entusiastas como profesionales del dise\u00f1o, situar influencias del dise\u00f1o en partes concretas del mundo y explorar diferencias de estilos, materiales y colores a trav\u00e9s de fronteras geogr\u00e1ficas y generaciones como no lo ha hecho ninguna publicaci\u00f3n hasta el momento.<\/p>\n<p style=\"text-align: justify;\">Cada proyecto est\u00e1 representado con hasta tres im\u00e1genes en color y va acompa\u00f1ado de un texto esclarecedor e informativo escrito por Dominic Bradbury, autor de m\u00e1s de 20 libros sobre arquitectura, dise\u00f1o e interiorismo, incluyendo publicaciones anteriores de Phaidon como <a href=\"https:\/\/amzn.to\/3aYNZGb\" target=\"_blank\" rel=\"noopener\"><em>Atlas of Mid-Century Modern Houses<\/em><\/a> y <a href=\"https:\/\/amzn.to\/3lZNxO1\" target=\"_blank\" rel=\"noopener\"><em>The Fife Arms<\/em><\/a>.<\/p>\n<p style=\"text-align: justify;\">En un recorrido por todo el planeta, los lectores descubrir\u00e1n fluidas viviendas australianas con un trasfondo de materiales naturales y nativos o con vistas a la playa, mientras que en Palm Springs brillan con luz propia las joyas del movimiento moderno de mediados de siglo. En Jaipur hay habitaciones de color caramelo inspiradas en el estilo de vida de los maraj\u00e1s de India; y en Par\u00eds, los objetos ingeniosamente ubicados llenan estancias con llamativos sof\u00e1s de terciopelo y techos de doble altura con molduras de \u00e9poca. En una casa de campo inglesa encontramos las dosis adecuadas de motivos florales y esp\u00edritu bohemio, adem\u00e1s de una enorme l\u00e1mpara de ara\u00f1a y una pared de color mantequilla.<\/p>\n<p style=\"text-align: justify;\">Dise\u00f1ado por Pentagram, <a href=\"https:\/\/amzn.to\/3Ga5oKc\" target=\"_blank\" rel=\"noopener\"><em>Atlas of Interior Design<\/em><\/a> ofrece una elegante presentaci\u00f3n con una sobrecubierta azul oscuro troquelada y una cubierta dorada debajo. Este estudio ambicioso, profundo e incomparable sobre el interiorismo ser\u00e1 una incorporaci\u00f3n necesaria a la biblioteca de aficionados del dise\u00f1o, arquitectos, interioristas y quienes busquen la inspiraci\u00f3n perfecta para crear hermosos espacios propios.<\/p>\n<p style=\"text-align: justify;\">SOBRE EL AUTOR<\/p>\n<p style=\"text-align: justify;\"><strong>Dominic Bradbury<\/strong> es un escritor y periodista independiente especializado en arquitectura y dise\u00f1o. Ha escrito m\u00e1s de 20 libros, entre ellos <em><a href=\"https:\/\/amzn.to\/3E213qH\" target=\"_blank\" rel=\"noopener\">Mid-Century Modern Complete<\/a>, <a href=\"https:\/\/amzn.to\/2ZeHk7R\" target=\"_blank\" rel=\"noopener\">The Iconic House<\/a>, <a href=\"https:\/\/amzn.to\/3vC1Dbq\" target=\"_blank\" rel=\"noopener\">The Iconic Interior<\/a><\/em> y <a href=\"https:\/\/amzn.to\/3jrFhES\" target=\"_blank\" rel=\"noopener\"><em>Atlas of Mid-Century Modern Houses<\/em><\/a> (Phaidon). Colabora con revistas y peri\u00f3dicos de Reino Unido, Estados Unidos, Australia y otros pa\u00edses, entre ellos Financial Times, The Times, Telegraph, House &amp; Garden, World of Interiors y Vogue Living.<\/p>\n<p><iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=1838663061&amp;linkId=bf8e0285aa5422bf730fd1cbf3efb8c8&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe> <iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=1838660550&amp;linkId=5bcbc58219dc043af2b523ffa1a81e52&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe> <iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=0714876747&amp;linkId=b429f6258378dbac0e22b088b8a600d0&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe> <iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=0500517274&amp;linkId=96ad4a68fa284ba96de7a917a66f848f&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe> <iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=050002295X&amp;linkId=1adf6aef242df22d6919e6c32daea841&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe> <iframe style=\"width: 120px; height: 240px;\" src=\"https:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?ref=qf_sp_asin_til&amp;t=veredes-21&amp;m=amazon&amp;o=30&amp;p=8&amp;l=as1&amp;IS2=1&amp;asins=0500516332&amp;linkId=9dc396d7f70d8af73c092b040194b257&amp;bc1=000000&amp;lt1=_blank&amp;fc1=333333&amp;lc1=0066C0&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"> <span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\">\ufeff<\/span><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Phaidon publica el estudio global m\u00e1s exhaustivo sobre dise\u00f1o de interiores que se haya publicado nunca, incluyendo m\u00e1s de 400 residencias de m\u00e1s de 50 pa\u00edses y 9 regiones continentales, de las \u00faltimas 80 d\u00e9cadas. Descubre los espacios residenciales m\u00e1s espectaculares e importantes del mundo con Atlas of Interior Design. Organizado geogr\u00e1ficamente, presenta m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":86264,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[15598,15594,15592,15588,15520,15591,15597,15589,15595,13224,15590,15593,15596],"class_list":["post-86262","post","type-post","status-publish","format-standard","has-post-thumbnail","category-libros","category-publicaciones","tag-andre-fu","tag-axel-vervoordt","tag-brigette-romanek","tag-dominic-bradbury","tag-faye-toogood","tag-jacques-grange","tag-katie-lockhart","tag-kelly-behun","tag-kelly-wearstler","tag-peter-marino","tag-stephane-boudin","tag-studio-ko","tag-tamsin-johnson"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Atlas of Interior Design - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Atlas of Interior Design\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Atlas of Interior Design - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Atlas of Interior Design\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-01T23:01:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1800\" \/>\n\t<meta property=\"og:image:height\" content=\"2074\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Atlas of Interior Design\",\"datePublished\":\"2021-12-01T23:01:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/\"},\"wordCount\":517,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Atlas-of-Interior-Design-phaidon.jpg\",\"keywords\":[\"Andr\u00e9 Fu\",\"Axel Vervoordt\",\"Brigette Romanek\",\"Dominic Bradbury\",\"Faye Toogood\",\"Jacques Grange\",\"Katie Lockhart\",\"Kelly Behun\",\"Kelly Wearstler\",\"Peter Marino\",\"St\u00e9phane Boudin\",\"Studio KO\",\"Tamsin Johnson\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/\",\"name\":\"Atlas of Interior Design - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Atlas-of-Interior-Design-phaidon.jpg\",\"datePublished\":\"2021-12-01T23:01:56+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Atlas of Interior Design\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Atlas-of-Interior-Design-phaidon.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/Atlas-of-Interior-Design-phaidon.jpg\",\"width\":1800,\"height\":2074},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/atlas-of-interior-design\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Atlas of Interior Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Atlas of Interior Design - veredes","description":"Toda la informaci\u00f3n sobre: Atlas of Interior Design","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/","og_locale":"es_ES","og_type":"article","og_title":"Atlas of Interior Design - veredes","og_description":"Toda la informaci\u00f3n sobre: Atlas of Interior Design","og_url":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2021-12-01T23:01:56+00:00","og_image":[{"width":1800,"height":2074,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Atlas of Interior Design","datePublished":"2021-12-01T23:01:56+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/"},"wordCount":517,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg","keywords":["Andr\u00e9 Fu","Axel Vervoordt","Brigette Romanek","Dominic Bradbury","Faye Toogood","Jacques Grange","Katie Lockhart","Kelly Behun","Kelly Wearstler","Peter Marino","St\u00e9phane Boudin","Studio KO","Tamsin Johnson"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/","url":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/","name":"Atlas of Interior Design - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg","datePublished":"2021-12-01T23:01:56+00:00","description":"Toda la informaci\u00f3n sobre: Atlas of Interior Design","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/atlas-of-interior-design\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/10\/Atlas-of-Interior-Design-phaidon.jpg","width":1800,"height":2074},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/atlas-of-interior-design\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Atlas of Interior Design"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/86262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=86262"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/86262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/86264"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=86262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=86262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=86262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}