{"id":86211,"date":"2021-11-24T00:01:58","date_gmt":"2021-11-23T23:01:58","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=86211"},"modified":"2021-10-22T11:53:20","modified_gmt":"2021-10-22T09:53:20","slug":"casa-del-calvari-endalt-arquitectes","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/","title":{"rendered":"Casa del Calvari | Endalt arquitectes"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86213\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1.jpg\" alt=\"\" width=\"1200\" height=\"1799\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1.jpg 1200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-200x300.jpg 200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-683x1024.jpg 683w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-1025x1536.jpg 1025w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">Se parte de la idea de respetar todo aquello que sea posible, dejando las huellas como homenaje a los que en alg\u00fan momento construyeron o fueron protagonistas de las transformaciones de la casa. Se intenta una arquitectura que hable del pasado con un lenguaje contempor\u00e1neo; que recuerde a aquella arquitectura sin arquitectos, resultado del saber colectivo y la experiencia acumulada.<\/p>\n<p style=\"text-align: justify;\">Esta intervenci\u00f3n busca poner en valor las cicatrices de lo que se elimina para adaptar la vivienda a un habitar contempor\u00e1neo. Aparecen en las paredes las huellas del forjado o la b\u00f3veda de tabica de la antigua escalera, sustituida por una escalera met\u00e1lica de chapa plegada. Se utilizan, adem\u00e1s, materiales contempor\u00e1neos f\u00e1cilmente identificables que ofrezcan a la nueva construcci\u00f3n una imagen impoluta que contraste con la aspereza e imperfecci\u00f3n de las capas m\u00e1s antiguas de la construcci\u00f3n primigenia. Por ello, se recurre a tabiquer\u00edas en seco de entramado autoportante as\u00ed como pavimentos uniformes y de gran formato que contribuyen a la fluidez del espacio.<\/p>\n<p style=\"text-align: justify;\">La vivienda se concibe desde la entrada como una secuencia de espacios que va adentr\u00e1ndose progresivamente en un mundo interior propio de la arquitectura tradicional valenciana: el corral. A medida que nos adentramos en la vivienda vamos ganando privacidad, hasta encontrarnos con el estar, que mediante un ventanal continuo, toma una inmensa bocanada de tranquilidad y frescura. En medio de este corral, y a modo de recordatorio de antiguas formas de vida, un viejo limonero rinde tributo a todos los que durante generaciones han habitado este edificio y se sirvieron de sus frutos.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-86214\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\" alt=\"\" width=\"1200\" height=\"1799\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg 1200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-200x300.jpg 200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-683x1024.jpg 683w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-1025x1536.jpg 1025w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/p>\n<p style=\"text-align: justify;\">\u200f\u200eEste recorrido secuencial se concibe como un recuerdo tambi\u00e9n de aquellas casas que todav\u00eda hoy copan los centros hist\u00f3ricos de los pueblos de l\u2019Horta de Val\u00e8ncia. Se van encadenando espacios cuya funci\u00f3n no siempre queda definida pero que no dejan de tener sentido: una entrada que descubre la totalidad del volumen original de la vivienda y su cubierta a dos aguas, una sala de estudio que se transforma en habitaci\u00f3n de invitados, una peque\u00f1a biblioteca, un espacio de estar, un comedor,\u2026 El espacio fluye de forma continua, interrumpido solo por el recuerdo de una puerta rescatada de la vivienda que filtra y protege el verdadero coraz\u00f3n de la vivienda; un corral que quiere ser parte del estar y un estar que quiere tambi\u00e9n ser corral. Y m\u00e1s all\u00e1, en lo m\u00e1s profundo de la vivienda, un espacio reservado para los invitados m\u00e1s excepcionales, aquellos que merecen adentrarse hasta lo m\u00e1s profundo del alma del anfitri\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Una vez superado el volumen original de la primera vivienda, se construye un nuevo pabell\u00f3n como resultado de eliminar las ampliaciones del edificio original, de menor calidad constructiva, para as\u00ed reinterpretarlas de nuevo. Para este nuevo espacio que alberga la zona de d\u00eda se genera un juego de dos planos horizontales sustentados por cuatro pilares. La estructura met\u00e1lica y el forjado de chapa colaborante permiten un lenguaje de nuestro tiempo con luces mayores y un espacio que por sus dimensiones contrasta con el primer volumen de edificaci\u00f3n.<\/p>\n<div id='gallery-1' class='gallery galleryid-86211 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-1-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-3.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-3-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-3-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-3-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-4-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-4-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-4-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-5-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-5-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-5-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-6.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-6-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-6-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-6-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-7.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-7-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-7-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-7-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-8.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-8-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-8-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-8-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-9.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-9-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-9-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-9-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-10.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-10-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-10-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-10-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-11-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-11-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-11-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-12.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-12-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-12-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-12-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-13-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-13-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-13-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-14.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-14-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-14-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-14-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-15.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-15-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-15-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-15-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-16.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-16-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-16-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-16-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-17.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-17-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-17-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-17-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-18-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-18-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-18-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-19.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-19-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-19-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-19-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-20.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-20-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-20-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-20-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-21.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-21-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-21-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-21-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-22.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-22-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-22-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-22-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-23-PlantaBaja.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-23-PlantaBaja-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-23-PlantaBaja-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-23-PlantaBaja-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-24-PlantaPrimera.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-24-PlantaPrimera-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-24-PlantaPrimera-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-24-PlantaPrimera-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-25-Seccio\u0301n1.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-25-Seccio\u0301n1-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-25-Seccio\u0301n1-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-25-Seccio\u0301n1-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-26-Seccio\u0301n2.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-26-Seccio\u0301n2-120x120.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-26-Seccio\u0301n2-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-26-Seccio\u0301n2-150x150.jpg 150w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Obra: Casa del Calvari<br \/>\nAutores: ENDALT Arquitectes<br \/>\nA\u00f1o finalizaci\u00f3n construcci\u00f3n: 2020<br \/>\nSuperficie construida: 269,70 m2<br \/>\nUbicaci\u00f3n: Alc\u00e0sser (Val\u00e8ncia, Espa\u00f1a)<br \/>\nFotograf\u00edas: <a href=\"http:\/\/davidzarzoso.com\/\" target=\"_blank\" rel=\"noopener\">David Zarzoso<\/a><br \/>\n<a href=\"http:\/\/www.endaltarquitectes.com\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #999999;\">+ endaltarquitectes.com<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se parte de la idea de respetar todo aquello que sea posible, dejando las huellas como homenaje a los que en alg\u00fan momento construyeron o fueron protagonistas de las transformaciones de la casa. Se intenta una arquitectura que hable del pasado con un lenguaje contempor\u00e1neo; que recuerde a aquella arquitectura sin arquitectos, resultado del saber [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":86214,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34,23,2039,1159,5951,59],"tags":[2631,11183,14659,14658,14660,12464,3686,1799,12455],"class_list":["post-86211","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arquitectura","category-obras","category-reforma-interior","category-rehabilitacion","category-slider-principal","tag-arquitectura-espanola","tag-arquitectura-valenciana","tag-carles-rosaleny","tag-endalt-arquitectes","tag-marcelli-rosaleny","tag-rehabilitacion","tag-rehabilitar","tag-valencia","tag-vivienda-unifamiliar"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Casa del Calvari | Endalt arquitectes - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casa del Calvari | Endalt arquitectes - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-23T23:01:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1799\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Casa del Calvari | Endalt arquitectes\",\"datePublished\":\"2021-11-23T23:01:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/\"},\"wordCount\":573,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\",\"keywords\":[\"arquitectura espa\u00f1ola\",\"arquitectura valenciana\",\"Carles Rosaleny\",\"Endalt arquitectes\",\"Marcel\u00b7l\u00ed Rosaleny\",\"rehabilitaci\u00f3n\",\"rehabilitar\",\"Valencia\",\"vivienda unifamiliar\"],\"articleSection\":[\"arquitectura\",\"obras\",\"reforma interior\",\"rehabilitaci\u00f3n\",\"slider principal\",\"vivienda unifamiliar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/\",\"name\":\"Casa del Calvari | Endalt arquitectes - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\",\"datePublished\":\"2021-11-23T23:01:58+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Casa-del-Calvari-Endalt-arquitectes-2.jpg\",\"width\":1200,\"height\":1799},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/casa-del-calvari-endalt-arquitectes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Casa del Calvari | Endalt arquitectes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casa del Calvari | Endalt arquitectes - veredes","description":"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/","og_locale":"es_ES","og_type":"article","og_title":"Casa del Calvari | Endalt arquitectes - veredes","og_description":"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes","og_url":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2021-11-23T23:01:58+00:00","og_image":[{"width":1200,"height":1799,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Casa del Calvari | Endalt arquitectes","datePublished":"2021-11-23T23:01:58+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/"},"wordCount":573,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg","keywords":["arquitectura espa\u00f1ola","arquitectura valenciana","Carles Rosaleny","Endalt arquitectes","Marcel\u00b7l\u00ed Rosaleny","rehabilitaci\u00f3n","rehabilitar","Valencia","vivienda unifamiliar"],"articleSection":["arquitectura","obras","reforma interior","rehabilitaci\u00f3n","slider principal","vivienda unifamiliar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/","url":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/","name":"Casa del Calvari | Endalt arquitectes - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg","datePublished":"2021-11-23T23:01:58+00:00","description":"Toda la informaci\u00f3n sobre: Casa del Calvari | Endalt arquitectes","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/11\/Casa-del-Calvari-Endalt-arquitectes-2.jpg","width":1200,"height":1799},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/casa-del-calvari-endalt-arquitectes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Casa del Calvari | Endalt arquitectes"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/86211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=86211"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/86211\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/86214"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=86211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=86211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=86211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}