{"id":81575,"date":"2021-04-02T00:01:46","date_gmt":"2021-04-01T22:01:46","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=81575"},"modified":"2020-10-12T20:45:02","modified_gmt":"2020-10-12T18:45:02","slug":"en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/","title":{"rendered":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel"},"content":{"rendered":"<figure id=\"attachment_81578\" aria-describedby=\"caption-attachment-81578\" style=\"width: 640px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-81578\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel-1024x486.jpg\" alt=\"\" width=\"640\" height=\"304\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel-1024x486.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel-300x142.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><figcaption id=\"caption-attachment-81578\" class=\"wp-caption-text\"><a href=\"https:\/\/anterior.eldigitalcastillalamancha.es\/articulo_anterior.asp?idarticulo=fallece-el-arquitecto-talaverano-manuel-de-las-casas-151993\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #999999;\">Manuel de las Casas G\u00f3mez | Fuente: eldigitalcastillalamancha.es<\/span><\/a><\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>Manuel de las Casas G\u00f3mez, un magn\u00edfico arquitecto y un gran profesor. Referente de la arquitectura espa\u00f1ola de la democracia<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/veredes.es\/blog\/tag\/manuel-de-las-casas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Manuel de las Casas<\/a> G\u00f3mez hab\u00eda nacido en Talavera de la Reina (1940) y falleci\u00f3 en<a href=\"https:\/\/www.coam.org\/es\/fundacion\/biblioteca\/bibliografia-muestras\/manuel-casas-gomez-fallecido-07-02-2014\" target=\"_blank\" rel=\"noopener noreferrer\"> Madrid<\/a> (2014). Hijo de un ilustre Aparejador y Abogado, Manuel estudi\u00f3 Arquitectura en la Escuela de Madrid y se titul\u00f3 en 1964. Como arquitecto fue socio en los primeros a\u00f1os de <a href=\"https:\/\/veredes.es\/blog\/tag\/javier-segui-de-la-riva\/\" target=\"_blank\" rel=\"noopener noreferrer\">Javier Segui<\/a> y de Santiago L\u00f3pez, luego de su hermano Ignacio y de Jaime Lorenzo y, finalmente, de sus hijos Ic\u00edar y Sergio. Toda su vida compatibiliz\u00f3 la ense\u00f1anza con el alto ejercicio de la profesi\u00f3n y, en ocasiones, con la funci\u00f3n p\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Fue disc\u00edpulo de <a href=\"https:\/\/veredes.es\/blog\/tag\/francisco-javier-saenz-de-oiza\/\" target=\"_blank\" rel=\"noopener noreferrer\">Francisco Javier S\u00e1enz de O\u00edza<\/a> y de <a href=\"https:\/\/veredes.es\/blog\/tag\/alejandro-de-la-sota\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alejandro de la Sota<\/a>, con quien empez\u00f3 a trabajar como profesor en la Escuela de Madrid en 1969. Fue luego Profesor adjunto del catedr\u00e1tico <a href=\"https:\/\/veredes.es\/blog\/tag\/antonio-fernandez-alba\/\" target=\"_blank\" rel=\"noopener noreferrer\">Antonio Fern\u00e1ndez Alba<\/a> (1976) y en 1987 catedr\u00e1tico de Proyectos Arquitect\u00f3nicos. Profesor enormemente significativo y de muy importante relieve en la Escuela de la UPM durante much\u00edsimos a\u00f1os, se jubil\u00f3 en el a\u00f1o 2010. Fue nombrado entonces Profesor em\u00e9rito por la Universidad de Castilla-La Mancha, que le encarg\u00f3 la fundaci\u00f3n y la direcci\u00f3n de una Escuela de Arquitectura en Toledo, hoy en feliz funcionamiento. Conferenciante e invitado en numerosas universidades e instituciones, fue profesor en la Facultad de Arquitectura de la Universidad de Bolonia, Italia.<\/p>\n<p style=\"text-align: justify;\">Habi\u00e9ndose iniciado en la restauraci\u00f3n de monumentos en los a\u00f1os 70, fue llamado por <a href=\"https:\/\/veredes.es\/blog\/tag\/dionisio-hernandez-gil\/\" target=\"_blank\" rel=\"noopener noreferrer\">Dionisio Hern\u00e1ndez Gil<\/a> para ocupar el cargo de Inspector General de Monumentos del Estado en la Direcci\u00f3n General de Bellas Artes, participando activamente en la renovaci\u00f3n de la pol\u00edtica y de la t\u00e9cnica de la restauraci\u00f3n en Espa\u00f1a, que en buena media protagoniz\u00f3. Llegado el primer gobierno de Felipe Gonz\u00e1lez (1982), fue nombrado Subdirector General de Arquitectura, habiendo realizado importantes campa\u00f1as, como fue la interesant\u00edsima y fruct\u00edfera de rehabilitaci\u00f3n de los Teatros espa\u00f1oles. Fue luego (1987) durante algunos a\u00f1os Director General de Arquitectura y Edificaci\u00f3n.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/88924771\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><a href=\"https:\/\/vimeo.com\/88924771\">MANUEL DE LAS CASAS. IN MEMORIAM (1940-2014)<\/a> from <a href=\"https:\/\/vimeo.com\/user24630377\">ajuarez<\/a> on <a href=\"https:\/\/vimeo.com\">Vimeo<\/a>.<\/p>\n<p style=\"text-align: justify;\">Como arquitecto ha sido una figura de especial relieve en el panorama espa\u00f1ol del \u00faltimo tercio del siglo XX y de la primera d\u00e9cada del XXI. Destac\u00f3 en la especialidad de restauraci\u00f3n y rehabilitaci\u00f3n de monumentos (catedral de Toledo, 1979-89, entre otros). Fue con su equipo uno de los m\u00e1s relevantes arquitectos de edificios y conjuntos de vivienda colectiva y social despu\u00e9s de la generaci\u00f3n de S\u00e1enz de O\u00edza, con interesant\u00edsimos trabajos, en Talavera de la Reina (1977), y, sobre todo, en las obras oficiales de remodelaci\u00f3n de la periferia en Madrid (Orcasur, Palomeras Sureste, Norte de Albufera, Plaza de San Francisco, Pol\u00edgono C de Carabanchel, 1976-1987) y tambi\u00e9n en otros sitios de Espa\u00f1a (Santiago de Compostela, 1988). M\u00e1s recientes fueron el conjunto de viviendas en Alcobendas (Madrid), y el conjunto en Vitoria (con sus hijos, 2004). La vivienda social y colectiva tom\u00f3 con su trabajo una calidad extraordinaria, realizando soluciones que pueden considerarse can\u00f3nicas.<\/p>\n<p style=\"text-align: justify;\">Pero no fue menos activo y brillante en arquitecturas de car\u00e1cter singular, como el vanguardista Colegio en Medina del Campo (con Segu\u00ed, 1968), la residencia de internas en Talavera de la Reina (1975) y la Biblioteca p\u00fablica en Valladolid (1984). Con el edificio de la Consejer\u00eda de Agricultura de Castilla-La Mancha, en Toledo (1989), demostr\u00f3 adem\u00e1s el modo en que una arquitectura moderna pod\u00eda compatibilizarse brillantemente con la ciudad hist\u00f3rica, demostraci\u00f3n que confirm\u00f3 con la casa patio particular S\u00e1nchez Medina, tambi\u00e9n en Toledo (2005). Un Palacio de Congresos para Pontevedra, una Facultad en La Coru\u00f1a (1997) y un Instituto en Torrevieja (2005) pueden completar las referencias de sus atractivas y acertadas arquitecturas p\u00fablicas.<\/p>\n<p style=\"text-align: justify;\">Pocas veces se dar\u00e1 un arquitecto tan intensa y brillantemente comprometido en el triple perfil de gran profesor, excelente profesional y muy eficiente alto funcionario, y a quien, por lo tanto, la sociedad espa\u00f1ola debe mucho. Descanse en paz un hombre entero, eximio arquitecto y ciudadano. Su atrayente y completo perfil est\u00e1 ya, por fortuna, en la historia.<\/p>\n<p style=\"text-align: justify;\">Antonio Gonz\u00e1lez-Capitel Mart\u00ednez \u00b7 Doctor arquitecto \u00b7 catedr\u00e1tico en ETSAM<br \/>\nMadrid \u00b7 febrero 2014<\/p>\n<p><a href=\"https:\/\/vimeo.com\/user25871083\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #999999;\">M\u00e1s v\u00eddeos en memorialmanueldelascasas<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Manuel de las Casas G\u00f3mez, un magn\u00edfico arquitecto y un gran profesor. Referente de la arquitectura espa\u00f1ola de la democracia Manuel de las Casas G\u00f3mez hab\u00eda nacido en Talavera de la Reina (1940) y falleci\u00f3 en Madrid (2014). Hijo de un ilustre Aparejador y Abogado, Manuel estudi\u00f3 Arquitectura en la Escuela de Madrid y se [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":81578,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,5951],"tags":[93,8626,5835,9446,147,8915,8094,542,1595,668,814,1690,12468,12454,1362,1363],"class_list":["post-81575","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faro","category-slider-principal","tag-alejandro-de-la-sota","tag-antonio-fernandez-alba","tag-antonio-gonzalez-capitel-martinez","tag-arquitectura-madrilena","tag-arquitectura-moderna","tag-dionisio-hernandez-gil","tag-escuela-de-arquitectura","tag-etsam","tag-francisco-javier-saenz-de-oiza","tag-historia","tag-madrid","tag-manuel-de-las-casas","tag-urbanismo","tag-vivienda-colectiva","tag-vivienda-publica","tag-vivienda-social"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-01T22:01:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"569\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ant\u00f3n Capitel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ant\u00f3n Capitel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/\"},\"author\":{\"name\":\"Ant\u00f3n Capitel\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/120779a73aacf8ac8b5596fd062a6d7b\"},\"headline\":\"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel\",\"datePublished\":\"2021-04-01T22:01:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/\"},\"wordCount\":761,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg\",\"keywords\":[\"Alejandro de la Sota\",\"Antonio Fern\u00e1ndez Alba\",\"Antonio Gonz\u00e1lez-Capitel Mart\u00ednez\",\"arquitectura madrile\u00f1a\",\"arquitectura moderna\",\"Dionisio Hern\u00e1ndez Gil\",\"escuela de arquitectura\",\"ETSAM\",\"Francisco Javier S\u00e1enz de Oiza\",\"historia\",\"Madrid\",\"Manuel de las Casas\",\"urbanismo\",\"vivienda colectiva\",\"vivienda p\u00fablica\",\"vivienda social\"],\"articleSection\":[\"faro\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/\",\"name\":\"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg\",\"datePublished\":\"2021-04-01T22:01:46+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg\",\"width\":1200,\"height\":569,\"caption\":\"Manuel de las Casas G\u00f3mez | Fuente: eldigitalcastillalamancha.es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/120779a73aacf8ac8b5596fd062a6d7b\",\"name\":\"Ant\u00f3n Capitel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/ant\u00f3n-capitel-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/ant\u00f3n-capitel-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/ant\u00f3n-capitel-96x96.jpg\",\"caption\":\"Ant\u00f3n Capitel\"},\"description\":\"Es arquitecto y catedr\u00e1tico de Proyectos de la Escuela de Arquitectura de Madrid, fue director de la revista Arquitectura (COAM) de 1981 a 1986 y de 2001 a 2009. Historiador, ensayista y cr\u00edtico, ha publicado numerosos art\u00edculos en revistas espa\u00f1olas y extranjeras sobre arquitectura espa\u00f1ola e internacional. Entre sus libros destacan diferentes monograf\u00edas sobre arquitectos.\",\"sameAs\":[\"http:\\\/\\\/acapitel.blogspot.com.es\\\/\",\"https:\\\/\\\/www.instagram.com\\\/explore\\\/tags\\\/antoncapitel\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/anton-capitel\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes","description":"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/","og_locale":"es_ES","og_type":"article","og_title":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes","og_description":"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel","og_url":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2021-04-01T22:01:46+00:00","og_image":[{"width":1200,"height":569,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg","type":"image\/jpeg"}],"author":"Ant\u00f3n Capitel","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Ant\u00f3n Capitel","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/"},"author":{"name":"Ant\u00f3n Capitel","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/120779a73aacf8ac8b5596fd062a6d7b"},"headline":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel","datePublished":"2021-04-01T22:01:46+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/"},"wordCount":761,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg","keywords":["Alejandro de la Sota","Antonio Fern\u00e1ndez Alba","Antonio Gonz\u00e1lez-Capitel Mart\u00ednez","arquitectura madrile\u00f1a","arquitectura moderna","Dionisio Hern\u00e1ndez Gil","escuela de arquitectura","ETSAM","Francisco Javier S\u00e1enz de Oiza","historia","Madrid","Manuel de las Casas","urbanismo","vivienda colectiva","vivienda p\u00fablica","vivienda social"],"articleSection":["faro","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/","url":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/","name":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg","datePublished":"2021-04-01T22:01:46+00:00","description":"Toda la informaci\u00f3n sobre: En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2020\/10\/En-recuerdo-de\u2026-Manuel-de-las-Casas-Ant\u00f3n-Capitel.jpg","width":1200,"height":569,"caption":"Manuel de las Casas G\u00f3mez | Fuente: eldigitalcastillalamancha.es"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/en-recuerdo-de-manuel-de-las-casas-gomez-anton-capitel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"En recuerdo de\u2026 Manuel de las Casas | Ant\u00f3n Capitel"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/120779a73aacf8ac8b5596fd062a6d7b","name":"Ant\u00f3n Capitel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/ant\u00f3n-capitel-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/ant\u00f3n-capitel-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/ant\u00f3n-capitel-96x96.jpg","caption":"Ant\u00f3n Capitel"},"description":"Es arquitecto y catedr\u00e1tico de Proyectos de la Escuela de Arquitectura de Madrid, fue director de la revista Arquitectura (COAM) de 1981 a 1986 y de 2001 a 2009. Historiador, ensayista y cr\u00edtico, ha publicado numerosos art\u00edculos en revistas espa\u00f1olas y extranjeras sobre arquitectura espa\u00f1ola e internacional. Entre sus libros destacan diferentes monograf\u00edas sobre arquitectos.","sameAs":["http:\/\/acapitel.blogspot.com.es\/","https:\/\/www.instagram.com\/explore\/tags\/antoncapitel\/"],"url":"https:\/\/veredes.es\/blog\/author\/anton-capitel\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/81575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=81575"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/81575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/81578"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=81575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=81575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=81575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}