{"id":7909,"date":"2010-12-28T09:00:27","date_gmt":"2010-12-28T09:00:27","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=7909"},"modified":"2020-11-25T15:39:29","modified_gmt":"2020-11-25T14:39:29","slug":"menos35","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/menos35\/","title":{"rendered":"Menos35"},"content":{"rendered":"<p>[:es]<\/p>\n<p style=\"text-align: justify;\">Una nueva generaci\u00f3n de Artistas y profesionales del dise\u00f1o componen este equipo multidisciplinar de <strong>Creadores<\/strong>. Aunando la especialidad de cada componente \u00a0hemos conseguido desarrollar un proyecto vanguardista en el que fabricamos, a trav\u00e9s del <strong>Arte<\/strong>, cualquier acto de dise\u00f1o. Pintura , escultura, arquitectura, dise\u00f1o gr\u00e1fico, dise\u00f1o de interiores, textil\u2026.\u00a0son entre otras, las herramientas de creaci\u00f3n que empleamos para realizar trabajos como el dise\u00f1o de logos, dise\u00f1o de espacios alternativos, stands, carteler\u00eda promocional, ropa, complementos , eventos culturales de integraci\u00f3n\/desarrollo, y todo aquello que tenga el Arte y la Cultura como palanca que catapulta personas y empresas hacia el \u00e9xito comercial y la realizaci\u00f3n personal. Un trabajo basado en el Desarrollo Sostenible soporta los cimientos de esta Estructura Social en la que Innovaci\u00f3n, Desarrollo e Investigaci\u00f3n forman parte de nuestro credo diario.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7910\" title=\"165658_111804415559243_111502772256074_91518_2073287_n\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\" alt=\"\" width=\"248\" height=\"720\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg 248w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n-103x300.jpg 103w\" sizes=\"auto, (max-width: 248px) 100vw, 248px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ahora, preg\u00fantanos como!!!<\/p>\n<p>[:gl]<\/p>\n<p><p style=\"text-align: justify;\">Unha nova xeraci\u00f3n de Artistas e profesionais do dese\u00f1o compo\u00f1en este equipo multidisciplinar de Creadores. Axuntando a especialidade de cada compo\u00f1ente\u00a0 conseguimos desenvolver un proxecto vangardista no que fabricamos, a trav\u00e9s da arte, calquera acto de dese\u00f1o. Pintura , escultura, arquitectura, dese\u00f1o gr\u00e1fico, dese\u00f1o de interiores, t\u00e9xtil\u2026. son entre outras, as ferramentas de creaci\u00f3n que empregamos para realizar traballos como o dese\u00f1o de logos, dese\u00f1o de espazos alternativos, casetas, cartelar\u00eda promocional, roupa, complementos , eventos culturais de integraci\u00f3n\/desenvolvo, e todo aquilo que te\u00f1a a arte e a Cultura como panca que catapulta persoas e empresas cara ao \u00e9xito comercial e a realizaci\u00f3n persoal. Un traballo baseado no Desenvolvemento Sustentable soporta os cimentos desta Estrutura Social na que Innovaci\u00f3n, Desenvolvemento e Investigaci\u00f3n forman parte do noso credo diario.<\/p>\n<p><a href=\"..\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"165658_111804415559243_111502772256074_91518_2073287_n\" src=\"..\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\" alt=\"\" width=\"248\" height=\"720\" \/><\/a><\/p>\n<p><strong>Agora, preg\u00fantanos como!!!<\/strong><\/p>\n<p>[:en]<\/p>\n<p><p style=\"text-align: justify;\">A new generation of Artists and professionals of the design compose this multidisciplinary team of Creators. Aunando The speciality of each component\u00a0 have achieved to develop a project vanguardista in which we manufacture, through the Art, any act of design. Painting , sculpture, architecture, graphic design, design of interiors, textile\u2026. They are between others, the tools of creation that employ to realise works like the design of logos, design of alternative spaces, stands, carteler\u00eda promotional, clothes, complementos , cultural events of integration\/develop, and all that that have the Art and the Culture like crowbar that catapults people and companies to the commercial success and the personal realisation. A work based in the Sustainable Development bears the cimientos of this Social Structure in which Innovation, Development and Investigation form part of our daily creed.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" title=\"165658_111804415559243_111502772256074_91518_2073287_n\" src=\"..\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\" alt=\"\" width=\"248\" height=\"720\" \/><strong><\/strong><\/p>\n<p><strong>Now, ask us as!!!<\/strong><\/p>\n<p>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:es] Una nueva generaci\u00f3n de Artistas y profesionales del dise\u00f1o componen este equipo multidisciplinar de Creadores. Aunando la especialidad de cada componente \u00a0hemos conseguido desarrollar un proyecto vanguardista en el que fabricamos, a trav\u00e9s del Arte, cualquier acto de dise\u00f1o. Pintura , escultura, arquitectura, dise\u00f1o gr\u00e1fico, dise\u00f1o de interiores, textil\u2026.\u00a0son entre otras, las herramientas de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7910,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,1382],"tags":[12470],"class_list":["post-7909","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos","category-exposiciones","tag-diseno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Menos35 - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Menos35\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/menos35\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Menos35 - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Menos35\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/menos35\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-28T09:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T14:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"248\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Menos35\",\"datePublished\":\"2010-12-28T09:00:27+00:00\",\"dateModified\":\"2020-11-25T14:39:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/\"},\"wordCount\":440,\"commentCount\":30,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\",\"keywords\":[\"dise\u00f1o\"],\"articleSection\":[\"eventos\",\"exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/\",\"name\":\"Menos35 - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\",\"datePublished\":\"2010-12-28T09:00:27+00:00\",\"dateModified\":\"2020-11-25T14:39:29+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Menos35\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/165658_111804415559243_111502772256074_91518_2073287_n.jpg\",\"width\":\"248\",\"height\":\"720\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/menos35\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Menos35\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Menos35 - veredes","description":"Toda la informaci\u00f3n sobre: Menos35","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/menos35\/","og_locale":"es_ES","og_type":"article","og_title":"Menos35 - veredes","og_description":"Toda la informaci\u00f3n sobre: Menos35","og_url":"https:\/\/veredes.es\/blog\/menos35\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2010-12-28T09:00:27+00:00","article_modified_time":"2020-11-25T14:39:29+00:00","og_image":[{"width":248,"height":720,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/menos35\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/menos35\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Menos35","datePublished":"2010-12-28T09:00:27+00:00","dateModified":"2020-11-25T14:39:29+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/menos35\/"},"wordCount":440,"commentCount":30,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/menos35\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg","keywords":["dise\u00f1o"],"articleSection":["eventos","exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/menos35\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/menos35\/","url":"https:\/\/veredes.es\/blog\/menos35\/","name":"Menos35 - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/menos35\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/menos35\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg","datePublished":"2010-12-28T09:00:27+00:00","dateModified":"2020-11-25T14:39:29+00:00","description":"Toda la informaci\u00f3n sobre: Menos35","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/menos35\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/menos35\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/menos35\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/165658_111804415559243_111502772256074_91518_2073287_n.jpg","width":"248","height":"720"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/menos35\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Menos35"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/7909","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=7909"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/7909\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/7910"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=7909"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=7909"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=7909"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}