{"id":7626,"date":"2010-12-20T10:50:54","date_gmt":"2010-12-20T10:50:54","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=7626"},"modified":"2020-06-03T12:02:35","modified_gmt":"2020-06-03T10:02:35","slug":"habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/","title":{"rendered":"Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/oa.upm.es\/1745\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n proyectual en los a\u00f1os del Tercer Reich<\/strong><\/a>. Tesis de Rafael Guridi Garc\u00eda. Emilio Tu\u00f1on. La presencia e importancia del contexto ha venido constituyendo un debate constante en la historiograf\u00eda arquitect\u00f3nica contempor\u00e1nea.<\/p>\n<p style=\"text-align: justify;\">Relegado a una limitada serie de datos precisos de partida por la modernidad m\u00e1s ortodoxa \u2014que prefer\u00eda operar sobre c\u00f3digos abstractos, derivados de principios universales racionales\u2014 su campo de actuaci\u00f3n ha venido siendo ampliado en sucesivas revisiones a lo largo del siglo anterior hasta abarcar lugares tan difusos como el territorio, la historia o la memoria del lugar.<\/p>\n<p style=\"text-align: justify;\">Mas all\u00e1 de la respuesta inmediata a un problema o programa espec\u00edfico, se impone el cuestionamiento y replanteamiento previo de este mismo problema bajo la mirada del Zeitgeist, el esp\u00edritu de la \u00e9poca.<\/p>\n<p style=\"text-align: justify;\">Pero, si la arquitectura esta vinculada a la expresi\u00f3n de la \u00e9poca y circunstancias que la producen \u00bfqu\u00e9 decir cuando esas mismas circunstancias conducen, hasta la imposici\u00f3n violenta, una determinada concepci\u00f3n, anclada en las peores pseudoteor\u00edas \u00e9tnicas y en la rancia mitificaci\u00f3n de un pasado ilusorio, en lo que se considera uno de los cap\u00edtulos mas oscuros de la reciente historia europea.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7627\" title=\"tumblr_ktp8nmA8O11qa4tai_01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg\" alt=\"\" width=\"620\" height=\"850\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n proyectual en los a\u00f1os del Tercer Reich. Tesis de Rafael Guridi Garc\u00eda. Emilio Tu\u00f1on. La presencia e importancia del contexto ha venido constituyendo un debate constante en la historiograf\u00eda arquitect\u00f3nica contempor\u00e1nea. Relegado a una limitada serie de datos precisos de partida por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7627,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[6553,3188,7127,668,737,9590,3091,3452,10329,1716,1287],"class_list":{"0":"post-7626","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-libros","8":"category-publicaciones","9":"tag-arquitectura-alemana","10":"tag-emilio-tunon","11":"tag-hans-scharoun","12":"tag-historia","13":"tag-investigacion","14":"tag-investigador","15":"tag-investigar","16":"tag-personaje","17":"tag-rafael-guridi-garcia","18":"tag-referencias","19":"tag-tesis"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2010-12-20T10:50:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-03T10:02:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"182\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n\",\"datePublished\":\"2010-12-20T10:50:54+00:00\",\"dateModified\":\"2020-06-03T10:02:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/\"},\"wordCount\":671,\"commentCount\":42,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/tumblr_ktp8nmA8O11qa4tai_01.jpg\",\"keywords\":[\"arquitectura alemana\",\"Emilio Tu\u00f1\u00f3n\",\"Hans Scharoun\",\"historia\",\"investigaci\u00f3n\",\"investigador\",\"investigar\",\"personaje\",\"Rafael Guridi Garc\u00eda\",\"referencias\",\"tesis\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/\",\"name\":\"[:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/tumblr_ktp8nmA8O11qa4tai_01.jpg\",\"datePublished\":\"2010-12-20T10:50:54+00:00\",\"dateModified\":\"2020-06-03T10:02:35+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/tumblr_ktp8nmA8O11qa4tai_01.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/12\\\/tumblr_ktp8nmA8O11qa4tai_01.jpg\",\"width\":\"182\",\"height\":\"250\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]","og_url":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2010-12-20T10:50:54+00:00","article_modified_time":"2020-06-03T10:02:35+00:00","og_image":[{"width":182,"height":250,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n","datePublished":"2010-12-20T10:50:54+00:00","dateModified":"2020-06-03T10:02:35+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/"},"wordCount":671,"commentCount":42,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg","keywords":["arquitectura alemana","Emilio Tu\u00f1\u00f3n","Hans Scharoun","historia","investigaci\u00f3n","investigador","investigar","personaje","Rafael Guridi Garc\u00eda","referencias","tesis"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/","url":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/","name":"[:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg","datePublished":"2010-12-20T10:50:54+00:00","dateModified":"2020-06-03T10:02:35+00:00","description":"Toda la informaci\u00f3n sobre: [:es]Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:gl]Habitar a noite: Hans Scharoun e a casa unifamiliar como veh\u00edculo de exploraci\u00f3n[:en]Inhabit the night: Hans Scharoun and the house unifamiliar like vehicle of exploration[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/12\/tumblr_ktp8nmA8O11qa4tai_01.jpg","width":"182","height":"250"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/habitar-la-noche-hans-scharoun-y-la-casa-unifamiliar-como-vehiculo-de-exploracion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Habitar la noche: Hans Scharoun y la casa unifamiliar como veh\u00edculo de exploraci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/7626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=7626"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/7626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/7627"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=7626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=7626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=7626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}