{"id":74459,"date":"2019-09-26T00:01:01","date_gmt":"2019-09-25T22:01:01","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=74459"},"modified":"2024-02-06T17:23:36","modified_gmt":"2024-02-06T16:23:36","slug":"para-durar-albert-faus-toni-cumella","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/","title":{"rendered":"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:]"},"content":{"rendered":"<p>[:es]<figure id=\"attachment_74461\" aria-describedby=\"caption-attachment-74461\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74461 size-full\" title=\"Para Durar\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg\" alt=\"Para-Durar\" width=\"1200\" height=\"742\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg 1200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-300x186.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-1024x633.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-74461\" class=\"wp-caption-text\">Para Durar<\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\">El <a href=\"http:\/\/www.museugranollers.org\/\" target=\"_blank\" rel=\"noopener\">Museo de Granollers<\/a> acoger\u00e1 la exposici\u00f3n\u00a0<strong>PARA DURAR<\/strong>, es la recopilaci\u00f3n del trabajo que durante las tres primeras semanas de marzo de 2018, m\u00e1s de un centenar de mujeres han participado en las tareas de restauraci\u00f3n de los enlucidos tradicionales en la concesi\u00f3n Allou-Sana, en el poblado de Tangassogo (Ti\u00e9b\u00e9l\u00e9), situado al sur de Burkina Faso. Con la ayuda de enseres cotidianos como una escombilla, una azada, o diferentes tipos de piedras, y utilizando tierras y pigmentos naturales, esta t\u00e9cnica documentada desde el siglo XVI, es un testigo excepcional de la cultura Kass\u00e9na, de valor universal, reconocido en la Lista Indicativa de Patrimonio de la UNESCO.<\/p>\n<p style=\"text-align: justify;\">El trabajo que llevan a cabo peri\u00f3dicamente las manos expertas de las mujeres Kass\u00e9na y su \u201csavoir-faire\u201d tradicional,\u00a0 convierte una necesidad que la modernidad descuida como es el mantenimiento de nuestras edificaciones, en una muestra de arte colectivo, hecho en comunidad y solidaridad entre familias vecinas.<\/p>\n<figure id=\"attachment_74462\" aria-describedby=\"caption-attachment-74462\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-74462 size-full\" title=\"Para Durar\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1.jpg\" alt=\"Para Durar o1\" width=\"1200\" height=\"925\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1.jpg 1200w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-300x231.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-1024x789.jpg 1024w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-74462\" class=\"wp-caption-text\">Para Durar<\/figcaption><\/figure>\n<blockquote>\n<p style=\"text-align: justify;\">La arquitectura se encuentra presente en todos los h\u00e1bitats en los que las personas desarrollamos nuestra actividad. Es por ello que, como arquitectos, tenemos la responsabilidad de proyectar espacios confortables, seguros e inclusivos, con capacidad de emocionar y que, al mismo tiempo, ayuden a hacer sociedades m\u00e1s justas.<\/p>\n<p style=\"text-align: justify;\">Con la voluntad de desarrollar los Objetivos de Desarrollo Sostenible (ODS), y desde hace a\u00f1os, el COAC tiene el compromiso de aportar el 0,7% del presupuesto de sus \u00f3rganos centrales para el apoyo de proyectos de desarrollo, en Catalu\u00f1a y pa\u00edses en v\u00edas de desarrollo, que sean impulsados por arquitectos conjuntamente con organizaciones sin \u00e1nimo de lucro. El \u00e1mbito de actuaci\u00f3n del Grupo de Trabajo de Cooperaci\u00f3n del COAC se centra en mejorar las condiciones del h\u00e1bitat. Esto puede ser tanto en el dise\u00f1o espacial y ordenaci\u00f3n del territorio, como en la cobertura de necesidades sociales b\u00e1sicas, la construcci\u00f3n de edificios de apoyo colectivo o la recuperaci\u00f3n y conservaci\u00f3n de la memoria hist\u00f3rica arquitect\u00f3nica, siempre con la mirada puesta en la reducci\u00f3n de las desigualdades sociales.<\/p>\n<p style=\"text-align: justify;\">El proyecto en Burkina Faso que muestra esta exposici\u00f3n forma parte de los proyectos realizados con el apoyo del COAC. Llevado a cabo en el poblado de Tangassogo, este proyecto de restauraci\u00f3n y protecci\u00f3n patrimonial ha contado con la participaci\u00f3n colectiva de las mujeres para mantener los enlucidos de sus casas de barro, dando a conocer no s\u00f3lo las tradiciones de una etnia, sino el trabajo conjunto entre familias y comunidades vecinas como un acto l\u00fadico de encuentro. Este proyecto refleja como el cuidado de la casa representa, al mismo tiempo, una oportunidad para reforzar los v\u00ednculos del trabajo en equipo, como esencia de las tradiciones.<\/p>\n<p style=\"text-align: justify;\">Tangassogo es un ejemplo de la importancia de la rehabilitaci\u00f3n integrada en lo m\u00e1s profundo de la cultura de un pueblo. Este trabajo comunitario de Burkina Faso nos devuelve la mirada a aquellas tareas que se hac\u00edan a las poblaciones cohesionadas de nuestro territorio, como pintar la casa, rehacer el tejado, reparar las fuentes de agua, reconstruir muros de piedra y muchos m\u00e1s trabajos de la vida cotidiana vinculados al h\u00e1bitat. La socializaci\u00f3n de los trabajos ayuda a aprender a trabajar juntos, encontrando cada uno su rol en la comunidad.<\/p>\n<p style=\"text-align: justify;\">Como sociedad, debemos profundizar en la cultura de la rehabilitaci\u00f3n, como compromiso personal para con el h\u00e1bitat com\u00fan, adapt\u00e1ndonos a los retos que tiene la rehabilitaci\u00f3n en nuestro contexto, como reducir los consumos de los edificios y afrontar el emergencia clim\u00e1tica.<\/p>\n<p style=\"text-align: justify;\">PARA DURAR nos explica y documenta este esp\u00edritu comunitario de apoyo mutuo, entendiendo colectivamente que es trabajando entre todos y conjuntamente que podremos socialmente \u00abperdurar\u00bb en el tiempo. A trav\u00e9s de las fant\u00e1sticas im\u00e1genes, se pone en valor que el mantenimiento de la casa (hogar) es una actividad colectiva, y que las mujeres tienen un papel primordial para que la casa -f\u00edsica y ambiental-, pueda perdurar a lo largo de generaciones.<\/p>\n<p>Miquel Sitj\u00e0\u00a0y Sandra Bestraten<br \/>\nCooperaci\u00f3n COAC<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Es un proyecto impulsado por el arquitecto Albert Faus y el ceramista Toni Cumella, con el apoyo del Colegio de Arquitectos de Catalu\u00f1a y el Museo de Granollers.<\/p>\n<p style=\"text-align: justify;\">Comisariado de la exposici\u00f3n: Carlos Quint\u00e1ns<br \/>\nTextos: Toni Cumella, Albert Faus, Carlos Quint\u00e1ns y Miquel Sitj\u00e0<br \/>\nV\u00eddeo: Agust\u00ed Corominas<br \/>\nAcuarelas: Jordi Castells<br \/>\nIm\u00e1genes: Toni Cumella, Anna Mas y Niek Kramer<br \/>\nMaqueta cer\u00e1mica: Carme Balada<\/p>\n<p style=\"text-align: justify;\">El proyecto tambi\u00e9n ha contado con la colaboraci\u00f3n de: Miquel Comadran, Carme Comellas, Concepci\u00f3 Escobet, Aziz Houssale\u00a0y Giovanni Quattrocolo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.arquitectes.cat\/es\/cultura\/exposici%C3%B3n-para-durar\" target=\"_blank\" rel=\"noopener\"><strong>Para Durar<\/strong><\/a><br \/>\nSitio: Museo de Granollers (C\/. d\u2019Anselm Clav\u00e9, 40-42)<br \/>\nDemarcaci\u00f3n: COAC<br \/>\nFecha inicio: Martes, 27 Agosto, 2019<br \/>\nFecha fin: Domingo, 17 Noviembre, 2019<br \/>\nHorario: Hasta el 31 de octubre: de martes a domingo, de 18 a 21h; domingo ma\u00f1ana de 11 a 14h De noviembre a marzo: de martes a domingo 17.30 a 20.30h; domingo ma\u00f1ana de 11 a 14h (cerrado en periodo de la exposici\u00f3n: todos los lunes y el 11 de septiembre)<\/p>\n<p>[:gl]<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-74461\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-1024x633.jpg\" alt=\"Para-Durar\" width=\"640\" height=\"396\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-1024x633.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-300x186.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">El <a href=\"http:\/\/www.museugranollers.org\/\" target=\"_blank\" rel=\"noopener\">Museo de Granollers<\/a> acoger\u00e1 la exposici\u00f3n\u00a0<strong>PARA DURAR<\/strong>, es la recopilaci\u00f3n del trabajo que durante las tres primeras semanas de marzo de 2018, m\u00e1s de un centenar de mujeres han participado en las tareas de restauraci\u00f3n de los enlucidos tradicionales en la concesi\u00f3n Allou-Sana, en el poblado de Tangassogo (Ti\u00e9b\u00e9l\u00e9), situado al sur de Burkina Faso. Con la ayuda de enseres cotidianos como una escombilla, una azada, o diferentes tipos de piedras, y utilizando tierras y pigmentos naturales, esta t\u00e9cnica documentada desde el siglo XVI, es un testigo excepcional de la cultura Kass\u00e9na, de valor universal, reconocido en la Lista Indicativa de Patrimonio de la UNESCO.<\/p>\n<p style=\"text-align: justify;\">El trabajo que llevan a cabo peri\u00f3dicamente las manos expertas de las mujeres Kass\u00e9na y su \u201csavoir-faire\u201d tradicional,\u00a0 convierte una necesidad que la modernidad descuida como es el mantenimiento de nuestras edificaciones, en una muestra de arte colectivo, hecho en comunidad y solidaridad entre familias vecinas.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-74462\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-1024x789.jpg\" alt=\"Para Durar o1\" width=\"640\" height=\"493\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-1024x789.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-300x231.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: justify;\">La arquitectura se encuentra presente en todos los h\u00e1bitats en los que las personas desarrollamos nuestra actividad. Es por ello que, como arquitectos, tenemos la responsabilidad de proyectar espacios confortables, seguros e inclusivos, con capacidad de emocionar y que, al mismo tiempo, ayuden a hacer sociedades m\u00e1s justas.<\/p>\n<p style=\"text-align: justify;\">Con la voluntad de desarrollar los Objetivos de Desarrollo Sostenible (ODS), y desde hace a\u00f1os, el COAC tiene el compromiso de aportar el 0,7% del presupuesto de sus \u00f3rganos centrales para el apoyo de proyectos de desarrollo, en Catalu\u00f1a y pa\u00edses en v\u00edas de desarrollo, que sean impulsados por arquitectos conjuntamente con organizaciones sin \u00e1nimo de lucro. El \u00e1mbito de actuaci\u00f3n del Grupo de Trabajo de Cooperaci\u00f3n del COAC se centra en mejorar las condiciones del h\u00e1bitat. Esto puede ser tanto en el dise\u00f1o espacial y ordenaci\u00f3n del territorio, como en la cobertura de necesidades sociales b\u00e1sicas, la construcci\u00f3n de edificios de apoyo colectivo o la recuperaci\u00f3n y conservaci\u00f3n de la memoria hist\u00f3rica arquitect\u00f3nica, siempre con la mirada puesta en la reducci\u00f3n de las desigualdades sociales.<\/p>\n<p style=\"text-align: justify;\">El proyecto en Burkina Faso que muestra esta exposici\u00f3n forma parte de los proyectos realizados con el apoyo del COAC. Llevado a cabo en el poblado de Tangassogo, este proyecto de restauraci\u00f3n y protecci\u00f3n patrimonial ha contado con la participaci\u00f3n colectiva de las mujeres para mantener los enlucidos de sus casas de barro, dando a conocer no s\u00f3lo las tradiciones de una etnia, sino el trabajo conjunto entre familias y comunidades vecinas como un acto l\u00fadico de encuentro. Este proyecto refleja como el cuidado de la casa representa, al mismo tiempo, una oportunidad para reforzar los v\u00ednculos del trabajo en equipo, como esencia de las tradiciones.<\/p>\n<p style=\"text-align: justify;\">Tangassogo es un ejemplo de la importancia de la rehabilitaci\u00f3n integrada en lo m\u00e1s profundo de la cultura de un pueblo. Este trabajo comunitario de Burkina Faso nos devuelve la mirada a aquellas tareas que se hac\u00edan a las poblaciones cohesionadas de nuestro territorio, como pintar la casa, rehacer el tejado, reparar las fuentes de agua, reconstruir muros de piedra y muchos m\u00e1s trabajos de la vida cotidiana vinculados al h\u00e1bitat. La socializaci\u00f3n de los trabajos ayuda a aprender a trabajar juntos, encontrando cada uno su rol en la comunidad.<\/p>\n<p style=\"text-align: justify;\">Como sociedad, debemos profundizar en la cultura de la rehabilitaci\u00f3n, como compromiso personal para con el h\u00e1bitat com\u00fan, adapt\u00e1ndonos a los retos que tiene la rehabilitaci\u00f3n en nuestro contexto, como reducir los consumos de los edificios y afrontar el emergencia clim\u00e1tica.<\/p>\n<p style=\"text-align: justify;\">PARA DURAR nos explica y documenta este esp\u00edritu comunitario de apoyo mutuo, entendiendo colectivamente que es trabajando entre todos y conjuntamente que podremos socialmente \u00abperdurar\u00bb en el tiempo. A trav\u00e9s de las fant\u00e1sticas im\u00e1genes, se pone en valor que el mantenimiento de la casa (hogar) es una actividad colectiva, y que las mujeres tienen un papel primordial para que la casa -f\u00edsica y ambiental-, pueda perdurar a lo largo de generaciones.<\/p>\n<p>Miquel Sitj\u00e0\u00a0y Sandra Bestraten<br \/>\nCooperaci\u00f3n COAC<\/p><\/blockquote>\n<p style=\"text-align: justify;\">Es un proyecto impulsado por el arquitecto Albert Faus y el ceramista Toni Cumella, con el apoyo del Colegio de Arquitectos de Catalu\u00f1a y el Museo de Granollers.<\/p>\n<p style=\"text-align: justify;\">Comisariado da exposici\u00f3n: Carlos Quint\u00e1ns<br \/>\nTextos: Toni Cumella, Albert Faus, Carlos Quint\u00e1ns\u00a0e Miquel Sitj\u00e0<br \/>\nV\u00eddeo: Agust\u00ed Corominas<br \/>\nAcuarelas: Jordi Castells<br \/>\nIm\u00e1xenes: Toni Cumella, Anna Mas y Niek Kramer<br \/>\nMaqueta cer\u00e1mica: Carme Balada<\/p>\n<p style=\"text-align: justify;\">O proxecto tam\u00e9n contou coa colaboraci\u00f3n de: Miquel Comadran, Carme Comellas, Concepci\u00f3 Escobet, Aziz Houssale\u00a0e Giovanni Quattrocolo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.arquitectes.cat\/es\/cultura\/exposici%C3%B3n-para-durar\" target=\"_blank\" rel=\"noopener\"><strong>Para Durar<\/strong><\/a><br \/>\nSitio: Museo de Granollers (C\/ d\u2019Anselm Clav\u00e9, 40-42)<br \/>\nDemarcaci\u00f3n: COAC<br \/>\nData inicio: Martes, 27 Agosto, 2019<br \/>\nData fin: Domingo, 17 Novembre, 2019<br \/>\nHorario: Ata o 31 de outubro: de martes a domingo, de 18 a 21 h; domingo ma\u00f1\u00e1 de 11 a 14 h De novembro a marzo: de martes a domingo 17.30 a 20.30 h; domingo ma\u00f1\u00e1 de 11 a 14 h (pechado en per\u00edodo da exposici\u00f3n: todos os luns e o 11 de setembro)<\/p>\n<p>[:en]<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-74461\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-1024x633.jpg\" alt=\"Para-Durar\" width=\"640\" height=\"396\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-1024x633.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-300x186.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">The <a href=\"http:\/\/www.museugranollers.org\/\" target=\"_blank\" rel=\"noopener\">Granollers Museum<\/a> will host the exhibition\u00a0<strong>FOR LASTING<\/strong>, it is the compilation of the work that during the first three weeks of March 2018, more than a hundred women have participated in the restoration of traditional plasters in the Allou-Sana concession, in the town of Tangassogo (Ti\u00e9b\u00e9l\u00e9), located south of Burkina Faso. With the help of everyday belongings such as a debris, a hoe, or different types of stones, and using natural earth and pigments, this technique documented since the 16th century, is an exceptional witness of the Kass\u00e9na culture, of universal value, recognized in the UNESCO Heritage Indicative List.<\/p>\n<p style=\"text-align: justify;\">The work carried out periodically by the expert hands of the Kass\u00e9na women and their traditional \u201csavoir-faire\u201d, turns a need that modernity neglects as is the maintenance of our buildings, in a sample of collective art, done in community and solidarity between neighboring families.<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-74462\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-1024x789.jpg\" alt=\"Para Durar o1\" width=\"640\" height=\"493\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-1024x789.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1-300x231.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar-o1.jpg 1200w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<blockquote>\n<p style=\"text-align: justify;\">The architecture is present in all the habitats in which people develop our activity. That is why, as architects, we have the responsibility of projecting comfortable, safe and inclusive spaces, with the ability to thrill and, at the same time, help to make fairer societies.<\/p>\n<p style=\"text-align: justify;\">With the will to develop the Sustainable Development Goals (SDGs), and for years, COAC is committed to contribute 0.7% of the budget of its central bodies for the support of development projects, in Catalonia and countries in which development paths, which are driven by architects in conjunction with non-profit organizations. The scope of the COAC Cooperation Working Group focuses on improving habitat conditions. This can be both in the spatial design and spatial planning, as well as in the coverage of basic social needs, the construction of collective support buildings or the recovery and conservation of architectural historical memory, always with an eye towards reducing the social inequalities.<\/p>\n<p style=\"text-align: justify;\">The project in Burkina Faso that shows this exhibition is part of the projects carried out with the support of COAC. Carried out in the town of Tangassogo, this restoration and heritage protection project has had the collective participation of women to maintain the plastering of their mud houses, making known not only the traditions of an ethnic group, but also the joint work between families and neighboring communities as a playful meeting. This project reflects how the care of the house represents, at the same time, an opportunity to strengthen the ties of teamwork, as the essence of traditions.<\/p>\n<p style=\"text-align: justify;\">Tangassogo is an example of the importance of integrated rehabilitation in the depths of a people&#8217;s culture. This community work of Burkina Faso looks back at those tasks that were done to the cohesive populations of our territory, such as painting the house, remaking the roof, repairing water fountains, rebuilding stone walls and many more works of life daily linked to the habitat. The socialization of jobs helps to learn to work together, each finding their role in the community.<\/p>\n<p style=\"text-align: justify;\">As a society, we must deepen the culture of rehabilitation, as a personal commitment to the common habitat, adapting to the challenges of rehabilitation in our context, such as reducing the consumption of buildings and facing the climatic emergency.<\/p>\n<p style=\"text-align: justify;\">FOR\u00a0LASTING explains and documents this community spirit of mutual support, collectively understanding that it is working together and together that we can socially \u00abendure\u00bb in time. Through the fantastic images, it is put in value that the maintenance of the house (home) is a collective activity, and that women have a primary role so that the house -physical and environmental-, can last throughout generations .<\/p>\n<p>Miquel Sitj\u00e0\u00a0and Sandra Bestraten<br \/>\nCOAC cooperation<\/p><\/blockquote>\n<p style=\"text-align: justify;\">It is a project promoted by the architect Albert Faus and the ceramist Toni Cumella, with the support of the College of Architects of Catalonia and the Granollers Museum.<\/p>\n<p style=\"text-align: justify;\">Exhibition curator: Carlos Quint\u00e1ns<br \/>\nTexts: Toni Cumella, Albert Faus, Carlos Quint\u00e1ns and Miquel Sitj\u00e0<br \/>\nVideo: Agust\u00ed Corominas<br \/>\nWatercolors: Jordi Castells<br \/>\nImages: Toni Cumella, Anna Mas and Niek Kramer<br \/>\nCeramic model: Carme Balada<\/p>\n<p style=\"text-align: justify;\">The project has also had the collaboration of: Miquel Comadran, Carme Comellas, Concepci\u00f3 Escobet, Aziz Houssale and Giovanni Quattrocolo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.arquitectes.cat\/es\/cultura\/exposici%C3%B3n-para-durar\" target=\"_blank\" rel=\"noopener\"><strong>For lasting<\/strong><\/a><br \/>\nSite: Granollers Museum (C \/. D\u2019Anselm Clav\u00e9, 40-42)<br \/>\nDemarcation: COAC<br \/>\nStart date: Tuesday, August 27, 2019<br \/>\nEnd date: Sunday, November 17, 2019<br \/>\nHours: Until October 31: from Tuesday to Sunday, from 6 pm to 9 pm; Sunday morning from 11 a.m. to 2 p.m. From November to March: from Tuesday to Sunday from 5.30 p.m. to 8.30 p.m. Sunday morning from 11 a.m. to 2 p.m. (closed during the exhibition period: every Monday and September 11)<\/p>\n<p>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:es] El Museo de Granollers acoger\u00e1 la exposici\u00f3n\u00a0PARA DURAR, es la recopilaci\u00f3n del trabajo que durante las tres primeras semanas de marzo de 2018, m\u00e1s de un centenar de mujeres han participado en las tareas de restauraci\u00f3n de los enlucidos tradicionales en la concesi\u00f3n Allou-Sana, en el poblado de Tangassogo (Ti\u00e9b\u00e9l\u00e9), situado al sur de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":74461,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,1382],"tags":[85,14251,14243,14255,11626,150,1581,14252,14246,1518,14247,556,14249,14253,4669,856,14245,14250,2994,14254,14211,3311,14244,1298,1319],"class_list":["post-74459","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos","category-exposiciones","tag-africa","tag-agusti-corominas","tag-albert-faus","tag-anna-mas","tag-arquitectura-africana","tag-arquitectura-tradicional","tag-carlos-quintans-eiras","tag-carme-balada","tag-carme-comellas","tag-cataluna","tag-concepcio-escobet","tag-exposicion","tag-giovanni-quattrocolo","tag-jordi-castells","tag-la-mujer-construye","tag-metodo-tradicional","tag-miquel-comadran","tag-miquel-sitja","tag-mujer","tag-niek-kramer","tag-s-xvi","tag-tecnica-tradicional","tag-toni-cumella","tag-tradicion","tag-unesco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-25T22:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-06T16:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:]\",\"datePublished\":\"2019-09-25T22:01:01+00:00\",\"dateModified\":\"2024-02-06T16:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/\"},\"wordCount\":2479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Para-Durar.jpg\",\"keywords\":[\"\u00c1frica\",\"Agust\u00ed Corominas\",\"Albert Faus\",\"Anna Mas\",\"arquitectura africana\",\"arquitectura tradicional\",\"Carlos Quint\u00e1ns Eiras\",\"Carme Balada\",\"Carme Comellas\",\"Catalu\u00f1a\",\"Concepci\u00f3 Escobet\",\"exposici\u00f3n\",\"Giovanni Quattrocolo\",\"Jordi Castells\",\"la mujer construye\",\"m\u00e9todo tradicional\",\"Miquel Comadran\",\"Miquel Sitj\u00e0\",\"mujer\",\"Niek Kramer\",\"s. xvi\",\"t\u00e9cnica tradicional\",\"Toni Cumella\",\"tradici\u00f3n\",\"UNESCO\"],\"articleSection\":[\"eventos\",\"exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/\",\"name\":\"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Para-Durar.jpg\",\"datePublished\":\"2019-09-25T22:01:01+00:00\",\"dateModified\":\"2024-02-06T16:23:36+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Para-Durar.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Para-Durar.jpg\",\"width\":1200,\"height\":742},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/para-durar-albert-faus-toni-cumella\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Para Durar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]","og_url":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2019-09-25T22:01:01+00:00","article_modified_time":"2024-02-06T16:23:36+00:00","og_image":[{"width":1200,"height":742,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:]","datePublished":"2019-09-25T22:01:01+00:00","dateModified":"2024-02-06T16:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/"},"wordCount":2479,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg","keywords":["\u00c1frica","Agust\u00ed Corominas","Albert Faus","Anna Mas","arquitectura africana","arquitectura tradicional","Carlos Quint\u00e1ns Eiras","Carme Balada","Carme Comellas","Catalu\u00f1a","Concepci\u00f3 Escobet","exposici\u00f3n","Giovanni Quattrocolo","Jordi Castells","la mujer construye","m\u00e9todo tradicional","Miquel Comadran","Miquel Sitj\u00e0","mujer","Niek Kramer","s. xvi","t\u00e9cnica tradicional","Toni Cumella","tradici\u00f3n","UNESCO"],"articleSection":["eventos","exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/","url":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/","name":"[:es]Para Durar[:gl]Per Durar[:en]For lasting[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg","datePublished":"2019-09-25T22:01:01+00:00","dateModified":"2024-02-06T16:23:36+00:00","description":"Toda la informaci\u00f3n sobre: [:es]Para Durar[:gl]Per Durar[:en]For lasting[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2019\/09\/Para-Durar.jpg","width":1200,"height":742},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/para-durar-albert-faus-toni-cumella\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Para Durar"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/74459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=74459"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/74459\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/74461"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=74459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=74459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=74459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}