{"id":66159,"date":"2017-11-14T00:05:44","date_gmt":"2017-11-13T23:05:44","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=66159"},"modified":"2023-03-14T15:03:54","modified_gmt":"2023-03-14T14:03:54","slug":"torno-fernando-higueras-desde","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/","title":{"rendered":"En torno a Fernando Higueras. Desde&#8230;"},"content":{"rendered":"<p><figure style=\"width: 1956px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" title=\"En torno a Fernando Higueras por Antonio L\u00f3pez | Sobre Arquitectura y m\u00e1s | Desde 1998\" src=\"https:\/\/www.metalocus.es\/sites\/default\/files\/styles\/mopis_news_carousel_item_desktop\/public\/metalocus_fernando-higueras_por_antonio-lopez_02.jpg?itok=-A1xlF3M\" alt=\"En torno a Fernando Higueras por Antonio L\u00f3pez | Sobre Arquitectura y m\u00e1s | Desde 1998\" width=\"1956\" height=\"1100\" \/><figcaption class=\"wp-caption-text\"><span style=\"color: #999999;\">En torno a Fernando Higueras por Antonio L\u00f3pez | Sobre Arquitectura y m\u00e1s | Desde 1998<\/span><\/figcaption><\/figure><\/p>\n<h5><a href=\"https:\/\/veredes.es\/blog\/?s=Fernando+Higueras\" target=\"_blank\" rel=\"noopener\"><strong>En torno a Fernando Higueras. Desde&#8230;<\/strong><\/a><\/h5>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/veredes.es\/blog\/?s=Fernando+Higueras+D%C3%ADaz\" target=\"_blank\" rel=\"noopener\"><strong>Fernando Higueras D\u00edaz<\/strong><\/a>, nace en Madrid el 26 de\u00a0noviembre de 1930. Cursa estudios en el Instituto Escuela y de bachiller en el madrile\u00f1o Colegio Estudio.\u00a0Finaliza en 1959\u00a0la carrera de arquitectura en la Escuela T\u00e9cnica Superior de Arquitectura de Madrid.<\/p>\n<p style=\"text-align: justify;\">La <a href=\"http:\/\/fernandohigueras.org\/\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n<\/a> Fernando Higueras tiene car\u00e1cter cultural y tiene como objetivos:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">\u00abEl estudio, catalogaci\u00f3n, conservaci\u00f3n de la obra proyectada y construida del arquitecto Fernando Higueras, la colaboraci\u00f3n con las administraciones p\u00fablicas tanto estatal como\u00a0auton\u00f3micas\u00a0y locales, universidades, academias, museos, colegios profesionales, y otras fundaciones de car\u00e1cter cultural, tanto espa\u00f1olas como extranjeras, en proyectos y actividades acad\u00e9micas de investigaci\u00f3n, docentes y expositivas, encaminadas al estudio y divulgaci\u00f3n pedag\u00f3gica de la obra y proyectos de Fernando Higueras, y\u00a0su significado en relaci\u00f3n con la arquitectura contempor\u00e1nea internacional.\u00bb<\/p>\n<\/blockquote>\n<h5 style=\"text-align: justify;\"><strong>I\u00f1aki \u00c1balos. Desde la colaboraci\u00f3n<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS - I\u00d1AKI \u00c1BALOS\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/OUP1cXZEifc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>Manuel Oca\u00f1a. Desde el an\u00e1lisis<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS _ MANUEL OCA\u00d1A\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/6fw6tr23UE0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>Nuria Espert. Desde la emoci\u00f3n<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS - NURIA ESPERT\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/K2RePqgd_PU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>Miguel Oriol. Desde el principio<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS _ MIGUEL ORIOL\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/T7rc6xNQfTY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>Juan Herreros. Desde la distancia<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS - JUAN HERREROS\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/Lb5V24kAb9c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>Salvador P\u00e9rez Arroyo. Desde la fundaci\u00f3n<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS -SALVADOR P\u00c9REZ ARROYO\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/u1YhhWpOrqQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5><strong>\u00d3scar Tusquets Blanca. Desde el entusiasmo<\/strong>.<\/h5>\n<p><iframe loading=\"lazy\" title=\"EN TORNO A FERNANDO HIGUERAS -OSCAR TUSQUETS\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/K3MhEnGAsF4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe><\/p>\n<h5 style=\"text-align: justify;\"><strong>Fernando de Higueras D\u00edaz (Madrid, 26 de Noviembre de 1930 &#8211; Madrid, 30 de enero de 2008) <\/strong><\/h5>\n<p style=\"text-align: justify;\">Fue un arquitecto espa\u00f1ol que se titul\u00f3 como arquitecto en la Escuela T\u00e9cnica Superior de Arquitectura de Madrid en 1959, dentro de una promoci\u00f3n caracterizada por su distanciamiento del racionalismo y su aproximaci\u00f3n a las corrientes organicistas, que ten\u00edan como referencia la obra de Frank Lloyd Wright.<\/p>\n<p style=\"text-align: justify;\">Gran aficionado a la m\u00fasica, a la pintura y a la fotograf\u00eda, disciplinas art\u00edsticas en las que tambi\u00e9n ha sido premiada su val\u00eda, la originalidad y potencia creadora de Higueras representa, dentro del panorama arquitect\u00f3nico espa\u00f1ol, una de las m\u00e1s singulares conjunciones de rigor constructivo con la adaptaci\u00f3n al medio f\u00edsico y natural y del entendimiento de la arquitectura popular desde planteamientos contempor\u00e1neos. Con una arquitectura bella y funcional a la vez, sus obras buscan el \u00e9nfasis tanto en los rasgos expresivos como en la l\u00f3gica interna.<\/p>\n<p style=\"text-align: justify;\">Desde muy temprano, incluso en su \u00e9poca de estudiante, alcanz\u00f3 algunos \u00e9xitos en el campo de la arquitectura, como el primer premio para un Refugio de alta monta\u00f1a, otorgado en 1958 por la Escuela de Bellas Artes de San Jorge de Barcelona.<\/p>\n<p style=\"text-align: justify;\">Premio Nacional de Arquitectura en 1961 al Proyecto de centro de restauraciones art\u00edsticas, en colaboraci\u00f3n con Rafael Moneo, Higueras realiza una arquitectura contra corriente, con un estilo personal caracter\u00edstico que lo mantendr\u00e1 a lo largo de su producci\u00f3n profesional, bien trabajando en solitario, o en colaboraci\u00f3n con Antonio Mir\u00f3 Valverde, a partir del a\u00f1o 1962.<\/p>\n<p style=\"text-align: justify;\">Entre sus obras primeras destacan un acertado proyecto para artistas en el monte de El Pardo, de 1960, y la casa Lucio Mu\u00f1oz en Torrelodones, Madrid, de los a\u00f1os 1962-63, con un estudiado ajuste a la naturaleza como objetivo cumplido.<\/p>\n<p style=\"text-align: justify;\">El estilo de Higueras se le reconoce por el uso sistem\u00e1tico del hormig\u00f3n armado \u00abvisto\u00bb, mostrando su estructuralismo calc\u00e1reo de modo natural, con una expresividad a veces libre y asim\u00e9trica, y a veces m\u00e1s clasicista y sosegada. A este tipo pertenece el espectacular edificio de hormig\u00f3n visto, de planta circular y cubierta inclinada con pin\u00e1culos de cristal, creado para Centro de Restauraciones Art\u00edsticas de Madrid en 1968, realizado en colaboraci\u00f3n con Antonio Mir\u00f3.<\/p>\n<p style=\"text-align: justify;\">Sus espectaculares y sencillas soluciones estructurales, junto con sus b\u00f3vedas tabicadas han influido en arquitectos posteriores de manera significativa. La riqueza de la obra de Higueras representa al tiempo la continuidad arquitect\u00f3nica en Espa\u00f1a del constructivismo ruso, de la mejor tradici\u00f3n constructiva de Wright pudiendo ser considerado tambi\u00e9n como uno de los precursores del informalismo en la arquitectura.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>En torno a Fernando Higueras. Desde&#8230; Fernando Higueras D\u00edaz, nace en Madrid el 26 de\u00a0noviembre de 1930. Cursa estudios en el Instituto Escuela y de bachiller en el madrile\u00f1o Colegio Estudio.\u00a0Finaliza en 1959\u00a0la carrera de arquitectura en la Escuela T\u00e9cnica Superior de Arquitectura de Madrid. La Fundaci\u00f3n Fernando Higueras tiene car\u00e1cter cultural y tiene como [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4854],"tags":[143,2631,9446,147,434,5333,13185,668,3197,761,7377,7378,13228,13186,1680,1021,1865,8119,1278],"class_list":{"0":"post-66159","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-tv","9":"tag-arquitectura-espanola","10":"tag-arquitectura-madrilena","11":"tag-arquitectura-moderna","12":"tag-documental","13":"tag-fernando-higueras","14":"tag-fundacion-fernando-higueras","15":"tag-historia","16":"tag-inaki-abalos","17":"tag-juan-herreros","18":"tag-manuel-ocana","19":"tag-manuel-ocana-arquitectos","20":"tag-miguel-de-oriol-e-ybarra","21":"tag-nuria-espert","22":"tag-oscar-tusquets-blanca","23":"tag-pensamiento","24":"tag-reflexion","25":"tag-salvador-perez-arroyo","26":"tag-teoria"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En torno a Fernando Higueras. Desde... - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-13T23:05:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-14T14:03:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"En torno a Fernando Higueras. Desde&#8230;\",\"datePublished\":\"2017-11-13T23:05:44+00:00\",\"dateModified\":\"2023-03-14T14:03:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/\"},\"wordCount\":1220,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/En-torno-a-Fernando-Higueras.-Desde....jpg\",\"keywords\":[\"arquitectura contempor\u00e1nea\",\"arquitectura espa\u00f1ola\",\"arquitectura madrile\u00f1a\",\"arquitectura moderna\",\"documental\",\"Fernando Higueras\",\"fundaci\u00f3n Fernando Higueras\",\"historia\",\"I\u00f1aki \u00c1balos\",\"Juan Herreros\",\"Manuel Oca\u00f1a\",\"Manuel Oca\u00f1a Arquitectos\",\"Miguel de Oriol e Ybarra\",\"Nuria Espert\",\"\u00d3scar Tusquets Blanca\",\"pensamiento\",\"reflexi\u00f3n\",\"Salvador P\u00e9rez Arroyo\",\"teor\u00eda\"],\"articleSection\":[\"tv\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/\",\"name\":\"[:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/En-torno-a-Fernando-Higueras.-Desde....jpg\",\"datePublished\":\"2017-11-13T23:05:44+00:00\",\"dateModified\":\"2023-03-14T14:03:54+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/En-torno-a-Fernando-Higueras.-Desde....jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/En-torno-a-Fernando-Higueras.-Desde....jpg\",\"width\":1024,\"height\":920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/torno-fernando-higueras-desde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En torno a Fernando Higueras. Desde&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]","og_url":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2017-11-13T23:05:44+00:00","article_modified_time":"2023-03-14T14:03:54+00:00","og_image":[{"width":1024,"height":920,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"En torno a Fernando Higueras. Desde&#8230;","datePublished":"2017-11-13T23:05:44+00:00","dateModified":"2023-03-14T14:03:54+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/"},"wordCount":1220,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg","keywords":["arquitectura contempor\u00e1nea","arquitectura espa\u00f1ola","arquitectura madrile\u00f1a","arquitectura moderna","documental","Fernando Higueras","fundaci\u00f3n Fernando Higueras","historia","I\u00f1aki \u00c1balos","Juan Herreros","Manuel Oca\u00f1a","Manuel Oca\u00f1a Arquitectos","Miguel de Oriol e Ybarra","Nuria Espert","\u00d3scar Tusquets Blanca","pensamiento","reflexi\u00f3n","Salvador P\u00e9rez Arroyo","teor\u00eda"],"articleSection":["tv"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/","url":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/","name":"[:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg","datePublished":"2017-11-13T23:05:44+00:00","dateModified":"2023-03-14T14:03:54+00:00","description":"Toda la informaci\u00f3n sobre: [:es]En torno a Fernando Higueras. Desde...[:gl]Ao redor de Fernando Higueras. Desde...[:en]Concerning Fernando Higueras. From...[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2017\/10\/En-torno-a-Fernando-Higueras.-Desde....jpg","width":1024,"height":920},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/torno-fernando-higueras-desde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"En torno a Fernando Higueras. Desde&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/66159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=66159"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/66159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/66160"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=66159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=66159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=66159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}