{"id":62534,"date":"2017-03-09T00:25:27","date_gmt":"2017-03-08T23:25:27","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=62534"},"modified":"2017-12-12T18:48:01","modified_gmt":"2017-12-12T17:48:01","slug":"bartlebooth-la-produccion-cuatro-estrategias-menores-2","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/","title":{"rendered":"Bartlebooth. La producci\u00f3n: Cuatro estrategias menores"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-62535\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\" alt=\"bartlebooth-la-produccion-cuatro-estrategias-menores\" width=\"640\" height=\"427\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg 1000w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores-300x200.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Las cosas cocinadas a fuego lento siempre salen mejor. Por eso, despu\u00e9s de tanto tiempo invertido nos hace much\u00edsima ilusi\u00f3n presentar el quinto experimento de Bartlebooth, reci\u00e9n llegado de la imprenta. Un experimento que comenz\u00f3 a gestarse a principios de 2016 y que nos tuvo enfrascados en su producci\u00f3n y edici\u00f3n casi diez meses.<\/p>\n<p style=\"text-align: justify;\">La producci\u00f3n: cuatro estrategias menores, es un trabajo colectivo donde m\u00e1s de veinticinco personas se han convertido en art\u00edfices, c\u00f3mplices, hackers, chatarrerxs, y responsables del \u00e9xito (o fracaso) de esta nueva publicaci\u00f3n que hoy se pone a la venta.<\/p>\n<p style=\"text-align: justify;\">Este quinto experimento se estructura en torno a cuatro estrategias diferentes con una idea o denominador com\u00fan. Cuatro estrategias menores a trav\u00e9s de las cuales producir nuevo contenido bas\u00e1ndose en los fragmentos, ruinas y cascotes de lo anterior, que rechazan la tabula rasa y los objetos. Frente a ello proponen procesos y t\u00e1cticas precarias de resistencia. Este es el punto de partida del quinto experimento, que a trav\u00e9s de 288 p\u00e1ginas va cobrando forma a trav\u00e9s de 20 colaboraciones&#8230;textos hackeados, archivos manipulados, sesiones de m\u00fasica. As\u00ed, los 20 colaboradores se convirtieron en hackers y chatarreros, personajes destructivos, saboteadores que generaron un nuevo material manipulando y destrozando sin piedad las ruinas y fragmentos de contenidos preexistentes.<\/p>\n<p style=\"text-align: justify;\">En este n\u00famero han colaborado las siguientes personas:<\/p>\n<p style=\"text-align: justify;\"><strong>Chatarrear<\/strong> | Mengya Yang,\u00a0Sara Escudero,\u00a0Pedro Hern\u00e1ndez,\u00a0Manuel Send\u00f3n, \u00c1ngel Mart\u00ednez Garc\u00eda-Posada<br \/>\n<strong>Hackear<\/strong> | Uriel Fogu\u00e9,\u00a0N\u00faria G\u00fcell,\u00a0Davide Tommaso Ferrando, Roberto Equisoain,\u00a0Francisco G Trivi\u00f1o,\u00a0Joaqu\u00edn Garc\u00eda Vicente<br \/>\n<strong>Samplear<\/strong> | Miguel Mesa del Castillo\u00a0+ Juan Carlos Castro,\u00a0Tatiana Poggi, Luis D\u00edaz D\u00edaz\u00a0y Eduardo Navas.<br \/>\n<strong>No Hacer<\/strong> | Atxu Amann +\u00a0Rodrigo Delso Gutierrez,\u00a0Santiago Sierra, Yolanda P\u00e9rez S\u00e1nchez, Juan Creus, Virginia de Diego<\/p>\n<p style=\"text-align: justify;\"><i>Incluye l\u00e1mina de Sandwich Mixto para las primeras 50 personas que la adquieran.<\/i><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Las cosas cocinadas a fuego lento siempre salen mejor. Por eso, despu\u00e9s de tanto tiempo invertido nos hace much\u00edsima ilusi\u00f3n presentar el quinto experimento de Bartlebooth, reci\u00e9n llegado de la imprenta. Un experimento que comenz\u00f3 a gestarse a principios de 2016 y que nos tuvo enfrascados en su producci\u00f3n y edici\u00f3n casi diez meses. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":62535,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[6042,12278,12758,9643,9651,12751,12757,12753,11509,12755,3053,4505,4720,825,12747,12754,12750,9654,1021,1120,1890,1173,12752,12759,12760,12748,12756,12749,12762,12761],"class_list":{"0":"post-62534","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-libros","8":"category-publicaciones","9":"tag-angel-martinez-garcia-posada","10":"tag-antonio-giraldez-lopez","11":"tag-atxu-amann","12":"tag-bartlebooth-mag","13":"tag-begona-hermida","14":"tag-davide-tommaso-ferrando","15":"tag-eduardo-navas","16":"tag-francisco-g-trivino","17":"tag-joaquin-garcia-vicente","18":"tag-juan-carlos-castro","19":"tag-juan-creus-andrade","20":"tag-landa-hernandez","21":"tag-luis-diaz-diaz","22":"tag-manuel-sendon","23":"tag-mengya-yang","24":"tag-miguel-mesa-del-castillo","25":"tag-nuria-guell","26":"tag-pablo-ibanez-ferrera","27":"tag-pensamiento","28":"tag-publicacion","29":"tag-reflexion-multidisciplinar","30":"tag-revista","31":"tag-roberto-equisoain","32":"tag-rodrigo-delso-gutierrez","33":"tag-santiago-sierra","34":"tag-sara-escudero","35":"tag-tatiana-poggi","36":"tag-uriel-fogue","37":"tag-virginia-de-diego","38":"tag-yolanda-perez-sanchez"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bartlebooth. La producci\u00f3n: Cuatro estrategias menores - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-08T23:25:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-12-12T17:48:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"667\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Bartlebooth. La producci\u00f3n: Cuatro estrategias menores\",\"datePublished\":\"2017-03-08T23:25:27+00:00\",\"dateModified\":\"2017-12-12T17:48:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/\"},\"wordCount\":972,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\",\"keywords\":[\"\u00c1ngel Mart\u00ednez Garc\u00eda-Posada\",\"Antonio Gir\u00e1ldez L\u00f3pez\",\"Atxu Amann\",\"bartlebooth mag\",\"Bego\u00f1a Hermida\",\"Davide Tommaso Ferrando\",\"Eduardo Navas\",\"Francisco G. Trivi\u00f1o\",\"Joaqu\u00edn Garc\u00eda Vicente\",\"Juan Carlos Castro\",\"Juan Creus Andrade\",\"Landa Hern\u00e1ndez\",\"Luis D\u00edaz D\u00edaz\",\"Manuel Send\u00f3n\",\"Mengya Yang\",\"Miguel Mesa del Castillo\",\"N\u00faria G\u00fcell\",\"Pablo Ib\u00e1\u00f1ez Ferrera\",\"pensamiento\",\"publicaci\u00f3n\",\"reflexi\u00f3n multidisciplinar\",\"revista\",\"Roberto Equisoain\",\"Rodrigo Delso Gutierrez\",\"Santiago Sierra\",\"Sara Escudero\",\"Tatiana Poggi\",\"Uriel Fogu\u00e9\",\"Virginia de Diego\",\"Yolanda P\u00e9rez S\u00e1nchez\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/\",\"name\":\"[:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\",\"datePublished\":\"2017-03-08T23:25:27+00:00\",\"dateModified\":\"2017-12-12T17:48:01+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg\",\"width\":1000,\"height\":667},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bartlebooth. La producci\u00f3n: Cuatro estrategias menores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]","og_url":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2017-03-08T23:25:27+00:00","article_modified_time":"2017-12-12T17:48:01+00:00","og_image":[{"width":1000,"height":667,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Bartlebooth. La producci\u00f3n: Cuatro estrategias menores","datePublished":"2017-03-08T23:25:27+00:00","dateModified":"2017-12-12T17:48:01+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/"},"wordCount":972,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg","keywords":["\u00c1ngel Mart\u00ednez Garc\u00eda-Posada","Antonio Gir\u00e1ldez L\u00f3pez","Atxu Amann","bartlebooth mag","Bego\u00f1a Hermida","Davide Tommaso Ferrando","Eduardo Navas","Francisco G. Trivi\u00f1o","Joaqu\u00edn Garc\u00eda Vicente","Juan Carlos Castro","Juan Creus Andrade","Landa Hern\u00e1ndez","Luis D\u00edaz D\u00edaz","Manuel Send\u00f3n","Mengya Yang","Miguel Mesa del Castillo","N\u00faria G\u00fcell","Pablo Ib\u00e1\u00f1ez Ferrera","pensamiento","publicaci\u00f3n","reflexi\u00f3n multidisciplinar","revista","Roberto Equisoain","Rodrigo Delso Gutierrez","Santiago Sierra","Sara Escudero","Tatiana Poggi","Uriel Fogu\u00e9","Virginia de Diego","Yolanda P\u00e9rez S\u00e1nchez"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/","url":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/","name":"[:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg","datePublished":"2017-03-08T23:25:27+00:00","dateModified":"2017-12-12T17:48:01+00:00","description":"Toda la informaci\u00f3n sobre: [:es]Bartlebooth. La producci\u00f3n: Cuatro estrategias menores[:gl]Bartlebooth. A producci\u00f3n: Catro estratexias menores[:en]Bartlebooth. The production: Four minor strategies[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2016\/11\/Bartlebooth.-La-producci\u00f3n-Cuatro-estrategias-menores.jpg","width":1000,"height":667},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/bartlebooth-la-produccion-cuatro-estrategias-menores-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Bartlebooth. La producci\u00f3n: Cuatro estrategias menores"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/62534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=62534"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/62534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/62535"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=62534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=62534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=62534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}