{"id":57778,"date":"2015-10-08T06:20:29","date_gmt":"2015-10-08T04:20:29","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=57778"},"modified":"2022-08-09T12:16:23","modified_gmt":"2022-08-09T10:16:23","slug":"la-casita-azul-fernando-higueras-canarias-y-las-salinas-2","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/","title":{"rendered":"La casita azul. Fernando Higueras. Canarias y Las Salinas"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">La figura de Fernando Higueras, uno de los maestros de la arquitectura madrile\u00f1a de los \u201960 y \u201970, disfruta actualmente de un renovado inter\u00e9s por su arquitectura desde hace ya cierto tiempo, redescubrimiento al que se une ahora CentroCentro Cibeles.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-57779\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\" alt=\"La casita azul. Fernando Higueras. Canarias y Las Salinas\" width=\"750\" height=\"732\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg 625w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas-300x293.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Fallecido en 2008, Higueras ha dejado multitud de huellas memorables en Madrid, algunas tan extraordinarias como la Corona de Espinas o las Viviendas en San Bernardo, adem\u00e1s de numerosas viviendas unifamiliares y otros casos de inter\u00e9s. Todas estas obras merecer\u00edan revisiones espec\u00edficas pero debido a su proximidad, no es a ellas a las que se dedica esta exposici\u00f3n sino a traer al presente otra faceta del trabajo de Higueras menos cercana, m\u00e1s ex\u00f3tica y lejana como es la de los proyectos y obras que desarroll\u00f3 en las Islas Canarias a lo largo de su carrera. Un conjunto de trabajos, muchos de ellos poco conocidos o presentados aqu\u00ed por primera vez, cuya elecci\u00f3n complementa la visi\u00f3n m\u00e1s urbana y confinada de los proyectos madrile\u00f1os y revela un laboratorio experimental paralelo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/Fernando-Higueras-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-57780\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/Fernando-Higueras-2.jpg\" alt=\"Fernando-Higueras-2\" width=\"750\" height=\"1045\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/Fernando-Higueras-2.jpg 625w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/Fernando-Higueras-2-215x300.jpg 215w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Este \u201claboratorio ex\u00f3tico\u201d arranca con el contacto fundacional entre Higueras y C\u00e9sar Manrique en 1960, y florece en un conjunto exuberante de propuestas que configuraron un completo programa para la redescripci\u00f3n, desde la arquitectura, del paisaje, la imagen, el car\u00e1cter y los posibles modos de empleo (desde lo l\u00fadico a lo cultural y desde lo tur\u00edstico hasta lo aut\u00f3ctono), de las Canarias y en especial de Lanzarote. Un programa de una ambici\u00f3n preclara que vislumbr\u00f3 anticipatoriamente un ed\u00e9n prosaico, real; una utop\u00eda pragm\u00e1tica en el futuro de las Islas que pocos alcanzaban a ver hace cuarenta a\u00f1os y que Higueras supo armar con razones, ideas, met\u00e1foras in\u00e9ditas y sobre todo con un pu\u00f1ado de intervenciones ejemplares cuya vigencia actual puede comprobar cualquier visitante que acuda a La Mareta, Las Salinas, el Palacio Sp\u00ednola o las intervenciones de Lago Marti\u00e1nez. Un imaginario al tiempo aleg\u00f3rico y operativo que no solo dio forma a estos importantes casos sino que, en manos de terceros, ha sido un material privilegiado a partir del cual entender las Islas y sus posibilidades. De todos estos proyectos, quiz\u00e1s sea el Hotel Las Salinas el que resuma de forma m\u00e1s potente los planteamientos program\u00e1tico- paisaj\u00edsticos de Fernando Higueras en Canarias y al que se dedica el n\u00facleo de esta exposici\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Jacobo Garc\u00eda-Germ\u00e1n, Comisario de la exposici\u00f3n.<\/p>\n<p><strong>La casita azul. Fernando Higueras. Canarias y Las Salinas<\/strong><br \/>\n06 OCTUBRE 2015 \u2013 10 ENERO 2016<\/p>","protected":false},"excerpt":{"rendered":"<p>La figura de Fernando Higueras, uno de los maestros de la arquitectura madrile\u00f1a de los \u201960 y \u201970, disfruta actualmente de un renovado inter\u00e9s por su arquitectura desde hace ya cierto tiempo, redescubrimiento al que se une ahora CentroCentro Cibeles. Fallecido en 2008, Higueras ha dejado multitud de huellas memorables en Madrid, algunas tan extraordinarias [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":57779,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,1382],"tags":[12139,2631,9446,6701,556,5333,5310,3591,775,814,1106,1171],"class_list":{"0":"post-57778","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventos","8":"category-exposiciones","10":"tag-arquitectura-espanola","11":"tag-arquitectura-madrilena","12":"tag-cesar-manrique","13":"tag-exposicion","14":"tag-fernando-higueras","15":"tag-islas-canarias","16":"tag-jacobo-garcia-german","17":"tag-laboratorio","18":"tag-madrid","19":"tag-programa","20":"tag-retrospectiva"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La casita azul. Fernando Higueras. Canarias y Las Salinas<\/title>\n<meta name=\"description\" content=\"La casita azul. Fernando Higueras. Canarias y Las Salinas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La casita azul. Fernando Higueras. Canarias y Las Salinas\" \/>\n<meta property=\"og:description\" content=\"La casita azul. Fernando Higueras. Canarias y Las Salinas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-08T04:20:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-09T10:16:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"La casita azul. Fernando Higueras. Canarias y Las Salinas\",\"datePublished\":\"2015-10-08T04:20:29+00:00\",\"dateModified\":\"2022-08-09T10:16:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/\"},\"wordCount\":1302,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\",\"keywords\":[\"arquitectura canaria\",\"arquitectura espa\u00f1ola\",\"arquitectura madrile\u00f1a\",\"C\u00e9sar Manrique\",\"exposici\u00f3n\",\"Fernando Higueras\",\"islas canarias\",\"Jacobo Garc\u00eda-Germ\u00e1n\",\"laboratorio\",\"Madrid\",\"programa\",\"retrospectiva\"],\"articleSection\":[\"eventos\",\"exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/\",\"name\":\"La casita azul. Fernando Higueras. Canarias y Las Salinas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\",\"datePublished\":\"2015-10-08T04:20:29+00:00\",\"dateModified\":\"2022-08-09T10:16:23+00:00\",\"description\":\"La casita azul. Fernando Higueras. Canarias y Las Salinas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg\",\"width\":625,\"height\":610},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La casita azul. Fernando Higueras. Canarias y Las Salinas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La casita azul. Fernando Higueras. Canarias y Las Salinas","description":"La casita azul. Fernando Higueras. Canarias y Las Salinas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/","og_locale":"es_ES","og_type":"article","og_title":"La casita azul. Fernando Higueras. Canarias y Las Salinas","og_description":"La casita azul. Fernando Higueras. Canarias y Las Salinas","og_url":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2015-10-08T04:20:29+00:00","article_modified_time":"2022-08-09T10:16:23+00:00","og_image":[{"width":625,"height":610,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"La casita azul. Fernando Higueras. Canarias y Las Salinas","datePublished":"2015-10-08T04:20:29+00:00","dateModified":"2022-08-09T10:16:23+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/"},"wordCount":1302,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg","keywords":["arquitectura canaria","arquitectura espa\u00f1ola","arquitectura madrile\u00f1a","C\u00e9sar Manrique","exposici\u00f3n","Fernando Higueras","islas canarias","Jacobo Garc\u00eda-Germ\u00e1n","laboratorio","Madrid","programa","retrospectiva"],"articleSection":["eventos","exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/","url":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/","name":"La casita azul. Fernando Higueras. Canarias y Las Salinas","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg","datePublished":"2015-10-08T04:20:29+00:00","dateModified":"2022-08-09T10:16:23+00:00","description":"La casita azul. Fernando Higueras. Canarias y Las Salinas","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2015\/10\/La-casita-azul.-Fernando-Higueras.-Canarias-y-Las-Salinas.jpg","width":625,"height":610},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/la-casita-azul-fernando-higueras-canarias-y-las-salinas-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"La casita azul. Fernando Higueras. Canarias y Las Salinas"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/57778","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=57778"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/57778\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/57779"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=57778"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=57778"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=57778"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}