{"id":38663,"date":"2014-02-27T06:37:34","date_gmt":"2014-02-27T05:37:34","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=38663"},"modified":"2021-07-08T14:15:44","modified_gmt":"2021-07-08T12:15:44","slug":"javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/","title":{"rendered":"[:es]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad[:gl]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 O aire da cidade[:en]Javier Fernandez Mu\u00f1oz \u00b7 The air of the city[:]"},"content":{"rendered":"<p>[:es]http:\/\/vimeo.com\/83853975<\/p>\n<p class=\"first\" style=\"text-align: justify;\">Conferencia de Javier Fern\u00e1ndez Mu\u00f1oz. Arquitecto, OCHiR Ayuntamiento de Santiago de Compostela dentro de las jornadas de Arquitectura y Territorio rural celebradas en Callobre (A Estrada) el viernes 26 de Julio de 2013.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00abAunque la charla se centra en la descripci\u00f3n de los planteamientos previos y las secuelas posteriores a una ambiciosa operaci\u00f3n de reurbanizaci\u00f3n de la Ciudad Hist\u00f3rica de Santiago de Compostela, ejecutada durante los a\u00f1os 2008-2011, a la que me he referido en alguna ocasi\u00f3n como \u201cO aire da Cidade\u201d (Premio Nacional de Arquitectura 2010), en realidad la utilizo tambi\u00e9n como excusa para comentar las diversas vicisitudes que el proceso urbanizador sufre en su lento navegar, y muchas veces naufragar, en el seno de la administraci\u00f3n, revelando una vez m\u00e1s como la acci\u00f3n pol\u00edtica es una contingencia que, tristemente, debemos tener tan en cuenta en el proceso arquitect\u00f3nico como a la acci\u00f3n de la gravedad o a las inclemencias meteorol\u00f3gicas. El tiempo de la pol\u00edtica no es de la misma substancia que el de la arquitectura, s\u00f3lo coinciden en el nombre\u2026\u00bb<\/em><\/p>\n<\/blockquote>\n<p>[:en]<\/p>\n<p class=\"first\" style=\"text-align: justify;\">Javier Fernandez Mu\u00f1oz&#8217;s conference. Architect, OCHiR Ayuntamiento of Santiago de Compostela inside the days of Architecture and rural Territory celebrated in Callobre (To Highway) on Friday, the 26th of July, 2013.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00abThough the chat centres on the description of the previous expositions and the sequels later to an ambitious operation of reurbanization of the Historical City of Santiago de Compostela, executed during the years 2008-2011, to that I have referred in some occasion as \u00bb Or air gives Cidade \u00bb (National Prize of Architecture 2010), actually I use it also as excuse to comment on the diverse vicissitudes that the process urbanizer suffers in his slow one to sail, and often to sink, in the bosom of the administration, revealing once again as the political action it is a contingency that, sadly, we must bear in mind so in the architectural process as to the action of the gravity or to the meteorological inclemencies.The time of the politics is not of the same substance that that of the architecture, only they coincide with the name\u2026\u00bb<\/em><\/p>\n<\/blockquote>\n<p>http:\/\/vimeo.com\/83853975[:gl]<\/p>\n<p class=\"first\" style=\"text-align: justify;\">Conferencia de Javier Fern\u00e1ndez Mu\u00f1oz. Arquitecto, OCHiR Concello de Santiago de Compostela dentro das xornadas de Arquitectura e Territorio rural celebradas en Callobre (A Estrada) o venres 26 de Xullo de 2013.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00abA\u00ednda que a charla se centra na descrici\u00f3n das formulaci\u00f3ns previas e as secuelas posteriores a unha ambiciosa operaci\u00f3n de reurbanizaci\u00f3n da Cidade Hist\u00f3rica de Santiago de Compostela, executada durante os anos 2008-2011, \u00e1 que me refer\u00edn nalgunha ocasi\u00f3n como \u00abO aire d\u00e1 Cidade\u00bb (Premio Nacional de Arquitectura 2010), en realidade a utilizo tam\u00e9n como escusa para comentar as diversas vicisitudes que o proceso urbanizador sofre no seu lento navegar, e moitas veces naufragar, no seo da administraci\u00f3n, revelando unha vez m\u00e1is como a acci\u00f3n pol\u00edtica \u00e9 unha continxencia que, tristemente, debemos ter tan en conta no proceso arquitect\u00f3nico como \u00e1 acci\u00f3n da gravidade ou \u00e1s inclemencias meteorol\u00f3xicas. O tempo da pol\u00edtica non \u00e9 da mesma substancia que o da arquitectura, s\u00f3 coinciden no nome&#8230; \u00ab<\/em><\/p>\n<\/blockquote>\n<p>http:\/\/vimeo.com\/83853975[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:es]http:\/\/vimeo.com\/83853975 Conferencia de Javier Fern\u00e1ndez Mu\u00f1oz. Arquitecto, OCHiR Ayuntamiento de Santiago de Compostela dentro de las jornadas de Arquitectura y Territorio rural celebradas en Callobre (A Estrada) el viernes 26 de Julio de 2013. \u00abAunque la charla se centra en la descripci\u00f3n de los planteamientos previos y las secuelas posteriores a una ambiciosa operaci\u00f3n de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":39021,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4854],"tags":[8820,4071,5865,4303,357,521,1787,8351,5426,619,8353,3784,8694,1197,1209,12474],"class_list":["post-38663","post","type-post","status-publish","format-standard","has-post-thumbnail","category-tv","tag-a-cidade-intuida","tag-alfonso-salgado-suarez","tag-arquitectura-gallega","tag-arquitectura-y-territorio-rural","tag-espana","tag-europa","tag-francisco-alonso-de-santos","tag-fundacion-maria-martinez-otero","tag-galicia","tag-javier-fernandez-munoz","tag-jose-valladares-duran","tag-ruben-ramos-balsa","tag-rvr-arquitectos","tag-santiago-de-compostela","tag-tv"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad<\/title>\n<meta name=\"description\" content=\"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-\u00b7-el-aire-de-la-ciudad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad\" \/>\n<meta property=\"og:description\" content=\"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-\u00b7-el-aire-de-la-ciudad\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2014-02-27T05:37:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-08T12:15:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"[:es]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad[:gl]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 O aire da cidade[:en]Javier Fernandez Mu\u00f1oz \u00b7 The air of the city[:]\",\"datePublished\":\"2014-02-27T05:37:34+00:00\",\"dateModified\":\"2021-07-08T12:15:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/javier-fernandez-munoz-el-aire.jpg\",\"keywords\":[\"A Cidade Intuida\",\"Alfonso Salgado Su\u00e1rez\",\"arquitectura gallega\",\"arquitectura y territorio rural\",\"conferencia\",\"Espa\u00f1a\",\"Europa\",\"Francisco Alonso de Santos\",\"fundaci\u00f3n Mar\u00eda Mart\u00ednez Otero\",\"Galicia\",\"javier fern\u00e1ndez mu\u00f1oz\",\"Jos\u00e9 Valladares Dur\u00e1n\",\"Rub\u00e9n Ramos Balsa\",\"rvr arquitectos\",\"Santiago de Compostela\",\"tv\"],\"articleSection\":[\"tv\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/\",\"name\":\"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/javier-fernandez-munoz-el-aire.jpg\",\"datePublished\":\"2014-02-27T05:37:34+00:00\",\"dateModified\":\"2021-07-08T12:15:44+00:00\",\"description\":\"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/javier-fernandez-munoz-el-aire.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/02\\\/javier-fernandez-munoz-el-aire.jpg\",\"width\":\"1280\",\"height\":\"960\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad","description":"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-\u00b7-el-aire-de-la-ciudad\/","og_locale":"es_ES","og_type":"article","og_title":"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad","og_description":"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad","og_url":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-\u00b7-el-aire-de-la-ciudad\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2014-02-27T05:37:34+00:00","article_modified_time":"2021-07-08T12:15:44+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"[:es]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad[:gl]Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 O aire da cidade[:en]Javier Fernandez Mu\u00f1oz \u00b7 The air of the city[:]","datePublished":"2014-02-27T05:37:34+00:00","dateModified":"2021-07-08T12:15:44+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg","keywords":["A Cidade Intuida","Alfonso Salgado Su\u00e1rez","arquitectura gallega","arquitectura y territorio rural","conferencia","Espa\u00f1a","Europa","Francisco Alonso de Santos","fundaci\u00f3n Mar\u00eda Mart\u00ednez Otero","Galicia","javier fern\u00e1ndez mu\u00f1oz","Jos\u00e9 Valladares Dur\u00e1n","Rub\u00e9n Ramos Balsa","rvr arquitectos","Santiago de Compostela","tv"],"articleSection":["tv"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/","url":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/","name":"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg","datePublished":"2014-02-27T05:37:34+00:00","dateModified":"2021-07-08T12:15:44+00:00","description":"Javier Fern\u00e1ndez Mu\u00f1oz El aire de la ciudad","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2014\/02\/javier-fernandez-munoz-el-aire.jpg","width":"1280","height":"960"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/javier-fernandez-munoz-%c2%b7-el-aire-de-la-ciudad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Javier Fern\u00e1ndez Mu\u00f1oz \u00b7 El aire de la ciudad"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/38663","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=38663"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/38663\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/39021"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=38663"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=38663"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=38663"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}