{"id":3749,"date":"2010-03-24T13:36:55","date_gmt":"2010-03-24T13:36:55","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=3749"},"modified":"2026-08-03T13:07:34","modified_gmt":"2026-08-03T11:07:34","slug":"omotesando-camino-al-templo","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/","title":{"rendered":"Omotesando; camino al templo | Ana Bastero"},"content":{"rendered":"<p><!--:es--><\/p>\n<p style=\"text-align: justify;\">Omotesando es el nombre de una de las calles comerciales m\u00e1s importantes de Tokio, as\u00ed mismo se est\u00e1 convirtiendo en una de la m\u00e1s interesantes para los amantes de la arquitectura y de la moda.<\/p>\n<p style=\"text-align: justify;\">En Jap\u00f3n hace tiempo que han demostrando que son grandes consumidores de lujo, por lo que importantes marcas de moda han decidido construir en Tokio, sus templos. Odas al consumismo vestidas con los dise\u00f1os de los arquitectos m\u00e1s vanguardistas.<\/p>\n<p style=\"text-align: justify;\">Si hacemos un breve repaso a las tradiciones y estructura de la sociedad nipona nos vamos haciendo una idea de las necesidades que los objetos de lujo cubren para ellos.<\/p>\n<figure style=\"width: 750px\" class=\"wp-caption alignnone\"><a style=\"color: #999999;\" href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"\" title=\"01 louis vuitton Omotesando store\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store-150x150.jpg\" alt=\"\" width=\"750\" height=\"750\" \/><\/a><figcaption class=\"wp-caption-text\"><\/span> <span style=\"color: #999999;\">Louis Vuitton Omotesando store<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Los j\u00f3venes japones son educados en el orden y el rigor desde su tierna infancia. Y hasta llegar al periodo universitario estas exigencias no bajan; por ello este constituye el periodo m\u00e1s independiente de sus vidas, aprovechan para vivir fuera de la casa de los padres y desarrollar inquietudes m\u00e1s art\u00edsticas. Una vez graduados, entran a formar parte del mundo laboral. A las empresas no les importa que estos reci\u00e9n titulados tengan o no conocimientos espec\u00edficos elevados, ya que ellas mismas se encargaran de seguir form\u00e1ndolos. Y as\u00ed es como los japoneses se ven, otra vez, inmersos en una estructura r\u00edgida donde no hay mucha cabida para la diferenciaci\u00f3n y la creatividad. Algunos cubren esta necesidad de diferenciaci\u00f3n con los art\u00edculos de lujo y con todo lo vintage llegado de occidente. Muchas j\u00f3venes japonesas se vuelven locas por los bolsos de marca, y por ser las m\u00e1s \u00abcool\u00bb adquiriendo el \u00faltimo modelo. Como nadie quiere renunciar a los objetos de alta gama, en Jap\u00f3n existen boutiques de segunda mano que se dedican a los productos de marca, que dan satisfacci\u00f3n al p\u00fablico menos pudiente. Desde las estudiantes a las mujeres trabajadoras, forman un nutrido y creciente grupo de entusiastas compradoras de marcas de lujo.<\/p>\n<figure style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/02-Tods-Omotesando-store.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"02 Tod's Omotesando store\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/02-Tods-Omotesando-store-150x150.jpg\" alt=\"Tod's Omotesando store\" width=\"750\" height=\"750\" \/><\/a><figcaption class=\"wp-caption-text\"><span style=\"color: #999999;\">Tod&#8217;s Omotesando store<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Con este panorama, que apunta un crecimiento incesante del consumo de las marcas de alta gama, es obvio que las empresas decidan instalar en Jap\u00f3n sus puntos de venta y oficinas m\u00e1s representativos.<\/p>\n<p style=\"text-align: justify;\">Los edificios corporativos, forman parte de la imagen que la empresa desea proyectar. As\u00ed las empresas buscan tener edificios emblem\u00e1ticos que trasmitan mensajes claros sobre ellas mismas. Cada uno de estos espacios est\u00e1 estudiado en todos los sentidos para fortalecer su distinci\u00f3n y reflejar cada uno de los principales valores de la marca.<\/p>\n<figure style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/03-ChristianDior-Omotesando-store1.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"03 ChristianDior Omotesando store\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/03-ChristianDior-Omotesando-store-150x150.jpg\" alt=\"ChristianDior Omotesando store\" width=\"750\" height=\"750\" \/><\/a><figcaption class=\"wp-caption-text\"><span style=\"color: #999999;\">ChristianDior Omotesando store<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Dior, Tod&#8217;s y Louis Vuitton son algunas de las marcas que han elegido en Tokio, el distrito de Omotesando como emplazamiento de una de sus tiendas, m\u00e1s destacadas.<\/p>\n<p style=\"text-align: justify;\">La firma Louis Vuitton confi\u00f3 en Jun Aoki para dise\u00f1ar su boutique inaugurada en 2002. Su fachada simula ba\u00fales de diferentes tama\u00f1os apilados, evocando las ra\u00edces de LV como fabricante de maletas y ba\u00fales. Una tradici\u00f3n que en la casa LV han sabido combinar muy bien con la modernidad, buena muestra de ello es la colaboraci\u00f3n constante con el artista nip\u00f3n Takashi Murakami, que ha revolucionado su monograma y en este caso ha sido el encargado de la decoraci\u00f3n interior de la tienda, d\u00e1ndole un toque muy colorista y m\u00e1s cercana a la est\u00e9tica japonesa.<\/p>\n<p style=\"text-align: justify;\">Muy cerca nos encontramos con Tod&#8217;s Omotesando Building, un proyecto vanguardista tanto en concepto como en t\u00e9cnica, inaugurado en 2004. En las siete plantas de este edificio convive la tienda con oficinas, espacios para eventos y una azotea ajardinada. La divisi\u00f3n de plantas se aprecia por la transparencia de la estructura y no por la delineaci\u00f3n de la fachada. La cual ha sido dise\u00f1ada siguiendo el dibujo que genera la superposici\u00f3n de nueve \u00e1rboles, construida en hormig\u00f3n y cristal. Toyo Ito, el arquitecto, compara la naturaleza cambiante del edificio a medida que avanzas en alturas con la forma de los \u00e1rboles de la base a la copa.<\/p>\n<p style=\"text-align: justify;\">Siguiendo nuestro paseo por Omotesando, nos encontramos con Dior, que nos presenta un edificio proyectado por SANAA, en el cual a parte de la tienda tambi\u00e9n hay cabida para salas de eventos y jardines. En este caso la cantidad exacta de plantas no se aprecia desde el exterior, lo que potencia la impresi\u00f3n de ambig\u00fcedad que genera el edificio. Esta est\u00e9tica deliberadamente voluble y enigm\u00e1tica guarda coherencia con la obra de uno de los dise\u00f1adores m\u00e1s coloristas y din\u00e1micos del momento, John Galiano.<\/p>\n<p style=\"text-align: justify;\">Otro de los edificios que nos llaman la atenci\u00f3n es el de Prada, la tienda dise\u00f1ada por los suizos Jacques Herzog y Pierre de Meuron, en 2003, aparece como una elemento escult\u00f3rico en medio de la trama compacta de la zona. La forma de Prada, con su vidrio verdoso, parece una especie de esmeralda, un edificio m\u00e1s bien tallado que construido. Se trata de un volumen irregular, sus seis pisos han sido trabajados de manera que el volumen no parezca tan alto. El armaz\u00f3n formado por rombos de tubos met\u00e1licos, rellenados con paneles de vidrio c\u00f3ncavos, convexos y planos, algunos transparentes y otros transl\u00facidos, le dan textura y variedad a la superficie.<\/p>\n<figure id=\"attachment_3937\" aria-describedby=\"caption-attachment-3937\" style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/04-prada-Omotesando-store.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3937\" title=\"04 prada Omotesando store\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/04-prada-Omotesando-store-150x150.jpg\" alt=\"prada Omotesando store\" width=\"750\" height=\"750\" \/><\/a><figcaption id=\"caption-attachment-3937\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Prada Omotesando store<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Burberry para unirse a esta tendencia, reabri\u00f3 a finales de 2009 su tienda, de 550 metros cuadrados, con un aspecto innovador y vanguardista. La boutique de Omotesando es la expresi\u00f3n m\u00e1s lujosa de la firma en Jap\u00f3n y alberga las colecciones de la l\u00ednea Burberry Prorsum tanto de hombre como de mujer as\u00ed como la colecci\u00f3n de accesorios. El suelo est\u00e1 realizado en madera oscura espigada mientras que la pared recoge el color trench en la zona dedicada a la l\u00ednea Outerwear. Los materiales brit\u00e1nicos y gui\u00f1os a los iconos de la firma son protagonistas en el espacio.<\/p>\n<figure id=\"attachment_3938\" aria-describedby=\"caption-attachment-3938\" style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/05-burberry-Omotesando-store.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3938\" title=\"05 burberry Omotesando store\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/05-burberry-Omotesando-store-150x150.jpg\" alt=\"Burberry Omotesando store\" width=\"750\" height=\"499\" \/><\/a><figcaption id=\"caption-attachment-3938\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Burberry Omotesando store<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Pero de todos, el proyecto m\u00e1s controvertido ha sido Omotesando Hill, conjunto mixto de 130 tiendas y 38 viviendas. Su dise\u00f1o lo inici\u00f3 Tadao Ando en 1996, en el 2003 se empez\u00f3 su construcci\u00f3n que acabar\u00eda en 2006. Esta obra caus\u00f3 controversia al reemplazar una obra en estilo Bauhaus, los D\u014djunkai Aoyama Apartments, uno de los espacios urbanos m\u00e1s ricos e hist\u00f3ricamente significativos de Tokio, un conjunto habitacional social construido en 1927 tras el terremoto de Kanto y superviviente a la segunda guerra mundial.<\/p>\n<p style=\"text-align: justify;\">La propuesta de Ando convive con la arboleda de zelkova, una especie japonesa de frondosa copa, que se encuentra en frente del edificio, controlando su altura para que no sobrepase la altura de dicha arboleda. La fachada del edificio se comporta como un anuncio electr\u00f3nico gigante de 250 metros, compuesta por una serie de pantallas LED que van cambiando continuamente. Para sacar provecho al enorme costo del terreno sin perturbar demasiado el perfil de la calle, Ando opt\u00f3 por construir el mayor n\u00famero de niveles subterr\u00e1neos, donde situ\u00f3 las tiendas y alg\u00fan espacio para el desarrollo cultural. Las viviendas se encuentran en el volumen superior, ya que la idea es aislarlas lo m\u00e1s posible del fren\u00e9tico mundo que se vive bajo ellas, tratando de resolverlas en un mundo aparte, a pesar de encontrarse en el coraz\u00f3n comercial de la ciudad.<\/p>\n<figure id=\"attachment_3940\" aria-describedby=\"caption-attachment-3940\" style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/07-OMONTESANDO-HILLS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3940\" title=\"07' OMONTESANDO HILLS\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/07-OMONTESANDO-HILLS-300x209.jpg\" alt=\"Omotesando Hill\" width=\"750\" height=\"523\" \/><\/a><figcaption id=\"caption-attachment-3940\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Omotesando Hill<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Fuera de los intentos de integraci\u00f3n y respeto por el entorno siempre habr\u00e1 qui\u00e9n simplifiquen este edificio al calificativo de mall, muy sofisticado y algo culturoso, pero al fin y al cabo un mall.<\/p>\n<p style=\"text-align: justify;\">La arquitectura de todas estas boutiques viene determinada por aquellos valores que las marcas pretenden comunicar, como transparencia, eficiencia, sostenibilidad, modernidad. La creatividad de cada uno de estos edificios ayuda a conseguir la implantaci\u00f3n de esos valores y su diferenciaci\u00f3n con el resto de las compa\u00f1\u00edas. En Omotesando estos conviven con id\u00e9nticos mensajes transmitidos por la sociedad japonesa, a trav\u00e9s de sus nuevos centros comerciales.<\/p>\n<figure id=\"attachment_3941\" aria-describedby=\"caption-attachment-3941\" style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/07-OMONTESANDO-HILLS-project.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3941\" title=\"07 OMONTESANDO HILLS project\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/07-OMONTESANDO-HILLS-project-300x154.jpg\" alt=\"omotesando hill project\" width=\"750\" height=\"387\" \/><\/a><figcaption id=\"caption-attachment-3941\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Omotesando Hill Project<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Al final del paseo queda claro que Omotesando es una de las calles m\u00e1s interesantes del mundo para los amantes de la arquitectura y tiendas de lujo. Adem\u00e1s hace honor a su ancestral nombre \u00abcamino al templo\u00bb, en esta ocasi\u00f3n a los templos del consumismo.<\/p>\n<p style=\"text-align: justify;\">ana bastero<br \/>\nvigo. marzo 2010<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\">imagenes<\/span> <span style=\"color: #888888;\">obtenidas de<\/span> <span style=\"color: #888888;\"><a href=\"http:\/\/moleskinearquitectonico.blogspot.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #888888;\">http:\/\/moleskinearquitectonico.blogspot.com<\/span><\/a><\/span><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Omotesando es el nombre de una de las calles comerciales m\u00e1s importantes de Tokio, as\u00ed mismo se est\u00e1 convirtiendo en una de la m\u00e1s interesantes para los amantes de la arquitectura y de la moda. En Jap\u00f3n hace tiempo que han demostrando que son grandes consumidores de lujo, por lo que importantes marcas de moda [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":3750,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[12276,3657,1922,12470,516,1575,877,5909,2677,1335],"class_list":["post-3749","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulos","category-slider-principal","tag-ana-bastero","tag-arquitectura-japonesa","tag-asia","tag-diseno","tag-espacio-publico","tag-japon","tag-moda","tag-omotesando","tag-tokio","tag-vanguardia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omotesando; camino al templo | Ana Bastero<\/title>\n<meta name=\"description\" content=\"omotesando\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omotesando; camino al templo | Ana Bastero\" \/>\n<meta property=\"og:description\" content=\"omotesando\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ana.bastero.5\" \/>\n<meta property=\"article:published_time\" content=\"2010-03-24T13:36:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T11:07:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"649\" \/>\n\t<meta property=\"og:image:height\" content=\"442\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Bastero\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Bastero\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/\"},\"author\":{\"name\":\"Ana Bastero\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/6a33eac8aaf4d9621c44b33daab0320f\"},\"headline\":\"Omotesando; camino al templo | Ana Bastero\",\"datePublished\":\"2010-03-24T13:36:55+00:00\",\"dateModified\":\"2026-08-03T11:07:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/\"},\"wordCount\":1452,\"commentCount\":20,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/03\\\/01-louis-vuitton-Omotesando-store1.jpg\",\"keywords\":[\"Ana Bastero\",\"arquitectura japonesa\",\"Asia\",\"dise\u00f1o\",\"espacio p\u00fablico\",\"Jap\u00f3n\",\"moda\",\"omotesando\",\"Tokio\",\"vanguardia\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/\",\"name\":\"Omotesando; camino al templo | Ana Bastero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/03\\\/01-louis-vuitton-Omotesando-store1.jpg\",\"datePublished\":\"2010-03-24T13:36:55+00:00\",\"dateModified\":\"2026-08-03T11:07:34+00:00\",\"description\":\"omotesando\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/03\\\/01-louis-vuitton-Omotesando-store1.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2010\\\/03\\\/01-louis-vuitton-Omotesando-store1.jpg\",\"width\":\"649\",\"height\":\"442\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/omotesando-camino-al-templo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Omotesando; camino al templo | Ana Bastero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/6a33eac8aaf4d9621c44b33daab0320f\",\"name\":\"Ana Bastero\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Ana-Bastero-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Ana-Bastero-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Ana-Bastero-96x96.jpg\",\"caption\":\"Ana Bastero\"},\"description\":\"A TIENTAS pero no a oscuras\",\"sameAs\":[\"https:\\\/\\\/atientass.wordpress.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/ana.bastero.5\",\"https:\\\/\\\/www.instagram.com\\\/anabastero\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/ana-bastero\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omotesando; camino al templo | Ana Bastero","description":"omotesando","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/","og_locale":"es_ES","og_type":"article","og_title":"Omotesando; camino al templo | Ana Bastero","og_description":"omotesando","og_url":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/ana.bastero.5","article_published_time":"2010-03-24T13:36:55+00:00","article_modified_time":"2026-08-03T11:07:34+00:00","og_image":[{"width":649,"height":442,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg","type":"image\/jpeg"}],"author":"Ana Bastero","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Ana Bastero","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/"},"author":{"name":"Ana Bastero","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/6a33eac8aaf4d9621c44b33daab0320f"},"headline":"Omotesando; camino al templo | Ana Bastero","datePublished":"2010-03-24T13:36:55+00:00","dateModified":"2026-08-03T11:07:34+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/"},"wordCount":1452,"commentCount":20,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg","keywords":["Ana Bastero","arquitectura japonesa","Asia","dise\u00f1o","espacio p\u00fablico","Jap\u00f3n","moda","omotesando","Tokio","vanguardia"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/","url":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/","name":"Omotesando; camino al templo | Ana Bastero","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg","datePublished":"2010-03-24T13:36:55+00:00","dateModified":"2026-08-03T11:07:34+00:00","description":"omotesando","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2010\/03\/01-louis-vuitton-Omotesando-store1.jpg","width":"649","height":"442"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/omotesando-camino-al-templo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Omotesando; camino al templo | Ana Bastero"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/6a33eac8aaf4d9621c44b33daab0320f","name":"Ana Bastero","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Ana-Bastero-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Ana-Bastero-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Ana-Bastero-96x96.jpg","caption":"Ana Bastero"},"description":"A TIENTAS pero no a oscuras","sameAs":["https:\/\/atientass.wordpress.com\/","https:\/\/www.facebook.com\/ana.bastero.5","https:\/\/www.instagram.com\/anabastero\/"],"url":"https:\/\/veredes.es\/blog\/author\/ana-bastero\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/3749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=3749"}],"version-history":[{"count":2,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/3749\/revisions"}],"predecessor-version":[{"id":108144,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/3749\/revisions\/108144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/3750"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=3749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=3749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=3749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}