{"id":35596,"date":"2013-11-14T06:24:18","date_gmt":"2013-11-14T06:24:18","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=35596"},"modified":"2015-09-23T15:39:33","modified_gmt":"2015-09-23T13:39:33","slug":"eso-dicen-%c2%b7-enrique-rodriguez","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/","title":{"rendered":"Eso dicen \u00b7 Enrique Rodr\u00edguez"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">El pr\u00f3ximo <strong>jueves 21 de novimbre<\/strong> tendr\u00e1 lugar una nueva sesi\u00f3n de la sesi\u00f3n coloquio de arquitectura, <em><strong>Eso dicen. <\/strong><\/em>En esta ocasi\u00f3n, el invitado ser\u00e1 <strong><strong>Enrique Rodr\u00edguez.<\/strong><\/strong> La sesi\u00f3n se dividir\u00e1 en media hora de presentaci\u00f3n del arquitecto y otros treinta minutos de coloquio informal con el p\u00fablico.<\/p>\n<p style=\"text-align: justify;\"><em>Eso dicen <\/em>es un ciclo de sesiones-coloquio que se celebra el primer y tercer jueves de cada mes entre las <strong>20:00h y las 21:00h<\/strong> en la planta baja del Taller Creativo No Importa (calle San Andr\u00e9s, 46); en \u00e9l participan arquitectos gallegos pertenecientes a distintas generaciones con la intenci\u00f3n de presentar un amplio espectro de enfoques de la disciplina, siempre con una reflexi\u00f3n acerca del papel del arquitecto en el momento actual como tel\u00f3n de fondo.<\/p>\n<p><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-35598\" title=\"ED-sesi\u00f3n-08-web\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg\" alt=\"\" width=\"620\" height=\"876\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web-212x300.jpg 212w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p><strong>ESO DICEN \u00b7 <\/strong>Enrique Rodr\u00edguez<br \/>\n<strong>Jueves 21 de noviembre 20:00 \u2013 21:00h<\/strong><br \/>\naforo limitado \u2013 entrada gratuita<br \/>\n<strong>[NO IMPORTA] taller creativo<\/strong><br \/>\nC\/San Andr\u00e9s 46 planta Baja<br \/>\nA Coru\u00f1a [Espa\u00f1a]<\/p>\n<p>Organiza:<br \/>\nAlberto Alonso Oro [veredes.es]<br \/>\nMaria Olmo B\u00e9jar + Borja L\u00f3pez Cotelo [lasonceymedia.com]<\/p>\n<p>Apoya:<br \/>\n<a href=\"http:\/\/www.grupodesarrolla.es\/\" target=\"_blank\">Grupo Desarrolla Works<\/a><\/p>\n<p><a href=\"http:\/\/www.grupodesarrolla.es\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" title=\"LOGO-DESARROLLA_peque\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/09\/LOGO-DESARROLLA_peque.jpg\" alt=\"\" width=\"200\" height=\"71\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo jueves 21 de novimbre tendr\u00e1 lugar una nueva sesi\u00f3n de la sesi\u00f3n coloquio de arquitectura, Eso dicen. En esta ocasi\u00f3n, el invitado ser\u00e1 Enrique Rodr\u00edguez. La sesi\u00f3n se dividir\u00e1 en media hora de presentaci\u00f3n del arquitecto y otros treinta minutos de coloquio informal con el p\u00fablico. Eso dicen es un ciclo de sesiones-coloquio [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35598,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5624],"tags":[66,12273,5865,3852,318,357,365,5212,6714,9137,7572,619,7574,5092,737,784,4145,3378,7573,12468,7945],"class_list":{"0":"post-35596","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-deriva","8":"tag-a-coruna","9":"tag-alberto-alonso-oro","10":"tag-arquitectura-gallega","11":"tag-borja-lopez-cotelo","12":"tag-ciudad","13":"tag-conferencia","14":"tag-construccion","15":"tag-disciplina","16":"tag-divulgacion","17":"tag-enrique-rodriguez","18":"tag-eso-dicen","19":"tag-galicia","20":"tag-hibridacion","21":"tag-interdisciplinar","22":"tag-investigacion","23":"tag-lasonceymedia","24":"tag-maria-olmo-bejar","25":"tag-mesa-redonda","26":"tag-no-importa","27":"tag-urbanismo","28":"tag-veredes"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eso dicen \u00b7 Enrique Rodr\u00edguez<\/title>\n<meta name=\"description\" content=\"Enrique Rodr\u00edguez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/eso-dicen-\u00b7-enrique-rodriguez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eso dicen \u00b7 Enrique Rodr\u00edguez\" \/>\n<meta property=\"og:description\" content=\"Enrique Rodr\u00edguez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/eso-dicen-\u00b7-enrique-rodriguez\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-11-14T06:24:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-09-23T13:39:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"876\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Eso dicen \u00b7 Enrique Rodr\u00edguez\",\"datePublished\":\"2013-11-14T06:24:18+00:00\",\"dateModified\":\"2015-09-23T13:39:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/\"},\"wordCount\":554,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/ED-sesi\u00f3n-08-web.jpg\",\"keywords\":[\"A Coru\u00f1a\",\"Alberto Alonso Oro\",\"arquitectura gallega\",\"Borja L\u00f3pez Cotelo\",\"ciudad\",\"conferencia\",\"construcci\u00f3n\",\"disciplina\",\"divulgaci\u00f3n\",\"enrique rodr\u00edguez\",\"eso dicen\",\"Galicia\",\"hibridaci\u00f3n\",\"interdisciplinar\",\"investigaci\u00f3n\",\"lasonceymedia\",\"maria olmo b\u00e9jar\",\"mesa redonda\",\"no importa\",\"urbanismo\",\"veredes\"],\"articleSection\":[\"deriva\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/\",\"name\":\"Eso dicen \u00b7 Enrique Rodr\u00edguez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/ED-sesi\u00f3n-08-web.jpg\",\"datePublished\":\"2013-11-14T06:24:18+00:00\",\"dateModified\":\"2015-09-23T13:39:33+00:00\",\"description\":\"Enrique Rodr\u00edguez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/ED-sesi\u00f3n-08-web.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/ED-sesi\u00f3n-08-web.jpg\",\"width\":\"620\",\"height\":\"876\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/eso-dicen-%c2%b7-enrique-rodriguez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eso dicen \u00b7 Enrique Rodr\u00edguez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eso dicen \u00b7 Enrique Rodr\u00edguez","description":"Enrique Rodr\u00edguez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/eso-dicen-\u00b7-enrique-rodriguez\/","og_locale":"es_ES","og_type":"article","og_title":"Eso dicen \u00b7 Enrique Rodr\u00edguez","og_description":"Enrique Rodr\u00edguez","og_url":"https:\/\/veredes.es\/blog\/eso-dicen-\u00b7-enrique-rodriguez\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2013-11-14T06:24:18+00:00","article_modified_time":"2015-09-23T13:39:33+00:00","og_image":[{"width":620,"height":876,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Eso dicen \u00b7 Enrique Rodr\u00edguez","datePublished":"2013-11-14T06:24:18+00:00","dateModified":"2015-09-23T13:39:33+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/"},"wordCount":554,"commentCount":1,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg","keywords":["A Coru\u00f1a","Alberto Alonso Oro","arquitectura gallega","Borja L\u00f3pez Cotelo","ciudad","conferencia","construcci\u00f3n","disciplina","divulgaci\u00f3n","enrique rodr\u00edguez","eso dicen","Galicia","hibridaci\u00f3n","interdisciplinar","investigaci\u00f3n","lasonceymedia","maria olmo b\u00e9jar","mesa redonda","no importa","urbanismo","veredes"],"articleSection":["deriva"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/","url":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/","name":"Eso dicen \u00b7 Enrique Rodr\u00edguez","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg","datePublished":"2013-11-14T06:24:18+00:00","dateModified":"2015-09-23T13:39:33+00:00","description":"Enrique Rodr\u00edguez","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/ED-sesi\u00f3n-08-web.jpg","width":"620","height":"876"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/eso-dicen-%c2%b7-enrique-rodriguez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Eso dicen \u00b7 Enrique Rodr\u00edguez"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/35596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=35596"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/35596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/35598"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=35596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=35596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=35596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}