{"id":35372,"date":"2013-10-19T10:20:23","date_gmt":"2013-10-19T10:20:23","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=35372"},"modified":"2015-02-09T19:50:13","modified_gmt":"2015-02-09T19:50:13","slug":"131-hechos-construidos","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/","title":{"rendered":"<!--:es-->13+1 Hechos construidos<!--:--><!--:gl-->13+1 Feitos construidos<!--:--><!--:en-->13+1 Constructed facts<!--:-->"},"content":{"rendered":"<p><!--:es--><\/p>\n<p style=\"text-align: justify;\">La Delegaci\u00f3n del Colexio Oficial de Arquitectos de Galicia en A Coru\u00f1a, en colaboraci\u00f3n con la empresa DESARROLLA, inicia con <strong>\u201c13+1 Hechos construidos\u201d<\/strong> su primer ciclo de conferencias sobre la realidad construida de la arquitectura gallega contempor\u00e1nea. Desde el <strong>23 de octubre de 2013 hasta el 29 de enero de 2014<\/strong>, con una periodicidad bisemanal, por la sala de la Delegaci\u00f3n pasar\u00e1n 7 equipos de arquitectos, de distintas generaciones, que nos mostrar\u00e1n su trabajo centr\u00e1ndose en dos \u00fanicas obras, seleccionadas y construidas \u00a0por ellos mismos, como exponente de su hacer y pensamiento arquitect\u00f3nico.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-35373\" title=\"01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\" alt=\"\" width=\"620\" height=\"1214\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01-153x300.jpg 153w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El nombre de este ciclo de conferencias procede de un pie de foto que aparece en el libro \u00abUne petit maison\u00bb, publicado por Le Corbusier en Editions Girsberger de Zurich en 1954. Libro que,como ustedes saben,el maestro dedica a la \u201cenorme\u201d casa que construy\u00f3 para sus padres a orillas del lago Leman. Existe una edici\u00f3n en espa\u00f1ol publicada en 2005 por Ediciones Infinito de Buenos Aires. Este mismo pie de foto, con el \u00a0hondo significado que contiene, \u00a0di\u00f3 t\u00edtulo al libro \u00abLos hechos de la arquitectura\u00bb, que Ediciones ARQ de Santiago de Chile public\u00f3 en 1999, y donde Alejandro Aravena, Fernando P\u00e9rez y Jos\u00e9 Quintanilla realizan uno de los, tal vez, m\u00e1s interesantes ejercicios escritos sobre historia de la arquitectura.<\/p>\n<p style=\"text-align: justify;\">Hechos de la arquitectura &#8211; Hechos construidos. El matiz, si bien es importante, tampoco quiere decir m\u00e1s de lo que evidentemente todos entendemos. Sobran explicaciones.<\/p>\n<p style=\"text-align: justify;\">El ciclo de conferencias\u00a0<strong>\u201c13+1 Hechos construidos\u201d<\/strong> nace con la voluntad de ser una cita fija en la agenda cultural gallega, \u00a0que con los a\u00f1os se vaya afirmando como un espacio donde el hecho arquitect\u00f3nico encuentre el lugar que le corresponde en la definici\u00f3n de la construcci\u00f3n de una realidad mejor para Galicia.<\/p>\n<p style=\"text-align: justify;\">La junta directiva de la Delegaci\u00f3n del COAG en A Coru\u00f1a quiere agradecer la generosa colaboraci\u00f3n de todos los participantes, as\u00ed como del inestimable e imprescindible apoyo recibido, desde el primer momento, \u00a0por la empresa Desarrolla, sin la cual este ciclo no hubiera sido posible.<\/p>\n<p>Carlos Pita.- Presidente de la Delegaci\u00f3n del COAG en A Coru\u00f1a<!--:--><!--:gl--><\/p>\n<p style=\"text-align: justify;\">A Delegaci\u00f3n do Colexio Oficial de Arquitectos de Galicia en A Coru\u00f1a, en colaboraci\u00f3n coa empresa DESARROLLA, inicia con <strong>\u201cFeitos construidos\u201d<\/strong> seu primeiro ciclo de conferencias sobre a realidade constru\u00efda da arquitectura galega contempor\u00e1nea. <strong>Dende o 23 de \u00a0outubro de 2013 ata o 29 de xaneiro de 2014<\/strong>, cada d\u00faas semanas, pola sala da Delegaci\u00f3n pasar\u00e1n \u00a07 equipos de arquitectos, de distintas xeraci\u00f3ns, pra amosarnos o seu traballo fix\u00e1ndose en d\u00faas \u00fanicas obras, seleccionadas e constru\u00eddas por eles mesmos, como expo\u00f1ente do seu facer e pensamento arquitect\u00f3nico.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\" alt=\"\" width=\"620\" height=\"1214\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">O nome de este ciclo de conferencias ven dun p\u00e9 de foto que at\u00f3pase no libro \u00abUne petit maison\u00bb, publicado por Le Corbusier en Editions Girsberger de Zurich no ano 1954. Libro que, como vostedes co\u00f1ecen, o mestre dedica a enorme casi\u00f1a feita pra os seus pa\u00eds nas ribeiras do lago Leman. Ediciones Infinito de Buenos Aires publicou, no 2005, unha edici\u00f3n en espa\u00f1ol. Este mesmo p\u00e9 de foto, coa fondura do significado que cont\u00e9n, deu titulo ao libro\u00a0 \u00abLos hechos de la arquitectura\u00bb, que Ediciones ARQ de Santiago de Chile publicou no 1999, onde Alejandro \u00a0Aravena, Fernando P\u00e9rez e Jos\u00e9 Quintanilla fan un dos m\u00e1is interesantes exercicios \u00a0escritos sobre historia da arquitectura.<\/p>\n<p style=\"text-align: justify;\">Feitos da arquitectura &#8211; Feitos constru\u00eddos. O matiz, si ben \u00e9 importante, tampouco quere \u00a0dicir m\u00e1is do que evidentemente todos entenden . Sobran explicaci\u00f3ns.<\/p>\n<p style=\"text-align: justify;\">O ciclo de conferencias <strong>\u201c13+1 Feitos construidos\u201d<\/strong> nace coa vontade de ser unha cita fixa na axenda \u00a0cultural galega, \u00a0que cos anos v\u00e1iase \u00a0afirmando como un espazo \u00a0onde o feito arquitect\u00f3nico atope o lugar que lle corresponde na definici\u00f3n da construcci\u00f3n dunha realidade \u00a0mellor pra Galicia.<\/p>\n<p style=\"text-align: justify;\">A xunta directiva da Delegaci\u00f3n do COAG na A Coru\u00f1a quere \u00a0agradecer a xenerosa colaboraci\u00f3n de todos os participantes, as\u00ed como do inestimable apoio recibido, dende \u00a0o primeiro momento, \u00a0pola empresa Desarrolla; esteo imprescindible sen o cal este ciclo non ter\u00eda sido posible. Os nosos m\u00e1is agarimosos reco\u00f1ecementos.<\/p>\n<p style=\"text-align: justify;\">Carlos Pita.- Presidente de la Delegaci\u00f3n del COAG en A Coru\u00f1a<\/p>\n<p><!--:--><!--:en--><\/p>\n<p style=\"text-align: justify;\">The Delegation of the Colexio Oficial de Arquitectos de Galicia in A Coru\u00f1a,\u00a0 in collaboration with the company DESARROLLA,initiates with <strong>\u201c13+1 Constructed facts\u201d<\/strong> his first cycle of conferences on the reality constructed of the Galician contemporary architecture. From October 23, 2013 until January 29, 2014, with a twice-weekly periodicity, for the room of the Delegation there will happen 7 equipments of architects, of different generations, who will show us his work centring on two only works selected and constructed by them themselves, as exponent of his to do and architectural thought.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\" alt=\"\" width=\"620\" height=\"1214\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">The name of this cycle of conferences comes from a foot of photo that appears in the book \u00abUne petit maison\u00bb, published by Him Corbusier in Editions Girsberger of Zurich in 1954. Book that, since you know, the teacher dedicates to the \u00abenormous\u00bb house that constructed for his parents on the banks of the Leman lake. An edition exists in Spanish published in 2005 by Editions Immensely of Buenos Aires. The same foot of photo, with the important depth that it contains, gave title to the book \u00bb The facts of the architecture\u00bb, which Editions ARQ of Santiago of Chile published in 1999, and where Alejandro Aravena, Fernando Perez and Jose Quintanilla realize one of them, maybe, more interesting exercises written on history of the architecture.<\/p>\n<p style=\"text-align: justify;\">Facts of the architecture &#8211; Facts constructed. The shade, though it is important, does not also want to say any more than evidently we all deal. They exceed explanations.<\/p>\n<p style=\"text-align: justify;\">The cycle of conferences\u00a0 <strong>\u201c13+1 Constructed facts\u201d<\/strong><strong><\/strong> is born with the will to be a fixed appointment in the cultural Galician agenda, which with the years is steadying itself as a space where the architectural fact should find the place that corresponds to him in the definition of the best construction of a reality for Galicia.<\/p>\n<p style=\"text-align: justify;\">The board of directors of the Delegation of the COAG in A Coru\u00f1a wants to be grateful for the generous collaboration of all the participants, as well as of the inestimable and indispensable received support, from the first moment, for the company DESARROLLA, without which this cycle had not been possible.<\/p>\n<p>Carlos Pita.- President of the Delegation of the COAG in A Coru\u00f1a<\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Delegaci\u00f3n del Colexio Oficial de Arquitectos de Galicia en A Coru\u00f1a, en colaboraci\u00f3n con la empresa DESARROLLA, inicia con \u201c13+1 Hechos construidos\u201d su primer ciclo de conferencias sobre la realidad construida de la arquitectura gallega contempor\u00e1nea. Desde el 23 de octubre de 2013 hasta el 29 de enero de 2014, con una periodicidad bisemanal, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35373,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1385,16],"tags":[66,5865,3242,312,9090,328,3716,5620,357,3462],"class_list":["post-35372","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conferencias","category-eventos","tag-a-coruna","tag-arquitectura-gallega","tag-carlos-pita-abad","tag-ciclo","tag-ciclo-131","tag-coag","tag-colexio-de-arquitectos","tag-concepcion-garcia","tag-conferencia","tag-jorge-meijide"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/131-hechos-construidos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/131-hechos-construidos\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2013-10-19T10:20:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-09T19:50:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"1214\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts\",\"datePublished\":\"2013-10-19T10:20:23+00:00\",\"dateModified\":\"2015-02-09T19:50:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/\"},\"wordCount\":1086,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/01.jpg\",\"keywords\":[\"A Coru\u00f1a\",\"arquitectura gallega\",\"Carlos Pita Abad\",\"ciclo\",\"ciclo 13+1\",\"COAG\",\"colexio de arquitectos\",\"concepci\u00f3n garc\u00eda\",\"conferencia\",\"Jorge Meijide\"],\"articleSection\":[\"conferencias\",\"eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/\",\"name\":\"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/01.jpg\",\"datePublished\":\"2013-10-19T10:20:23+00:00\",\"dateModified\":\"2015-02-09T19:50:13+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/01.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/10\\\/01.jpg\",\"width\":\"620\",\"height\":\"1214\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/131-hechos-construidos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"13+1 Hechos construidos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes","description":"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/","og_locale":"es_ES","og_type":"article","og_title":"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes","og_description":"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts","og_url":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2013-10-19T10:20:23+00:00","article_modified_time":"2015-02-09T19:50:13+00:00","og_image":[{"width":620,"height":1214,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts","datePublished":"2013-10-19T10:20:23+00:00","dateModified":"2015-02-09T19:50:13+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/"},"wordCount":1086,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg","keywords":["A Coru\u00f1a","arquitectura gallega","Carlos Pita Abad","ciclo","ciclo 13+1","COAG","colexio de arquitectos","concepci\u00f3n garc\u00eda","conferencia","Jorge Meijide"],"articleSection":["conferencias","eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/131-hechos-construidos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/","url":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/","name":"13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg","datePublished":"2013-10-19T10:20:23+00:00","dateModified":"2015-02-09T19:50:13+00:00","description":"Toda la informaci\u00f3n sobre: 13+1 Hechos construidos13+1 Feitos construidos13+1 Constructed facts","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/131-hechos-construidos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/10\/01.jpg","width":"620","height":"1214"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/131-hechos-construidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"13+1 Hechos construidos"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/35372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=35372"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/35372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/35373"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=35372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=35372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=35372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}