{"id":30590,"date":"2013-06-10T08:04:49","date_gmt":"2013-06-10T08:04:49","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=30590"},"modified":"2026-08-03T15:20:56","modified_gmt":"2026-08-03T13:20:56","slug":"contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/","title":{"rendered":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga"},"content":{"rendered":"<p><!--:es--><\/p>\n<p style=\"text-align: justify;\">Como arquitectos resulta un suplicio tener que lidiar con los cables a\u00e9reos que encontramos en muchas de nuestras ciudades latinoamericanas, las visuales exteriores quedan obstruidas por una mara\u00f1a de cables que han sido colocados por diversos servicios\u00a0p\u00fablicos\u00a0y en los \u00faltimos a\u00f1os ha ido aumentando, desmereciendo el ornato y la salud p\u00fablica.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-30591\" title=\"Cables-en-postes_480_311\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg\" alt=\"\" width=\"750\" height=\"440\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311-300x176.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De que nos sirven las regulaciones si se permite este cableado abusivo y desconsiderado en nuestras calles. Es lamentable habitar un espacio donde la visual es desmerecida por los cables de diversos servicios que continuan coloc\u00e1ndolos y desmejorando la salud urbana.<\/p>\n<p style=\"text-align: justify;\">Tengamos en cuenta esta situaci\u00f3n para evitar esta tendencia y promover la necesidad de soterrarlos a la brevedad, permitiendo una mejor salubridad en nuestras calles.<\/p>\n<p style=\"text-align: justify;\">A continuaci\u00f3n se exponen unas im\u00e1genes referenciales producto de esta contaminaci\u00f3n\u2026<\/p>\n<div id='gallery-1' class='gallery galleryid-30590 gallery-columns-4 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_01.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_01-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_01-150x150.jpg 150w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_01-120x120.jpg 120w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_02.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_02-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_02-150x150.jpg 150w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_02-120x120.jpg 120w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_03.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_03-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_03-150x150.jpg 150w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/eje_03-120x120.jpg 120w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"120\" height=\"120\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311-150x150.jpg 150w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311-120x120.jpg 120w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n<p>Fernando Freire Forga \u00b7 Doctor Arquitecto<br \/>\nLima \u00b7 junio 2013 \u00b7 Autor del Blog <a href=\"http:\/\/laformamodernaenlatinoamerica.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">La Forma Moderna en Latinoam\u00e9rica<\/a><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como arquitectos resulta un suplicio tener que lidiar con los cables a\u00e9reos que encontramos en muchas de nuestras ciudades latinoamericanas, las visuales exteriores quedan obstruidas por una mara\u00f1a de cables que han sido colocados por diversos servicios\u00a0p\u00fablicos\u00a0y en los \u00faltimos a\u00f1os ha ido aumentando, desmereciendo el ornato y la salud p\u00fablica. De que nos sirven [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":30591,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,5951],"tags":[318,5363,5553,1021,1865],"class_list":["post-30590","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faro","category-slider-principal","tag-ciudad","tag-contaminacion","tag-fernando-freire-forga","tag-pensamiento","tag-reflexion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/La.Forma.Moderna.en.la.Arquitectura\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-10T08:04:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-03T13:20:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Fernando Freire Forga\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LFMlat\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Fernando Freire Forga\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/\"},\"author\":{\"name\":\"Fernando Freire Forga\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/a890bb1d09f43aeb88a6295946b99561\"},\"headline\":\"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\",\"datePublished\":\"2013-06-10T08:04:49+00:00\",\"dateModified\":\"2026-08-03T13:20:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/\"},\"wordCount\":169,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/Cables-en-postes_480_311.jpg\",\"keywords\":[\"ciudad\",\"contaminaci\u00f3n\",\"Fernando Freire Forga\",\"pensamiento\",\"reflexi\u00f3n\"],\"articleSection\":[\"faro\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/\",\"name\":\"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/Cables-en-postes_480_311.jpg\",\"datePublished\":\"2013-06-10T08:04:49+00:00\",\"dateModified\":\"2026-08-03T13:20:56+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/Cables-en-postes_480_311.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2013\\\/04\\\/Cables-en-postes_480_311.jpg\",\"width\":\"620\",\"height\":\"364\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/a890bb1d09f43aeb88a6295946b99561\",\"name\":\"Fernando Freire Forga\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Fernando-Freire-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Fernando-Freire-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Fernando-Freire-96x96.jpg\",\"caption\":\"Fernando Freire Forga\"},\"description\":\"Fernando Freire Forga nace en Lima el 21 de marzo de 1977. Entre los a\u00f1os 1994 y 2000 realiza estudios de arquitectura en la Universidad Peruana de Ciencias Aplicadas en la misma ciudad. En 1999 obtiene el primer premio en el Concurso a nivel nacional organizado por PROCOBRE-PER\u00da con la tesis: Edificio Automatizado de Oficinas: \u201cUsos del Cobre en la Arquitectura\u201d. Ha realizado estudios de Doctorado sobre Arquitectura Moderna en la ETSAB, Escuela T\u00e9cnica Superior de Arquitectura de Barcelona en la Universidad Polit\u00e9cnica de Catalu\u00f1a, Espa\u00f1a. Actualmente , se encuentra inmerso en el desarrollo de trabajos de recopilaci\u00f3n e investigaci\u00f3n de Arquitectura Moderna en el Per\u00fa. Es docente de la Pontificia Universidad Cat\u00f3lica del Per\u00fa y se desenvuelve como proyectista de manera independiente.\",\"sameAs\":[\"https:\\\/\\\/www.fernandofreirearquitecto.pe\\\/\",\"https:\\\/\\\/www.facebook.com\\\/La.Forma.Moderna.en.la.Arquitectura\",\"https:\\\/\\\/www.instagram.com\\\/fernandofreirearquitecto\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/fernando-freire-2a38791a\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/LFMlat\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/fernando-freire-forga\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","description":"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/","og_locale":"es_ES","og_type":"article","og_title":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","og_description":"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","og_url":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/La.Forma.Moderna.en.la.Arquitectura","article_published_time":"2013-06-10T08:04:49+00:00","article_modified_time":"2026-08-03T13:20:56+00:00","og_image":[{"width":620,"height":364,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg","type":"image\/jpeg"}],"author":"Fernando Freire Forga","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/LFMlat","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Fernando Freire Forga","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/"},"author":{"name":"Fernando Freire Forga","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/a890bb1d09f43aeb88a6295946b99561"},"headline":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","datePublished":"2013-06-10T08:04:49+00:00","dateModified":"2026-08-03T13:20:56+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/"},"wordCount":169,"commentCount":1,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg","keywords":["ciudad","contaminaci\u00f3n","Fernando Freire Forga","pensamiento","reflexi\u00f3n"],"articleSection":["faro","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/","url":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/","name":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg","datePublished":"2013-06-10T08:04:49+00:00","dateModified":"2026-08-03T13:20:56+00:00","description":"Toda la informaci\u00f3n sobre: Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2013\/04\/Cables-en-postes_480_311.jpg","width":"620","height":"364"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/contaminacion-visual-en-nuestras-ciudades-fernando-freire-forga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Contaminaci\u00f3n visual en nuestras ciudades | Fernando Freire Forga"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/a890bb1d09f43aeb88a6295946b99561","name":"Fernando Freire Forga","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Fernando-Freire-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Fernando-Freire-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Fernando-Freire-96x96.jpg","caption":"Fernando Freire Forga"},"description":"Fernando Freire Forga nace en Lima el 21 de marzo de 1977. Entre los a\u00f1os 1994 y 2000 realiza estudios de arquitectura en la Universidad Peruana de Ciencias Aplicadas en la misma ciudad. En 1999 obtiene el primer premio en el Concurso a nivel nacional organizado por PROCOBRE-PER\u00da con la tesis: Edificio Automatizado de Oficinas: \u201cUsos del Cobre en la Arquitectura\u201d. Ha realizado estudios de Doctorado sobre Arquitectura Moderna en la ETSAB, Escuela T\u00e9cnica Superior de Arquitectura de Barcelona en la Universidad Polit\u00e9cnica de Catalu\u00f1a, Espa\u00f1a. Actualmente , se encuentra inmerso en el desarrollo de trabajos de recopilaci\u00f3n e investigaci\u00f3n de Arquitectura Moderna en el Per\u00fa. Es docente de la Pontificia Universidad Cat\u00f3lica del Per\u00fa y se desenvuelve como proyectista de manera independiente.","sameAs":["https:\/\/www.fernandofreirearquitecto.pe\/","https:\/\/www.facebook.com\/La.Forma.Moderna.en.la.Arquitectura","https:\/\/www.instagram.com\/fernandofreirearquitecto\/","https:\/\/www.linkedin.com\/in\/fernando-freire-2a38791a\/","https:\/\/x.com\/https:\/\/twitter.com\/LFMlat"],"url":"https:\/\/veredes.es\/blog\/author\/fernando-freire-forga\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/30590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=30590"}],"version-history":[{"count":2,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/30590\/revisions"}],"predecessor-version":[{"id":108337,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/30590\/revisions\/108337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/30591"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=30590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=30590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=30590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}