{"id":28240,"date":"2013-01-18T06:57:58","date_gmt":"2013-01-18T06:57:58","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=28240"},"modified":"2020-05-04T21:02:29","modified_gmt":"2020-05-04T19:02:29","slug":"necropolis-antonio-s-rio-vazquez","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/","title":{"rendered":"<!--:es-->Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez<!--:--><!--:gl-->Necr\u00f3pole | Antonio S. R\u00edo V\u00e1zquez<!--:--><!--:en-->Necropolis | Antonio S. R\u00edo V\u00e1zquez<!--:-->"},"content":{"rendered":"<p><!--:es--><figure id=\"attachment_28241\" aria-describedby=\"caption-attachment-28241\" style=\"width: 620px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28241\" title=\"Interior del barrio alem\u00e1n en Dugway  Fotograf\u00eda de Joe C. Freeman  loc.gov\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\" alt=\"\" width=\"620\" height=\"486\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_-300x235.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-28241\" class=\"wp-caption-text\"><span style=\"color: #888888;\">Interior del barrio alem\u00e1n en Dugway | Fotograf\u00eda de Joe C. Freeman | loc.gov<\/span><\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\">Existen maquetas de arquitectura, ensayos previos a la construcci\u00f3n final d\u00f3nde se concretan, aportando material y tiempo, los t\u00e9rminos que permitir\u00e1n resolver de modo m\u00e1s adecuado el proyecto. Pero tambi\u00e9n existen maquetas anat\u00f3micas, cartogr\u00e1ficas, l\u00fadicas\u2026 que representan o sirven a la vida a escala.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/en.wikipedia.org\/wiki\/Arthur_Nersesian\">Arthur Nersesian<\/a>, en su novela <a href=\"http:\/\/www.alphadecay.org\/libro\/staten-island\"><em>Staten Island<\/em><\/a>, nos presenta un tipo de maqueta muy distinta: Uli, el protagonista, se despierta en medio de una ciudad incivilizada y peligrosa, que va recorriendo hasta descubrir que se trata de una inmensa reproducci\u00f3n de Nueva York emplazada en el coraz\u00f3n del desierto de Nevada. Se trata de la maqueta convertida en experimento, en laboratorio habitable.<\/p>\n<p style=\"text-align: justify;\">Al igual que esa versi\u00f3n de la Gran Manzana, existen maquetas realizadas con fines militares, como decorados de cine proyectados para ser utilizados por actores reales. <a href=\"http:\/\/www.elmundo.es\/elmundo\/2012\/05\/24\/espana\/1337847593.html\">Una aldea<\/a> construida por la Brigada de Infanter\u00eda Ligera en Salcedo, pr\u00f3xima a Pontevedra, imita un poblado afgano a escala 1:1, con sus calles, casas y mezquitas. Una r\u00e9plica fantasma, habitada temporal y teatralmente por los vivos y los posibles muertos.<\/p>\n<p style=\"text-align: justify;\">Aunque los lugares para simulaciones b\u00e9licas son cada vez m\u00e1s abundantes y m\u00e1s \u00abaut\u00e9nticos\u00bb en los mundos virtuales, su presencia en el mundo real constituye uno de los ejemplos m\u00e1s singulares de maquetas, a medio camino entre la escenograf\u00eda y la necr\u00f3polis.<\/p>\n<p style=\"text-align: justify;\">Entre todas ellas destacan de un modo especial los <a href=\"http:\/\/en.wikipedia.org\/wiki\/German_Village_%28Dugway_proving_ground%29\">barrios alem\u00e1n<\/a> y <a href=\"http:\/\/en.wikipedia.org\/wiki\/Japanese_village\">japon\u00e9s<\/a> construidos en 1943 por el ej\u00e9rcito de los Estados Unidos dentro del <a href=\"http:\/\/en.wikipedia.org\/wiki\/Dugway_Proving_Ground\">Dugway Proving Ground<\/a>, en el desierto de Utah. El ej\u00e9rcito reclut\u00f3 en secreto al arquitecto exiliado <a href=\"http:\/\/es.wikipedia.org\/wiki\/Erich_Mendelsohn\">Erich Mendelsohn<\/a>, qui\u00e9n planific\u00f3 una ciudad cuyo destino final era \u2014inevitablemente\u2014 ser destruida.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.guardian.co.uk\/artanddesign\/2003\/may\/12\/architecture.artsfeatures\">La maqueta<\/a> tuvo la precisi\u00f3n del modelo real: los mismos escen\u00f3grafos de la \u00e9poca dorada de Hollywood definieron los interiores hasta el punto de igualar el lino alem\u00e1n de las cortinas o de duplicar los muebles que se empleaban habitualmente como dote matrimonial en las casas del proletariado berlin\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Mendelsohn se preocup\u00f3 de que las maderas empleadas replicaran el envejecimiento y las cualidades espec\u00edficas de las viejas construcciones de su tierra natal. S\u00f3lo as\u00ed pod\u00edan verificar el comportamiento adecuado al incendiarlas. El realismo se llev\u00f3 al nivel de regar los objetivos regularmente para simular la lluvia prusiana en el seco y \u00e1rido clima de Utah.<\/p>\n<p style=\"text-align: justify;\">Paralelamente, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Antonin_Raymond\">Antonin Raymond<\/a> \u2014disc\u00edpulo de Frank Lloyd Wright\u2014 trabaj\u00f3 en el dise\u00f1o del barrio japon\u00e9s, vali\u00e9ndose de su experiencia como conocedor de la arquitectura de Jap\u00f3n, pa\u00eds en el que hab\u00eda vivido antes de la guerra. Pero aqu\u00ed no se trataba de aplicar sus conocimientos como constructor, si no como destructor. Como recordaba en sus memorias \u00abLas partes eran luego armadas en el Proving Ground y sometidas a bombardeo. Inmediatamente despu\u00e9s de ser destruidas, se levantaban otras nuevas, hasta que el resultado fuera satisfactorio\u00bb. Eran edificios completamente reales, amueblados con todos los elementos t\u00edpicos de la casa japonesa, aunque proyectados para los que iban a morir.<\/p>\n<p style=\"text-align: justify;\">La historia de \u00e9stas y otras necr\u00f3polis modernas est\u00e1 magn\u00edficamente contada en el libro de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Mike_Davis_%28scholar%29\">Mike Davis<\/a> <em>Ciudades Muertas. Ecolog\u00eda, cat\u00e1strofe y revuelta<\/em>. Davis relata como todo el complejo de Utah fue dinamitado con <em>thermite<\/em> y <em>napalm<\/em>, y reconstruido completamente por lo menos tres veces entre mayo y septiembre de 1943. La maqueta y la arquitectura se hab\u00edan convertido en herramientas perfectas para la guerra o, quiz\u00e1, es que siempre lo hab\u00edan sido.<\/p>\n<p>antonio s. r\u00edo v\u00e1zquez\u00a0. arquitecto<br \/>\na coru\u00f1a. enero de 2013<!--:--><!--:en--><figure id=\"attachment_28241\" aria-describedby=\"caption-attachment-28241\" style=\"width: 620px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28241\" title=\"Interior del barrio alem\u00e1n en Dugway  Fotograf\u00eda de Joe C. Freeman  loc.gov\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\" alt=\"\" width=\"620\" height=\"486\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_-300x235.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-28241\" class=\"wp-caption-text\"><span style=\"color: #888888;\">Interior of the German neighborhood in Dugway\u00a0| Photography: Joe C. Freeman | loc.gov<\/span><\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\">Models of architecture exist, tests before the final construction where they make concrete, contributing material and time, the terms that will allow to solve in a more suitable way the project. But also there exist anatomical, cartographic, playful models \u2026 that represent or serve to the life to scale.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/en.wikipedia.org\/wiki\/Arthur_Nersesian\">Arthur Nersesian<\/a>,\u00a0in his novel <a href=\"http:\/\/www.alphadecay.org\/libro\/staten-island\"><em>Staten Island<\/em><\/a>, us presents a type of very different model: Uli, the protagonist, wakes up in the middle of an uncivilized and dangerous city, which it is crossing up to discovering that it is a question of an immense reproduction of New York located in the heart of the desert of Nevada. It is a question of the model turned into experiment, into inhabitable laboratory.<\/p>\n<p style=\"text-align: justify;\">As this version of the Great Apple, there exist models realized with military ends, as sets of cinema projected to be used by royal actors. <a href=\"http:\/\/www.elmundo.es\/elmundo\/2012\/05\/24\/espana\/1337847593.html\">A village<\/a> is constructed by the Brigade of Light Infantry in Willow grove, near Pontevedra, imitates an Afghan settlement to scale 1:1, with his streets, houses and mosques. A reply ghost, lived temporary and theatrically for the alive ones and the possible dead men.<\/p>\n<p style=\"text-align: justify;\">Though the places for warlike simulations are increasingly abundant and \u00abmore \u00abauthentic\u00bb in the virtual worlds, his presence in the real world constitutes one of the most singular examples of models, to half a way between the scenery and the necropolis.<\/p>\n<p style=\"text-align: justify;\">Between all of them stand out in a special\u00a0 way the <a href=\"http:\/\/en.wikipedia.org\/wiki\/German_Village_%28Dugway_proving_ground%29\">germany<\/a> and <a href=\"http:\/\/en.wikipedia.org\/wiki\/Japanese_village\">japones<\/a> neighborhoods\u00a0constructed in 1943 by the army of the United States inside the <a href=\"http:\/\/en.wikipedia.org\/wiki\/Dugway_Proving_Ground\">Dugway Proving Ground<\/a>,\u00a0in the desert of Utah.\u00a0The army recruited privately the exiled architect <a href=\"http:\/\/es.wikipedia.org\/wiki\/Erich_Mendelsohn\">Erich Mendelsohn<\/a>, who planned a city which final destination was &#8211; inevitably &#8211; to be destroyed.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.guardian.co.uk\/artanddesign\/2003\/may\/12\/architecture.artsfeatures\">The model<\/a> had the precision of the royal model: the same set designers of the golden epoch of Hollywood defined the interiors up to the point of equalizing the German linen of the curtains or of duplicating the furniture that were used habitually as matrimonial ability in the houses of the Berlin proletariat.<\/p>\n<p style=\"text-align: justify;\">Mendelsohn worried that the used wood was answering the aging and the specific qualities of the old constructions of his natal land. Only this way they could check the behavior adapted on having inflamed them. The realism removed at the level of watering the aims regularly to simulate the Prussian rain in the dry and arid climate of Utah.<\/p>\n<p style=\"text-align: justify;\">Parallel, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Antonin_Raymond\">Antonin Raymond<\/a> -disciple of Frank Lloyd Wright &#8211; was employed at the design of the Japanese neighborhood, using of his experience as connoisseur of the architecture of Japan, country in which it had lived before the war. But here it was not a question of applying his knowledge to him as builder, if not as destroyer. Since he remembered in his memories \u00bb The parts were armed then in the Proving Ground and submitted to bombardment. Immediately after being destroyed, new others were getting up, until the result was satisfactory \u00ab. They were completely royal buildings furnished with all the typical elements of the Japanese house, though projected for those who were going to die.<\/p>\n<p style=\"text-align: justify;\">he history of\u00a0 this and\u00a0other modern necropolis is magnificently counted in book as <a href=\"http:\/\/en.wikipedia.org\/wiki\/Mike_Davis_%28scholar%29\">Mike Davis<\/a> <em>Dead cities. <em>And Other Tales<\/em><\/em>. Davis reports since everything the complex of Utah was dinamitado with thermite and napalm, and reconstructed completely at least three times between May and September, 1943. The model and the architecture had turned into perfect tools for the war or, probably, it is that always they it had been.<\/p>\n<p>antonio s. r\u00edo v\u00e1zquez . architect<br \/>\na coru\u00f1a. january 2013<\/p>\n<p><!--:--><!--:gl--><figure id=\"attachment_28241\" aria-describedby=\"caption-attachment-28241\" style=\"width: 620px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28241\" title=\"Interior del barrio alem\u00e1n en Dugway  Fotograf\u00eda de Joe C. Freeman  loc.gov\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\" alt=\"\" width=\"620\" height=\"486\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_-300x235.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><figcaption id=\"caption-attachment-28241\" class=\"wp-caption-text\"><span style=\"color: #888888;\">Interior do barrio alem\u00e1n en Dugway | Fotograf\u00eda: Joe C. Freeman | loc.gov<\/span><\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\">Existen maquetas de arquitectura, ensaios previos \u00e1 construci\u00f3n final onde se concretan, aportando material e tempo, os t\u00e9rminos que permitir\u00e1n resolver de modo m\u00e1is adecuado o proxecto. Pero tam\u00e9n existen maquetas anat\u00f3micas, cartogr\u00e1ficas, l\u00fadicas\u2026 que representan ou serven \u00e1 vida a escala.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/en.wikipedia.org\/wiki\/Arthur_Nersesian\">Arthur Nersesian<\/a>,\u00a0na s\u00faa novela <a href=\"http:\/\/www.alphadecay.org\/libro\/staten-island\"><em>Staten Island<\/em><\/a>, pres\u00e9ntanos un tipo de maqueta moi distinta: Uli, o protagonista, esp\u00e9rtase no medio dunha cidade incivilizada e perigosa, que vai percorrendo ata descubrir que se trata dunha inmensa reproduci\u00f3n de Nova York emplazada no coraz\u00f3n do deserto de Nevada. Tr\u00e1tase da maqueta convertida en experimento, en laboratorio habitable.<\/p>\n<p style=\"text-align: justify;\">Do mesmo xeito que esa versi\u00f3n da Gran Maz\u00e1, existen maquetas realizadas con fins militares, como decorados de cine proxectados para ser utilizados por actores reais. <a href=\"http:\/\/www.elmundo.es\/elmundo\/2012\/05\/24\/espana\/1337847593.html\">Unha aldea<\/a> pola Brigada de Infanter\u00eda Lixeira en Salcedo, pr\u00f3xima a Pontevedra, imita un poboado afgano a escala 1:1, coas s\u00faas r\u00faas, casas e mezquitas. Unha r\u00e9plica pantasma, habitada temporal e teatralmente polos vivos e os posibles mortos.<\/p>\n<p style=\"text-align: justify;\">A\u00ednda que os lugares para simulaciones b\u00e9licas son cada vez m\u00e1is abundantes e m\u00e1is \u00abaut\u00e9nticos\u00bb nos mundos virtuales, a s\u00faa presenza no mundo real constit\u00fae un dos exemplos m\u00e1is singulares de maquetas, a medio cami\u00f1o entre a escenograf\u00eda e a necr\u00f3poles.<\/p>\n<p style=\"text-align: justify;\">Entre todas elas destacan dun modo especial os <a href=\"http:\/\/en.wikipedia.org\/wiki\/German_Village_%28Dugway_proving_ground%29\">barrios alem\u00e1ns<\/a> e <a href=\"http:\/\/en.wikipedia.org\/wiki\/Japanese_village\">xapon\u00e9s<\/a> construidos en 1943 polo ex\u00e9rcito dos Estados Unidos dentro do <a href=\"http:\/\/en.wikipedia.org\/wiki\/Dugway_Proving_Ground\">Dugway Proving Ground<\/a>, no deserto de Utah. O ex\u00e9rcito reclutou en segredo o arquitecto exiliado <a href=\"http:\/\/es.wikipedia.org\/wiki\/Erich_Mendelsohn\">Erich Mendelsohn<\/a>, qu\u00e9n planificou unha cidade cuio destino final era \u2014inevitablemente\u2014 ser destruida.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.guardian.co.uk\/artanddesign\/2003\/may\/12\/architecture.artsfeatures\">A maqueta<\/a> tivo a precisi\u00f3n do modelo real: os mesmos escen\u00f3grafos da \u00e9poca dourada de Hollywood definiron os interiores ata o punto de igualar o lino alem\u00e1n das cortinas ou de duplicar os mobles que se empleaban habitualmente como dote matrimonial nas casas do proletariado berlin\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Mendelsohn preocupouse de que as madeiras empregadas replicasen o envejecimiento e as calidades espec\u00edficas das vellas construci\u00f3ns da s\u00faa terra natal. S\u00f3 as\u00ed pod\u00edan verificar o comportamento adecuado ao incendialas. O realismo levouse ao nivel de regar os obxectivos regularmente para simular a choiva prusiana no seco e \u00e1rido clima de Utah.<\/p>\n<p style=\"text-align: justify;\">Paralelamente, <a href=\"http:\/\/en.wikipedia.org\/wiki\/Antonin_Raymond\">Antonin Raymond<\/a> \u2014disc\u00edpulo de Frank Lloyd Wright\u2014 traballou no dese\u00f1o do barrio xapon\u00e9s, val\u00e9ndose da s\u00faa experiencia como co\u00f1ecedor da arquitectura de Xap\u00f3n, pa\u00eds no que vivira antes da guerra. Pero aqu\u00ed non se trataba de aplicar os seus co\u00f1ecementos como constructor, si non como destructor. Como recordaba nas s\u00faas memorias \u00abAs partes eran logo armadas no Proving Ground e sometidas a bombardeo. Inmediatamente logo de ser destru\u00eddas, levant\u00e1banse outras novas, ata que o resultado fose satisfactorio\u00bb. Eran edificios completamente reais, amueblados con todos os elementos t\u00edpicos da casa xaponesa, a\u00ednda que proxectados para os que \u00edan morrer.<\/p>\n<p style=\"text-align: justify;\">A historia destas e outras necr\u00f3poles modernas est\u00e1 magn\u00edficamente contada no libro de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Mike_Davis_%28scholar%29\">Mike Davis<\/a> <em>Ciudades Mortas. Ecolox\u00eda, cat\u00e1strofe e revolta<\/em>. Davis relata como todo o complejo de Utah foi dinamitado con <em>thermite<\/em> e <em>napalm<\/em>, e reconstru\u00eddo completamente polo menos tres veces entre maio e setembro de 1943. A maqueta e a arquitectura convert\u00e9ronse en ferramentas perfectas para a guerra ou, quiz\u00e1, \u00e9 que sempre o foron.<\/p>\n<p>antonio s. r\u00edo v\u00e1zquez . arquitecto<br \/>\na coru\u00f1a. xaneiro de 2013<\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Existen maquetas de arquitectura, ensayos previos a la construcci\u00f3n final d\u00f3nde se concretan, aportando material y tiempo, los t\u00e9rminos que permitir\u00e1n resolver de modo m\u00e1s adecuado el proyecto. Pero tambi\u00e9n existen maquetas anat\u00f3micas, cartogr\u00e1ficas, l\u00fadicas\u2026 que representan o sirven a la vida a escala. Arthur Nersesian, en su novela Staten Island, nos presenta un tipo [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":28241,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[95,6675,4024,6673,6474,195,318,6674,5139,1575,828,6676,1823],"class_list":["post-28240","post","type-post","status-publish","format-standard","has-post-thumbnail","category-articulos","category-slider-principal","tag-alemania","tag-antonin-raymond","tag-antonio-s-rio-vazquez","tag-arthur-nersesian","tag-articulo","tag-barrio","tag-ciudad","tag-decorado","tag-erich-mendelsohn","tag-japon","tag-maqueta","tag-mike-davis","tag-utah"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ariovazquez\" \/>\n<meta property=\"article:published_time\" content=\"2013-01-18T06:57:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-04T19:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio S. R\u00edo V\u00e1zquez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/ariovazquez\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio S. R\u00edo V\u00e1zquez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/\"},\"author\":{\"name\":\"Antonio S. R\u00edo V\u00e1zquez\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/cd1e20b1fe2cdb8bf8f1333e323b7149\"},\"headline\":\"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez\",\"datePublished\":\"2013-01-18T06:57:58+00:00\",\"dateModified\":\"2020-05-04T19:02:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/\"},\"wordCount\":1873,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\",\"keywords\":[\"Alemania\",\"Antonin Raymond\",\"Antonio S. R\u00edo V\u00e1zquez\",\"Arthur Nersesian\",\"art\u00edculo\",\"barrio\",\"ciudad\",\"decorado\",\"Erich Mendelsohn\",\"Jap\u00f3n\",\"maqueta\",\"Mike Davis\",\"utah\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/\",\"name\":\"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\",\"datePublished\":\"2013-01-18T06:57:58+00:00\",\"dateModified\":\"2020-05-04T19:02:29+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/12\\\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg\",\"width\":\"620\",\"height\":\"486\",\"caption\":\"Interior del barrio alem\u00e1n en Dugway | Fotograf\u00eda de Joe C. Freeman | loc.gov\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/necropolis-antonio-s-rio-vazquez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/cd1e20b1fe2cdb8bf8f1333e323b7149\",\"name\":\"Antonio S. R\u00edo V\u00e1zquez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg\",\"caption\":\"Antonio S. R\u00edo V\u00e1zquez\"},\"description\":\"Antonio S. R\u00edo V\u00e1zquez (A Coru\u00f1a, 1981) es arquitecto por la E.T.S.A. de A Coru\u00f1a, master en Urbanismo y doctor por la Universidade da Coru\u00f1a, d\u00f3nde ejerce su labor como docente e investigador. Especializado en teor\u00eda y dise\u00f1o, su l\u00ednea de trabajo se ha centrado en la investigaci\u00f3n y divulgaci\u00f3n del patrimonio arquitect\u00f3nico moderno, desarrollando proyectos a diferentes escalas de modo independiente o en colaboraci\u00f3n con varios estudios. Profesor en el Departamento de Proyectos Arquitect\u00f3nicos, Urbanismo y Composici\u00f3n de la Universidade da Coru\u00f1a, imparte las asignaturas Introducci\u00f3n a la Arquitectura, Historia de la Arquitectura, Paisaje Cultural y T\u00e9cnicas de Investigaci\u00f3n y Documentaci\u00f3n en Arquitectura. Profesor invitado en la Robert Gordon University de Aberdeen (Reino Unido), en la Universidade do Minho (Portugal) y en la Universit\u00e0 degli Studi di Roma La Sapienza (Italia). Director del proyecto de investigaci\u00f3n \u00abHistoria de la restauraci\u00f3n y puesta en valor del patrimonio arquitect\u00f3nico en Galicia\u00bb, becado por la Diputaci\u00f3n Provincial de A Coru\u00f1a en el a\u00f1o 2007. Miembro de la red UEDXX Urbanism of European Dictatorships during the XXth Century, del Grupo de Investigaci\u00f3n en Historia de la Arquitectura y del Grupo de Innovaci\u00f3n Docente en Historia de la Arquitectura. Los resultados de sus investigaciones, tanto personales como conjuntas, han servido como aportaci\u00f3n a varios seminarios, jornadas, congresos y otros eventos de difusi\u00f3n cient\u00edfica nacionales e internacionales y han sido publicados en libros y revistas.\",\"sameAs\":[\"https:\\\/\\\/asrv.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/ariovazquez\",\"https:\\\/\\\/www.instagram.com\\\/antonio_rio_vazquez\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ariovazquez\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/ariovazquez\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/antonio-s-rio-vazquez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez","description":"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/","og_locale":"es_ES","og_type":"article","og_title":"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez","og_description":"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez","og_url":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/ariovazquez","article_published_time":"2013-01-18T06:57:58+00:00","article_modified_time":"2020-05-04T19:02:29+00:00","og_image":[{"width":620,"height":486,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg","type":"image\/jpeg"}],"author":"Antonio S. R\u00edo V\u00e1zquez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/ariovazquez","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Antonio S. R\u00edo V\u00e1zquez","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/"},"author":{"name":"Antonio S. R\u00edo V\u00e1zquez","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/cd1e20b1fe2cdb8bf8f1333e323b7149"},"headline":"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez","datePublished":"2013-01-18T06:57:58+00:00","dateModified":"2020-05-04T19:02:29+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/"},"wordCount":1873,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg","keywords":["Alemania","Antonin Raymond","Antonio S. R\u00edo V\u00e1zquez","Arthur Nersesian","art\u00edculo","barrio","ciudad","decorado","Erich Mendelsohn","Jap\u00f3n","maqueta","Mike Davis","utah"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/","url":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/","name":"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg","datePublished":"2013-01-18T06:57:58+00:00","dateModified":"2020-05-04T19:02:29+00:00","description":"Toda la informaci\u00f3n sobre: Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquezNecr\u00f3pole | Antonio S. R\u00edo V\u00e1zquezNecropolis | Antonio S. R\u00edo V\u00e1zquez","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/12\/Interior-del-barrio-alem\u00e1n-en-Dugway-Fotograf\u00eda-de-Joe-C.-Freeman-loc.gov_.jpg","width":"620","height":"486","caption":"Interior del barrio alem\u00e1n en Dugway | Fotograf\u00eda de Joe C. Freeman | loc.gov"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/necropolis-antonio-s-rio-vazquez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Necr\u00f3polis | Antonio S. R\u00edo V\u00e1zquez"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/cd1e20b1fe2cdb8bf8f1333e323b7149","name":"Antonio S. R\u00edo V\u00e1zquez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Antonio-S.-R\u00edo-V\u00e1zquez-96x96.jpg","caption":"Antonio S. R\u00edo V\u00e1zquez"},"description":"Antonio S. R\u00edo V\u00e1zquez (A Coru\u00f1a, 1981) es arquitecto por la E.T.S.A. de A Coru\u00f1a, master en Urbanismo y doctor por la Universidade da Coru\u00f1a, d\u00f3nde ejerce su labor como docente e investigador. Especializado en teor\u00eda y dise\u00f1o, su l\u00ednea de trabajo se ha centrado en la investigaci\u00f3n y divulgaci\u00f3n del patrimonio arquitect\u00f3nico moderno, desarrollando proyectos a diferentes escalas de modo independiente o en colaboraci\u00f3n con varios estudios. Profesor en el Departamento de Proyectos Arquitect\u00f3nicos, Urbanismo y Composici\u00f3n de la Universidade da Coru\u00f1a, imparte las asignaturas Introducci\u00f3n a la Arquitectura, Historia de la Arquitectura, Paisaje Cultural y T\u00e9cnicas de Investigaci\u00f3n y Documentaci\u00f3n en Arquitectura. Profesor invitado en la Robert Gordon University de Aberdeen (Reino Unido), en la Universidade do Minho (Portugal) y en la Universit\u00e0 degli Studi di Roma La Sapienza (Italia). Director del proyecto de investigaci\u00f3n \u00abHistoria de la restauraci\u00f3n y puesta en valor del patrimonio arquitect\u00f3nico en Galicia\u00bb, becado por la Diputaci\u00f3n Provincial de A Coru\u00f1a en el a\u00f1o 2007. Miembro de la red UEDXX Urbanism of European Dictatorships during the XXth Century, del Grupo de Investigaci\u00f3n en Historia de la Arquitectura y del Grupo de Innovaci\u00f3n Docente en Historia de la Arquitectura. Los resultados de sus investigaciones, tanto personales como conjuntas, han servido como aportaci\u00f3n a varios seminarios, jornadas, congresos y otros eventos de difusi\u00f3n cient\u00edfica nacionales e internacionales y han sido publicados en libros y revistas.","sameAs":["https:\/\/asrv.es\/","https:\/\/www.facebook.com\/ariovazquez","https:\/\/www.instagram.com\/antonio_rio_vazquez\/","https:\/\/www.linkedin.com\/in\/ariovazquez\/","https:\/\/x.com\/https:\/\/twitter.com\/ariovazquez"],"url":"https:\/\/veredes.es\/blog\/author\/antonio-s-rio-vazquez\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/28240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=28240"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/28240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/28241"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=28240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=28240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=28240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}