{"id":27776,"date":"2012-11-29T06:42:47","date_gmt":"2012-11-29T06:42:47","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=27776"},"modified":"2015-02-07T17:28:17","modified_gmt":"2015-02-07T17:28:17","slug":"cancha","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/cancha\/","title":{"rendered":"Cancha"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\">El pabell\u00f3n de Chile a la 13. Muestra Internacional de Arquitectura de la Biennale di Venezia, invita a\u00a0 reflexionar sobre suelo, en t\u00e9rminos de recursos, patrimonio y paisaje, y la importancia de la visi\u00f3n disciplinar sobre su explotaci\u00f3n y\/o preservaci\u00f3n, considerando variables mas all\u00e1 de los factores econ\u00f3micos contingentes puros.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-27778\" title=\"Cancha-Pdfbook\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg\" alt=\"\" width=\"620\" height=\"763\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg 620w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook-243x300.jpg 243w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La palabra quechua <em>CANCHA<\/em> pre-colombino de origen incaico en uso vigente en toda Sur Am\u00e9rica, designa un territorio de juego que preserva la sacralidad, y define en su origen los lineamientos principales en la organizaci\u00f3n urbana, la medici\u00f3n y justa distribuci\u00f3n de las cosechas y la comprensi\u00f3n de la existencia de espacios de uso colectivo que prioriza el orden social sobre el inter\u00e9s individual, y cuyos\u00a0 conceptos asociados se presentan la segunda inflexi\u00f3n y el principal problema, <em>\u00bfC\u00f3mo mostrar una reflexi\u00f3n disciplinar en torno a la arquitectura?<\/em><\/p>\n<p style=\"text-align: justify;\">El Isolotto de l\u2019Arsenale se construye entre 1170 y 1300 y protagoniza el canto XXI del Infierno de La Divina Comedia de Dante, y posteriormente se menciona por Galileo en su \u201c<em>Debido lezioni all\u2019Accademia Fiorentina\u201d<\/em> alrededor de \u201c<em>La Figura, sito e Grandezza dell\u2019Inferno di Dante\u201d, <\/em>ambos textos revisados m\u00e1s de 500 a\u00f1os despu\u00e9s por el fallecido poeta argentino Godofredo Iommi, uno de los fundadores de la Escuela de Arquitectura de la Universidad Cat\u00f3lica de Valpara\u00edso. Chile en su texto \u201c<em>Una digresi\u00f3n acerca de Galileo\u201d<\/em> y en el que la sal nos vuelve al propio origen de la ciudad de Venecia, que fuera una explotaci\u00f3n salina durante la \u00e9poca romana y posteriormente el lugar del control comercial de la Sal del Adri\u00e1tico, en una curiosa traslaci\u00f3n cultural y pol\u00edtica, reflejo inevitable de los movimientos temporales, econ\u00f3micos, pol\u00edticos, sociales y por supuesto culturales.<\/p>\n<p style=\"text-align: justify;\">Este espacio m\u00e1s all\u00e1 del tiempo\u00a0 se concibe como un <em>chiaroscuro<\/em> barroco de gran intensidad, donde todos los elementos son neutros salvo la luz de siete expositores cada uno dedicado a un arquitecto que dirigen su luz hacia un suelo de 12,9m3 de sal tra\u00edda por barco desde el Salar de Tarapac\u00e1 en Chile, sobre el cual las diferencias entre los siete arquitectos seleccionados no dejan de existir, sino que dejan de importar invitando a comprender la complejidad de un territorio pr\u00e1cticamente vac\u00edo, expresando los dos opuestos espaciales de la cancha en relaci\u00f3n a nuestro territorio: la necesidad de acotar y cerrar en el desierto del norte, y abrir y despejar en nuestros bosques del sur.<\/p>\n<p style=\"text-align: justify;\"><strong>El Atlas <\/strong><\/p>\n<p style=\"text-align: justify;\">La curadur\u00eda deriva del rol otorgado al naturalista franc\u00e9s Claude Gay, quien en 1830 realizara por encargo del \u00a0gobierno de Chile un primer levantamiento territorial, etnogr\u00e1fico, biol\u00f3gico y de recursos de la nueva rep\u00fablica post colonial: \u00bfHasta d\u00f3nde llegaba Chile?\u00bfQu\u00e9 se pod\u00eda encontrar en \u00e9l? \u00bfC\u00f3mo se desenvolv\u00edan sus habitantes sobre el territorio?. Gay acometi\u00f3 la empresa reuniendo a diversos especialistas para una construcci\u00f3n colectiva de un primer Atlas (Pintoresco) de Chile, en flora, fauna, cartograf\u00eda, historia e ilustraci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Siendo \u00a0representante de la deslocalizaci\u00f3n posibilitada por la tecnolog\u00eda (la mitad del equipo vive en Chile, la otra mitad en Espa\u00f1a, muchos colaboradores en distintos pa\u00edses y la obra se realiza en Italia), invitamos\u00a0 a\u00a0<strong>7 arquitectos: Alejandro Aravena (Elemental), Pedro Alonso, Juan Pablo Corval\u00e1n (junto a Susuka y Jos\u00e9 Abasolo), Genaro Cuadros, Germ\u00e1n del Sol, Iv\u00e1n Ivelic y Rodrigo Tisi, <\/strong>como relatores e ilustradores de nuestro actual territorio, desde su propio lenguaje y enfoque, convocados a pensar, describir y ensayar el estado actual suelo de Chile desarrollando un material in\u00e9dito para la <em>Biennale<\/em>, que \u00a0se complement\u00f3 con un corto documental realizado por Crist\u00f3bal Palma, construyendo nuestra Cancha, esa que se coloniza, se reparte, se tranza y es parte de un todo que incluye al animal, el \u00e1rbol y la persona tal como lo ve\u00edan los antiguos Mapuches, los hombres del suelo que habitan el sur de Chile.<\/p>\n<p><iframe loading=\"lazy\" id=\"doc_45046\" src=\"http:\/\/www.scribd.com\/embeds\/114194901\/content?start_page=1&amp;view_mode=book&amp;access_key=key-77v8pqja3d4l5waw26l\" frameborder=\"0\" scrolling=\"no\" width=\"600\" height=\"600\" data-auto-height=\"true\" data-aspect-ratio=\"0.802356020942408\"><\/iframe><\/p>\n<p style=\"text-align: justify;\">Cr\u00e9ditos Pabell\u00f3n de Chile:<br \/>\nCuradores y arquitectos del montaje: Mar\u00eda Pilar Pinchart Saavedra (Pinchart Arquitectos) y Bernardo Vald\u00e9s Echenique (Mapa Consultores).<br \/>\nComisario: Crist\u00f3bal Molina Baeza (Consejo Nacional de la Cultura y las Artes).<br \/>\nDirecci\u00f3n de Arte: Isaac Gimeno Pujabet &#8211; Loreto Varela Morey.<br \/>\nDirecci\u00f3n de Arte en fase de concurso: Esteban Iglesias Francheteau (Mim\u00e9tico).<br \/>\nFotograf\u00eda y documentales: Crist\u00f3bal Palma Dom\u00ednguez.<br \/>\nEscultura de Ne\u00f3n: Iv\u00e1n Navarro Carvacho &#8211; Pedro Pulido Anker.<br \/>\nArquitecto y productor local: Luigi D&#8217;Oro.<br \/>\nConsultor\u00eda de iluminaci\u00f3n: Interdesign (Chile).<br \/>\nDesarrolladores web: DID.<br \/>\nColaboradores: Sof\u00eda Quiroga Fern\u00e1ndez (Pinchart Architects), Mapa Consultores,\u00a0 Alfonso D\u00edaz Manr\u00edquez (Oficina de Asuntos Culturales, DIRAC), Santiago Elordi Mena y Ana de Pari (Embajada de Chile en Italia), Mar\u00eda Aparicio Puentes, Mariana Sanfuentes Astaburuaga y Francisco Adriasola Caro (CNCA).<br \/>\nTraducciones: Ana Mar\u00eda Sanhueza Jardel.<br \/>\nMedia Partners: Plataforma Arquitectura, Edgar Gonz\u00e1lez.<br \/>\nOrganizador: Consejo Nacional de la Cultura y las Artes.<br \/>\nAuspiciadores: Direcci\u00f3n de Asuntos Culturales (DIRAC) y ProChile del Ministerio de Relaciones Exteriores, Fundaci\u00f3n Imagen de Chile, SPL (Sal Punta Lobos) e Interdesign.<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>El pabell\u00f3n de Chile a la 13. Muestra Internacional de Arquitectura de la Biennale di Venezia, invita a\u00a0 reflexionar sobre suelo, en t\u00e9rminos de recursos, patrimonio y paisaje, y la importancia de la visi\u00f3n disciplinar sobre su explotaci\u00f3n y\/o preservaci\u00f3n, considerando variables mas all\u00e1 de los factores econ\u00f3micos contingentes puros. La palabra quechua CANCHA pre-colombino [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27778,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26,5951],"tags":[6549,211,309,972,2787,5715],"class_list":{"0":"post-27776","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-libros","8":"category-publicaciones","9":"category-slider-principal","10":"tag-bernardo-valdes","11":"tag-bienal-de-venecia","12":"tag-chile","13":"tag-pabellon","14":"tag-patrimonio-cultural","15":"tag-pilar-pinchart"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CanchaCanchaCancha - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: CanchaCanchaCancha\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/cancha\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CanchaCanchaCancha - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: CanchaCanchaCancha\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/cancha\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-29T06:42:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-07T17:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"763\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Cancha\",\"datePublished\":\"2012-11-29T06:42:47+00:00\",\"dateModified\":\"2015-02-07T17:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/\"},\"wordCount\":2526,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Cancha-Pdfbook.jpg\",\"keywords\":[\"Bernardo Vald\u00e9s\",\"bienal de Venecia\",\"Chile\",\"pabell\u00f3n\",\"patrimonio cultural\",\"Pilar Pinchart\"],\"articleSection\":[\"libros\",\"publicaciones\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/\",\"name\":\"CanchaCanchaCancha - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Cancha-Pdfbook.jpg\",\"datePublished\":\"2012-11-29T06:42:47+00:00\",\"dateModified\":\"2015-02-07T17:28:17+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: CanchaCanchaCancha\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Cancha-Pdfbook.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/11\\\/Cancha-Pdfbook.jpg\",\"width\":\"620\",\"height\":\"763\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/cancha\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cancha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CanchaCanchaCancha - veredes","description":"Toda la informaci\u00f3n sobre: CanchaCanchaCancha","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/cancha\/","og_locale":"es_ES","og_type":"article","og_title":"CanchaCanchaCancha - veredes","og_description":"Toda la informaci\u00f3n sobre: CanchaCanchaCancha","og_url":"https:\/\/veredes.es\/blog\/cancha\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2012-11-29T06:42:47+00:00","article_modified_time":"2015-02-07T17:28:17+00:00","og_image":[{"width":620,"height":763,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"13 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/cancha\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/cancha\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Cancha","datePublished":"2012-11-29T06:42:47+00:00","dateModified":"2015-02-07T17:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/cancha\/"},"wordCount":2526,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/cancha\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg","keywords":["Bernardo Vald\u00e9s","bienal de Venecia","Chile","pabell\u00f3n","patrimonio cultural","Pilar Pinchart"],"articleSection":["libros","publicaciones","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/cancha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/cancha\/","url":"https:\/\/veredes.es\/blog\/cancha\/","name":"CanchaCanchaCancha - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/cancha\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/cancha\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg","datePublished":"2012-11-29T06:42:47+00:00","dateModified":"2015-02-07T17:28:17+00:00","description":"Toda la informaci\u00f3n sobre: CanchaCanchaCancha","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/cancha\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/cancha\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/cancha\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/11\/Cancha-Pdfbook.jpg","width":"620","height":"763"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/cancha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Cancha"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/27776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=27776"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/27776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/27778"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=27776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=27776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=27776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}