{"id":21312,"date":"2012-04-09T05:12:16","date_gmt":"2012-04-09T05:12:16","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=21312"},"modified":"2018-11-02T18:04:02","modified_gmt":"2018-11-02T17:04:02","slug":"historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/","title":{"rendered":"<!--:es-->Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez<!--:--><!--:gl-->Historia da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mez<!--:--><!--:en-->History of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez<!--:-->"},"content":{"rendered":"<p><!--:es--><\/p>\n<p style=\"text-align: justify;\">Sinsal ha programado dos conferencias para Espacio Sirvent en las que plantear\u00e1n una introducci\u00f3n al arte y paisaje sonoro bajo el t\u00edtulo Historia del Paisaje Sonoro: un recorrido por la historia a trav\u00e9s de sus sonidos. Espacio Sirvent abre sus puertas a la celebraci\u00f3n del d\u00e9cimo aniversario de Sinsal Julio G\u00f3mez y Juan Gil presentar\u00e1n en dos jornadas un recorrido por la historia del sonido cuyo punto de inflexi\u00f3n sit\u00faan en la primera grabaci\u00f3n realizada por Thomas Edison.<\/p>\n<p style=\"text-align: justify;\">El Festival Sinsal cumple este a\u00f1o su d\u00e9cimo aniversario y, para celebrarlo, realizar\u00e1 una serie de eventos en diferentes espacios de la ciudad. Adem\u00e1s de su programaci\u00f3n musical, el Festival Sinsal 2012 incluir\u00e1 otras actividades vinculadas a la difusi\u00f3n y conocimiento del patrimonio sonoro. En este contexto, y en colaboraci\u00f3n con el Espacio Sirvent, presentar\u00e1 dos conferencias de introducci\u00f3n al arte y paisaje sonoro que tendr\u00e1n lugar los d\u00edas 12 y 26 de abril a las 20:00 horas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-21313\" title=\"sonido01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\" alt=\"\" width=\"620\" height=\"423\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg 400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01-300x204.jpg 300w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La primera de ellas, impartida por Julio G\u00f3mez, girar\u00e1 en relaci\u00f3n a la historia del sonido antes del nacimiento de la grabaci\u00f3n a finales del siglo XIX por el inventor Thomas Edison. En esta introducci\u00f3n, plantear\u00e1 c\u00f3mo la historiograf\u00eda y la arqueolog\u00eda modernas, debido al papel cada vez m\u00e1s preponderante de la percepci\u00f3n sonora, investigan en el pasado para analizar ac\u00fasticamente a las sociedades que nos precedieron: iremos hasta Stonehenge y nos preguntaremos si all\u00ed naci\u00f3 la primera sala de conciertos hace 5000 a\u00f1os; tambi\u00e9n buscaremos las primeras marcas sonoras entre los emblemas de los caballeros feudales; pasearemos por los sofisticados y sensoriales jardines barrocos; y nos detendremos en los silencios c\u00f3mplices de la pintura flamenca.<\/p>\n<p style=\"text-align: justify;\">Por su parte, en la segunda de las conferencias a cargo del music\u00f3logo Juan Gil, se reflexionar\u00e1 sobre el papel que juega el sonido en la sociedad contempor\u00e1nea, desde los or\u00edgenes del registro sonoro a finales del siglo XIX. Nos aproximaremos al arte sonoro, una de las disciplinas m\u00e1s desconocidas del arte a pesar del reciente premio Turner 2010 de la escocesa Susan Philipsz. Analizaremos la obra de algunos de sus artistas m\u00e1s representativos, buscando aplicaciones pr\u00e1cticas en la vida cotidiana y recordando c\u00f3mo cada vez m\u00e1s, nuestra sociedad est\u00e1 expuesta al dise\u00f1o sonoro en la arquitectura, el urbanismo o el marketing comercial.<\/p>\n<p style=\"text-align: justify;\">En ambas sesiones, diferentes v\u00eddeos y ejemplos pr\u00e1cticos guiar\u00e1n al p\u00fablico de forma entretenida por los entresijos del sonido. Cada una de las conferencias complementar\u00e1 su actividad con varias pr\u00e1cticas que ayudar\u00e1n a reflexionar sobre el sonido y su papel en nuestra sociedad. As\u00ed, desde el punto de vista de la grabaci\u00f3n se registrar\u00e1 un cilindro de cera tal y como se realiz\u00f3 durante las primeras d\u00e9cadas del siglo XX. Mientras, en la segunda sesi\u00f3n, se dibujar\u00e1 un mapa sonoro colectivo de Vigo con aquellos sonidos que han desaparecido recientemente o lo har\u00e1n en los pr\u00f3ximos a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">M\u00e1s all\u00e1 de las propuestas de Sinsal para el mes de abril, Espacio Sirvent prepara para mayo y junio dos nuevas actos a cargo de la dise\u00f1adora Nani Marquina y el arquitecto Eduardo Souto de Moura, ganador del premio Pritzker el pasado a\u00f1o 2.011.<\/p>\n<p style=\"text-align: justify;\">Julio G\u00f3mez es gestor cultural, investigador sonoro y comisario musical. Cr\u00edtico musical en los a\u00f1os ochenta y noventa para diferentes medios de comunicaci\u00f3n como Radio 4 de RNE, Radio Ecca, Faro de Vigo o Diario 16 de Galicia. Desde hace diez a\u00f1os codirige la promotora y agencia Sinsalaudio de Vigo. Es coordinador del Festival Sinsal y director de A Escola Sinsal, el \u00fanico proyecto pedag\u00f3gico dedicado a la educaci\u00f3n sobre el Registro Sonoro. Es miembro del colectivo gallego escoitar.org, que en la actualidad est\u00e1 trabajando en el primer mapa sonoro europeo junto a la Universidad TAMK de Finlandia, el laboratorio de arquitectura ac\u00fastica Cresson en Francia y la fonoteca m\u00e1s antigua de Europa, Phonogrammarchiv de Austria.<\/p>\n<p style=\"text-align: justify;\">Juan Gil es music\u00f3logo e investigador sonoro. Forma parte de los proyectos mediateletipos.net y artesornoro.org. En los \u00faltimos a\u00f1os ha desarrollado diversas investigaciones tanto en el campo de la etnomusicolog\u00eda como en el de la m\u00fasica contempor\u00e1nea. Actualmente est\u00e1 doctorando en arte y m\u00fasica y est\u00e1 realizando su tesis sobre auralidad, paisaje sonoro y la utilizaci\u00f3n de sonidos ambientales en la creaci\u00f3n sonora contempor\u00e1nea dentro del Grupo de Investigaci\u00f3n DX7 Tracker. Es miembro del colectivo gallego escoitar.org, que en la actualidad est\u00e1 trabajando en el primer mapa sonoro europeo junto a la Universidad TAMK de Finlandia, el laboratorio de arquitectura ac\u00fastica Cresson en Francia y la fonoteca m\u00e1s antigua de Europa, Phonogrammarchiv de Austria.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\">HISTORIA DEL PAISAJE SONORO: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez<\/span><br \/>\n<span style=\"color: #888888;\"> 12 de Abril a las 20,00 horas<\/span><br \/>\n<span style=\"color: #888888;\"> Espacio Sirvent<\/span><br \/>\n<span style=\"color: #888888;\"> Gran V\u00eda 129 \u2013 Vigo<\/span><br \/>\n<span style=\"color: #888888;\"> Galicia, Espa\u00f1a<\/span><br \/>\n<span style=\"color: #888888;\"> www.sirventvigo.com<\/span><\/p>\n<p><!--:--><!--:gl--><\/p>\n<p style=\"text-align: justify;\">Sinsal programou d\u00faas conferencias para Espazo Sirvent nas que suscitar\u00e1n unha introduci\u00f3n \u00e1 arte e paisaxe sonora baixo o t\u00edtulo Historia da Paisaxe Sonora: un percorrido pola historia a trav\u00e9s dos seus sons. Espazo Sirvent abre as s\u00faas portas \u00e1 celebraci\u00f3n do d\u00e9cimo aniversario de Sinsal Xullo G\u00f3mez e Juan Gil presentar\u00e1n en d\u00faas xornadas un percorrido pola historia do son cuxo punto de inflexi\u00f3n sit\u00faan na primeira grabaci\u00f3n realizada por Thomas Edison.<\/p>\n<p style=\"text-align: justify;\">O Festival Sinsal cumpre este ano o seu d\u00e9cimo aniversario e, para celebralo, realizar\u00e1 unha serie de eventos en diferentes espazos da cidade. Ademais do seu programaci\u00f3n musical, o Festival Sinsal 2012 incluir\u00e1 outras actividades vinculadas \u00e1 difusi\u00f3n e co\u00f1ecemento do patrimonio sonoro. Neste contexto, e en colaboraci\u00f3n co Espazo Sirvent, presentar\u00e1 d\u00faas conferencias de introduci\u00f3n \u00e1 arte e paisaxe sonora que ter\u00e1n lugar os d\u00edas 12 e 26 de abril \u00e1s 20:00 horas.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"sonido01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\" alt=\"\" width=\"620\" height=\"423\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">A primeira delas, impartida por Xullo G\u00f3mez, virar\u00e1 en relaci\u00f3n \u00e1 historia do son antes do nacemento da grabaci\u00f3n a finais do s\u00e9culo XIX polo inventor Thomas Edison. Nesta introduci\u00f3n, suscitar\u00e1 como a historiograf\u00eda e a arqueolog\u00eda modernas, debido ao papel cada vez m\u00e1is preponderante da percepci\u00f3n sonora, investigan no pasado para analizar acusticamente \u00e1s sociedades que nos precederon: iremos ata Stonehenge e preguntar\u00e9monos\/preguntar\u00e9mosnos si al\u00ed naceu a primeira sala de concertos fai 5000 anos; tam\u00e9n buscaremos as primeiras marcas sonoras entre os emblemas dos cabaleiros feudales; pasearemos polos sofisticados e sensoriais xard\u00edns barrocos; e deter\u00e9monos\/deter\u00e9mosnos nos silencios c\u00f3mplices da pintura flamenca.<\/p>\n<p style=\"text-align: justify;\">Pola s\u00faa banda, na segunda das conferencias a cargo do music\u00f3logo Juan Gil, reflexionarase sobre o papel que xoga o son na sociedade contempor\u00e1nea, desde as orixes do rexistro sonoro a finais do s\u00e9culo XIX. Aproximar\u00e9monos\/Aproximar\u00e9mosnos \u00e1 arte sonora, unha das disciplinas m\u00e1is desco\u00f1ecidas da arte a pesar do recente premio Turner 2010 da escocesa Susan Philipsz. Analizaremos a obra dalg\u00fans dos seus artistas m\u00e1is representativos, buscando aplicaci\u00f3ns pr\u00e1cticas na vida coti\u00e1 e recordando como cada vez m\u00e1is, a nosa sociedade est\u00e1 exposta ao dese\u00f1o sonoro na arquitectura, o urbanismo ou o marketing comercial.<\/p>\n<p style=\"text-align: justify;\">En ambas sesi\u00f3ns, diferentes v\u00eddeos e exemplos pr\u00e1cticos guiar\u00e1n ao p\u00fablico de forma entretida polos entresijos do son. Cada unha das conferencias complementar\u00e1 a s\u00faa actividade con varias pr\u00e1cticas que axudar\u00e1n a reflexionar sobre o son e o seu papel na nosa sociedade. As\u00ed, desde o punto de vista da grabaci\u00f3n rexistrarase un cilindro de cera tal e como se realizou durante as primeiras d\u00e9cadas do s\u00e9culo XX. Mentres, na segunda sesi\u00f3n, debuxarase un mapa sonoro colectivo de Vigo con aqueles sons que desapareceron recientemente ou o far\u00e1n nos pr\u00f3ximos anos.<\/p>\n<p style=\"text-align: justify;\">M\u00e1is al\u00f3 das propostas de Sinsal para o mes de abril, Espazo Sirvent prepara para maio e xu\u00f1o dous novas actos a cargo da dise\u00f1adora Nani Marquina e o arquitecto Eduardo Souto de Moura, ganador do premio Pritzker o pasado ano 2.011.<\/p>\n<p style=\"text-align: justify;\">Xullo G\u00f3mez \u00e9 xestor cultural, investigador sonoro e comisario musical. Cr\u00edtico musical nos anos oitenta e noventa para diferentes medios de comunicaci\u00f3n como Radio 4 de RNE, Radio Ecca, Faro de Vigo ou Diario 16 de Galicia. Desde fai dez anos codirige a promotora e axencia Sinsalaudio de Vigo. \u00c9 coordinador do Festival Sinsal e director da Escola Sinsal, o \u00fanico proxecto pedag\u00f3gico dedicado \u00e1 educaci\u00f3n sobre o Rexistro Sonoro. \u00c9 membro do colectivo galego escoitar.org, que na actualidade est\u00e1 traballando no primeiro mapa sonoro europeo xunto \u00e1 Universidade TAMK de Finlandia, o laboratorio de arquitectura ac\u00fastica Cresson en Francia e a fonoteca m\u00e1is antiga de Europa, Phonogrammarchiv de Austria.<\/p>\n<p style=\"text-align: justify;\">Juan Gil \u00e9 music\u00f3logo e investigador sonoro. Forma parte dos proxectos mediateletipos.net e artesornoro.org. Nos \u00faltimos anos desenvolveu diversas investigaci\u00f3ns tanto no campo da etnomusicolog\u00eda como no da m\u00fasica contempor\u00e1nea. Actualmente est\u00e1 doctorando en arte e m\u00fasica e est\u00e1 realizando a s\u00faa tese sobre auralidad, paisaxe sonora e a utilizaci\u00f3n de sons ambientais na creaci\u00f3n sonora contempor\u00e1nea dentro do Grupo de Investigaci\u00f3n DX7 Tracker. \u00c9 membro do colectivo galego escoitar.org, que na actualidade est\u00e1 traballando no primeiro mapa sonoro europeo xunto \u00e1 Universidade TAMK de Finlandia, o laboratorio de arquitectura ac\u00fastica Cresson en Francia e a fonoteca m\u00e1is antiga de Europa, Phonogrammarchiv de Austria.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\">HISTORIA DEL PAISAJE SONORO: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez<\/span><\/p>\n<p><span style=\"color: #888888;\"> 12 de Abril as 20,00 horas<\/span><\/p>\n<p><span style=\"color: #888888;\"> Espacio Sirvent<\/span><\/p>\n<p><span style=\"color: #888888;\"> Gran V\u00eda 129 \u2013 Vigo<\/span><\/p>\n<p><span style=\"color: #888888;\"> Galicia, Espa\u00f1a<\/span><\/p>\n<p><span style=\"color: #888888;\"> www.sirventvigo.com<\/span><\/p>\n<p><!--:--><!--:en--><\/p>\n<p style=\"text-align: justify;\">Sinsal has programmed two conferences for Space Sirvent in those who will raise an introduction to the art and sonorous landscape under the title Tells the history of the Sonorous Landscape: a tour for the history across his sounds. Space Sirvent opens his doors for the celebration of Sinsal Julio&#8217;s tenth anniversary G\u00f3mez and Juan Gil they will present in two days a tour for the history of the sound which point of inflexion they place in the first recording realized by Thomas Edison.<\/p>\n<p style=\"text-align: justify;\">The Festival Sinsal fulfills this year his tenth anniversary and, to celebrate it, it will realize a series of events in different spaces of the city. Besides his musical programming, the Festival Sinsal 2012 will include other activities linked to the diffusion and knowledge of the sonorous heritage. In this context, and in collaboration with the Space Sirvent, he will present two conferences of introduction to the art and sonorous landscape that they will take place on the 12th and 26th from April to 20:00.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\"><img loading=\"lazy\" decoding=\"async\" title=\"sonido01\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\" alt=\"\" width=\"620\" height=\"423\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">The first one of them, given by Julio G\u00f3mez, will turn in relation to the history of the sound before the birth of the recording at the end of the 19th century for the inventor Thomas Edison. In this introduction, it will raise how the modern historiography and the archaeology, due to the paper increasingly preponderant of the sonorous perception, investigate in the past to analyze acoustic to the companies that preceded us: iremos up to Stonehenge and us we will ask if there the first room of concerts was born 5000 years ago; also we will look for the first sonorous brands between the emblems of the feudal gentlemen; we will walk along the sophisticated and sensory baroque gardens; and we will detain in the silences accomplices of the Flemish painting.<\/p>\n<p style=\"text-align: justify;\">For your part, in the second one of the conferences at the expense of the musicologist Juan Gil, one will think about the paper that plays the sound in the contemporary company, from the origins of the sonorous record at the end of the 19th century. We will come closer the sonorous art, one of the most unknown disciplines of the art in spite of the recent prize Turner 2010 of the Scot Susan Philipsz. We will analyze the work of some of his more representative artists, looking for practical applications in the daily life and remembering how increasingly, our company is exposed to the sonorous design in the architecture, the urbanism or the commercial marketing.<\/p>\n<p style=\"text-align: justify;\">In both meetings, different videoes and practical examples will guide the public of form entertained by the mesenteries of the sound. Each of the conferences will complement his activity with several practices that they will help to think over on the sound and his paper in our company. This way, from the point of view of the recording a cylinder of wax will be registered as it was realized during the first decades of the 20th century. While, in the second session, a sonorous collective map of Vigo will show itself with those sounds that have disappeared recently or they will do it in the next years.<\/p>\n<p style=\"text-align: justify;\">Beyond Sinsal&#8217;s offers for April, Space Sirvent prepares for May and June two new acts at the expense of the designer Nani Marquina and the architect Eduardo Souto de Moura, winner of the prize Pritzker last year 2.011.<\/p>\n<p style=\"text-align: justify;\">Julio G\u00f3mez is cultural manager, sonorous investigator and musical commissioner. Musical critic in the eighties and nineties for different mass media like Radio 4 of RNE, Radio Ecca, Faro of Vigo or Diary 16 of Galicia. For ten years it co-directs the promoter and agency Sinsalaudio of Vigo. He is a coordinator of the Festival Sinsal and the director of To Escola Sinsal, the only pedagogic project dedicated to the education on the Sonorous Record. He is a member of the Galician group escoitar.org, which at present is employed at the first sonorous European map close to the University TAMK of Finland, the laboratory of acoustic architecture Cresson at France and the most ancient music library of Europe, Phonogrammarchiv of Austria.<\/p>\n<p style=\"text-align: justify;\">Juan Gil is musicologist and sonorous investigator. It forms a part of the projects mediateletipos.net and artesornoro.org. In the last years it has developed diverse investigations so much in the field of the etnomusicolog\u00eda as in that of the contemporary music. Nowadays he is conferring a doctor&#8217;s degree in art and music and realizes his thesis on auralidad, sonorous landscape and the utilization of environmental sounds in the sonorous contemporary creation inside the Group of Investigation DX7 Tracker. He is a member of the Galician group escoitar.org, which at present is employed at the first sonorous European map close to the University TAMK of Finland, the laboratory of acoustic architecture Cresson at France and the most ancient music library of Europe, Phonogrammarchiv of Austria.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\">HISTORIA DEL PAISAJE SONORO: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez<\/span><\/p>\n<p><span style=\"color: #888888;\"> On April 12 at 20:00<\/span><\/p>\n<p><span style=\"color: #888888;\"> Espacio Sirvent<\/span><\/p>\n<p><span style=\"color: #888888;\"> Gran V\u00eda 129 \u2013 Vigo<\/span><\/p>\n<p><span style=\"color: #888888;\"> Galicia, Spa\u00f1a<\/span><\/p>\n<p><span style=\"color: #888888;\"> www.sirventvigo.com<\/span><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sinsal ha programado dos conferencias para Espacio Sirvent en las que plantear\u00e1n una introducci\u00f3n al arte y paisaje sonoro bajo el t\u00edtulo Historia del Paisaje Sonoro: un recorrido por la historia a trav\u00e9s de sus sonidos. Espacio Sirvent abre sus puertas a la celebraci\u00f3n del d\u00e9cimo aniversario de Sinsal Julio G\u00f3mez y Juan Gil presentar\u00e1n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":21313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1385,16],"tags":[12471,357,1598,434,3199,521,1787,619,4387,4384,4386,4385],"class_list":["post-21312","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conferencias","category-eventos","tag-cine","tag-conferencia","tag-cortometraje","tag-documental","tag-espana","tag-europa","tag-galicia","tag-juan-gil","tag-julio-gomez","tag-paisaje-sonoro","tag-sinsal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-\u00b7-julio-gomez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-\u00b7-julio-gomez\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-09T05:12:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-02T17:04:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez\",\"datePublished\":\"2012-04-09T05:12:16+00:00\",\"dateModified\":\"2018-11-02T17:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/\"},\"wordCount\":2547,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/sonido01.jpg\",\"keywords\":[\"cine\",\"conferencia\",\"cortometraje\",\"documental\",\"espacio sirvent\",\"Espa\u00f1a\",\"Europa\",\"Galicia\",\"juan gil\",\"julio g\u00f3mez\",\"paisaje sonoro\",\"sinsal\"],\"articleSection\":[\"conferencias\",\"eventos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/\",\"name\":\"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/sonido01.jpg\",\"datePublished\":\"2012-04-09T05:12:16+00:00\",\"dateModified\":\"2018-11-02T17:04:02+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/sonido01.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/sonido01.jpg\",\"width\":\"400\",\"height\":\"273\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes","description":"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-\u00b7-julio-gomez\/","og_locale":"es_ES","og_type":"article","og_title":"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes","og_description":"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez","og_url":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-\u00b7-julio-gomez\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2012-04-09T05:12:16+00:00","article_modified_time":"2018-11-02T17:04:02+00:00","og_image":[{"width":400,"height":273,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez","datePublished":"2012-04-09T05:12:16+00:00","dateModified":"2018-11-02T17:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/"},"wordCount":2547,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg","keywords":["cine","conferencia","cortometraje","documental","espacio sirvent","Espa\u00f1a","Europa","Galicia","juan gil","julio g\u00f3mez","paisaje sonoro","sinsal"],"articleSection":["conferencias","eventos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/","url":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/","name":"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg","datePublished":"2012-04-09T05:12:16+00:00","dateModified":"2018-11-02T17:04:02+00:00","description":"Toda la informaci\u00f3n sobre: Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mezHistoria da paisaxe sonoro: Un percorrido pola historia a trav\u00e9s dos seus sons \u00b7 Julio G\u00f3mezHistory of the sonorous landscape: A tour for the history across his sounds \u00b7 Julio G\u00f3mez","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2012\/04\/sonido01.jpg","width":"400","height":"273"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/historia-del-paisaje-sonoro-un-recorrido-por-la-historia-a-traves-de-sus-sonidos-%c2%b7-julio-gomez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Historia del paisaje sonoro: Un recorrido por la historia a trav\u00e9s de sus sonidos \u00b7 Julio G\u00f3mez"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/21312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=21312"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/21312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/21313"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=21312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=21312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=21312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}