{"id":16270,"date":"2011-09-12T07:43:42","date_gmt":"2011-09-12T07:43:42","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=16270"},"modified":"2020-11-25T08:48:37","modified_gmt":"2020-11-25T07:48:37","slug":"el-banquete","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/el-banquete\/","title":{"rendered":"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]"},"content":{"rendered":"<p>[:es]<\/p>\n<p style=\"text-align: justify;\">La galer\u00eda ROM for Kunst og Arkitektur, en Oslo, especializada en arte y arquitectura, homenajea al arquitecto espa\u00f1ol J. Herreros. La muestra pretende convertirse en un punto de encuentro y reflexi\u00f3n sobre la relaci\u00f3n entre el arte y la arquitectura, los nuevos museos y la cultura como infraestructura. Juan Herreros es <strong>Catedr\u00e1tico en las universidades Polit\u00e9cnica de Madrid y Columbia de Nueva York<\/strong>, actividad que compagina con su estudio Herrero Arquitectos, es conocido por su particular filosof\u00eda de trabajo, basada en la creaci\u00f3n de plataformas colaborativas en las que son invitados clientes, t\u00e9cnicos y agentes implicados en cada proyecto. <strong>Su trabajo m\u00e1s importante<\/strong> es el dise\u00f1o y construcci\u00f3n del barrio avanzado de <strong>Bj\u00f8rvika <\/strong>(Menci\u00f3n Especial de la Bienal de Arquitectura Espa\u00f1ola) y el <strong>Museo Edward Munch, ambos en Oslo<\/strong>, ganados en 2009 tras un concurso internacional.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\"><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16271\" title=\"1315304866_0\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg 400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-300x199.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-145x95.jpg 145w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>La Galer\u00eda ROM de Oslo donde tendr\u00e1 lugar la exposici\u00f3n &#8216;El Banquete&#8217;. | elmundo.es<\/span><\/p>\n<p style=\"text-align: justify;\">[&#8230;]<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.elmundo.es\/elmundo\/2011\/09\/06\/suvivienda\/1315304866.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #888888;\">+ art\u00edculo publicado en elmundo.es<\/span><\/a><\/p>\n<p>[:gl]<\/p>\n<p><p style=\"text-align: justify;\">A galer\u00eda ROM for Kunst og Arkitektur, en Oslo, especializada en arte e arquitectura, homenaxea ao arquitecto espa\u00f1ol J. Ferreiros. A mostra pretende converterse nun punto de encontro e reflexi\u00f3n sobre a relaci\u00f3n entre a arte e a arquitectura, os novos museos e a cultura como infraestrutura. Juan Ferreiros \u00e9 Catedr\u00e1tico nas universidades Polit\u00e9cnica de Madrid e Columbia de Nova York, actividade que compaxina co seu estudo Ferreiro Arquitectos, \u00e9 co\u00f1ecido pola s\u00faa particular filosof\u00eda de traballo, baseada na creaci\u00f3n de plataformas colaborativas nas que son invitados clientes, t\u00e9cnicos e axentes implicados en cada proxecto. O seu traballo m\u00e1is importante \u00e9 o dese\u00f1o e construci\u00f3n do barrio avanzado de Bj\u00f8rvika (Menci\u00f3n Especial da Bienal de Arquitectura Espa\u00f1ola) e o Museo Edward Munch, ambos en Oslo, ga\u00f1ados en 2009 tras un concurso internacional.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\"><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16271\" title=\"1315304866_0\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg 400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-300x199.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-145x95.jpg 145w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>A Galer\u00eda ROM de Oslo onde ter\u00e1 lugar a exposici\u00f3n &#8216;El Banquete&#8217;. | elmundo.es<\/span><\/p>\n<p style=\"text-align: justify;\">[&#8230;]<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.elmundo.es\/elmundo\/2011\/09\/06\/suvivienda\/1315304866.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #888888;\">+ artigo publicado en elmundo.es<\/span><\/a><\/p>\n<\/p>\n<p>[:en]<\/p>\n<p><p style=\"text-align: justify;\">The gallery ROM for Kunst og Arkitektur, in Oslo, specialized in art and architecture, honours the Spanish architect J. Blacksmiths. The sample tries to turn into a point of meeting and reflection on the relation between the art and the architecture, the new museums and the culture as infrastructure. Juan Herreros is A Professor in the universities Technical of Madrid and Columbia of New York, activity that Blacksmith reconciles with his study Architects, is known by his particular philosophy of work, based on the creation of collaborative platforms in which there are invited clients, technical personnel and agents involved in every project. His more important work is the design and construction of Bj\u00f8rvika&#8217;s advanced neighborhood (Special Mention of the Biennial show of Spanish Architecture) and the Museum Edward Munch, both in Oslo, cattles in 2009 after an international contest.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #888888;\"><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-16271\" title=\"1315304866_0\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\" alt=\"\" width=\"400\" height=\"266\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg 400w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-300x199.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0-145x95.jpg 145w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/span><span style=\"color: #888888;\">The Gallery ROM of Oslo where there will take place the exhibition &#8216; The Banquet &#8216; | elmundo.es<\/span><\/p>\n<p style=\"text-align: justify;\">[&#8230;]<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.elmundo.es\/elmundo\/2011\/09\/06\/suvivienda\/1315304866.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #888888;\">+ article is published in elmundo.es<\/span><\/a><\/p>\n<\/p>\n<p>[:]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[:es] La galer\u00eda ROM for Kunst og Arkitektur, en Oslo, especializada en arte y arquitectura, homenajea al arquitecto espa\u00f1ol J. Herreros. La muestra pretende convertirse en un punto de encuentro y reflexi\u00f3n sobre la relaci\u00f3n entre el arte y la arquitectura, los nuevos museos y la cultura como infraestructura. Juan Herreros es Catedr\u00e1tico en las [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":16271,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,1382],"tags":[1787,556,761,941],"class_list":["post-16270","post","type-post","status-publish","format-standard","has-post-thumbnail","category-eventos","category-exposiciones","tag-europa","tag-exposicion","tag-juan-herreros","tag-noruega"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/el-banquete\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/el-banquete\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-09-12T07:43:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-25T07:48:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"266\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]\",\"datePublished\":\"2011-09-12T07:43:42+00:00\",\"dateModified\":\"2020-11-25T07:48:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/\"},\"wordCount\":513,\"commentCount\":208,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/1315304866_0.jpg\",\"keywords\":[\"Europa\",\"exposici\u00f3n\",\"Juan Herreros\",\"Noruega\"],\"articleSection\":[\"eventos\",\"exposiciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/\",\"name\":\"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/1315304866_0.jpg\",\"datePublished\":\"2011-09-12T07:43:42+00:00\",\"dateModified\":\"2020-11-25T07:48:37+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/1315304866_0.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/09\\\/1315304866_0.jpg\",\"width\":\"400\",\"height\":\"266\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/el-banquete\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Banquete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes","description":"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/el-banquete\/","og_locale":"es_ES","og_type":"article","og_title":"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes","og_description":"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]","og_url":"https:\/\/veredes.es\/blog\/el-banquete\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2011-09-12T07:43:42+00:00","article_modified_time":"2020-11-25T07:48:37+00:00","og_image":[{"width":400,"height":266,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/el-banquete\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]","datePublished":"2011-09-12T07:43:42+00:00","dateModified":"2020-11-25T07:48:37+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/"},"wordCount":513,"commentCount":208,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg","keywords":["Europa","exposici\u00f3n","Juan Herreros","Noruega"],"articleSection":["eventos","exposiciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/el-banquete\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/el-banquete\/","url":"https:\/\/veredes.es\/blog\/el-banquete\/","name":"[:es]El Banquete[:gl]O Banquete[:en]The Banquet[:] - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg","datePublished":"2011-09-12T07:43:42+00:00","dateModified":"2020-11-25T07:48:37+00:00","description":"Toda la informaci\u00f3n sobre: [:es]El Banquete[:gl]O Banquete[:en]The Banquet[:]","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/el-banquete\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/el-banquete\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/el-banquete\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/09\/1315304866_0.jpg","width":"400","height":"266"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/el-banquete\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"El Banquete"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/16270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=16270"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/16270\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/16271"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=16270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=16270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=16270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}