{"id":15731,"date":"2011-08-08T11:50:51","date_gmt":"2011-08-08T11:50:51","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=15731"},"modified":"2019-12-27T14:40:16","modified_gmt":"2019-12-27T13:40:16","slug":"urbanalizacion","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/urbanalizacion\/","title":{"rendered":"Urbanalizaci\u00f3n"},"content":{"rendered":"<p><\/p>\n<div style=\"text-align: justify;\">\n<p>Este libro hace un certero diagn\u00f3stico de la evoluci\u00f3n reciente de algunos procesos globales de urbanizaci\u00f3n que analiza conjuntamente. Su autor utiliza para ello las herramientas disciplinares que corresponden a una perspectiva eminentemente sociol\u00f3gica y geogr\u00e1fica. Usando recursos ret\u00f3ricos relacionados con la invenci\u00f3n de nuevos vocablos, como territoriantes o la misma urbanalizaci\u00f3n, se describen y explican algunas claves significativas de la forma en que, se han ido transformando de una manera bastante parecida diversas \u00e1reas urbanizadas en muchos pa\u00edses a lo largo y ancho del planeta.<\/p>\n<\/div>\n<p style=\"text-align: justify;\"><strong><a href=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone  wp-image-15733\" title=\"110717-Urbanalizacion-PortadaS\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg\" alt=\"\" width=\"620\" height=\"920\" \/><\/a><\/strong><\/p>\n<div style=\"text-align: justify;\">\n<p>Para Francesc Mu\u00f1oz lo ocurrido en las \u00faltimas d\u00e9cadas en las ciudades y territorios metropolitanos ha sido una consecuencia de la imposici\u00f3n de pautas de consumo del espacio orientadas a la adaptaci\u00f3n de los lugares a las necesidades del capitalismo avanzado, o postfordista como hoy algunos lo adjetivan. Se han impuesto as\u00ed unos paisajes replicados planetariamente en cualquier sitio, en los que es m\u00e1s importante la continuidad en la integraci\u00f3n de un comportamiento social, adaptado a las nuevas estrategias de distribuci\u00f3n masiva de productos, que la respuesta a las verdaderas necesidades de los propios habitantes de los lugares.<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p>[&#8230;]<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p>Federico Garc\u00eda Barba<\/p>\n<\/div>\n<div style=\"text-align: justify;\">\n<p><a href=\"http:\/\/islasterritorio.blogspot.com\/2011\/08\/urbanalizacion.html\" target=\"_blank\"><span style=\"color: #888888;\">+ art\u00edculo publicado en islasyterriotorio<\/span><\/a><\/p>\n<\/div>\n<p><iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"http:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?t=veredes-21&amp;o=30&amp;p=8&amp;l=as1&amp;asins=842521873X&amp;ref=tf_til&amp;fc1=000000&amp;IS2=1&amp;lt1=_blank&amp;m=amazon&amp;lc1=ED9913&amp;bc1=000000&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" width=\"320\" height=\"240\"><\/iframe> <iframe loading=\"lazy\" style=\"width: 120px; height: 240px;\" src=\"http:\/\/rcm-eu.amazon-adsystem.com\/e\/cm?t=veredes-21&amp;o=30&amp;p=8&amp;l=as1&amp;asins=B009P4W69U&amp;ref=tf_til&amp;fc1=000000&amp;IS2=1&amp;lt1=_blank&amp;m=amazon&amp;lc1=ED9913&amp;bc1=000000&amp;bg1=FFFFFF&amp;f=ifr\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" width=\"320\" height=\"240\"><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Este libro hace un certero diagn\u00f3stico de la evoluci\u00f3n reciente de algunos procesos globales de urbanizaci\u00f3n que analiza conjuntamente. Su autor utiliza para ello las herramientas disciplinares que corresponden a una perspectiva eminentemente sociol\u00f3gica y geogr\u00e1fica. Usando recursos ret\u00f3ricos relacionados con la invenci\u00f3n de nuevos vocablos, como territoriantes o la misma urbanalizaci\u00f3n, se describen y [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":15733,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[249,318,2514,530,3950,630,977,2351,1241,1243,1980,1286,12468,1326],"class_list":{"0":"post-15731","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-libros","8":"category-publicaciones","9":"tag-capitalismo","10":"tag-ciudad","11":"tag-editorial-gustavo-gili","12":"tag-estrategias","13":"tag-francesc-munoz","14":"tag-geografia","15":"tag-paisaje","16":"tag-procesos-globales","17":"tag-sociedad","18":"tag-sociologia","19":"tag-sociologia-urbana","20":"tag-territorio","21":"tag-urbanismo","22":"tag-urbanizacion"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/urbanalizacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/urbanalizacion\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-08-08T11:50:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-27T13:40:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"215\" \/>\n\t<meta property=\"og:image:height\" content=\"320\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Urbanalizaci\u00f3n\",\"datePublished\":\"2011-08-08T11:50:51+00:00\",\"dateModified\":\"2019-12-27T13:40:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/\"},\"wordCount\":603,\"commentCount\":982,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/110717-Urbanalizacion-PortadaS.jpg\",\"keywords\":[\"capitalismo\",\"ciudad\",\"editorial Gustavo Gili\",\"estrategias\",\"Francesc Mu\u00f1oz\",\"geograf\u00eda\",\"paisaje\",\"procesos globales\",\"sociedad\",\"sociologia\",\"sociologia urbana\",\"territorio\",\"urbanismo\",\"urbanizaci\u00f3n\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/\",\"name\":\"Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/110717-Urbanalizacion-PortadaS.jpg\",\"datePublished\":\"2011-08-08T11:50:51+00:00\",\"dateModified\":\"2019-12-27T13:40:16+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/110717-Urbanalizacion-PortadaS.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/08\\\/110717-Urbanalizacion-PortadaS.jpg\",\"width\":\"215\",\"height\":\"320\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/urbanalizacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urbanalizaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes","description":"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/urbanalizacion\/","og_locale":"es_ES","og_type":"article","og_title":"Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes","og_description":"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n","og_url":"https:\/\/veredes.es\/blog\/urbanalizacion\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2011-08-08T11:50:51+00:00","article_modified_time":"2019-12-27T13:40:16+00:00","og_image":[{"width":215,"height":320,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Urbanalizaci\u00f3n","datePublished":"2011-08-08T11:50:51+00:00","dateModified":"2019-12-27T13:40:16+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/"},"wordCount":603,"commentCount":982,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg","keywords":["capitalismo","ciudad","editorial Gustavo Gili","estrategias","Francesc Mu\u00f1oz","geograf\u00eda","paisaje","procesos globales","sociedad","sociologia","sociologia urbana","territorio","urbanismo","urbanizaci\u00f3n"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/urbanalizacion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/","url":"https:\/\/veredes.es\/blog\/urbanalizacion\/","name":"Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg","datePublished":"2011-08-08T11:50:51+00:00","dateModified":"2019-12-27T13:40:16+00:00","description":"Toda la informaci\u00f3n sobre: Urbanalizaci\u00f3nUrbanalizaci\u00f3nUrbanalizaci\u00f3n","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/urbanalizacion\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/08\/110717-Urbanalizacion-PortadaS.jpg","width":"215","height":"320"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/urbanalizacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Urbanalizaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/15731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=15731"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/15731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/15733"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=15731"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=15731"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=15731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}