{"id":14159,"date":"2011-06-01T07:17:08","date_gmt":"2011-06-01T07:17:08","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=14159"},"modified":"2019-11-19T17:53:58","modified_gmt":"2019-11-19T16:53:58","slug":"b-web-2011","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/b-web-2011\/","title":{"rendered":"b-web 2011"},"content":{"rendered":"<p><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14160\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg\" alt=\"IMG_1378-455x609\" width=\"640\" height=\"856\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg 299w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609-224x300.jpg 224w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p style=\"text-align: justify;\">Todo sigue cambiando\u2026 la comunicaci\u00f3n, el marketing y los modelos de negocio han ido modul\u00e1ndose hasta llegar al momento en el que nos encontramos, con decenas de redes sociales y un planteamiento de la comunicaci\u00f3n en aut\u00e9ntica ebullici\u00f3n 2.0. Hablamos de nuevos canales de comunicaci\u00f3n, nuevas oportunidades de venta y de la posibilidad de interacci\u00f3n directa con nuestros clientes. Exprimir estas herramientas en nuestros planteamientos de comunicaci\u00f3n marcar\u00e1 el posicionamiento de la empresa y sus productos y servicios. Pero, \u00bfC\u00f3mo?<\/p>\n<p style=\"text-align: justify;\">B-web 2011 busca dar respuesta a estas y a todas las preguntas que asaltan al hablar de Facebook, Twitter, Tuenti, Foursquare, Linkedin o Flickr, a trav\u00e9s de los expertos m\u00e1s reputados del sector. Durante sus dos d\u00edas de duraci\u00f3n, se dar\u00e1n cita en EXPOCoru\u00f1a nombres como: Juan Merodio, autor del libro \u2018C\u00f3mo empezar a promocionar tu negocio en redes sociales\u2019;\u00a0 Juan Pablo Bustos, uno de los precursores de la combinaci\u00f3n de la publicidad y la tecnolog\u00eda; Carlos Blanco, uno de los empresarios pioneros en el sector de Internet en Espa\u00f1a y fundador de Grupo ITNet; y Javier Pedreira, <em>Wicho,<\/em> responsable de Inform\u00e1tica de los Museos Cient\u00edficos de A Coru\u00f1a\u00a0y uno de los autores del blog espa\u00f1ol m\u00e1s le\u00eddo: <span style=\"color: #888888;\"><a href=\"https:\/\/www.microsiervos.com\/\" target=\"_blank\">www.microsiervos.com<\/a><\/span>.<\/p>\n<p style=\"text-align: justify;\">La gran novedad de esta edici\u00f3n ser\u00e1\u00a0el <strong>Sal\u00f3n profesional<\/strong>. \u00a0La zona denominada \u201cb-linked\u201d se destinar\u00e1 a la ubicaci\u00f3n de stands de las empresas m\u00e1s destacadas del sector, donde dar\u00e1n a conocer sus productos y servicios. Los stands son responsabilidad de la arquitecta Ana Gallego.<\/p>\n<p style=\"text-align: justify;\"><strong>Conferencias y Case Studies<\/strong>: en el espacio llamado \u201cb-updated\u201d se suceder\u00e1n las ponencias de diferentes instructores de reconocido prestigio del entorno 2.0. Nombres como Gaby Castellanos, Rub\u00e9n Bast\u00f3n o V\u00edctor Salgado acercar\u00e1n las grandes novedades del sector. Adem\u00e1s, se suceder\u00e1n los casos pr\u00e1cticos en los que diferentes empresas acercar\u00e1n su experiencia profesional.<\/p>\n<p style=\"text-align: justify;\"><strong>Workshops<\/strong>: una de las necesidades actuales m\u00e1s demandadas por las empresas es el desarrollo de un Social Media Plan eficaz. b-web crea \u201cb-social\u201d, un taller donde expertos impartir\u00e1n las nociones necesarias para dise\u00f1ar, construir y gestionar una marca\/producto en las redes sociales m\u00e1s adecuadas para su target.<\/p>\n<p style=\"text-align: justify;\"><strong>Networking:<\/strong> \u201cb-twitt\u201d ser\u00e1 una zona de descanso donde los asistentes podr\u00e1n conectar ordenadores y twittear, favoreciendo el intercambio de informaci\u00f3n entre los participantes. Un punto de encuentro para compartir intereses, inquietudes y establecer relaciones comerciales.<\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/player.vimeo.com\/video\/24255959\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><a href=\"https:\/\/vimeo.com\/24255959\">entrevista Juan Merodio<\/a> from <a href=\"https:\/\/vimeo.com\/bweb\">BWEB<\/a> on <a href=\"https:\/\/vimeo.com\">Vimeo<\/a>.<\/p>\n<p style=\"text-align: justify;\">B-web. D\u00edas 2 y 3 de Junio de 2011<br \/>\n10:00 horas a 20:00 horas en EXPOCoru\u00f1a.<br \/>\nEl acceso a la feria es gratuito.<br \/>\n<span style=\"color: #888888;\">+ b-web.es<\/span><\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Todo sigue cambiando\u2026 la comunicaci\u00f3n, el marketing y los modelos de negocio han ido modul\u00e1ndose hasta llegar al momento en el que nos encontramos, con decenas de redes sociales y un planteamiento de la comunicaci\u00f3n en aut\u00e9ntica ebullici\u00f3n 2.0. Hablamos de nuevos canales de comunicaci\u00f3n, nuevas oportunidades de venta y de la posibilidad de interacci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":14160,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1385,16,1382,18],"tags":[357,521,619,2179,1264],"class_list":{"0":"post-14159","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-conferencias","8":"category-eventos","9":"category-exposiciones","10":"category-ferias","12":"tag-espana","13":"tag-galicia","14":"tag-social-media","15":"tag-taller"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>b-web 2011 - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: b-web 2011\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/b-web-2011\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"b-web 2011 - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: b-web 2011\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/b-web-2011\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2011-06-01T07:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-19T16:53:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"299\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"b-web 2011\",\"datePublished\":\"2011-06-01T07:17:08+00:00\",\"dateModified\":\"2019-11-19T16:53:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/\"},\"wordCount\":1358,\"commentCount\":1898,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/IMG_1378-455x609.jpg\",\"keywords\":[\"conferencia\",\"Espa\u00f1a\",\"Galicia\",\"social media\",\"taller\"],\"articleSection\":[\"conferencias\",\"eventos\",\"exposiciones\",\"ferias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/\",\"name\":\"b-web 2011 - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/IMG_1378-455x609.jpg\",\"datePublished\":\"2011-06-01T07:17:08+00:00\",\"dateModified\":\"2019-11-19T16:53:58+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: b-web 2011\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/IMG_1378-455x609.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/IMG_1378-455x609.jpg\",\"width\":\"299\",\"height\":\"400\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/b-web-2011\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"b-web 2011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"b-web 2011 - veredes","description":"Toda la informaci\u00f3n sobre: b-web 2011","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/b-web-2011\/","og_locale":"es_ES","og_type":"article","og_title":"b-web 2011 - veredes","og_description":"Toda la informaci\u00f3n sobre: b-web 2011","og_url":"https:\/\/veredes.es\/blog\/b-web-2011\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2011-06-01T07:17:08+00:00","article_modified_time":"2019-11-19T16:53:58+00:00","og_image":[{"width":299,"height":400,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"b-web 2011","datePublished":"2011-06-01T07:17:08+00:00","dateModified":"2019-11-19T16:53:58+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/"},"wordCount":1358,"commentCount":1898,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg","keywords":["conferencia","Espa\u00f1a","Galicia","social media","taller"],"articleSection":["conferencias","eventos","exposiciones","ferias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/b-web-2011\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/b-web-2011\/","url":"https:\/\/veredes.es\/blog\/b-web-2011\/","name":"b-web 2011 - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg","datePublished":"2011-06-01T07:17:08+00:00","dateModified":"2019-11-19T16:53:58+00:00","description":"Toda la informaci\u00f3n sobre: b-web 2011","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/b-web-2011\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/IMG_1378-455x609.jpg","width":"299","height":"400"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/b-web-2011\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"b-web 2011"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/14159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=14159"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/14159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/14160"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=14159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=14159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=14159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}