{"id":14122,"date":"2016-08-15T05:56:53","date_gmt":"2016-08-15T03:56:53","guid":{"rendered":"http:\/\/veredes.es\/blog\/?p=14122"},"modified":"2022-02-15T09:25:01","modified_gmt":"2022-02-15T08:25:01","slug":"new-york-times-oscar-tenreiro-degwitz","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/","title":{"rendered":"New York Times | \u00d3scar Tenreiro Degwitz"},"content":{"rendered":"<p><figure id=\"attachment_58776\" aria-describedby=\"caption-attachment-58776\" style=\"width: 750px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-58776\" src=\"http:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg\" alt=\"Siguen unas fotos de la fot\u00f3grafa venezolana residente en Nueva York Patricia Burmicky. La primera es un collage en el cual se puede apreciar en el centro, arriba, la vista hacia la calle, filtrada por tubulares, del edificio de MIT de Fumihiko Maki | oscartenreiro.com\" width=\"750\" height=\"563\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg 625w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB-300x225.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><figcaption id=\"caption-attachment-58776\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Fotos de la fot\u00f3grafa venezolana residente en Nova York Patricia Burmicky. Un collage en cual se puede apreciar en el centro, arriba, una vista hac\u00eda la calle, filtrada por tubulares, del edificio de MIT de Fumihiko Maki | oscartenreiro.com<\/span><\/figcaption><\/figure><\/p>\n<p style=\"text-align: justify;\">Pese a que su producci\u00f3n se resiente del exceso y le hubiera venido bien tener s\u00f3lo el 10% de los trabajos que acumula en su carrera, creo que Renzo Piano (1937) es un arquitecto que ha producido algunos de los mejores edificios de estos tiempos en que se le pide a la arquitectura tantas cosas equivocadas..<\/p>\n<p style=\"text-align: justify;\">Ha insistido en mantener el rigor t\u00e9cnico asociado a una visi\u00f3n muy depurada del dise\u00f1o que le ha cuidado de transitar los caminos m\u00e1s confusos de Richard Rogers (1933), su antiguo socio y coautor del centro Pompidou, una de las obras m\u00e1s publicitadas y visitadas del siglo veinte. Piano y Rogers ganaron ese concurso en 1970 y saltaron a la fama, pese a los aspectos pol\u00e9micos de esa obra que vino a ser el antecesor \u201cideol\u00f3gico\u201d de los edificios-emblema que se han regado por el mundo.<\/p>\n<p style=\"text-align: justify;\">Piano ha sido etiquetado como un arquitecto high-tech junto a Norman Foster (1935), el mismo Rogers y otros menos conocidos. Una etiqueta que se apoya en que los tres han sido cultores de una aproximaci\u00f3n a la arquitectura que insiste en \u201cmostrar\u201d o hacer evidente el esqueleto estructural y sus agregados, tomando decisiones de dise\u00f1o justificadas en nociones t\u00e9cnicas.<\/p>\n<p style=\"text-align: justify;\">El esqueleto se concibe tratando de diferenciar en el dise\u00f1o el papel de los elementos sometidos a tracci\u00f3n o a compresi\u00f3n, lo cual llev\u00f3 a Kenneth Frampton a denominarlas estructuras \u201ctensiles\u201d, en un esfuerzo de clasificaci\u00f3n. Va de s\u00ed que estas estructuras, por querer hacer visible su forma de trabajo, son invariablemente de acero porque el concreto armado es un material que muestra mucho menos su mec\u00e1nica interna. Se inscriben adem\u00e1s en un universo est\u00e9tico derivado de la racionalidad constructiva, de la depuraci\u00f3n del dise\u00f1o de los elementos, de sus conexiones, de sus proporciones.<\/p>\n<p style=\"text-align: justify;\"><strong>Tradici\u00f3n moderna.<\/strong><\/p>\n<p style=\"text-align: justify;\">Las tres figuras que he nombrado no logran resultados del mismo nivel, pero podr\u00eda decirse que son herederos de la tradici\u00f3n moderna en su versi\u00f3n m\u00e1s ortodoxa.<\/p>\n<p style=\"text-align: justify;\">No soy un seguidor de sus pasos, pero s\u00ed me interesa visitar sus obras cuando tengo la oportunidad. Ha sido el caso con Piano en dos obras importantes. Una que he comentado aqu\u00ed, el Parque de la M\u00fasica en Roma (2002). Y otro, el que motiva el comentario de hoy, el edificio del New York Times, en Nueva York, terminado en 2007.<\/p>\n<p style=\"text-align: justify;\">Edificio m\u00e1s bien discreto porque no busca impresionar con ning\u00fan gesto especial, como es el caso por ejemplo del de la Corporaci\u00f3n Hearst de Foster (2006) all\u00ed mismo en Nueva York, cuyo volumen se hace facetado en virtud de un esfuerzo de diferenciaci\u00f3n un tanto forzado, como sucede en algunas obras recientes de Foster. Tal vez queriendo acercarse a las im\u00e1genes de edificios en altura con estructuras \u201ctridimensionales\u201d que circularon en los a\u00f1os sesenta, de las cuales una muy precisa fue la del rascacielos no construido de Louis I. Kahn para Filadelfia, de fines de los cincuenta.<\/p>\n<p style=\"text-align: justify;\">Piano, por el contrario, se limita al volumen prism\u00e1tico que coloca al borde de la calle, dejando el fondo del lote para una serie de oficinas especiales y el Auditorio, uno de cuyos lados se abre hacia un muy hermoso patio interior con vegetaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Esa idea de aproximar, de acercar el edificio a la calle, sigue el alineamiento preponderante, pero hace preguntarse si es imposible en Nueva York que un edificio corporativo pueda aceptar que la Planta Baja ceda espacio a la ciudad tal como lo hizo en su momento el Seagram de Mies Van der Rohe (1958) que en Park Avenue rompi\u00f3 con los alineamientos de un modo radical, creando una plaza que ha venido a convertirse en su distinci\u00f3n m\u00e1s notoria.<\/p>\n<p style=\"text-align: justify;\"><strong>Piel protectora.<\/strong><\/p>\n<p style=\"text-align: justify;\">Imaginamos los argumentos para que esto no fuese posible, entre los cuales destacar\u00e1 el de la seguridad ante amenazas terroristas. Pero de todos modos uno lo piensa, llevado tal vez por una visi\u00f3n de lo urbano ajena a esta ciudad, lugar de prisa y de circulaci\u00f3n siempre estresante. Y sin embargo all\u00ed est\u00e1n de todos modos, como secuela interesante del gesto del Seagram, los rascacielos m\u00e1s o menos an\u00f3nimos de la Ave. de Las Am\u00e9ricas (\u201canonimato\u201d que les ha valido muchas cr\u00edticas desde hace cuarenta a\u00f1os), que crearon un sistema de plazas p\u00fablicas de acceso muy gratas y que hacen m\u00e1s amable a ese sector de la ciudad, creando oportunidad para un fugaz descanso que se agradece.<\/p>\n<p style=\"text-align: justify;\">El volumen prism\u00e1tico est\u00e1 rodeado por una piel de tubulares de aluminio (o acero inoxidable) que protege el muro cortina que envuelve las oficinas. Hace poco coment\u00e9 aqu\u00ed que un edificio del japon\u00e9s Fumihiko Maki (1928) en el campus de MIT en Boston recurre a un principio muy similar, que se hace hoy t\u00e9cnicamente accesible y es el resultado de la b\u00fasqueda de principios de control de la incidencia solar m\u00e1s sutiles que el ya un poco mal visto \u201cquiebrasol\u201d corbusiano y por supuesto que el horripilante cristal entintado de color que somete los usuarios a un permanente ambiente de discoteca.<\/p>\n<p style=\"text-align: justify;\">Pero aqu\u00ed, a diferencia de lo que hace Maki, la piel se interrumpe en bandas horizontales coincidentes con las ventanas de cada piso. Y surge la pregunta sobre el por qu\u00e9 de esta decisi\u00f3n, ya que como se demuestra claramente en Boston (<a href=\"https:\/\/www.patriciaburmicky.com\/?auth_sid=a85b714cb895d51f4d902feac096ac3d#214_engagement_photographer_nyc-147.jpg#home\" target=\"_blank\" rel=\"noopener\">ver foto superior central en el \u201ccollage\u201d fotogr\u00e1fico<\/a>), la percepci\u00f3n del paisaje \u201cfiltrado\u201d por los tubos es perfecta, menos el resplandor solar. Si ya se hab\u00eda adoptado el principio protector \u00bfpor qu\u00e9 no hacerlo en todo el volumen?<\/p>\n<p style=\"text-align: justify;\">El tamizar permanentemente la vista hubiera planteado un precedente pionero siempre riesgoso, pero no tengo dudas del inter\u00e9s del resultado, y quedar\u00eda siempre la opci\u00f3n de crear puntos abiertos en sitios escogidos. Uno siente la sensaci\u00f3n de oportunidad perdida si nos imaginamos el enorme volumen, filtrando y reflejando la luz, sin la presencia molesta de los elementos verticales de soporte de la \u201cpiel\u201d, bien notorios en la realidad.<\/p>\n<p>\u00d3scar Tenreiro Degwitz, Arquitecto.<br \/>\nVenezuela, mayo 2010,<br \/>\n<span style=\"color: #999999;\"><em>Entre lo Cierto y lo Verdadero<\/em><\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Pese a que su producci\u00f3n se resiente del exceso y le hubiera venido bien tener s\u00f3lo el 10% de los trabajos que acumula en su carrera, creo que Renzo Piano (1937) es un arquitecto que ha producido algunos de los mejores edificios de estos tiempos en que se le pide a la arquitectura tantas cosas [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":58776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5934,5951],"tags":[3657,147,460,12456,12460,2619,1621,3104,865,930,2422,11762,12269,2447,3607,1298],"class_list":{"0":"post-14122","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-articulos","8":"category-slider-principal","9":"tag-arquitectura-japonesa","10":"tag-arquitectura-moderna","11":"tag-eeuu","12":"tag-equipamiento-cultural","13":"tag-fotografia","14":"tag-fumihiko-maki","15":"tag-kenneth-frampton","16":"tag-louis-i-kahn","17":"tag-mies-van-der-rohe","18":"tag-new-york","19":"tag-norman-foster","20":"tag-oscar-tenreiro-degwitz","21":"tag-patricia-burmicky","22":"tag-renzo-piano","23":"tag-richard-rogers","24":"tag-tradicion"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New York Times | \u00d3scar Tenreiro Degwitz - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New York Times | \u00d3scar Tenreiro Degwitz - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-15T03:56:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-15T08:25:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"469\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/\"},\"author\":{\"name\":\"\u00d3scar Tenreiro Degwitz\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\"},\"headline\":\"New York Times | \u00d3scar Tenreiro Degwitz\",\"datePublished\":\"2016-08-15T03:56:53+00:00\",\"dateModified\":\"2022-02-15T08:25:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/\"},\"wordCount\":3303,\"commentCount\":36,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/new_york_times_building_PB.jpg\",\"keywords\":[\"arquitectura japonesa\",\"arquitectura moderna\",\"EEUU\",\"equipamiento cultural\",\"fotograf\u00eda\",\"Fumihiko Maki\",\"Kenneth Frampton\",\"Louis I. Kahn\",\"Mies van der Rohe\",\"New York\",\"Norman Foster\",\"\u00d3scar Tenreiro Degwitz\",\"Patricia Burmicky\",\"Renzo Piano\",\"Richard Rogers\",\"tradici\u00f3n\"],\"articleSection\":[\"art\u00edculos\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/\",\"name\":\"New York Times | \u00d3scar Tenreiro Degwitz - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/new_york_times_building_PB.jpg\",\"datePublished\":\"2016-08-15T03:56:53+00:00\",\"dateModified\":\"2022-02-15T08:25:01+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/new_york_times_building_PB.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2011\\\/06\\\/new_york_times_building_PB.jpg\",\"width\":625,\"height\":469,\"caption\":\"Siguen unas fotos de la fot\u00f3grafa venezolana residente en Nueva York Patricia Burmicky. La primera es un collage en el cual se puede apreciar en el centro, arriba, la vista hacia la calle, filtrada por tubulares, del edificio de MIT de Fumihiko Maki | oscartenreiro.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/new-york-times-oscar-tenreiro-degwitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New York Times | \u00d3scar Tenreiro Degwitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\",\"name\":\"\u00d3scar Tenreiro Degwitz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"caption\":\"\u00d3scar Tenreiro Degwitz\"},\"description\":\"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.\",\"sameAs\":[\"https:\\\/\\\/oscartenreiro.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/oscar-tenreiro-degwitz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New York Times | \u00d3scar Tenreiro Degwitz - veredes","description":"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/","og_locale":"es_ES","og_type":"article","og_title":"New York Times | \u00d3scar Tenreiro Degwitz - veredes","og_description":"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz","og_url":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2016-08-15T03:56:53+00:00","article_modified_time":"2022-02-15T08:25:01+00:00","og_image":[{"width":625,"height":469,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg","type":"image\/jpeg"}],"author":"\u00d3scar Tenreiro Degwitz","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"\u00d3scar Tenreiro Degwitz","Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/"},"author":{"name":"\u00d3scar Tenreiro Degwitz","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19"},"headline":"New York Times | \u00d3scar Tenreiro Degwitz","datePublished":"2016-08-15T03:56:53+00:00","dateModified":"2022-02-15T08:25:01+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/"},"wordCount":3303,"commentCount":36,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg","keywords":["arquitectura japonesa","arquitectura moderna","EEUU","equipamiento cultural","fotograf\u00eda","Fumihiko Maki","Kenneth Frampton","Louis I. Kahn","Mies van der Rohe","New York","Norman Foster","\u00d3scar Tenreiro Degwitz","Patricia Burmicky","Renzo Piano","Richard Rogers","tradici\u00f3n"],"articleSection":["art\u00edculos","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/","url":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/","name":"New York Times | \u00d3scar Tenreiro Degwitz - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg","datePublished":"2016-08-15T03:56:53+00:00","dateModified":"2022-02-15T08:25:01+00:00","description":"Toda la informaci\u00f3n sobre: New York Times | \u00d3scar Tenreiro Degwitz","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2011\/06\/new_york_times_building_PB.jpg","width":625,"height":469,"caption":"Siguen unas fotos de la fot\u00f3grafa venezolana residente en Nueva York Patricia Burmicky. La primera es un collage en el cual se puede apreciar en el centro, arriba, la vista hacia la calle, filtrada por tubulares, del edificio de MIT de Fumihiko Maki | oscartenreiro.com"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/new-york-times-oscar-tenreiro-degwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"New York Times | \u00d3scar Tenreiro Degwitz"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19","name":"\u00d3scar Tenreiro Degwitz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","caption":"\u00d3scar Tenreiro Degwitz"},"description":"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.","sameAs":["https:\/\/oscartenreiro.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/oscar-tenreiro-degwitz\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/14122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=14122"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/14122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/58776"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=14122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=14122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=14122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}