{"id":105753,"date":"2026-04-09T21:58:50","date_gmt":"2026-04-09T19:58:50","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=105753"},"modified":"2026-04-09T21:58:50","modified_gmt":"2026-04-09T19:58:50","slug":"grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/","title":{"rendered":"Grandes damas de la pintura china. La historia pintada en el silencio"},"content":{"rendered":"<figure id=\"attachment_105754\" aria-describedby=\"caption-attachment-105754\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105754\" title=\"Grandes damas de la pintura china. La historia pintada en el silencio - Manuela Ech\u00e1niz\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\" alt=\"Grandes damas de la pintura china. La historia pintada en el silencio - Manuela Ech\u00e1niz\" width=\"750\" height=\"1211\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg 668w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz-186x300.jpg 186w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz-634x1024.jpg 634w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz-260x420.jpg 260w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-105754\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Grandes damas de la pintura china. La historia pintada en el silencio | Manuela Ech\u00e1niz<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En la China cl\u00e1sica el arte se ha expresado a trav\u00e9s de la tinta, el papel y el pincel, y la poes\u00eda, la caligraf\u00eda y la pintura formaron una uni\u00f3n inseparable llamada las\u00a0\u00abtres perfecciones\u00bb.<\/p>\n<p style=\"text-align: justify;\">En <a href=\"https:\/\/amzn.to\/4vgIpXz\" target=\"_blank\" rel=\"noopener\">este libro<\/a> la autora hace un recorrido por las diferentes dinast\u00edas Imperiales presentando a las mujeres pintoras chinas m\u00e1s importantes cuyas obras han sido seleccionadas por su riqueza y variedad para ser analizadas y contempladas. La vida de estas artistas estuvo \u00edntimamente vinculada a sus or\u00edgenes sociales y a tradiciones como el confucionismo que limitaron en gran medida su espacio de actuaci\u00f3n. En la soledad de sus hogares o rodeadas de numerosos admiradores, indiferentes a la fama o resueltas a encontrarla, todas llegaron a la madurez t\u00e9cnica y supieron captar el verdadero esp\u00edritu de la naturaleza que representaron con una belleza ilimitada y un delicioso estilo po\u00e9tico.<\/p>\n<p style=\"text-align: justify;\"><em>Las Grandes Damas de la Pintura China<\/em>, llegar\u00e1n al coraz\u00f3n de todos los seres sensibles sin obst\u00e1culos y cuando contemplen sus obras, comprender\u00e1n inmediatamente los misterios que ante ustedes se revelar\u00e1n, y su huella ser\u00e1 tan fuerte como el trueno que logra romper el arte de pintar en silencio.<\/p>\n<h5><strong>Manuela Ech\u00e1niz <\/strong><\/h5>\n<p>Es licenciada en Bellas Artes por la Universidad Complutense de Madrid. Realiz\u00f3 su Tesis Doctoral sobre Pintura Meditativa y Contemplativa budista en China. Ha estudiando en profundidad las t\u00e9cnicas de la pintura tradicional China con tinta sobre papel de arroz, en la Imperial Painting Academy de Kaifeng (China) donde aprendi\u00f3 a dibujar la perspectiva a\u00e9rea en gran formato vertical. Ha realizado numerosos cursos, seminarios y conferencias haciendo divulgaci\u00f3n en diversos medios visuales adem\u00e1s de colaborar con el IUCR de Madrid, realizando videos y art\u00edculos para revistas especializadas. Actualmente compagina la investigaci\u00f3n con exposiciones de su obra gr\u00e1fica y cer\u00e1mica art\u00edstica que est\u00e1n claramente inspiradas en extremo Oriente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la China cl\u00e1sica el arte se ha expresado a trav\u00e9s de la tinta, el papel y el pincel, y la poes\u00eda, la caligraf\u00eda y la pintura formaron una uni\u00f3n inseparable llamada las\u00a0\u00abtres perfecciones\u00bb. En este libro la autora hace un recorrido por las diferentes dinast\u00edas Imperiales presentando a las mujeres pintoras chinas m\u00e1s importantes [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":105754,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[310,9387,12205,18395,12466,1120],"class_list":["post-105753","post","type-post","status-publish","format-standard","has-post-thumbnail","category-libros","category-publicaciones","tag-china","tag-ediciones-asimetricas","tag-libro","tag-manuela-echaniz","tag-pintura","tag-publicacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grandes damas de la pintura china. La historia pintada en el silencio - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grandes damas de la pintura china. La historia pintada en el silencio - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-09T19:58:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"668\" \/>\n\t<meta property=\"og:image:height\" content=\"1079\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"Grandes damas de la pintura china. La historia pintada en el silencio\",\"datePublished\":\"2026-04-09T19:58:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\",\"keywords\":[\"china\",\"ediciones asim\u00e9tricas\",\"libro\",\"Manuela Ech\u00e1niz\",\"pintura\",\"publicaci\u00f3n\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/\",\"name\":\"Grandes damas de la pintura china. La historia pintada en el silencio - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\",\"datePublished\":\"2026-04-09T19:58:50+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg\",\"width\":668,\"height\":1079,\"caption\":\"Grandes damas de la pintura china. La historia pintada en el silencio - Manuela Ech\u00e1niz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grandes damas de la pintura china. La historia pintada en el silencio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grandes damas de la pintura china. La historia pintada en el silencio - veredes","description":"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/","og_locale":"es_ES","og_type":"article","og_title":"Grandes damas de la pintura china. La historia pintada en el silencio - veredes","og_description":"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio","og_url":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2026-04-09T19:58:50+00:00","og_image":[{"width":668,"height":1079,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"Grandes damas de la pintura china. La historia pintada en el silencio","datePublished":"2026-04-09T19:58:50+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg","keywords":["china","ediciones asim\u00e9tricas","libro","Manuela Ech\u00e1niz","pintura","publicaci\u00f3n"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/","url":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/","name":"Grandes damas de la pintura china. La historia pintada en el silencio - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg","datePublished":"2026-04-09T19:58:50+00:00","description":"Toda la informaci\u00f3n sobre: Grandes damas de la pintura china. La historia pintada en el silencio","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/04\/Grandes-damas-de-la-pintura-china.-La-historia-pintada-en-el-silencio-Manuela-Echaniz.jpg","width":668,"height":1079,"caption":"Grandes damas de la pintura china. La historia pintada en el silencio - Manuela Ech\u00e1niz"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/grandes-damas-de-la-pintura-china-la-historia-pintada-en-el-silencio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Grandes damas de la pintura china. La historia pintada en el silencio"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=105753"}],"version-history":[{"count":1,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105753\/revisions"}],"predecessor-version":[{"id":105755,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105753\/revisions\/105755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/105754"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=105753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=105753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=105753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}