{"id":105357,"date":"2026-03-13T00:01:25","date_gmt":"2026-03-12T23:01:25","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=105357"},"modified":"2026-02-27T16:08:38","modified_gmt":"2026-02-27T15:08:38","slug":"anti-ciudad-landa-hernandez-martinez","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/","title":{"rendered":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez"},"content":{"rendered":"<figure id=\"attachment_105359\" aria-describedby=\"caption-attachment-105359\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105359\" title=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 1\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\" alt=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 1\" width=\"800\" height=\"597\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg 720w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1-300x224.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1-563x420.jpg 563w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1-80x60.jpg 80w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1-696x519.jpg 696w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-105359\" class=\"wp-caption-text\"><span style=\"color: #999999;\">CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El manifiesto del blog <a href=\"https:\/\/caminaranarquista.wordpress.com\/\" target=\"_blank\" rel=\"noopener\"><em>Caminar Anarquista<\/em><\/a>, escrito y editado por el fot\u00f3grafo <a href=\"https:\/\/francisconavamuel.net\/\" target=\"_blank\" rel=\"noopener\">Francisco Navamuel<\/a>, nos recuerda que \u00abCaminar es gratis\u00bb. Un pensamiento que enlaza con un texto de Enrique Fraguas publicado en <a href=\"https:\/\/elpais.com\/cultura\/2012\/03\/17\/actualidad\/1332004193_268688.html\" target=\"_blank\" rel=\"noopener\"><em>El Pa\u00eds<\/em><\/a>:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cAndar es un acto aparentemente in\u00fatil e improductivo, en t\u00e9rminos mercantilistas. No genera gasto ni consumo y da pie, nunca mejor dicho, al pensamiento y a cierta forma de resistencia. (\u2026) caminar se revela como un acto de reflexi\u00f3n y de subversi\u00f3n en un mundo saturado de consumo y di\u00f3xido de carbono\u201d.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Pensadores \u2014Charles Baudelaire, Walter Benjamin, Robert Walser\u2014, colectivos \u2014del Situacionismo a Stalker\u2014 y artistas \u2014Sophie Calle, Vito Acconci o Richard Long\u2014 han convertido convirtieron el acto de caminar en un medio para relacionarse con el territorio m\u00e1s all\u00e1 de los criterios productivos. El origen de esta l\u00ednea de pensamiento podr\u00eda ubicarse en Europa, especialmente en la figura del <em>fl\u00e2neur<\/em>, ese caminante urbano dedicado a callejear sin rumbo ni objetivo pero con mirada atenta a lo que se encuentra.<\/p>\n<p style=\"text-align: justify;\">Pero Europa ya no es lo que era: el espacio urbano en sus ciudades se ha regularizado y acomodado tanto que el paseante ha terminado sustituido por el<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201c<a href=\"https:\/\/zuerawalkscape.blogspot.com\/\" target=\"_blank\" rel=\"noopener\">VOYEUR<\/a> de escaparates. Un consumidor \u00e1vido por mezclarse entre la multitud y los maniqu\u00eds\u201d.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">El mundo ya no admite el paseo improductivo; si caminamos lo hacemos dirigi\u00e9ndonos siempre alg\u00fan lugar donde tengas algo que hacer. Caminar a la deriva es hoy, entonces, en un acto cuestionable, en especial desde estructuras poco amantes de la espontaneidad, quiz\u00e1 propio de vagos.<\/p>\n<figure id=\"attachment_105360\" aria-describedby=\"caption-attachment-105360\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105360\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-2.jpg\" alt=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 2\" width=\"800\" height=\"598\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-2.jpg 640w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-2-300x224.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-2-562x420.jpg 562w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-2-80x60.jpg 80w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-105360\" class=\"wp-caption-text\"><span style=\"color: #999999;\">CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">De entre los paseantes urbanos que no caminan con un fin claro, cabr\u00eda destacar una figura como la del artista (arquitecto de formaci\u00f3n) Francis Al\u00ffs. Negando ser descrito como <em>fl\u00e2neur,<\/em> Al\u00ffs ha hecho de la Ciudad de M\u00e9xico su principal laboratorio; ha definido sus (anti)paseos como su m\u00e9todo de trabajo y acercamiento al espacio a fin de exponerse y chocar con la ciudad y lo que sucede en ella.<\/p>\n<p style=\"text-align: justify;\">Chocar es referido aqu\u00ed de manera literal; Ciudad de M\u00e9xico es un espacio extremadamente duro para desplazarse. De manera especial para aquel visitante que est\u00e9 acostumbrado a las suaves condiciones de las ciudades europeas, siempre lisas, c\u00f3modas, sin fricciones para el consumo del turista de masas<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u201cacostumbrado a la tranquilidad y confort de los bulevares o centros comerciales\u201d.<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_105361\" aria-describedby=\"caption-attachment-105361\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105361\" title=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 3\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-3.jpg\" alt=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 3\" width=\"800\" height=\"598\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-3.jpg 640w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-3-300x224.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-3-562x420.jpg 562w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-3-80x60.jpg 80w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-105361\" class=\"wp-caption-text\"><span style=\"color: #999999;\">CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En la CDMX, la enorme cantidad de obst\u00e1culos y est\u00edmulos que podemos encontrar a nuestro paso o la incomodidad de la calzada \u2014tanto por su condici\u00f3n material como por la ocupaci\u00f3n y apropiaci\u00f3n de sus espacios\u2014 convierten sus aceras en una aventura, incluso dolorosa, para unos pies advenedizos. Se comprende entonces la fascinaci\u00f3n que pudo sentir Francis Al\u00ffs como (anti)paseante europeo ante la espontaneidad de la ciudad.<\/p>\n<p style=\"text-align: justify;\">Podr\u00edamos definir aqu\u00ed a la Ciudad de M\u00e9xico como una urbe incomoda; las pol\u00edticas urbanas han estado enfocadas durante mucho tiempo a favorecer casi en exclusiva el uso del transporte rodado privado. El peat\u00f3n est\u00e1 tan fuera de lugar que incluso las estad\u00edsticas elaboradas por el Instituto Nacional de Estad\u00edstica y Geograf\u00eda (INEGI) de los sistemas de desplazamiento utilizados en la Zona Metropolitana lo hacen desaparecer: 72.1% de los viajes se realizan en transporte p\u00fablico, 20.7% en autom\u00f3vil particular, 6.2% en taxi, y un magro 1% en bicicleta. <a href=\"https:\/\/ciudadpedestre.wordpress.com\/2012\/11\/20\/el-peaton-invisible\/\" target=\"_blank\" rel=\"noopener\">La suma de estas cantidades da 100%<\/a>.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00bfD\u00f3nde queda el peat\u00f3n? No existe. \u00bfPor qu\u00e9 habr\u00eda que preocuparnos de su figura?<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_105362\" aria-describedby=\"caption-attachment-105362\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105362\" title=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 4\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4.jpg\" alt=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 4\" width=\"800\" height=\"597\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4.jpg 720w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4-300x224.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4-563x420.jpg 563w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4-80x60.jpg 80w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-4-696x519.jpg 696w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-105362\" class=\"wp-caption-text\"><span style=\"color: #999999;\">CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El <a href=\"http:\/\/www.arquine.com\/blog\/al-peatondesconocido\/\" target=\"_blank\" rel=\"noopener\"><em>peat\u00f3n, desconocido e invisible<\/em><\/a>, debe enfrentarse solo a una ciudad llena de obst\u00e1culos: aceras en mal estado, invadidas por coches, llenas de baches y agujeros donde perder un pie; ausencia de sem\u00e1foros que indiquen al peat\u00f3n cuando tiene que cruzar; alcantarillas con enormes agujeros sin tapar; pesados maceteros o cabinas telef\u00f3nicas que crecen por doquier cort\u00e1ndonos el paso, bordillos insalvables o ruinosos pasos de cebra. En una ciudad pensada para el auto, de calzadas enormes y aceras rid\u00edculas y circundada, adem\u00e1s, por un segundo piso que aplasta edificios bajo \u00e9l, se evidencia una falta total de dise\u00f1o que ha apartado por completo al peat\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Pero, aunque parezca una ciudad anti-peatones, los cuerpos resisten y en la calle se lucha intensamente: los ambulantes llenan el escaso espacio de las aceras, otros venden productos cargados con un meg\u00e1fono, unas cubetas o piedras \u2018reservan\u2019 el espacio de estacionamiento, las personas hacen cola para entrar a los bancos y recibir su sueldo. Los pocos cent\u00edmetros que haya pueden hacer una grand\u00edsima diferencia. Pasear por Ciudad de M\u00e9xico se convierte en un estar presente, de hacerse fuerte por reivindicar este deambular, luchando constantemente contra lo que nos obstruye en el camino.<\/p>\n<p style=\"text-align: justify;\">\u00a1Viva la paradoja! El lugar del anti-paseo contiene un espacio urbano de enorme potencial, ah\u00ed donde reside el\u00a0<a href=\"http:\/\/www.arquine.com\/blog\/el-animal-publico\/\" target=\"_blank\" rel=\"noopener\">animal p\u00fablico<\/a>.<\/p>\n<figure id=\"attachment_105363\" aria-describedby=\"caption-attachment-105363\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-105363\" title=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 5\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5.jpg\" alt=\"Anti-ciudad Landa Hern\u00e1ndez Mart\u00ednez CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez 5\" width=\"800\" height=\"1208\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5.jpg 720w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5-199x300.jpg 199w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5-678x1024.jpg 678w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5-278x420.jpg 278w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-5-696x1051.jpg 696w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-105363\" class=\"wp-caption-text\"><span style=\"color: #999999;\">CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez<\/span><\/figcaption><\/figure>\n<p>Landa Hern\u00e1ndez Mart\u00ednez \u00b7 arquitecto<br \/>\nCiudad de M\u00e9xico. Abril 2021<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El manifiesto del blog Caminar Anarquista, escrito y editado por el fot\u00f3grafo Francisco Navamuel, nos recuerda que \u00abCaminar es gratis\u00bb. Un pensamiento que enlaza con un texto de Enrique Fraguas publicado en El Pa\u00eds: \u201cAndar es un acto aparentemente in\u00fatil e improductivo, en t\u00e9rminos mercantilistas. No genera gasto ni consumo y da pie, nunca mejor [&hellip;]<\/p>\n","protected":false},"author":36,"featured_media":105359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,5951],"tags":[11157,13718,16189,516,1848,18351,4505,3456,6359,10754,12162,1278,18352,8599],"class_list":["post-105357","post","type-post","status-publish","format-standard","has-post-thumbnail","category-faro","category-slider-principal","tag-charles-pierre-baudelaire","tag-colectivo-stalker","tag-enrique-fraguas","tag-espacio-publico","tag-espacio-urbano","tag-francisco-navamuel","tag-landa-hernandez","tag-pensador","tag-richard-long","tag-situacionismo","tag-sophie-calle","tag-teoria","tag-vito-acconci","tag-walter-benjamin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/pehemar\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T23:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Landa Hern\u00e1ndez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/laperiferia\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Landa Hern\u00e1ndez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/\"},\"author\":{\"name\":\"Landa Hern\u00e1ndez\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/c2e70e079f5cb4810ff9e002286ae4d4\"},\"headline\":\"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez\",\"datePublished\":\"2026-03-12T23:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/\"},\"wordCount\":906,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\",\"keywords\":[\"Charles Pierre Baudelaire\",\"colectivo Stalker\",\"Enrique Fraguas\",\"espacio p\u00fablico\",\"espacio urbano\",\"Francisco Navamuel\",\"Landa Hern\u00e1ndez\",\"pensador\",\"Richard Long\",\"situacionismo\",\"Sophie Calle\",\"teor\u00eda\",\"Vito Acconci\",\"Walter Benjamin\"],\"articleSection\":[\"faro\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/\",\"name\":\"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\",\"datePublished\":\"2026-03-12T23:01:25+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg\",\"width\":720,\"height\":537,\"caption\":\"CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/anti-ciudad-landa-hernandez-martinez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/c2e70e079f5cb4810ff9e002286ae4d4\",\"name\":\"Landa Hern\u00e1ndez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g\",\"caption\":\"Landa Hern\u00e1ndez\"},\"description\":\"Soy arquitecto por la Universidad de Alicante, pero mi inter\u00e9s sobre esta disciplina se encuentra alejado de su papel tradicional de dise\u00f1o de espacios. M\u00e1s bien, me interesa entender c\u00f3mo las representaciones de la arquitectura, el paisaje, el dise\u00f1o o el territorio construyen y materializan determinados discursos ideol\u00f3gicos, imponiendo posturas, subjetividades y formas de acci\u00f3n sobre los cuerpos que la habitan. En mi trabajo edito estos discursos \u2013sus im\u00e1genes, sus historias o sus restos materiales\u2013 y reelaboro comentarios cr\u00edticos que ponen en evidencia sus controversias y contradicciones, formaliz\u00e1ndolos en diversos formatos como textos, fotograf\u00edas, v\u00eddeos, objetos o instalaciones, muchas veces entrecruzados entre s\u00ed. He publicado art\u00edculos y ensayos en diversos medios de Estados Unidos, Italia, Croacia, Espa\u00f1a, Chile y M\u00e9xico. Desde enero de 2013 resido en la Ciudad de M\u00e9xico donde trabajo como coordinador de contenidos en Arquine.\",\"sameAs\":[\"http:\\\/\\\/laperiferiadomestica.tumblr.com\\\/\",\"https:\\\/\\\/www.facebook.com\\\/pehemar\",\"https:\\\/\\\/www.instagram.com\\\/laperiferia\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/pedrohm\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/laperiferia\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/pedro-hernandez-martinez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes","description":"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/","og_locale":"es_ES","og_type":"article","og_title":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes","og_description":"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez","og_url":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/pehemar","article_published_time":"2026-03-12T23:01:25+00:00","og_image":[{"width":720,"height":537,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg","type":"image\/jpeg"}],"author":"Landa Hern\u00e1ndez","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/laperiferia","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Landa Hern\u00e1ndez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/"},"author":{"name":"Landa Hern\u00e1ndez","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/c2e70e079f5cb4810ff9e002286ae4d4"},"headline":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez","datePublished":"2026-03-12T23:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/"},"wordCount":906,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg","keywords":["Charles Pierre Baudelaire","colectivo Stalker","Enrique Fraguas","espacio p\u00fablico","espacio urbano","Francisco Navamuel","Landa Hern\u00e1ndez","pensador","Richard Long","situacionismo","Sophie Calle","teor\u00eda","Vito Acconci","Walter Benjamin"],"articleSection":["faro","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/","url":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/","name":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg","datePublished":"2026-03-12T23:01:25+00:00","description":"Toda la informaci\u00f3n sobre: Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2026\/03\/Anti-ciudad-Landa-Hernandez-Martinez-CDMX-\u00a9-Landa-Hernandez-Martinez-1.jpg","width":720,"height":537,"caption":"CDMX \u00a9 Landa Hern\u00e1ndez Mart\u00ednez"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/anti-ciudad-landa-hernandez-martinez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"Anti-ciudad | Landa Hern\u00e1ndez Mart\u00ednez"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/c2e70e079f5cb4810ff9e002286ae4d4","name":"Landa Hern\u00e1ndez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/557e510e5576322e0c38a78a1bfab7d33982187ff66668704d6978d3f690ceb1?s=96&r=g","caption":"Landa Hern\u00e1ndez"},"description":"Soy arquitecto por la Universidad de Alicante, pero mi inter\u00e9s sobre esta disciplina se encuentra alejado de su papel tradicional de dise\u00f1o de espacios. M\u00e1s bien, me interesa entender c\u00f3mo las representaciones de la arquitectura, el paisaje, el dise\u00f1o o el territorio construyen y materializan determinados discursos ideol\u00f3gicos, imponiendo posturas, subjetividades y formas de acci\u00f3n sobre los cuerpos que la habitan. En mi trabajo edito estos discursos \u2013sus im\u00e1genes, sus historias o sus restos materiales\u2013 y reelaboro comentarios cr\u00edticos que ponen en evidencia sus controversias y contradicciones, formaliz\u00e1ndolos en diversos formatos como textos, fotograf\u00edas, v\u00eddeos, objetos o instalaciones, muchas veces entrecruzados entre s\u00ed. He publicado art\u00edculos y ensayos en diversos medios de Estados Unidos, Italia, Croacia, Espa\u00f1a, Chile y M\u00e9xico. Desde enero de 2013 resido en la Ciudad de M\u00e9xico donde trabajo como coordinador de contenidos en Arquine.","sameAs":["http:\/\/laperiferiadomestica.tumblr.com\/","https:\/\/www.facebook.com\/pehemar","https:\/\/www.instagram.com\/laperiferia\/","https:\/\/www.linkedin.com\/in\/pedrohm\/","https:\/\/x.com\/https:\/\/twitter.com\/laperiferia"],"url":"https:\/\/veredes.es\/blog\/author\/pedro-hernandez-martinez\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=105357"}],"version-history":[{"count":2,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105357\/revisions"}],"predecessor-version":[{"id":105364,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/105357\/revisions\/105364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/105359"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=105357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=105357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=105357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}