{"id":103825,"date":"2025-11-11T00:01:13","date_gmt":"2025-11-10T23:01:13","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=103825"},"modified":"2025-10-31T14:33:13","modified_gmt":"2025-10-31T13:33:13","slug":"puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/","title":{"rendered":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson"},"content":{"rendered":"<p style=\"text-align: justify;\">Esta magn\u00edfica obra re\u00fane 41 conversaciones que\u00a0<strong>Henri Cartier-Bresson<\/strong>\u00a0mantuvo a lo largo de su carrera entre 1951 y 2003. Algunas de ellas in\u00e9ditas, las entrevistas con este excepcional artista y pensador ponen de manifiesto su esp\u00edritu refinado y provocador \u2014m\u00e1s inclinado a evocar la pintura o la literatura que la fotograf\u00eda pura y dura\u2014y nos ofrecen las claves para comprender su enfoque est\u00e9tico y la evoluci\u00f3n de su pensamiento sobre la fotograf\u00eda y su relaci\u00f3n con el cine, el dibujo y la pintura.<\/p>\n<figure id=\"attachment_103830\" aria-describedby=\"caption-attachment-103830\" style=\"width: 972px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-103830\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\" alt=\"\u00bfPuedo guardarme alg\u00fan secreto Entrevistas con Henri Cartier-Bresson gg\" width=\"972\" height=\"1528\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg 972w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg-191x300.jpg 191w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg-651x1024.jpg 651w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg-267x420.jpg 267w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg-696x1094.jpg 696w\" sizes=\"auto, (max-width: 972px) 100vw, 972px\" \/><figcaption id=\"caption-attachment-103830\" class=\"wp-caption-text\"><span style=\"color: #999999;\">\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\u00a0<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ilustrado con una selecci\u00f3n de sus fotograf\u00edas y dibujos, estos textos nos abren una nueva e iluminadora perspectiva a la hora de acercarnos a la vida y la obra de uno de los grandes referentes de la fotograf\u00eda de la segunda mitad del siglo XX. Henri Cartier-Bresson (1908-2004) es un fot\u00f3grafo franc\u00e9s considerado uno de los padres del fotoperiodismo.<\/p>\n<p style=\"text-align: justify;\">Desde la\u00a0<strong>agencia Magnum<\/strong>, que fund\u00f3 en 1947 junto a Robert Capa, David (Chim) Seymour, William Vandivert y George Rodger, realiz\u00f3 algunos de los grandes reportajes sobre Europa, Oriente y la antigua URSS que le dieron fama mundial como cronista gr\u00e1fico.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00abEs una suposici\u00f3n, digna de figurar en el Diccionario de lugares comunes de Gustave Flaubert, pensar que los fot\u00f3grafos se expresan exclusivamente a trav\u00e9s de sus im\u00e1genes y que, por lo tanto, no tienen nada que decir. John Szarkowski, director del departamento de <\/em><em>fotograf\u00eda del Museo de Arte Moderno de Nueva York, lo sab\u00eda bien pues afirmaba, por el contrario, que los fot\u00f3grafos eran sin duda quienes hablaban mejor sobre el medio. El caso de Henri Cartier-Bresson es un buen ejemplo. Aunque sus fotograf\u00edas hayan sido objeto <\/em><em>de numerosas ex\u00e9gesis, en todas las lenguas, y por los autores m\u00e1s prestigiosos, nada es comparable a sus propias palabras\u00bb.<\/em><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta magn\u00edfica obra re\u00fane 41 conversaciones que\u00a0Henri Cartier-Bresson\u00a0mantuvo a lo largo de su carrera entre 1951 y 2003. Algunas de ellas in\u00e9ditas, las entrevistas con este excepcional artista y pensador ponen de manifiesto su esp\u00edritu refinado y provocador \u2014m\u00e1s inclinado a evocar la pintura o la literatura que la fotograf\u00eda pura y dura\u2014y nos ofrecen [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":103830,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[794,26],"tags":[8740,12471,424,2514,484,12460,8739,12205,2132,2812,12466,1120],"class_list":{"0":"post-103825","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-libros","8":"category-publicaciones","9":"tag-agencia-magnum","10":"tag-cine","11":"tag-dibujo","12":"tag-editorial-gustavo-gili","13":"tag-entrevista","14":"tag-fotografia","15":"tag-henri-cartier-bresson","16":"tag-libro","17":"tag-literatura","18":"tag-manifiesto","19":"tag-pintura","20":"tag-publicacion"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-10T23:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"972\" \/>\n\t<meta property=\"og:image:height\" content=\"1528\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"veredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"veredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/\"},\"author\":{\"name\":\"veredes\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\"},\"headline\":\"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\",\"datePublished\":\"2025-11-10T23:01:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/\"},\"wordCount\":341,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\",\"keywords\":[\"agencia Magnum\",\"cine\",\"dibujo\",\"editorial Gustavo Gili\",\"entrevista\",\"fotograf\u00eda\",\"Henri Cartier-Bresson\",\"libro\",\"literatura\",\"manifiesto\",\"pintura\",\"publicaci\u00f3n\"],\"articleSection\":[\"libros\",\"publicaciones\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/\",\"name\":\"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\",\"datePublished\":\"2025-11-10T23:01:13+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg\",\"width\":972,\"height\":1528,\"caption\":\"\u00bfPuedo guardarme alg\u00fan secreto Entrevistas con Henri Cartier-Bresson gg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/0bbb669073ef7faba5168a0844e93d2c\",\"name\":\"veredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/face-96x96.jpg\",\"caption\":\"veredes\"},\"description\":\"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.\",\"sameAs\":[\"https:\\\/\\\/veredes.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/www.pinterest.es\\\/veredes\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/veredes\",\"https:\\\/\\\/veredes.tumblr.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/alberto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes","description":"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes","og_description":"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson","og_url":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2025-11-10T23:01:13+00:00","og_image":[{"width":972,"height":1528,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg","type":"image\/jpeg"}],"author":"veredes","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"veredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/"},"author":{"name":"veredes","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c"},"headline":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson","datePublished":"2025-11-10T23:01:13+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/"},"wordCount":341,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg","keywords":["agencia Magnum","cine","dibujo","editorial Gustavo Gili","entrevista","fotograf\u00eda","Henri Cartier-Bresson","libro","literatura","manifiesto","pintura","publicaci\u00f3n"],"articleSection":["libros","publicaciones"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/","url":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/","name":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg","datePublished":"2025-11-10T23:01:13+00:00","description":"Toda la informaci\u00f3n sobre: \u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/11\/\u00bfPuedo-guardarme-algun-secreto-Entrevistas-con-Henri-Cartier-Bresson-gg.jpg","width":972,"height":1528,"caption":"\u00bfPuedo guardarme alg\u00fan secreto Entrevistas con Henri Cartier-Bresson gg"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/puedo-guardarme-algun-secreto-entrevistas-con-henri-cartier-bresson\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfPuedo guardarme alg\u00fan secreto? Entrevistas con Henri Cartier-Bresson"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/0bbb669073ef7faba5168a0844e93d2c","name":"veredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/face-96x96.jpg","caption":"veredes"},"description":"Surge enero de 2009 como b\u00fasqueda de satisfacer el conocimiento de la actividad arquitect\u00f3nica y tangentes que se generan. La idea es crear un espacio para divulgar los diversos proyectos en busca de nueva inspiraci\u00f3n y de intercambio.","sameAs":["https:\/\/veredes.es\/","https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/www.instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/www.pinterest.es\/veredes\/","https:\/\/x.com\/https:\/\/twitter.com\/veredes","https:\/\/veredes.tumblr.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/alberto\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/103825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=103825"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/103825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/103830"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=103825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=103825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=103825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}