{"id":103494,"date":"2025-10-03T00:01:16","date_gmt":"2025-10-02T22:01:16","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=103494"},"modified":"2025-10-03T12:07:28","modified_gmt":"2025-10-03T10:07:28","slug":"a-proposito-de-willy-ossott-oscar-tenreiro-degwitz","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/","title":{"rendered":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz"},"content":{"rendered":"<p style=\"text-align: justify;\">El que decida<sup>1 <\/sup>hoy hablar de Willy Ossott (1913-1975) tiene directa relaci\u00f3n con la situaci\u00f3n actual <a href=\"https:\/\/veredes.es\/blog\/tag\/arquitectura-venezolana\/\" target=\"_blank\" rel=\"noopener\">venezolana<\/a>, porque <a href=\"https:\/\/fundaayc.com\/tag\/willy-ossot\/\" target=\"_blank\" rel=\"noopener\">record\u00e1ndolo a \u00e9l<\/a>, fundador de la Facultad de Arquitectura de nuestra Universidad Central de Venezuela y su primer Decano en 1953, podemos aprender sobre la diferencia que existe entre asumir nuestros actos desde los l\u00edmites del discernimiento moral personal o, por el contrario usar la ideolog\u00eda como escudo, como parapeto que oculta la responsabilidad de cada quien. Porque el Dr. Ossott, como lo llam\u00e1bamos, sin ser un rutinario ejemplarizante (era conocida su dipsoman\u00eda, que sin embargo nunca le impidi\u00f3 atender las obligaciones de su cargo) era un profesional de s\u00f3lida formaci\u00f3n y un hombre de amplia cultura. De all\u00ed su inter\u00e9s por ampliar los contenidos human\u00edsticos de su profesi\u00f3n de ingeniero, inter\u00e9s que lo llev\u00f3 a seguir la carrera de Arquitectura, nueva aqu\u00ed, en la instituci\u00f3n que precedi\u00f3 a la fundaci\u00f3n de la Facultad, primero un Departamento de la Facultad de Ingenier\u00eda (1943) y luego (1946) Escuela.<\/p>\n<p style=\"text-align: justify;\">Pero no es tanto de la trayectoria profesional del Dr. Ossott de lo que quiero ocuparme sino de una an\u00e9cdota en relaci\u00f3n con \u00e9l que es demostrativa de lo que acabo de decir m\u00e1s arriba en relaci\u00f3n al tema de la integridad personal. La impresi\u00f3n que era com\u00fan sobre su desempe\u00f1o era que se trataba de un ser humano cuyos principios \u00e9ticos, su rectitud y su calidad humana estaba por encima del rol pol\u00edtico que eventualmente pod\u00eda asign\u00e1rsele a su cargo, particularmente el de Vicerector de la UCV, el cual ejerc\u00eda conjuntamente con el Decanato.<\/p>\n<p style=\"text-align: justify;\">Para nosotros era por sobre todo el muy exigente profesor de Geometr\u00eda Descriptiva<sup>2 <\/sup>y una especie de figura paterna que manejaba con maneras suaves, de refinada educaci\u00f3n y sobre todo de extrema decencia, incapaz de expresarse en t\u00e9rminos autoritarios derivados del contexto pol\u00edtico de entonces, a una Facultad de menos de 400 estudiantes de atm\u00f3sfera particularmente din\u00e1mica.<\/p>\n<figure id=\"attachment_103496\" aria-describedby=\"caption-attachment-103496\" style=\"width: 940px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-103496 size-full\" title=\"autorretrato de Willy Ossott,\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg\" alt=\"autorretrato de Willy Ossott,\" width=\"940\" height=\"1280\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg 940w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott-220x300.jpg 220w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott-752x1024.jpg 752w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott-308x420.jpg 308w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott-696x948.jpg 696w\" sizes=\"auto, (max-width: 940px) 100vw, 940px\" \/><figcaption id=\"caption-attachment-103496\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Autorretrato de Willy Ossott<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Pero, como ya he narrado otras veces, hab\u00eda un r\u00edo subterr\u00e1neo ya en 1957 de suficiente caudal como para que culminara en las protestas estudiantiles de Noviembre. Durante esos meses dif\u00edciles no se conoci\u00f3 de parte del Dr. Ossott ninguna iniciativa, disposici\u00f3n o acto menor que lo ubicara entre quienes soportaban al sistema dictatorial. Pero l\u00f3gicamente, la din\u00e1mica pol\u00edtica lo exig\u00eda, despu\u00e9s de Enero del 58 el Dr. Ossott fue separado de la Universidad.<\/p>\n<p style=\"text-align: justify;\">Luego, en Noviembre de 1958, lo nombr\u00f3 el Ing. Luis B\u00e1ez D\u00edaz, Ministro de Obras P\u00fablicas del Gobierno Provisional, como su Director de Edificios, nombramiento que origin\u00f3 un documento publicado con la firma de un grupo de ingenieros y algunos arquitectos al servicio de ese Ministerio que repudiaban el nombramiento dando razones que tanto para m\u00ed (que en ese momento era Presidente del Centro de Estudiantes de Arquitectura) como para muchos de mis compa\u00f1eros, era un pronunciamiento\u00a0<em>de baja ralea pol\u00edtica<\/em>\u00a0que al poco tiempo fue seguido de noticias de prensa vejatorias para nuestro viejo profesor que culminaron en una desatinada y alevosa publicaci\u00f3n en un diario de \u00ednfimo nivel (el periodismo oportunista siempre al acecho) que hab\u00eda surgido en esos tiempos y se llamaba (\u00bf?) <em>La Raz\u00f3n<\/em>.<\/p>\n<h5 style=\"text-align: justify;\"><strong>Y lo que interesa se\u00f1alar es la actitud que tomamos los estudiantes de arquitectura<\/strong><\/h5>\n<p style=\"text-align: justify;\">Redactamos un comunicado que publicamos y adem\u00e1s le\u00edmos el 11 de Enero de 1959 en nuestro programa de radio dominical (<em>Arquitectura y Humanismo por Radio Continente<\/em>) donde rechaz\u00e1bamos la campa\u00f1a de descr\u00e9dito contra el Dr. Ossott en t\u00e9rminos como los que siguen:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00ab\u2026a nadie se le escapa el hecho de la preocupaci\u00f3n del Dr. Ossott por mejorar la Escuela de Arquitectura y sus sanas intenciones para con el fututo de ella\u2026la comprensi\u00f3n que mostr\u00f3 repetidas veces para con nosotros sus alumnos \u2026condenamos en\u00e9rgicamente la publicaci\u00f3n del comunicado al que aludimos (el de los profesionales empleados del Ministerio), lo consideramos un atentado contra la \u00e9tica universitaria\u2026\u00bb<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">El lenguaje<sup>3 <\/sup>era simple, nada versado en jerga pol\u00edtica. Quer\u00eda se\u00f1alar hacia la persona de nuestro profesor, rescatarlo de la calificaci\u00f3n exclusivamente pol\u00edtica, un pecado para el marxismo radical que dominaba todas las Facultades menos la nuestra e Ingenier\u00eda (nos llamaban despectivamente\u00a0<em>Guant\u00e1namo<\/em>). Su estilo y contenido fue criticado e incluso ridiculizado, escenificando lo que hoy sabemos: la permanente confusi\u00f3n de las izquierdas reaccionarias, al hacer juicios gruesos alentados por la manipulaci\u00f3n ideol\u00f3gica. La imposibilidad de discernir entre los contenidos \u00e9ticos que alimentan la moral personal y los postulados pol\u00edtico-ideol\u00f3gicos convertidos en \u00eddolos.<\/p>\n<p style=\"text-align: justify;\">Tropec\u00e9 con el texto de este comunicado y con una carta donde explicaba lo que nos suced\u00eda, hace dos d\u00edas. No pude dejar de comparar lo de entonces con lo que hoy acontece aqu\u00ed. Con la erosi\u00f3n conformista, precisamente, de la moral personal de gente formada en el mundo universitario de aquellos tiempos, que presum\u00eda de esp\u00edritu cr\u00edtico y abundaba en palabras deseosas de lapidar a quien no estuviera con ellos, hasta llegar a apoyar hoy en silencio todas las triqui\u00f1uelas perversas que se desarrollan ante sus ojos. Silencio culpable que creen ocultar, como digo m\u00e1s arriba, con el biombo de la ideolog\u00eda. No les vendr\u00eda mal, esta nota lo explicita, tener en cuenta que lo que perdura, lo que recordamos medio siglo despu\u00e9s y define la figura de cada quien en el escenario \u00e9tico que a todos nos ata\u00f1e, es la conducta personal, la capacidad de ser testimonio de humanidad, superando el peso de las circunstancias que a veces nos superan.<\/p>\n<p style=\"text-align: justify;\">Y manteniendo la dignidad, como ocurri\u00f3 con Willy Ossott.<\/p>\n<p>\u00d3scar Tenreiro Degwitz, arquitecto.<br \/>\nVenezuela, Agosto 2013<\/p>\n<h6><strong>Notas:<\/strong><\/h6>\n<p style=\"text-align: justify;\"><sup>1 <\/sup>Y hace unos d\u00edas, como digo en la nota de hoy, mientras ordenaba los planos de un viejo proyecto (me empe\u00f1o ahora en digitalizar todo mi trabajo anterior) distra\u00eddamente tom\u00e9 una de las carpetas y tropec\u00e9 en una carta con un recuento de los primeros d\u00edas de Enero del 59 que incluyen el episodio de nuestro viejo profesor Willy Ossott.<\/p>\n<p style=\"text-align: justify;\">Willy, sus nombres lo delatan, era descendiente de alemanes y su padre Eugen Ossott (Her Ossott para sus alumnos), casado con Maria Luisa Machado, del Pao, Edo. Cojedes, Venezuela, fund\u00f3 y dirigi\u00f3 durante muchos a\u00f1os en Caracas el Colegio Froebel o Instituto Cat\u00f3lico Alem\u00e1n, que luego se traslad\u00f3 a Valencia, cuya ense\u00f1anza se basaba en el m\u00e9todo froebeliano.<\/p>\n<p style=\"text-align: justify;\">Willy ten\u00eda sin duda rastros en su car\u00e1cter que lo vinculaban a su sangre (disciplinado, riguroso, honesto, de palabra) sin que pueda dejarse de decir que su relaci\u00f3n con Venezuela era profunda y total, hasta llegar a convertirlo en un cultor de nuestra arquitectura colonial, culto que lo llev\u00f3 a incorporar a nuestra Facultad a ese sabio de nuestro pasado construido que fue Carlos Manuel M\u00f6ller, tambi\u00e9n de origen alem\u00e1n. Su casa (la de Willy), que visit\u00e9 una vez muy de pasada, era una buena muestra ecl\u00e9ctica con destacada presencia de la huella arquitect\u00f3nica de nuestros tiempos anteriores.<\/p>\n<p style=\"text-align: justify;\"><sup>2 <\/sup>Por razones muy particulares, mi compa\u00f1ero de estudios, amigo de ese entonces y hoy colega que veo con la frecuencia con que nos vemos los de m\u00e1s edad, Pedro Sosa Franco, tiene un autorretrato de Willy Ossott, porque Willy era pintor de t\u00e9cnica depurada y muy especial inter\u00e9s, sobre todo porque sin tener pretensiones de mucho alcance cultiv\u00f3 ese medio expresivo con asiduidad mientras su salud y su lucha con la subsistencia se lo permiti\u00f3. Est\u00e1 pintado a la manera surrealista y siempre me atrajo. Lo record\u00e9 al escribir lo de hoy y le ped\u00ed a Pedro, como favor de amigo, que lo trajese a casa durante unos pocos minutos para tomarle la fotograf\u00eda que ilustrar\u00eda estas l\u00edneas. Lo hizo, y mientras tomaba la foto me cont\u00f3 detalles de mucho inter\u00e9s que ayudan a definir la personalidad de Ossott y sobre todo su rigor, que para nosotros como estudiantes quedaba claro en la forma precisa, ordenada, ayudada con estupendos dibujos en el pizarr\u00f3n, como ense\u00f1aba la Geometr\u00eda Descriptiva, que era la materia problem\u00e1tica con la que nos encontr\u00e1bamos durante los dos primeros a\u00f1os de carrera.<\/p>\n<p style=\"text-align: justify;\">Ossott le hizo notar por ejemplo que el cuadro hab\u00eda sido pintado con \u00f3leo preparado por \u00e9l mismo con pigmentos \u00aba la manera de Memling\u00bb, que hab\u00eda fabricado los pinceles y que el bigote por ejemplo lo hab\u00eda pintado con pelo de caballo, pelo por pelo, en la tradici\u00f3n flamenca. Incluso el marco, una versi\u00f3n muy personal en tallado r\u00fastico de los elaborados marcos renacentistas, lo hab\u00eda hecho con sus manos. Que hab\u00eda usado los tonos de color de H\u00e9ctor Poleo (1918-1989) pintor nuestro que tuvo una \u00e9poca dorada en los cincuenta y sesenta del siglo pasado, de t\u00e9cnica figurativa muy cuidada. Y que se hab\u00eda dibujado con la cabeza rapada porque quer\u00eda parecer alem\u00e1n, para delatar su herencia.<\/p>\n<p style=\"text-align: justify;\">No se trata, me parece, de detalles sin importancia. Apuntan hacia la complejidad de motivos y est\u00edmulos de la gente de nuestra parte del mundo. Tal vez hacia la superposici\u00f3n de la herencia con lo contingente, con lo que termina dejando un sello directo en lo que somos, lo que hac\u00eda decir al soci\u00f3logo brasile\u00f1o Darcy Ribeiro (1922-1997) que bastaba con que un europeo cruzara el Atl\u00e1ntico y tocara tierra aqu\u00ed para que empezara a pensar de modo diferente, como uno de aqu\u00ed. Posibilidad aumentada y estimulada por el hecho de que somos en realidad, con todas nuestras mezclas, con todo nuestro mestizaje, prolongaci\u00f3n, desarrollo, evoluci\u00f3n y transformaci\u00f3n de la mirada europea.<\/p>\n<p style=\"text-align: justify;\"><sup>3 <\/sup>Y me refer\u00ed al principio a las cartas. Lo que inmediatamente me hizo pensar en la importancia de la escritura, del esfuerzo de comunicaci\u00f3n. Y cambi\u00e9 de idea respecto a ellas, ya no las destruir\u00e9. S\u00e9 que a nadie le interesar\u00e1n, como a m\u00ed en muchos sentidos tampoco ya me interesan, pero contienen algo que en definitiva me parece invalorable: son como una cr\u00f3nica de los tiempos vividos en el fin de la adolescencia. Tiempos tan particulares, singulares y en cierto modo fundacionales como cualquier tiempo adolescente, en los cuales ciertos sentimientos personales, entre ellos el religioso, eran muy fuertes en m\u00ed. Ahora veo que me sirven para situarme en una etapa en la que se fueron afirmando puntos de vista que ir\u00edan ocupando mi escena personal.<\/p>\n<p style=\"text-align: justify;\">Y la reflexi\u00f3n que inevitablemente deb\u00eda acompa\u00f1ar, o ser origen, de esa cr\u00f3nica fue probablemente la base de algo que se ha convertido para m\u00ed en asunto esencial que es el escribir. Ejercicio \u00fatil, casi fundamental, para afinar las ideas, tal vez para darles forma, o en todo caso para tratar de saber de donde vienen y hacia donde quieren conducirme. Escribir, eso s\u00ed, no para llenar o construir una apariencia, sino para comunicar. O comunicarme.<\/p>\n<p style=\"text-align: justify;\">Se lo he recomendado mucho a mis hijos, a los m\u00e1s j\u00f3venes, tan atrapados como est\u00e1n por s\u00f3lo la imagen, s\u00f3lo lo inmediato, el SMS y tantas cosas. Y poco caso me hacen ,como tiene que ser. Mientras que yo agradezco que eso \u00abse me haya dado\u00bb. Me permiti\u00f3 por ejemplo, pensar unas horas en mi viejo profesor, tam<em>bi\u00e9n en lo que trat\u00f3 de dejarnos.<\/em><\/p>\n<p style=\"text-align: justify;\"><sup>4 <\/sup>Guardo entre mis papeles varias carpetas de cartas que pertenece a una \u00e9poca temprana de mi vida entre los 19 y 21 a\u00f1os. Son las que intercambiaba con Delia Pic\u00f3n Cento, chilena y venezolana, a quien hab\u00eda conocido en Brasil, Noviembre de 1958, cuando regresaba acompa\u00f1ado del compa\u00f1ero de estudios Gonzalo Castellanos, de un Congreso de Estudiantes de Arquitectura celebrado en Septiembre en Santiago de Chile. Ese viaje fue para m\u00ed memorable. Por una parte me abri\u00f3 en el alma algo as\u00ed como una comprensi\u00f3n del ser latinoamericano que nunca me ha abandonado (estuvimos tambi\u00e9n en Per\u00fa, Argentina y Uruguay), y en el terreno m\u00e1s \u00edntimo convirti\u00f3 al encuentro con Delia (Pascualita le dec\u00edan en la casa por haber nacido el 24 de Diciembre) en comienzo de una historia com\u00fan que nos llev\u00f3 a dar al mundo cuatro hijos (Oscar, Daniel, Paula, Esteban) nacidos de un matrimonio que, iniciado en 1960, durar\u00eda hasta 1971.<\/p>\n<p style=\"text-align: justify;\">Compartimos al conocernos algo m\u00e1s de dos semanas de un verano de 42 grados a la sombra en R\u00edo de Janeiro (su pap\u00e1, Mariano Pic\u00f3n Salas, era all\u00ed Embajador de Venezuela) y desde entonces se abri\u00f3 espacio para un noviazgo mayoritariamente por carta (nos vimos s\u00f3lo despu\u00e9s en dos oportunidades m\u00e1s o menos largas antes de casarnos) que sell\u00f3 mi ritmo e intenciones de vida en los a\u00f1os inmediatos. Y a mi regreso a Caracas comenz\u00f3 una intensa actividad epistolar que se prolong\u00f3 hasta mi llegada a Chile (ella viv\u00eda en Chile con su madre, Isabel Cento) el 13 de Agosto de 1960 para casarme el 6 de Noviembre, seis d\u00edas antes de yo cumplir los 21 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\">Las cartas (las m\u00edas y las de ella) est\u00e1n all\u00ed en una estanter\u00eda de mi archivo, envejeciendo. A veces releo alguna para encontrar demasiadas cosas propias del lenguaje adolescente de dos novios, que ya me averg\u00fcenzan un poco. Pero tambi\u00e9n contienen otras cosas referidas a lo que acontec\u00eda a mi alrededor porque me empe\u00f1aba en hacerle a ella un recuento de todo, o casi todo, lo que me ocurr\u00eda.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El que decida1 hoy hablar de Willy Ossott (1913-1975) tiene directa relaci\u00f3n con la situaci\u00f3n actual venezolana, porque record\u00e1ndolo a \u00e9l, fundador de la Facultad de Arquitectura de nuestra Universidad Central de Venezuela y su primer Decano en 1953, podemos aprender sobre la diferencia que existe entre asumir nuestros actos desde los l\u00edmites del discernimiento [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":103496,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[568,5951],"tags":[9142,393,668,11762,1021,1531,18186],"class_list":{"0":"post-103494","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-faro","8":"category-slider-principal","9":"tag-arquitectura-venezolana","10":"tag-critica","11":"tag-historia","12":"tag-oscar-tenreiro-degwitz","13":"tag-pensamiento","14":"tag-venezuela","15":"tag-willy-ossott"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T22:01:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-03T10:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@veredes\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00d3scar Tenreiro Degwitz\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/\"},\"author\":{\"name\":\"\u00d3scar Tenreiro Degwitz\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\"},\"headline\":\"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\",\"datePublished\":\"2025-10-02T22:01:16+00:00\",\"dateModified\":\"2025-10-03T10:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/\"},\"wordCount\":2331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/autorretrato-de-Willy-Ossott.jpg\",\"keywords\":[\"arquitectura venezolana\",\"cr\u00edtica\",\"historia\",\"\u00d3scar Tenreiro Degwitz\",\"pensamiento\",\"Venezuela\",\"Willy Ossott\"],\"articleSection\":[\"faro\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/\",\"name\":\"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/autorretrato-de-Willy-Ossott.jpg\",\"datePublished\":\"2025-10-02T22:01:16+00:00\",\"dateModified\":\"2025-10-03T10:07:28+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/autorretrato-de-Willy-Ossott.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/autorretrato-de-Willy-Ossott.jpg\",\"width\":940,\"height\":1280,\"caption\":\"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/3612c3173c340910b53bc7a6a8816b19\",\"name\":\"\u00d3scar Tenreiro Degwitz\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg\",\"caption\":\"\u00d3scar Tenreiro Degwitz\"},\"description\":\"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.\",\"sameAs\":[\"https:\\\/\\\/oscartenreiro.com\\\/\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/oscar-tenreiro-degwitz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes","description":"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/","og_locale":"es_ES","og_type":"article","og_title":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes","og_description":"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz","og_url":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_published_time":"2025-10-02T22:01:16+00:00","article_modified_time":"2025-10-03T10:07:28+00:00","og_image":[{"width":940,"height":1280,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg","type":"image\/jpeg"}],"author":"\u00d3scar Tenreiro Degwitz","twitter_card":"summary_large_image","twitter_creator":"@veredes","twitter_site":"@veredes","twitter_misc":{"Escrito por":"\u00d3scar Tenreiro Degwitz","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/"},"author":{"name":"\u00d3scar Tenreiro Degwitz","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19"},"headline":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz","datePublished":"2025-10-02T22:01:16+00:00","dateModified":"2025-10-03T10:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/"},"wordCount":2331,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg","keywords":["arquitectura venezolana","cr\u00edtica","historia","\u00d3scar Tenreiro Degwitz","pensamiento","Venezuela","Willy Ossott"],"articleSection":["faro","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/","url":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/","name":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg","datePublished":"2025-10-02T22:01:16+00:00","dateModified":"2025-10-03T10:07:28+00:00","description":"Toda la informaci\u00f3n sobre: A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/10\/autorretrato-de-Willy-Ossott.jpg","width":940,"height":1280,"caption":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz"},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/a-proposito-de-willy-ossott-oscar-tenreiro-degwitz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"A prop\u00f3sito de Willy Ossott | \u00d3scar Tenreiro Degwitz"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/3612c3173c340910b53bc7a6a8816b19","name":"\u00d3scar Tenreiro Degwitz","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/\u00d3scar-Tenreiro-Degwitz-96x96.jpg","caption":"\u00d3scar Tenreiro Degwitz"},"description":"Es un arquitecto venezolano, nacido en 1939, Premio Nacional de Arquitectura de su pa\u00eds en 2002-2003, profesor de Dise\u00f1o Arquitect\u00f3nico por m\u00e1s de treinta a\u00f1os en la Universidad Central de Venezuela, quien paralelamente con su ejercicio ha mantenido ya por a\u00f1os presencia en la prensa de su pa\u00eds en un esfuerzo de comunicaci\u00f3n hacia la gente en general de los puntos de vista del arquitecto acerca de los m\u00e1s diversos temas, entre los cuales figuran los agudos problemas pol\u00edticos de una sociedad como la venezolana. Tenreiro practica as\u00ed lo que el llama el \u201cpensamiento desde y hacia la arquitectura\u201d, insistiendo en que lo hace como arquitecto en ejercicio, para escapar de los estereotipos y cautelas propios de la \u201ccr\u00edtica arquitect\u00f3nica\u201d. Respecto a la cual no oculta su desconfianza, que explica recurriendo al aforismo de Nietzsche sobre el cr\u00edtico de arte \u201cque ve el arte desde cerca sin llegar a tocarlo nunca\u201d.","sameAs":["https:\/\/oscartenreiro.com\/"],"url":"https:\/\/veredes.es\/blog\/author\/oscar-tenreiro-degwitz\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/103494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=103494"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/103494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/103496"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=103494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=103494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=103494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}