{"id":101248,"date":"2025-03-21T00:01:44","date_gmt":"2025-03-20T23:01:44","guid":{"rendered":"https:\/\/veredes.es\/blog\/?p=101248"},"modified":"2025-03-21T08:41:00","modified_gmt":"2025-03-21T07:41:00","slug":"la-plastica-es-culpable-jose-ramon-hernandez-correa","status":"publish","type":"post","link":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/","title":{"rendered":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: justify;\"><em>Si un pintor encuentra a un hombre en harapos y si se conmueve por empat\u00eda, de hombre a hombre, ante la condici\u00f3n de pobreza en la que el hombre se encuentra, puede ocurrir que el pintor traslade esta emoci\u00f3n de pobreza a una situaci\u00f3n pintada, pero ligada a la aparici\u00f3n de un hombre en harapos.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Vista y reproducida de esta forma, puede surgir una imagen t\u00edpica de la pobreza que, sin embargo, muy poco o nada tenga que ver con el arte est\u00e9tico y pl\u00e1stico. [&#8230;]<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Si, por el contrario, la relaci\u00f3n del artista con su objeto de la experiencia es predominantemente est\u00e9tica, los sentimientos de placer o de desplacer, lo personal y lo individualmente humano, har\u00e1n lugar a los acentos m\u00e1s generales, est\u00e9ticos [&#8230;]. No dejar\u00e1 predominar en su obra los acentos emocionales, sino los est\u00e9ticos. [&#8230;]<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Esta exageraci\u00f3n [de los acentos est\u00e9ticos] se lleva a cabo por medio de una definici\u00f3n m\u00e1s intensa de los valores espaciales y de los valores del color. No por empat\u00eda ante la situaci\u00f3n en la que el objeto de la experiencia se encuentra, sino precisamente por lo contrario, por la abstracci\u00f3n de toda particularidad local del objeto, el artista llegar\u00e1 a exponer las relaciones c\u00f3smicas m\u00e1s generales y valores como los de: equilibrio, posici\u00f3n, masa, n\u00famero, etc., que la particularidad local del caso hubiera cubierto o velado.<\/em><\/p>\n<p style=\"text-align: right;\">Theo van Doesburg<sup>1<\/sup><\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En 2017 a\u00f1o se cumpli\u00f3 un siglo de la creaci\u00f3n de <a href=\"https:\/\/veredes.es\/blog\/tag\/de-stijl\/\" target=\"_blank\" rel=\"noopener\"><em>De Stijl<\/em><\/a>. Fue un movimiento que quer\u00eda abarcar todas las artes, y que pretend\u00eda que estas fueran <em>antitr\u00e1gicas<\/em>. Es decir, que no se ocuparan de representar la realidad emocional y emocionante, sino que construyeran puras relaciones pl\u00e1sticas, liberadas de la an\u00e9cdota.<\/p>\n<p style=\"text-align: justify;\">Pretend\u00edan, ante este mundo ca\u00f3tico, caprichoso, desordenado y tr\u00e1gico, crear un universo est\u00e9tico ordenado y organizado por las meras relaciones pl\u00e1sticas.<\/p>\n<figure id=\"attachment_101250\" aria-describedby=\"caption-attachment-101250\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101250\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Theo van Doesburg Dibujos y pinturas representando y reelaborando una vaca\" width=\"750\" height=\"500\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg 688w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca-300x200.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca-630x420.jpg 630w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-101250\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Theo van Doesburg: Dibujos y pinturas representando y reelaborando una vaca, yendo desde <\/span><span style=\"color: #999999;\">la representaci\u00f3n \u00abrealista\u00bb hasta la abstracci\u00f3n y las puras relaciones pl\u00e1sticas primarias <\/span><span style=\"color: #999999;\">y geom\u00e9tricas. (Pero este es un momento inicial e inmaduro: Al madurar, De Stijl ya no <\/span><span style=\"color: #999999;\">trata de cuadricular una vaca, sino que no parte de una vaca para empezar a pintar).<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Las fotos que vimos en la anterior entrada son como el hombre en harapos al que se refiere <a href=\"https:\/\/veredes.es\/blog\/tag\/theo-van-doesburg\/\" target=\"_blank\" rel=\"noopener\">Theo van Doesburg:<\/a> basan su eficacia pl\u00e1stica en la empat\u00eda. Su pl\u00e1stica es<em> tr\u00e1gica y expresionista<\/em>: Las cualidades puramente pl\u00e1sticas (color, tama\u00f1o, forma&#8230;) est\u00e1n al servicio de un sentimiento emp\u00e1tico.<\/p>\n<p style=\"text-align: justify;\">Por el contrario, <em><a href=\"https:\/\/fragmentosdelcosmos.blogspot.com\/2011\/02\/la-revista-de-stijl-1917-1932.html\" target=\"_blank\" rel=\"noopener\">De Stijl<\/a> <\/em>se basa s\u00f3lo en cualidades pl\u00e1sticas, sin referencia alguna a sentimientos o a experiencias vitales.<sup>2\u00a0<\/sup><\/p>\n<h6 style=\"text-align: justify;\"><strong>\u00bfEntonces, por fin, la pl\u00e1stica de De Stijl es inocente? <\/strong><\/h6>\n<p style=\"text-align: justify;\">En absoluto. La pl\u00e1stica nunca es inocente. La pl\u00e1stica de <em>De Stijl<\/em> quiere ser <em>antitr\u00e1gica<\/em>, pero no por ello se libra de culpa.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de buscar una pura pl\u00e1stica, sin acentos emocionales, los fundadores de <em>De Stijl<\/em> quisieron restringirla al protagonismo del plano, a las l\u00edneas rectas verticales y horizontales y a los colores primarios. Con estas severas restricciones el arte ten\u00eda que salir como un objeto de laboratorio o como un teorema.<\/p>\n<p style=\"text-align: justify;\">Podr\u00edamos pensar que con estos condicionantes antitr\u00e1gicos y estas normas severas la pl\u00e1stica ser\u00eda inocente y desenfadada, e ideol\u00f3gicamente neutra. Nada de eso. No se trataba de un mero ejercicio de dise\u00f1o. Se trataba de construir un universo, y eso es muy duro.<\/p>\n<figure id=\"attachment_101253\" aria-describedby=\"caption-attachment-101253\" style=\"width: 1600px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-101253\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Theo van Doesburg, Contra-composici\u00f3n XVI, 1925\" width=\"1600\" height=\"880\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925.jpg 1600w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-300x165.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-1024x563.jpg 1024w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-1536x845.jpg 1536w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-764x420.jpg 764w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-696x383.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Contra-composicion-XVI-1925-1068x587.jpg 1068w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><figcaption id=\"caption-attachment-101253\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Theo van Doesburg, Contra-composici\u00f3n XVI, 1925.<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">En cierto momento, ya un poco aburrido de siempre lo mismo, Theo van Doesburg inclin\u00f3 las l\u00edneas y adopt\u00f3 colores no primarios, y Mondrian dej\u00f3 de hablarle. Nadie se agarra semejante cabreo b\u00edblico por una pl\u00e1stica inocente, por un mero juego de formas y colores.<br \/>\nNo era tan sencillo, y de ninguna manera era algo tonto o inocente. No hay m\u00e1s que leer a Mondrian y sus rollos teos\u00f3ficos y sus disquisiciones sobre lo que significa la horizontal, la vertical, los colores&#8230;<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>\u00a1Uf! Ah\u00ed hay mucha seriedad, mucho af\u00e1n de trascendencia y mucho misticismo.<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_101252\" aria-describedby=\"caption-attachment-101252\" style=\"width: 925px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101252 size-full\" title=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Piet Mondrian, Composici\u00f3n I con azul y amarillo, 1925\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-I-con-azul-y-amarillo-1925.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Piet Mondrian, Composici\u00f3n I con azul y amarillo, 1925\" width=\"925\" height=\"900\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-I-con-azul-y-amarillo-1925.jpg 925w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-I-con-azul-y-amarillo-1925-300x292.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-I-con-azul-y-amarillo-1925-432x420.jpg 432w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-I-con-azul-y-amarillo-1925-696x677.jpg 696w\" sizes=\"auto, (max-width: 925px) 100vw, 925px\" \/><figcaption id=\"caption-attachment-101252\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Piet Mondrian, Composici\u00f3n I con azul y amarillo, 1925.<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Cuando Theo van Doesburg gira las l\u00edneas y figuras del cuadro Mondrian gira el marco, pero el contenido del cuadro sigue siendo vertical-horizontal. Mucha enjundia. Mucha tensi\u00f3n.<\/p>\n<figure id=\"attachment_101251\" aria-describedby=\"caption-attachment-101251\" style=\"width: 1584px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101251 size-full\" title=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Piet Mondrian, Composici\u00f3n con dos l\u00edneas, 1931\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Piet Mondrian, Composici\u00f3n con dos l\u00edneas, 1931\" width=\"1584\" height=\"1600\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931.jpg 1584w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-297x300.jpg 297w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-1014x1024.jpg 1014w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-1521x1536.jpg 1521w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-416x420.jpg 416w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-696x703.jpg 696w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Piet-Mondrian-Composicion-con-dos-lineas-1931-1068x1079.jpg 1068w\" sizes=\"auto, (max-width: 1584px) 100vw, 1584px\" \/><figcaption id=\"caption-attachment-101251\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Piet Mondrian, Composici\u00f3n con dos l\u00edneas, 1931.<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">No es ninguna broma romper con un amigo porque ha girado las l\u00edneas y, una vez rota la amistad, reconcentrarse en el estudio, pensar, probar, reflexionar&#8230; y terminar girando el cuadro entero pero las l\u00edneas no.<\/p>\n<p style=\"text-align: justify;\">Ah\u00ed no hay nada inocente. Eso es algo muy serio. (Y adem\u00e1s hay que estar <em>mu loco<\/em>. Pero <em>mu loco<\/em>).<sup>3<\/sup><\/p>\n<p style=\"text-align: justify;\">Me imagino a Mondrian ahora, asistiendo al triunfo de sus dise\u00f1os en teteras, vestidos y relojes y sufriendo un serio jamacuco. Su arte convertido en objeto de decoraci\u00f3n, en broma, su carga explosiva desactivada, su fuerza vital convertida en un chiste.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_101255\" aria-describedby=\"caption-attachment-101255\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101255\" title=\"Chorradicas mondrianesca\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-1.jpg\" alt=\"Chorradicas mondrianesca\" width=\"750\" height=\"1450\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-1.jpg 377w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-1-155x300.jpg 155w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-1-217x420.jpg 217w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-101255\" class=\"wp-caption-text\"><span style=\"color: #999999;\"><em>Chorradica mondrianesca<\/em><\/span><\/figcaption><\/figure>\n<h6 style=\"text-align: justify;\"><strong>La pl\u00e1stica no es inocente<\/strong><\/h6>\n<p style=\"text-align: justify; padding-left: 40px;\">&#8211; El caso es que son objetos bonitos.<br \/>\n&#8211; \u00bfBonitos? \u00a1No digas esa palabra! \u00a1Fuera de mi vista!<br \/>\n&#8211; Quiero decir que tienen gracia.<br \/>\n&#8211; \u00bfGracia? \u00bfT\u00fa quieres matarme o que te mate?<\/p>\n<p style=\"text-align: justify;\">Nada de bromas con la \u00abpura est\u00e9tica\u00bb, con la \u00abpl\u00e1stica pura\u00bb. No est\u00e1 la cosa para tonter\u00edas ni el horno para bollos.<\/p>\n<figure id=\"attachment_101256\" aria-describedby=\"caption-attachment-101256\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101256\" title=\"Chorradicas mondrianesca\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-mondrian-mierder-2.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa mondrian mierder 2\" width=\"750\" height=\"552\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-mondrian-mierder-2.jpg 500w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-mondrian-mierder-2-300x221.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-mondrian-mierder-2-80x60.jpg 80w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-101256\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Chorradica mondrianesca<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Theo van Doesburg, uno de los personajes m\u00e1s interesantes (y m\u00e1s tramposos) de la vanguardia art\u00edstica del siglo XX, se cans\u00f3 muy pronto del r\u00edgido catecismo que \u00e9l mismo hab\u00eda coescrito y hab\u00eda extendido por todo el mundo. Pero no contento con saltarse algunas normas (todas), girando las l\u00edneas y ampliando la paleta de colores, se apunt\u00f3 al enemigo con seud\u00f3nimos varios, con los que escrib\u00eda art\u00edculos contrarios a\u00a0<em>De Stijl\u00a0<\/em>en revistas de otras corrientes. No solo militaba en<em>\u00a0De Stijl<\/em>: es que era el jefe (o uno de los dos jefes m\u00e1s jefes). Pero al mismo tiempo era miembro (con nombre falso) del\u00a0<a href=\"https:\/\/veredes.es\/blog\/tag\/dadaismo\/\" target=\"_blank\" rel=\"noopener\"><em>Dad\u00e1<\/em><\/a>, que era lo m\u00e1s opuesto que cab\u00eda imaginar. Y participaba en otras corrientes. Con su verdadero nombre (su \u00abverdadero nombre\u00bb era ya un seud\u00f3nimo) hablaba de la pura pl\u00e1stica geom\u00e9trica, sin expresionismo, meras relaciones de forma, de color y de espacio, y con otros nombres hablaba de surrealismo, de expresi\u00f3n, de acci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Pod\u00e9is re\u00edros de los agentes dobles y triples de <a href=\"https:\/\/es.wikipedia.org\/wiki\/John_le_Carr%C3%A9\" target=\"_blank\" rel=\"noopener\">John le Carr\u00e9<\/a>. Theo van Doesburg polemizaba desde dos o tres tribunas diferentes, discut\u00eda consigo mismo, se llevaba la contraria, se desafiaba y se venc\u00eda.<\/p>\n<p style=\"text-align: justify;\">Y, lo que es peor, se tomaba a s\u00ed mismo en serio en todo ello.<\/p>\n<figure id=\"attachment_101257\" aria-describedby=\"caption-attachment-101257\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101257\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-3.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Mondrian mierder 3\" width=\"750\" height=\"750\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-3.jpg 550w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-3-300x300.jpg 300w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-3-120x120.jpg 120w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-3-420x420.jpg 420w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-101257\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Chorradica mondrianesca<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">No. No era una mera \u00abcuesti\u00f3n pl\u00e1stica\u00bb. No era una \u00abcosa est\u00e9tica\u00bb. Era la pura vida de sus autores. Y la nuestra. Era la lucha y la b\u00fasqueda.<\/p>\n<p style=\"text-align: justify;\">Se cuenta que Theo van Doesburg llevaba una pistola en sus conferencias en la <a href=\"https:\/\/veredes.es\/blog\/tag\/bauhaus\/\" target=\"_blank\" rel=\"noopener\">Bauhaus<\/a>, e incluso se dice que lleg\u00f3 a utilizarla (disparando al aire).<\/p>\n<p style=\"text-align: justify;\">La ideolog\u00eda estaba detr\u00e1s de las formas. Las formas nunca eran inocentes. Hab\u00eda grandes tensiones y luchas.<\/p>\n<figure id=\"attachment_101258\" aria-describedby=\"caption-attachment-101258\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101258\" title=\"Chorradica mondrianesca\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-4.jpg\" alt=\"La pl\u00e1stica es culpable Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa Mondrian mierder 4\" width=\"750\" height=\"851\" srcset=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-4.jpg 402w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-4-264x300.jpg 264w, https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Mondrian-mierder-4-370x420.jpg 370w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><figcaption id=\"caption-attachment-101258\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Chorradica mondrianesca<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La est\u00e9tica de <em>De Stijl<\/em> era limpia, s\u00ed, pero tambi\u00e9n era dura. Era de una pureza sobrehumana. Mondrian la empap\u00f3 de misticismo teos\u00f3fico. <a href=\"https:\/\/es.wikipedia.org\/wiki\/Jacobus_Henricus_van_%27t_Hoff\" target=\"_blank\" rel=\"noopener\">Jacobus Henricus van&#8217;t Hoff<\/a> quiso que construyera la nueva vivienda y la nueva f\u00e1brica del hombre concienciado y de izquierdas, y al ver que la arquitectura no pod\u00eda cambiar el mundo abandon\u00f3 la arquitectura.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><em>No; de est\u00e9tica bonita nada. De frusler\u00edas nada. Las cosas eran muy serias. Demasiado serias.<\/em><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Y, hablando de cosas muy serias y terribles, este a\u00f1o se cumple un siglo del nacimiento de\u00a0<em>De Stijl<\/em>, pero tambi\u00e9n de la Revoluci\u00f3n Rusa. Otro d\u00eda, tal vez, hablaremos de los vanguardistas sovi\u00e9ticos. Pero para eso no tengo ahora fuerzas y esto est\u00e1 quedando ya muy largo.<\/p>\n<figure id=\"attachment_101259\" aria-describedby=\"caption-attachment-101259\" style=\"width: 750px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-101259\" src=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-mondrian-mierder-5.jpg\" alt=\"\" width=\"750\" height=\"643\" \/><figcaption id=\"caption-attachment-101259\" class=\"wp-caption-text\"><span style=\"color: #999999;\">Chorradica mondrianesca<\/span><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa \u00b7 Doctor Arquitecto<br \/>\nToledo \u00b7 Febrero 2017<\/p>\n<h6 style=\"text-align: justify;\">Notas:<\/h6>\n<p style=\"text-align: justify;\"><sup>1 <\/sup>Doesburg, Theo van,\u00bb<em>Grondbegrippen van de nieuwe beeldende kunst\u00bb<\/em>,\u00a0Tijdschrift voor Wijsbejeerte, XIII, 1919, editado despu\u00e9s en alem\u00e1n, con algunas modificaciones, \u00abGrundbegriffe der neuen gestaltenden kunst\u00bb,\u00a0Bauhausb\u00fccher, n\u00ba 6, M\u00fanich, 1925. (De esta \u00faltima se ha hecho la traducci\u00f3n castellana que cito: <em>\u00abPrincipios del nuevo arte pl\u00e1stico<\/em>\u00ab, pp. 29-92, en el libro antol\u00f3gico\u00a0Principios del nuevo arte pl\u00e1stico y otros escritos, selecci\u00f3n, traducci\u00f3n y pr\u00f3logo de Charo Crego, Colegio Oficial de Aparejadores y Arquitectos T\u00e9cnicos, Murcia, 1985, pp. 260). (La cita est\u00e1 en las pp. 54-58 de este libro).<\/p>\n<p style=\"text-align: justify;\"><sup>2 <\/sup>Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa en <a href=\"http:\/\/arquitectamoslocos.blogspot.com.es\/2017\/02\/la-plastica-no-es-inocente.html\" target=\"_blank\" rel=\"noopener\">\u00abLa pl\u00e1stica no es inocente\u00bb,<\/a> y hace menci\u00f3n a que aquella resalta cualidades tr\u00e1gicas.<\/p>\n<p style=\"text-align: justify;\"><sup>3 <\/sup>Quiero darle a esta entrada un tono desenfadado y ligero. <em>De Stijl<\/em> es un movimiento art\u00edstico muy profundo y complejo, a cuyo estudio dediqu\u00e9 varios a\u00f1os cuando preparaba mi ya tan lejana tesis doctoral. Pero me da mucho miedo aburriros, y adem\u00e1s este espacio no es el sitio id\u00f3neo para meterse en fregados. Apenas doy un par de pinceladas y me refugio en este tono ligero e incluso tosco, pero espero haber podido al menos esbozar algo de cierto inter\u00e9s sin ponerme muy pesado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si un pintor encuentra a un hombre en harapos y si se conmueve por empat\u00eda, de hombre a hombre, ante la condici\u00f3n de pobreza en la que el hombre se encuentra, puede ocurrir que el pintor traslade esta emoci\u00f3n de pobreza a una situaci\u00f3n pintada, pero ligada a la aparici\u00f3n de un hombre en harapos. [&hellip;]<\/p>\n","protected":false},"author":33,"featured_media":101250,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36,39,3,5951],"tags":[12449,155,199,404,3032,17876,17877,3653,4390,4654],"class_list":["post-101248","post","type-post","status-publish","format-standard","has-post-thumbnail","category-arte-blog","category-artistas","category-capturas","category-slider-principal","tag-arte","tag-arte-contemporaneo","tag-bauhaus","tag-dadaismo","tag-de-stijl","tag-jacobus-henricus-van-t-hoff","tag-john-le-carre","tag-jose-ramon-hernandez-correa","tag-piet-mondrian","tag-theo-van-doesburg"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes<\/title>\n<meta name=\"description\" content=\"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes\" \/>\n<meta property=\"og:description\" content=\"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/\" \/>\n<meta property=\"og:site_name\" content=\"veredes, arquitectura y divulgaci\u00f3n\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/joseramon.hernandezcorrea\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-20T23:01:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-21T07:41:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"688\" \/>\n\t<meta property=\"og:image:height\" content=\"459\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/arquitectamos\" \/>\n<meta name=\"twitter:site\" content=\"@veredes\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/\"},\"author\":{\"name\":\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/eefca3204fa5a4349162c2869bee6c49\"},\"headline\":\"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\",\"datePublished\":\"2025-03-20T23:01:44+00:00\",\"dateModified\":\"2025-03-21T07:41:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/\"},\"wordCount\":1677,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\",\"keywords\":[\"arte\",\"arte contemporaneo\",\"Bauhaus\",\"dada\u00edsmo\",\"De Stijl\",\"Jacobus Henricus van 't Hoff\",\"John le Carr\u00e9\",\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\",\"Piet Mondrian\",\"Theo van Doesburg\"],\"articleSection\":[\"arte\",\"artistas\",\"capturas\",\"slider principal\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/\",\"name\":\"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\",\"datePublished\":\"2025-03-20T23:01:44+00:00\",\"dateModified\":\"2025-03-21T07:41:00+00:00\",\"description\":\"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg\",\"width\":688,\"height\":459,\"caption\":\"Theo van Doesburg: Dibujos y pinturas representando y reelaborando una vaca, yendo desde la representaci\u00f3n \\\"realista\\\" hasta la abstracci\u00f3n y las puras relaciones pl\u00e1sticas primarias y geom\u00e9tricas. (Pero este es un momento inicial e inmaduro: Al madurar, De Stijl ya no trata de cuadricular una vaca, sino que no parte de una vaca para empezar a pintar).\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/la-plastica-es-culpable-jose-ramon-hernandez-correa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"description\":\"veredes\",\"publisher\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\"},\"alternateName\":\"veredes\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veredes.es\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#organization\",\"name\":\"veredes, arquitectura y divulgaci\u00f3n\",\"alternateName\":\"veredes\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/veredes-logo-centrado_140x54.png\",\"width\":140,\"height\":54,\"caption\":\"veredes, arquitectura y divulgaci\u00f3n\"},\"image\":{\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/veredesArquitecturayDivulgacion\\\/\",\"https:\\\/\\\/x.com\\\/veredes\",\"https:\\\/\\\/instagram.com\\\/veredes\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/veredes-arquitectura-y-divulgacion\\\/\",\"https:\\\/\\\/es.pinterest.com\\\/veredes\\\/\",\"https:\\\/\\\/www.tumblr.com\\\/veredes\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/#\\\/schema\\\/person\\\/eefca3204fa5a4349162c2869bee6c49\",\"name\":\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg\",\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/veredes.es\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg\",\"caption\":\"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa\"},\"description\":\"Nac\u00ed en 1960. Arquitecto por la ETSAM, 1985. Doctor Arquitecto por la Universidad Polit\u00e9cnica de Madrid, 1992. Soy, en el buen sentido de la palabra, bueno. Ahora estoy algo cansado, pero sigo atento y curioso. Arquitecto, bloguero, saxofonero, escritor... pero todo mal.\",\"sameAs\":[\"http:\\\/\\\/arquitectamoslocos.blogspot.com.es\\\/\",\"https:\\\/\\\/www.facebook.com\\\/joseramon.hernandezcorrea\",\"https:\\\/\\\/www.instagram.com\\\/arquitectamoslocos\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/jos-ramn-hernndez-correa-b6378b2a\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/arquitectamos\"],\"url\":\"https:\\\/\\\/veredes.es\\\/blog\\\/author\\\/arquitectamos\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes","description":"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/","og_locale":"es_ES","og_type":"article","og_title":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes","og_description":"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","og_url":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/","og_site_name":"veredes, arquitectura y divulgaci\u00f3n","article_publisher":"https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","article_author":"https:\/\/www.facebook.com\/joseramon.hernandezcorrea","article_published_time":"2025-03-20T23:01:44+00:00","article_modified_time":"2025-03-21T07:41:00+00:00","og_image":[{"width":688,"height":459,"url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg","type":"image\/jpeg"}],"author":"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/arquitectamos","twitter_site":"@veredes","twitter_misc":{"Escrito por":"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#article","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/"},"author":{"name":"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/eefca3204fa5a4349162c2869bee6c49"},"headline":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","datePublished":"2025-03-20T23:01:44+00:00","dateModified":"2025-03-21T07:41:00+00:00","mainEntityOfPage":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/"},"wordCount":1677,"commentCount":0,"publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"image":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg","keywords":["arte","arte contemporaneo","Bauhaus","dada\u00edsmo","De Stijl","Jacobus Henricus van 't Hoff","John le Carr\u00e9","Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","Piet Mondrian","Theo van Doesburg"],"articleSection":["arte","artistas","capturas","slider principal"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/","url":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/","name":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa - veredes","isPartOf":{"@id":"https:\/\/veredes.es\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#primaryimage"},"image":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#primaryimage"},"thumbnailUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg","datePublished":"2025-03-20T23:01:44+00:00","dateModified":"2025-03-21T07:41:00+00:00","description":"Toda la informaci\u00f3n sobre: La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","breadcrumb":{"@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#primaryimage","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2025\/03\/La-plastica-es-culpable-Jose-Ramon-Hernandez-Correa-Theo-van-Doesburg-Dibujos-y-pinturas-representando-y-reelaborando-una-vaca.jpg","width":688,"height":459,"caption":"Theo van Doesburg: Dibujos y pinturas representando y reelaborando una vaca, yendo desde la representaci\u00f3n \"realista\" hasta la abstracci\u00f3n y las puras relaciones pl\u00e1sticas primarias y geom\u00e9tricas. (Pero este es un momento inicial e inmaduro: Al madurar, De Stijl ya no trata de cuadricular una vaca, sino que no parte de una vaca para empezar a pintar)."},{"@type":"BreadcrumbList","@id":"https:\/\/veredes.es\/blog\/la-plastica-es-culpable-jose-ramon-hernandez-correa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/veredes.es\/blog\/"},{"@type":"ListItem","position":2,"name":"La pl\u00e1stica es culpable | Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa"}]},{"@type":"WebSite","@id":"https:\/\/veredes.es\/blog\/#website","url":"https:\/\/veredes.es\/blog\/","name":"veredes, arquitectura y divulgaci\u00f3n","description":"veredes","publisher":{"@id":"https:\/\/veredes.es\/blog\/#organization"},"alternateName":"veredes","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veredes.es\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/veredes.es\/blog\/#organization","name":"veredes, arquitectura y divulgaci\u00f3n","alternateName":"veredes","url":"https:\/\/veredes.es\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2021\/12\/veredes-logo-centrado_140x54.png","width":140,"height":54,"caption":"veredes, arquitectura y divulgaci\u00f3n"},"image":{"@id":"https:\/\/veredes.es\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/veredesArquitecturayDivulgacion\/","https:\/\/x.com\/veredes","https:\/\/instagram.com\/veredes\/","https:\/\/www.linkedin.com\/company\/veredes-arquitectura-y-divulgacion\/","https:\/\/es.pinterest.com\/veredes\/","https:\/\/www.tumblr.com\/veredes"]},{"@type":"Person","@id":"https:\/\/veredes.es\/blog\/#\/schema\/person\/eefca3204fa5a4349162c2869bee6c49","name":"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg","url":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg","contentUrl":"https:\/\/veredes.es\/blog\/wp-content\/uploads\/2018\/04\/Jos\u00e9-Ram\u00f3n-Hern\u00e1ndez-Correa-96x96.jpg","caption":"Jos\u00e9 Ram\u00f3n Hern\u00e1ndez Correa"},"description":"Nac\u00ed en 1960. Arquitecto por la ETSAM, 1985. Doctor Arquitecto por la Universidad Polit\u00e9cnica de Madrid, 1992. Soy, en el buen sentido de la palabra, bueno. Ahora estoy algo cansado, pero sigo atento y curioso. Arquitecto, bloguero, saxofonero, escritor... pero todo mal.","sameAs":["http:\/\/arquitectamoslocos.blogspot.com.es\/","https:\/\/www.facebook.com\/joseramon.hernandezcorrea","https:\/\/www.instagram.com\/arquitectamoslocos\/","https:\/\/www.linkedin.com\/in\/jos-ramn-hernndez-correa-b6378b2a\/","https:\/\/x.com\/https:\/\/twitter.com\/arquitectamos"],"url":"https:\/\/veredes.es\/blog\/author\/arquitectamos\/"}]}},"_links":{"self":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/101248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/users\/33"}],"replies":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/comments?post=101248"}],"version-history":[{"count":0,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/posts\/101248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media\/101250"}],"wp:attachment":[{"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/media?parent=101248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/categories?post=101248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/veredes.es\/blog\/wp-json\/wp\/v2\/tags?post=101248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}